{"id":333609,"date":"2020-08-16T02:00:00","date_gmt":"2020-08-16T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/resultats-actuels-et-avis-dexperts-en-cardiologie-sur-les-iec-et-les-ara\/"},"modified":"2020-08-16T02:00:00","modified_gmt":"2020-08-16T00:00:00","slug":"resultats-actuels-et-avis-dexperts-en-cardiologie-sur-les-iec-et-les-ara","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/resultats-actuels-et-avis-dexperts-en-cardiologie-sur-les-iec-et-les-ara\/","title":{"rendered":"R\u00e9sultats actuels et avis d&#8217;experts en cardiologie sur les IEC et les ARA"},"content":{"rendered":"<p><strong>Les personnes concern\u00e9es et les professionnels de la sant\u00e9 se demandent si les IEC et les ARA sont associ\u00e9s \u00e0 un risque accru. Les donn\u00e9es empiriques \u00e0 ce sujet sont incoh\u00e9rentes, mais il existe des raisons valables pour ne pas arr\u00eater ces m\u00e9dicaments par crainte d&#8217;une contamination par le coronavirus ou pendant une infection par le COVID-19.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>&#8220;L&#8217;hypertension et les autres facteurs de risque cardiovasculaire ne sont pas associ\u00e9s en soi \u00e0 une sensibilit\u00e9 accrue aux infections, mais les maladies cardiovasculaires pr\u00e9existantes entra\u00eenent une \u00e9volution grave et sont associ\u00e9es \u00e0 un mauvais pronostic lorsqu&#8217;elles sont associ\u00e9es \u00e0 un \u00e2ge avanc\u00e9 et au sexe masculin&#8221;, a expliqu\u00e9 le professeur Franz Eberli, m\u00e9decin-chef en cardiologie \u00e0 l&#8217;h\u00f4pital municipal de Triemli, lors du congr\u00e8s en ligne du Forum f\u00fcr medizinische Fortbildung (FomF).&nbsp;  le 23.6.2020 [1]. Il n&#8217;a pas encore \u00e9t\u00e9 \u00e9tabli si les personnes souffrant d&#8217;hypertension comme seule comorbidit\u00e9 constituent un groupe \u00e0 risque, les r\u00e9sultats \u00e0 ce sujet \u00e9tant inconsistants. Dans une analyse bivari\u00e9e d&#8217;une \u00e9tude publi\u00e9e en 2020 dans le JAMA, ni l&#8217;hypertension, ni le diab\u00e8te, ni les ant\u00e9c\u00e9dents cardiovasculaires ne se sont r\u00e9v\u00e9l\u00e9s \u00eatre des facteurs de risque ind\u00e9pendants de SDRA (syndrome de d\u00e9tresse respiratoire aigu\u00eb) et de d\u00e9c\u00e8s chez les patients COVID-19 [2]. En revanche, une \u00e9tude d&#8217;observation r\u00e9trospective \u00e9galement men\u00e9e en Chine a montr\u00e9 une mortalit\u00e9 deux fois plus \u00e9lev\u00e9e chez les patients hypertendus [3].<\/p>\n<h2 id=\"devise-actuelle-ne-pas-arreter-les-inhibiteurs-de-leca-et-les-ara\">Devise actuelle : ne pas arr\u00eater les inhibiteurs de l&#8217;ECA et les ARA<\/h2>\n<p>La question de savoir si un traitement par IEC et ARA doit \u00eatre poursuivi ou non en cas de maladie COVID-19 est \u00e9galement controvers\u00e9e. Apr\u00e8s avoir \u00e9mis l&#8217;hypoth\u00e8se que les inhibiteurs de l&#8217;ECA et les antagonistes des r\u00e9cepteurs de l&#8217;angiotensine II (ARA) pouvaient pr\u00e9senter un risque dans le contexte d&#8217;une infection par le SRAS-CoV-2, trois \u00e9tudes publi\u00e9es dans le New England Journal of Medicine ont r\u00e9fut\u00e9 cette hypoth\u00e8se. Ces derniers ont conclu qu&#8217;un traitement par IEC et ARA n&#8217;avait pas d&#8217;impact n\u00e9gatif sur l&#8217;\u00e9volution de la maladie COVID-19. Mancia et al. ont pu montrer dans une \u00e9tude cas-t\u00e9moins qu&#8217;il n&#8217;y avait pas d&#8217;augmentation du taux d&#8217;intubation ou de mortalit\u00e9, ind\u00e9pendamment de l&#8217;\u00e2ge et du sexe [4]. 6272 patients ayant contract\u00e9 le virus dans le nord de l&#8217;Italie entre le 21 f\u00e9vrier et le 11 mars ont \u00e9t\u00e9 analys\u00e9s et compar\u00e9s \u00e0 30 759 volontaires appari\u00e9s selon l&#8217;\u00e2ge, le sexe et le lieu de r\u00e9sidence en termes de prescriptions de m\u00e9dicaments et de caract\u00e9ristiques cliniques. Il s&#8217;est av\u00e9r\u00e9 que les patients infect\u00e9s \u00e9taient certes plus souvent trait\u00e9s par des IEC ou des ARA que les t\u00e9moins, mais qu&#8217;ils prenaient \u00e9galement plus souvent d&#8217;autres antihypertenseurs tels que des antagonistes des canaux calciques ou des b\u00eatabloquants. Cela s&#8217;explique par le fait que les patients infect\u00e9s souffraient plus souvent de maladies cardiovasculaires telles que l&#8217;hypertension que les t\u00e9moins. Apr\u00e8s ajustement en fonction des maladies concomitantes et d&#8217;autres facteurs d&#8217;influence, la prise d&#8217;inhibiteurs du SRAA n&#8217;\u00e9tait pas significativement associ\u00e9e au risque d&#8217;infection et aucun lien n&#8217;a pu \u00eatre \u00e9tabli avec la gravit\u00e9 de l&#8217;\u00e9volution de l&#8217;infection. Une \u00e9tude de cohorte r\u00e9alis\u00e9e par Reynolds et al. plaide \u00e9galement contre l&#8217;hypoth\u00e8se selon laquelle les inhibiteurs du SRAA favorisent les \u00e9volutions graves du COVID-19 [5]. Au total, les donn\u00e9es de 12 594 patients de la ville de New York ont \u00e9t\u00e9 analys\u00e9es. 46,8% d&#8217;entre eux ont \u00e9t\u00e9 test\u00e9s positifs au SRAS-CoV-2, dont 17% ont \u00e9t\u00e9 class\u00e9s comme graves (\u00e0 l&#8217;admission aux urgences, assistance respiratoire ou d\u00e9c\u00e8s). Les patients COVID-19 trait\u00e9s par des inhibiteurs du SRAA, des b\u00eatabloquants, des antagonistes des canaux calciques ou des diur\u00e9tiques thiazidiques ont \u00e9t\u00e9 compar\u00e9s aux patients sans prescription de ce type en termes de pronostic et d&#8217;oucome. L&#8217;analyse d&#8217;une correspondance par score de propension a montr\u00e9 qu&#8217;aucune des classes d&#8217;antihypertenseurs \u00e9tudi\u00e9es n&#8217;\u00e9tait associ\u00e9e \u00e0 une augmentation substantielle du risque d&#8217;\u00e9volution grave et que le risque d&#8217;infection n&#8217;\u00e9tait pas non plus accru pour les patients trait\u00e9s par ces classes. Dans une \u00e9tude de registre r\u00e9alis\u00e9e par Mehra et al. [6] a \u00e9galement r\u00e9fut\u00e9 le fait que les inhibiteurs du SRAA augmentent le risque de mortalit\u00e9 li\u00e9 au COVID-19. Au total, les donn\u00e9es de 8910 patients de 11 pays qui ont d\u00fb \u00eatre hospitalis\u00e9s pour COVID-19 ont \u00e9t\u00e9 incluses. Une analyse de r\u00e9gression multivari\u00e9e a montr\u00e9 que ni la prise d&#8217;IEC ni celle d&#8217;ARA n&#8217;\u00e9taient associ\u00e9es \u00e0 un risque accru de mortalit\u00e9 intrahospitali\u00e8re.<\/p>\n<h2 id=\"que-sait-on-de-linteraction-entre-le-sars-cov-2-et-le-raas\">Que sait-on de l&#8217;interaction entre le SARS-CoV-2 et le RAAS ?<\/h2>\n<p>&#8220;Le syst\u00e8me RAAS est complexe et il est impossible de pr\u00e9dire un simple m\u00e9canisme de cause \u00e0 effet&#8221;, a expliqu\u00e9 le professeur Eberli. Au cours de l&#8217;infection par le SRAS-CoV-2, on a constat\u00e9 une diminution de l&#8217;ACE2 \u00e0 la surface des cellules et l&#8217;on pense actuellement que l&#8217;ACE2 joue un r\u00f4le critique dans l&#8217;infection par le SRAS-CoV-2. L&#8217;ACE2 n&#8217;est pas seulement exprim\u00e9 dans le c\u0153ur et le syst\u00e8me vasculaire, mais aussi dans d&#8217;autres organes de l&#8217;organisme humain (par exemple les reins, les poumons, le foie). Selon une publication de Vaduganathan et al. [7], l&#8217;infection par le SRAS-CoV-2 provoque une diminution de l&#8217;ACE2 \u00e0 la surface des cellules et une l\u00e9sion pulmonaire aigu\u00eb via l&#8217;activation du syst\u00e8me RAAS. L&#8217;activation du SRAA par le virus du SRAS-CoV-2 contribue \u00e0 l&#8217;atteinte des organes (poumons, c\u0153ur, reins). Le blocage de l&#8217;action de l&#8217;angiotensine II par des inhibiteurs de l&#8217;ECA ou des ARA est potentiellement b\u00e9n\u00e9fique. Des \u00e9tudes d&#8217;observation ont montr\u00e9 que les inhibiteurs de l&#8217;ECA et le traitement par ARA r\u00e9duisent la mortalit\u00e9 [3].&nbsp;  En revanche, l&#8217;hypertension et l&#8217;arr\u00eat d&#8217;un traitement hypertenseur sont associ\u00e9s \u00e0 un risque accru de mortalit\u00e9.&nbsp; &nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Eberli F : COVID-19 et le syst\u00e8me cardiovasculaire. Prof. Franz Eberli, FOMF m\u00e9decine interne, 23.6.20.<\/li>\n<li>Wu C, et al : Risk Factors Associated With Acute Respiratory Distress Syndrome and Death in Patients With Coronavirus Disease 2019 Pneumonia in Wuhan, China. JAMA Intern Med 2020 ; 180(7) : 1-11.<\/li>\n<li>Gao C et al : Association de l&#8217;hypertension et du traitement antihypertenseur avec la mortalit\u00e9 COVID-19 : une \u00e9tude observationnelle r\u00e9trospective European Heart Journal 2020 ; 41 : 2058-2066.<\/li>\n<li>Mancia G, et al. : Bloqueurs du syst\u00e8me r\u00e9nine-angiotensine-aldost\u00e9rone et le risque de Covid-19. N Engl J Med 2020 ; DOI : 10.1056\/NEJMoa2006923<\/li>\n<li>Reynolds HR et al. Inhibiteurs du syst\u00e8me r\u00e9nine-angiotensine-aldost\u00e9rone et risque de Covid-19. N Engl J Med 2020 ; DOI : 10.1056\/NEJMoa2008975<\/li>\n<li>Mehra M, et al : Cardiovascular Disease, Drug Therapy, and Mortality in Covid-19 ; N Engl J Med 2020 ; DOI : 10.1056\/NEJMoa2007621<\/li>\n<li>Vaduganathan M, et al : Inhibiteurs du syst\u00e8me r\u00e9nine-angiotensine-aldost\u00e9rone chez les patients atteints de Covid-19. rapport sp\u00e9cial. N Engl J Med 2020 ; 382 : 1653-1659.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>HAUSARZT PRAXIS 2020 ; 15(8) : 33 (publi\u00e9 le 16.8.20, ahead of print)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les personnes concern\u00e9es et les professionnels de la sant\u00e9 se demandent si les IEC et les ARA sont associ\u00e9s \u00e0 un risque accru. Les donn\u00e9es empiriques \u00e0 ce sujet sont&hellip;<\/p>\n","protected":false},"author":7,"featured_media":98816,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"COVID-19 et maladies cardiovasculaires  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11523,11378,11531,11428,11315,11549],"tags":[13253,13255,13458,13192],"powerkit_post_featured":[],"class_list":["post-333609","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-cardiologie","category-formation-continue","category-infectiologie","category-medecine-interne-generale","category-rx-fr","tag-corona-fr","tag-covid-fr","tag-hypertension-fr","tag-sars-cov-2-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:44:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":333616,"slug":"risultati-attuali-e-opinione-di-esperti-cardiologi-sugli-ace-inibitori-e-gli-arb","post_title":"Risultati attuali e opinione di esperti cardiologi sugli ACE inibitori e gli ARB","href":"https:\/\/medizinonline.com\/it\/risultati-attuali-e-opinione-di-esperti-cardiologi-sugli-ace-inibitori-e-gli-arb\/"},"pt_PT":{"locale":"pt_PT","id":333653,"slug":"conclusoes-actuais-e-opiniao-de-peritos-cardiologicos-sobre-inibidores-da-eca-e-bar","post_title":"Conclus\u00f5es actuais e opini\u00e3o de peritos cardiol\u00f3gicos sobre inibidores da ECA e BAR","href":"https:\/\/medizinonline.com\/pt-pt\/conclusoes-actuais-e-opiniao-de-peritos-cardiologicos-sobre-inibidores-da-eca-e-bar\/"},"es_ES":{"locale":"es_ES","id":333664,"slug":"hallazgos-actuales-y-opinion-de-expertos-cardiologos-sobre-los-inhibidores-de-la-eca-y-los-ara","post_title":"Hallazgos actuales y opini\u00f3n de expertos cardi\u00f3logos sobre los inhibidores de la ECA y los ARA","href":"https:\/\/medizinonline.com\/es\/hallazgos-actuales-y-opinion-de-expertos-cardiologos-sobre-los-inhibidores-de-la-eca-y-los-ara\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/333609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=333609"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/333609\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=333609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=333609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=333609"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=333609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}