{"id":334400,"date":"2020-04-24T00:00:00","date_gmt":"2020-04-23T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/faits-marquants-et-donnees-actuelles-du-monde-de-lhematologie\/"},"modified":"2020-04-24T00:00:00","modified_gmt":"2020-04-23T22:00:00","slug":"faits-marquants-et-donnees-actuelles-du-monde-de-lhematologie","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/faits-marquants-et-donnees-actuelles-du-monde-de-lhematologie\/","title":{"rendered":"Faits marquants et donn\u00e9es actuelles du monde de l&#8217;h\u00e9matologie"},"content":{"rendered":"<p><strong>Les participants \u00e0 l&#8217;ASH se sont plong\u00e9s dans le monde de l&#8217;h\u00e9matologie fin 2019. Les participants ont pu d\u00e9couvrir les derni\u00e8res donn\u00e9es d&#8217;\u00e9tudes et les d\u00e9couvertes concernant notamment le my\u00e9lome multiple, le traitement par cellules CAR-T dans le LBCL et le traitement d&#8217;entretien dans la LAM.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La majorit\u00e9 des patients atteints de my\u00e9lome malin sont touch\u00e9s par une r\u00e9cidive, qui survient dans de nombreux cas sous traitement par l\u00e9nalidomide. L&#8217;\u00e9tude men\u00e9e par Usmai et al. a donc \u00e9valu\u00e9 l&#8217;efficacit\u00e9 des r\u00e9gimes sans l\u00e9nalidomide chez les patients atteints de my\u00e9lome multiple r\u00e9cidivant\/r\u00e9fractaire (r\/r). Un total de 466 patients ayant re\u00e7u auparavant de un \u00e0 trois traitements ant\u00e9rieurs ont \u00e9t\u00e9 inclus dans l&#8217;\u00e9tude ouverte de phase III. Environ un tiers des patients \u00e9taient r\u00e9fractaires au l\u00e9nalidomide. Ils ont \u00e9t\u00e9 randomis\u00e9s pour recevoir le carfilzomib et la dexam\u00e9thasone (Cd) ou le daratumumab plus le carfilzomib et la dexam\u00e9thasone (DCd). Apr\u00e8s un suivi moyen de 17 mois, la survie sans progression (PFS) moyenne sous Cd \u00e9tait de 16 mois ; dans le groupe sous la triple association, la PFS n&#8217;\u00e9tait pas encore atteinte. Cet avantage en termes de SSP a \u00e9galement \u00e9t\u00e9 observ\u00e9 chez les patients expos\u00e9s au l\u00e9nalidomide et r\u00e9fractaires. En outre, le pourcentage de patients chez lesquels aucune maladie r\u00e9siduelle minimale (MRD) n&#8217;a \u00e9t\u00e9 d\u00e9tect\u00e9e \u00e0 12 mois \u00e9tait presque 10 fois plus \u00e9lev\u00e9 sous DCd que sous Cd (12,5% contre 1,3%). La fr\u00e9quence des arr\u00eats de traitement en raison d&#8217;\u00e9v\u00e9nements ind\u00e9sirables \u00e9tait comparable dans les deux groupes.<\/p>\n<h2 id=\"axicabtagen-ciloleucel-succes-dans-le-lbcl-r-r\">Axicabtagen-Ciloleucel :&nbsp;Succ\u00e8s dans le LBCL r\/r<\/h2>\n<p>La th\u00e9rapie par cellules CAR-T consiste \u00e0 modifier g\u00e9n\u00e9tiquement des cellules T autologues pour qu&#8217;elles portent \u00e0 leur surface un r\u00e9cepteur antig\u00e9nique chim\u00e9rique (CAR) sp\u00e9cifique \u00e0 la tumeur. Apr\u00e8s la r\u00e9injection, les cellules CAR-T d\u00e9clenchent l&#8217;apoptose et la n\u00e9crose des cellules cibles reconnues. Axicabtagen-Ciloleucel (Axi-cel) est un traitement par cellules CAR-T ciblant les cellules tumorales exprimant CD19. Il est utilis\u00e9 pour traiter les patients atteints de lymphome B \u00e0 grandes cellules r\/r (LBCL) sur la base des donn\u00e9es de l&#8217;\u00e9tude ZUMA-1 (cohortes 1 et 2). Les donn\u00e9es pr\u00e9sent\u00e9es montrent clairement que les patients peuvent b\u00e9n\u00e9ficier d&#8217;un traitement par Axi-cel avec une augmentation significative de la survie globale (OS) par rapport aux r\u00e9gimes de sauvetage disponibles jusqu&#8217;\u00e0 pr\u00e9sent. C&#8217;est la conclusion que l&#8217;on peut tirer d&#8217;une comparaison descriptive des r\u00e9sultats de l&#8217;\u00e9tude ZUMA 1 et de la cohorte SCHOLAR 1. Dans cette analyse r\u00e9trospective de 497 patients LBCL r\/r trait\u00e9s avec les r\u00e9gimes de sauvetage disponibles jusqu&#8217;\u00e0 pr\u00e9sent, le taux d&#8217;OS \u00e0 deux ans \u00e9tait de 12%, contre 50% sous Axi-cel (hazard ratio 0,27). Les donn\u00e9es \u00e0 trois ans des cohortes 1 et 2 de l&#8217;\u00e9tude ZUMA-1 sont \u00e9galement disponibles et soulignent l&#8217;efficacit\u00e9 continue d&#8217;Axi-cel : Apr\u00e8s un suivi m\u00e9dian de 39,1 mois, le taux de survie globale \u00e9tait de 47%.<\/p>\n<h2 id=\"limmunotherapie-est-superieure-a-la-chimiotherapie-chez-les-enfants-atteints-de-b-all-recidivante\">L&#8217;immunoth\u00e9rapie est sup\u00e9rieure \u00e0 la chimioth\u00e9rapie chez les enfants atteints de B-ALL r\u00e9cidivante<\/h2>\n<p>Des donn\u00e9es confirmant l&#8217;utilit\u00e9 du blinatumomab &#8211; une construction d&#8217;anticorps T-cell-Engager bisp\u00e9cifique (<sup>BiTE\u00ae<\/sup>) &#8211; chez des patients p\u00e9diatriques atteints de leuc\u00e9mie lymphoblastique aigu\u00eb (B-ALL) en rechute et pr\u00e9sentant une maladie r\u00e9siduelle minimale (MRD) apr\u00e8s une chimioth\u00e9rapie initiale ont \u00e9t\u00e9 pr\u00e9sent\u00e9es en tant que late breaker abstract. L&#8217;inclusion dans l&#8217;\u00e9tude a \u00e9t\u00e9 arr\u00eat\u00e9e pr\u00e9matur\u00e9ment apr\u00e8s qu&#8217;une analyse interm\u00e9diaire a mis en \u00e9vidence les avantages du blinatumomab par rapport \u00e0 la chimioth\u00e9rapie standard : Apr\u00e8s un suivi moyen de 1,4 an, les taux de PFS et d&#8217;OS des patients sous blinatumomab \u00e9taient significativement plus \u00e9lev\u00e9s que ceux des patients sous chimioth\u00e9rapie standard (respectivement 59% vs 41% et 79% vs 59%). En outre, davantage de patients atteints de blinatumomab ont pu b\u00e9n\u00e9ficier d&#8217;une transplantation (73% contre 45%). Le blinatumomab a en outre \u00e9t\u00e9 mieux tol\u00e9r\u00e9 que la chimioth\u00e9rapie standard.<\/p>\n<h2 id=\"lazacitidine-orale-futur-traitement-dentretien-de-la-lam\">L&#8217;azacitidine orale, futur traitement d&#8217;entretien de la LAM ?<\/h2>\n<p>Selon un autre r\u00e9sum\u00e9 r\u00e9cent, une forme orale du traitement par azacitidine (CC-486) permet d&#8217;obtenir une am\u00e9lioration statistiquement significative et cliniquement significative de la SG et de la survie sans r\u00e9cidive chez des patients \u00e2g\u00e9s atteints de leuc\u00e9mie my\u00e9lo\u00efde aigu\u00eb (LMA) nouvellement diagnostiqu\u00e9e et qui \u00e9taient en r\u00e9mission apr\u00e8s une chimioth\u00e9rapie d&#8217;induction standard. 472 patients atteints de LAM, \u00e2g\u00e9s de 55 \u00e0 86 ans et pr\u00e9sentant un risque cytog\u00e9n\u00e9tique moyen ou faible, ont \u00e9t\u00e9 randomis\u00e9s dans l&#8217;\u00e9tude QUAZAR AML-001 pour recevoir le CC-486 ou un placebo &#8211; chacun plus les meilleurs soins de soutien &#8211; jusqu&#8217;\u00e0 la r\u00e9cidive dans les quatre mois suivant l&#8217;obtention d&#8217;une r\u00e9mission compl\u00e8te. Apr\u00e8s un suivi moyen de 41,2 mois, les patients trait\u00e9s par CC-486 ont vu leur risque de d\u00e9c\u00e8s diminuer de 31% par rapport au placebo (OS m\u00e9dian de 24,7 contre 14,8 mois). Les \u00e9v\u00e9nements ind\u00e9sirables de grade \u22653 ou 4 les plus fr\u00e9quents \u00e9taient les neutrop\u00e9nies, les thrombocytop\u00e9nies et les an\u00e9mies.<\/p>\n<h2 id=\"ameliorer-lacces-a-la-therapie\">Am\u00e9liorer l&#8217;acc\u00e8s \u00e0 la th\u00e9rapie<\/h2>\n<p>Des \u00e9tudes ont \u00e9galement \u00e9t\u00e9 pr\u00e9sent\u00e9es \u00e0 Orlando pour d\u00e9terminer dans quelle mesure la d\u00e9mographie et le statut socio-\u00e9conomique affectent l&#8217;acc\u00e8s aux essais cliniques et aux traitements efficaces pour les patients atteints de maladies h\u00e9matologiques. Certaines \u00e9tudes ont montr\u00e9 que les minorit\u00e9s ethniques et les patients \u00e2g\u00e9s b\u00e9n\u00e9ficient des traitements contre le cancer de la m\u00eame mani\u00e8re que les autres groupes de patients. Cependant, certaines \u00e9tudes ont montr\u00e9 que des lacunes importantes subsistent en termes d&#8217;acc\u00e8s aux soins et de r\u00e9sultats. Cela souligne la n\u00e9cessit\u00e9 urgente de redoubler d&#8217;efforts pour \u00e9liminer les disparit\u00e9s.<\/p>\n<h2 id=\"doacs-plus-ass-plus-de-mal-que-de-bien\">DOACs plus ASS &#8211; plus de mal que de bien<\/h2>\n<p>Une \u00e9tude portant sur des patients souffrant de fibrillation auriculaire ou ayant des ant\u00e9c\u00e9dents de thromboembolie veineuse (TEV) a \u00e9galement retenu l&#8217;attention. Elle a montr\u00e9 que la prise d&#8217;acide ac\u00e9tylsalicylique (ASA) en plus d&#8217;un anticoagulant oral direct (DOAC) entra\u00eenait davantage d&#8217;\u00e9pisodes h\u00e9morragiques avec des taux comparables d&#8217;AVC, de TEV et d&#8217;infarctus du myocarde par rapport \u00e0 un DOAC seul. Pour pr\u00e8s d&#8217;un tiers des patients inclus dans l&#8217;\u00e9tude (n=2045), il n&#8217;y avait pas d&#8217;indication claire pour la prise d&#8217;AAS, comme par exemple un infarctus du myocarde r\u00e9cent. Le professeur Jordan Schaefer, Ann Arbor, Michigan, \u00c9tats-Unis, a donc appel\u00e9 \u00e0 bien \u00e9valuer le risque relatif et le b\u00e9n\u00e9fice potentiel pour le patient en cas d&#8217;ajout d&#8217;ASA ou de poursuite de l&#8217;administration d&#8217;ASA en plus d&#8217;un DOAC.<\/p>\n<p><em>Source : ASH 2019<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo ONKOLOGIE &amp; H\u00c4MATOLOGIE 2020 ; 8(1) : 31 (publi\u00e9 le 23.2.20, ahead of print)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les participants \u00e0 l&#8217;ASH se sont plong\u00e9s dans le monde de l&#8217;h\u00e9matologie fin 2019. Les participants ont pu d\u00e9couvrir les derni\u00e8res donn\u00e9es d&#8217;\u00e9tudes et les d\u00e9couvertes concernant notamment le my\u00e9lome&hellip;<\/p>\n","protected":false},"author":7,"featured_media":94694,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"N\u00e9oplasies h\u00e9matologiques","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11373,11389,11535,11549],"tags":[25716,13859],"powerkit_post_featured":[],"class_list":["post-334400","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hematologie","category-oncologie","category-rapports-de-congres","category-rx-fr","tag-ash-fr","tag-myelome-multiple","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:03:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":334411,"slug":"dati-salienti-e-attuali-dal-mondo-dellematologia","post_title":"Dati salienti e attuali dal mondo dell'ematologia","href":"https:\/\/medizinonline.com\/it\/dati-salienti-e-attuali-dal-mondo-dellematologia\/"},"pt_PT":{"locale":"pt_PT","id":334419,"slug":"destaques-e-dados-actuais-do-mundo-da-hematologia","post_title":"Destaques e dados actuais do mundo da hematologia","href":"https:\/\/medizinonline.com\/pt-pt\/destaques-e-dados-actuais-do-mundo-da-hematologia\/"},"es_ES":{"locale":"es_ES","id":334426,"slug":"lo-mas-destacado-y-los-datos-mas-actuales-del-mundo-de-la-hematologia","post_title":"Lo m\u00e1s destacado y los datos m\u00e1s actuales del mundo de la hematolog\u00eda","href":"https:\/\/medizinonline.com\/es\/lo-mas-destacado-y-los-datos-mas-actuales-del-mundo-de-la-hematologia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/334400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=334400"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/334400\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=334400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=334400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=334400"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=334400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}