{"id":334464,"date":"2020-04-09T03:00:00","date_gmt":"2020-04-09T01:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/qui-cherche-plus-trouve\/"},"modified":"2020-04-09T03:00:00","modified_gmt":"2020-04-09T01:00:00","slug":"qui-cherche-plus-trouve","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/qui-cherche-plus-trouve\/","title":{"rendered":"Qui cherche (plus) trouve"},"content":{"rendered":"<p><strong>Le nombre de personnes nouvellement infect\u00e9es est un indicateur cl\u00e9 d&#8217;un \u00e9ventuel assouplissement du lockdown &#8211; il suffit de l&#8217;interpr\u00e9ter correctement.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Le nombre de personnes nouvellement infect\u00e9es par le COVID-19 est un indicateur cl\u00e9 pour d\u00e9terminer si le lockdown doit \u00eatre assoupli ou maintenu \u00e0 son niveau actuel apr\u00e8s le 19 avril.<\/p>\n<p>Les chiffres publi\u00e9s par l&#8217;OFSP concernant les personnes nouvellement infect\u00e9es ne peuvent toutefois \u00eatre correctement \u00e9valu\u00e9s que par rapport au nombre de tests de d\u00e9pistage du SRAS-CoV-2 effectu\u00e9s par unit\u00e9 de temps. Sur 150 000 tests effectu\u00e9s, environ 21 000 ont \u00e9t\u00e9 d\u00e9clar\u00e9s &#8220;positifs&#8221; jusqu&#8217;\u00e0 pr\u00e9sent. En comparaison internationale, la Suisse fait beaucoup de tests, entre-temps aussi dans le cadre d&#8217;un home- ou drive-in-testing. En supposant qu&#8217;il y ait de plus en plus de tests Corona effectu\u00e9s chaque jour, le pr\u00e9tendu &#8220;nombre stable&#8221; de personnes nouvellement infect\u00e9es (environ 1000\/jour) serait donc en fait une v\u00e9ritable diminution relative du nombre de personnes nouvellement infect\u00e9es (= accalmie).<\/p>\n<p>Outre les cons\u00e9quences \u00e9conomiques de la poursuite du lockdown actuel, il existe actuellement en Suisse un grand risque que les patients non COVID-19 soient sous-trait\u00e9s sur le plan m\u00e9dical, et ce bien que la majorit\u00e9 des h\u00f4pitaux suisses soient actuellement vides \u00e0 50-70% et que le personnel m\u00e9dical associ\u00e9 n&#8217;ait rien \u00e0 faire.<\/p>\n<p><em>Prof Dr med Paul Mohacsi, eMBA UZH, Herrliberg<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size:11px\">\u00a9 NZZ<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nombre de personnes nouvellement infect\u00e9es est un indicateur cl\u00e9 d&#8217;un \u00e9ventuel assouplissement du lockdown &#8211; il suffit de l&#8217;interpr\u00e9ter correctement.<\/p>\n","protected":false},"author":7,"featured_media":95802,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Lettre de lecteur","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11523,11428,11477,11549],"tags":[],"powerkit_post_featured":[],"class_list":["post-334464","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-infectiologie","category-pneumologie-fr","category-rx-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:53:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":334471,"slug":"chi-cerca-di-piu-trova","post_title":"Chi cerca (di pi\u00f9) trova","href":"https:\/\/medizinonline.com\/it\/chi-cerca-di-piu-trova\/"},"pt_PT":{"locale":"pt_PT","id":334478,"slug":"aquele-que-procura-mais-encontra","post_title":"Aquele que procura (mais) encontra","href":"https:\/\/medizinonline.com\/pt-pt\/aquele-que-procura-mais-encontra\/"},"es_ES":{"locale":"es_ES","id":334488,"slug":"el-que-busca-mas-encuentra","post_title":"El que busca (m\u00e1s) encuentra","href":"https:\/\/medizinonline.com\/es\/el-que-busca-mas-encuentra\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/334464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=334464"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/334464\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=334464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=334464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=334464"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=334464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}