{"id":334831,"date":"2020-02-03T16:09:39","date_gmt":"2020-02-03T15:09:39","guid":{"rendered":"https:\/\/medizinonline.com\/points-communs-et-differences-entre-les-agonistes-partiels-de-la-dopamine\/"},"modified":"2020-02-03T16:09:39","modified_gmt":"2020-02-03T15:09:39","slug":"points-communs-et-differences-entre-les-agonistes-partiels-de-la-dopamine","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/points-communs-et-differences-entre-les-agonistes-partiels-de-la-dopamine\/","title":{"rendered":"Points communs et diff\u00e9rences entre les agonistes partiels de la dopamine"},"content":{"rendered":"<p><strong>Les antipsychotiques sont le principal pilier du traitement aigu et \u00e0 long terme des troubles schizophr\u00e9niques. Plus le traitement antipsychotique est mis en place t\u00f4t, plus les chances de contr\u00f4ler ou de stopper la progression de la psychose sont grandes.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Le terme de schizophr\u00e9nie a \u00e9t\u00e9 invent\u00e9 par Eugen Bleuler et publi\u00e9 pour la premi\u00e8re fois en 1911 dans sa monographie &#8220;Groupe des schizophr\u00e9nies&#8221;. Aujourd&#8217;hui encore, ce terme technique vieux de 108 ans est utilis\u00e9 pour d\u00e9signer le principal trouble psychotique. Il y a six ans, le DSM-5, le manuel am\u00e9ricain de diagnostic, a introduit le terme de &#8220;trouble du spectre de la schizophr\u00e9nie&#8221;. Cependant, le premier traitement r\u00e9ellement efficace du trouble schizophr\u00e9nique n&#8217;a \u00e9t\u00e9 mis \u00e0 la disposition des h\u00f4pitaux psychiatriques qu&#8217;en 1952\/53. Cette th\u00e9rapie \u00e9tait bas\u00e9e sur des m\u00e9dicaments : Chlorpromazine. La chlorpromazine a \u00e9t\u00e9 transf\u00e9r\u00e9e d\u00e8s 1952 par Felix Labhart directement de la clinique psychiatrique universitaire parisienne \u00e0 la clinique universitaire b\u00e2loise. On peut supposer qu&#8217;\u00e0 l&#8217;\u00e9poque, cela s&#8217;est fait sans trop de bureaucratie.<\/p>\n<h2 id=\"petite-histoire-des-neuroleptiques-antipsychotiques\">Petite histoire des neuroleptiques\/antipsychotiques<\/h2>\n<p><sup>Chlorpromazine\/Largactil\u00ae<\/sup> a entra\u00een\u00e9 un bouleversement de la psychiatrie institutionnelle de l&#8217;\u00e9poque dans les ann\u00e9es qui ont suivi. Selon le professeur Raymond Battegay, les services dits &#8220;agit\u00e9s&#8221; sont devenus soudainement moins bruyants et beaucoup plus d\u00e9tendus avec les psychotiques excit\u00e9s. De nouvelles formes de relations plus humaines avec ces personnes atteintes de graves maladies mentales \u00e9taient d\u00e9sormais possibles.<\/p>\n<p>Le terme &#8220;neuroleptique&#8221; vient du grec et a \u00e9t\u00e9 introduit dans la litt\u00e9rature scientifique par Delay et Deniker en 1955. L&#8217;objectif \u00e9tait de cr\u00e9er un mod\u00e8le &#8220;\u00e9tiologique&#8221; pour le mode d&#8217;action des nouveaux m\u00e9dicaments antipsychotiques. Les deux Fran\u00e7ais avaient d\u00e9couvert que la chlorpromazine avait des effets s\u00e9datifs et anxiolytiques. En cons\u00e9quence, il a \u00e9t\u00e9 utilis\u00e9 pour l&#8217;agitation psychomotrice, principalement chez les patients schizophr\u00e8nes.<\/p>\n<p>L&#8217;introduction des neuroleptiques a ouvert une porte importante dans le traitement des troubles schizophr\u00e9niques. Il s&#8217;agissait tout d&#8217;abord d&#8217;un traitement r\u00e9versible (contrairement aux lobotomies, par exemple, qui \u00e9taient encore utilis\u00e9es \u00e0 l&#8217;\u00e9poque) et, ensuite, l&#8217;effet \u00e9tait rapide et efficace. En cons\u00e9quence, les dur\u00e9es de s\u00e9jour des personnes psychotiques dans les \u00e9tablissements de l&#8217;\u00e9poque ont \u00e9t\u00e9 massivement r\u00e9duites, ce qui a permis de d\u00e9sengorger les h\u00f4pitaux surpeupl\u00e9s. Des rechutes se sont produites lorsque les patients ont cess\u00e9 de prendre les m\u00e9dicaments. Les raisons \u00e9taient le manque de compr\u00e9hension de la maladie ou des effets secondaires non n\u00e9gligeables tels que la s\u00e9dation massive, le parkinsonisme (EPMS) ou la photosensibilit\u00e9.<\/p>\n<h2 id=\"decouverte-de-la-dopamine-comme-neurotransmetteur\">D\u00e9couverte de la dopamine comme neurotransmetteur<\/h2>\n<p>\u00c0 peu pr\u00e8s au m\u00eame moment o\u00f9 la chlorpromazine a \u00e9t\u00e9 introduite dans les h\u00f4pitaux psychiatriques, Arvid Carlsson (1923-2018) a d\u00e9couvert en Su\u00e8de la dopamine, sa structure et sa fonction en tant que neurotransmetteur important dans le cerveau. Carlsson et Lindqvist ont \u00e9galement fond\u00e9 par leurs travaux l&#8217;hypoth\u00e8se de la dopamine dans les psychoses, \u00e9tablie plus tard par van Rossum et Snyder et toujours en vigueur aujourd&#8217;hui. Celle-ci stipule que les antagonistes de la dopamine, c&#8217;est-\u00e0-dire les neuroleptiques ou les antipsychotiques, occupent les r\u00e9cepteurs de la dopamine (en particulier les r\u00e9cepteurs D2) au niveau postsynaptique et bloquent ainsi la neurotransmission de la dopamine. Il en r\u00e9sulte une am\u00e9lioration de la symptomatologie positive des troubles schizophr\u00e9niques. Alors que les neuroleptiques typiques am\u00e9liorent surtout les id\u00e9es d\u00e9lirantes et les hallucinations, ils n&#8217;ont que peu d&#8217;effet sur les caract\u00e9ristiques de la maladie appel\u00e9es plus tard sympt\u00f4mes n\u00e9gatifs, comme l&#8217;aplatissement affectif, l&#8217;alogie, le retrait social et l&#8217;apathie, voire les aggravent. C&#8217;est l\u00e0 que la clozapine et les antipsychotiques atypiques, mieux connus sous le nom d&#8217;antagonistes de la s\u00e9rotonine et de la dopamine, ont apport\u00e9 un net \u00e9largissement du spectre d&#8217;action.<\/p>\n<h2 id=\"introduction-de-medicaments-a-effet-antipsychotique\">Introduction de m\u00e9dicaments \u00e0 effet antipsychotique<\/h2>\n<p>Apr\u00e8s l&#8217;introduction de la chlorpromazine en 1952, divers neuroleptiques dits tricycliques, dont certains sont encore disponibles aujourd&#8217;hui, ont \u00e9t\u00e9 autoris\u00e9s au cours des 20 ann\u00e9es suivantes :  &nbsp;<\/p>\n<ul>\n<li>Du groupe de substances des ph\u00e9nothiazines (chlorpromazine, l\u00e9vom\u00e9promazine, fluph\u00e9nazine, promazine et triflupromazine),<\/li>\n<li>Du groupe de substances des thioxanth\u00e8nes (chlorprothix\u00e8ne et flupentixol).<\/li>\n<\/ul>\n<p>Au cours de la m\u00eame p\u00e9riode, d&#8217;autres neuroleptiques de structure non tricyclique, mais pr\u00e9sentant un profil d&#8217;effets secondaires similaire, ont \u00e9t\u00e9 autoris\u00e9s :<\/p>\n<ul>\n<li>Du groupe de substances des butyroph\u00e9nones (halop\u00e9ridol, pipamp\u00e9rone, melp\u00e9rone),<\/li>\n<li>De la famille des diph\u00e9nylbutylpip\u00e9ridines (fluspirile et pimozide\/plus sur le march\u00e9 aujourd&#8217;hui).<\/li>\n<\/ul>\n<p>La classification ci-dessus, bas\u00e9e sur la chimie structurelle, s&#8217;appuie sur les manuels de M\u00f6ller et al (2015) et de Kaplan Sadock (2015).<\/p>\n<p>En 1972, la clozapine (d\u00e9couverte d\u00e8s 1959) a \u00e9t\u00e9 autoris\u00e9e en Suisse. Elle pr\u00e9sentait un profil d&#8217;action particulier et un spectre d&#8217;effets secondaires diff\u00e9rent de celui des neuroleptiques utilis\u00e9s jusqu&#8217;alors. La FDA n&#8217;a autoris\u00e9 la clozapine qu&#8217;en 1990, ce qui explique que les \u00c9tats-Unis n&#8217;aient d\u00e9couvert son caract\u00e8re unique que plus tard. En tant que premier &#8220;antipsychotique atypique&#8221;, il est n\u00e9 :<\/p>\n<ul>\n<li>De la famille des dibenzodiaz\u00e9pines (clozapine) : ce groupe est \u00e9galement appel\u00e9 &#8220;pines&#8221; par St. Stahl dans son manuel en raison de leur terminaison : Cloza-pin ; comprend l&#8217;olanzapine, la qu\u00e9tiapine (toutes deux de structure \u00e9troitement apparent\u00e9e \u00e0 la clozapine) ; l&#8217;as\u00e9napine et la zot\u00e9pine. Le point commun de ces substances est leur profil multir\u00e9cepteur.<\/li>\n<\/ul>\n<p>Autres antipsychotiques atypiques :<\/p>\n<ul>\n<li>Du groupe de substances des benzisoxazoles (risp\u00e9ridone et ziprasidone) ; pour simplifier, on utilise \u00e9galement le terme g\u00e9n\u00e9rique de &#8220;dones&#8221; (risperi-done) sugg\u00e9r\u00e9 par St. Stahl pour d\u00e9signer les substances similaires au niveau des r\u00e9cepteurs : Risperidone, Paliperidone, Lurasidone, Ziprasidone. Ces derniers ont une pharmacologie des r\u00e9cepteurs moins &#8220;riche&#8221; que les &#8220;pines&#8221; et pr\u00e9sentent, \u00e0 des doses plus \u00e9lev\u00e9es avec l&#8217;EPMS, des EI similaires \u00e0 ceux des antagonistes dopaminergiques purs. La risp\u00e9ridone et la palip\u00e9ridone peuvent en outre entra\u00eener une augmentation de la prolactine ind\u00e9pendamment de la dose.<\/li>\n<li>Du groupe de substances des d\u00e9riv\u00e9s de la pip\u00e9razine (aripiprazole, brexpiprazole et cariprazine). Ces substances pr\u00e9sentent un effet nouveau et pharmacologiquement tr\u00e8s int\u00e9ressant. Ce sont des agonistes partiels de la dopamine. St. Stahl les appelle &#8220;two pips and a rip&#8221;, d&#8217;apr\u00e8s leur nom : Ari-pip-razol, Brex-pip-razol et Ca-rip-razin ; chez nous, ils sont appel\u00e9s en termes de m\u00e9moire l&#8217;ABC des agonistes partiels de la dopamine.<\/li>\n<\/ul>\n<p>Le point commun de toutes ces nouvelles substances (&#8220;pines\/dones\/two pips and a rip&#8221;) est l&#8217;antagonisme combin\u00e9 de la s\u00e9rotonine (5-HT2A) et de la dopamine D2. Ils ont \u00e9t\u00e9 introduits en Suisse apr\u00e8s 1990. L&#8217;aripiprazole est disponible en Suisse depuis 2004, la cariprazine et le brexpiprazole sont autoris\u00e9s depuis 2018. D&#8217;autres nouveaux antipsychotiques du groupe des benzamides ont \u00e9t\u00e9 introduits en Europe (mais pas aux \u00c9tats-Unis) (sulpiride en 1972 et amisulpride en 1999) ; l&#8217;amisulpride est \u00e9galement consid\u00e9r\u00e9 comme un antipsychotique atypique, bien qu&#8217;il soit principalement un antagoniste D2 et D3. A plus forte dose, les EPMS sont connus et surtout l&#8217;augmentation consid\u00e9rable de la prolactine.<\/p>\n<h2 id=\"agonisme-partiel-de-la-dopamine\">Agonisme partiel de la dopamine<\/h2>\n<p>La raison d&#8217;\u00eatre de l&#8217;agonisme partiel de la dopamine est une compensation optimale de la d\u00e9r\u00e9gulation dopaminergique associ\u00e9e aux psychoses (hypoth\u00e8se dopaminergique des psychoses). En toile de fond, on trouve les fameuses voies de la dopamine dans le cerveau <strong>(Fig.&nbsp;1). <\/strong>Dans ces conditions, il est logique<\/p>\n<ul>\n<li>diminuer l&#8217;activit\u00e9 dopaminergique sur la voie m\u00e9solimbique (am\u00e9liorer les sympt\u00f4mes positifs tels que le d\u00e9lire et les hallucinations par un effet antagoniste)<\/li>\n<li>renforcer l&#8217;activit\u00e9 dopaminergique sur la voie m\u00e9socorticale (am\u00e9liorer les sympt\u00f4mes n\u00e9gatifs, y compris les d\u00e9ficits cognitifs par un effet agoniste sur le r\u00e9cepteur de la dopamine)<\/li>\n<li>d&#8217;exercer aucun effet sur la voie nigrostriatale ou tub\u00e9ro-infundibulaire (pas de modification de la motricit\u00e9, pas d&#8217;EPMS, et pas d&#8217;augmentation de la prolactine).<\/li>\n<\/ul>\n<p>L&#8217;aripiprazole produit cet effet en bloquant \u00e0 la fois le r\u00e9cepteur D2 postsynaptique et l&#8217;autor\u00e9cepteur pr\u00e9synaptique. Il en r\u00e9sulte un effet agoniste partiel, \u00e9galement appel\u00e9 effet dopaminergique intrins\u00e8que, d&#8217;environ 30%. Trop d&#8217;antagonisme rapproche la substance des antagonistes classiques de la dopamine, trop d&#8217;agonisme conduit \u00e0 une amplification des sympt\u00f4mes psychotiques.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-12717\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/abb1_np6_s17.jpg\" style=\"height:286px; width:600px\" width=\"1100\" height=\"524\"><\/p>\n<p>&nbsp;<\/p>\n<p>Les trois agonistes partiels de la dopamine pr\u00e9sentent la constellation typique des antipsychotiques atypiques avec un antagonisme sur l&#8217;axe de la s\u00e9rotonine avec 5-HT2A, mais avec l&#8217;agonisme partiel mentionn\u00e9 pour le r\u00e9cepteur D2 et \u00e9galement pour le r\u00e9cepteur 5-HT1A, ce qui pourrait expliquer l&#8217;effet antid\u00e9presseur des substances.<br \/>\nL&#8217;aripiprazole pr\u00e9sente peu d&#8217;indices pharmacologiques de s\u00e9dation (faible blocage H1 et faible effet muscarinique\/anticholinergique M1). De plus, il a peu d&#8217;effet sur le poids et peu d&#8217;effet diab\u00e9tog\u00e8ne. L&#8217;aripiprazole est introduit en Suisse depuis 2004 et est disponible pour les cliniciens sous forme d&#8217;administration orale et intramusculaire, ainsi que sous forme de d\u00e9p\u00f4t.<\/p>\n<p>Selon St. Stahl, le brexpiprazole est un agoniste de la dopamine plus faible que l&#8217;aripiprazole, mais il pr\u00e9sente un antagonisme plus fort sur le r\u00e9cepteur 5-HT2A, un effet agoniste partiel plus fort sur le r\u00e9cepteur 5-HT1A et un antagonisme alpha-1 plus important. Cela signifie peu d&#8217;EPMS et surtout moins d&#8217;akathisie.<\/p>\n<p>La cariprazine se comporte comme le brexpiprazole en termes d&#8217;antagonisme (5-HT2A) et d&#8217;agonisme partiel (D2 et 5-HT1A), mais elle pr\u00e9sente en outre un agonisme partiel pour le r\u00e9cepteur D3, ce qui devrait favoriser la lib\u00e9ration de dopamine dans la r\u00e9gion m\u00e9socorticale. Celle-ci serait favorable au traitement de la symptomatologie n\u00e9gative. Les propri\u00e9t\u00e9s de r\u00e9duction de l&#8217;akathisie du brexpiprazole sont moins pr\u00e9sentes avec la cariprazine. De plus, comme avec l&#8217;aripirazole, le r\u00e9cepteur de l&#8217;histamine est moyennement bloqu\u00e9, ce qui pourrait expliquer une certaine fatigue (St. Stahl, 2013).<\/p>\n<p>Les diff\u00e9rences entre les trois agonistes partiels de la dopamine ont \u00e9t\u00e9 compil\u00e9es par L. Citrome, 2018. Il convient de noter que les comparaisons ne sont pas pond\u00e9r\u00e9es<em> t\u00eate-b\u00eache,<\/em> mais indirectement par rapport au placebo<strong> (tableau 1).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12718 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/787;height:429px; width:600px\" width=\"1100\" height=\"787\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-800x572.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-120x86.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-90x64.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-320x229.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-560x401.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"nomenclature-des-antipsychotiques\">Nomenclature des antipsychotiques<\/h2>\n<p>La d\u00e9signation chimique structurelle des substances \u00e0 effet antipsychotique a \u00e9t\u00e9 principalement utilis\u00e9e dans les publications scientifiques et lors de l&#8217;introduction de nouvelles substances. Dans la pratique quotidienne de la prescription, elle \u00e9tait peu pratique. La plupart des antipsychotiques mis sur le march\u00e9 avant la clozapine (CH 1972\/USA 1990) diff\u00e9raient certes en termes de gamme de doses et de s\u00e9dation (faible puissance versus puissance moyenne versus puissance \u00e9lev\u00e9e), mais il n&#8217;y a que des diff\u00e9rences mineures en ce qui concerne la fr\u00e9quence de l&#8217;EPMS <strong>(aper\u00e7u 1).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12719 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/ubersicht1_np6_s18.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/739;height:403px; width:600px\" width=\"1100\" height=\"739\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;adoption de cette classification en fonction de la puissance antipsychotique et des tableaux d&#8217;\u00e9quivalence de dose qui en d\u00e9coulent, traditionnellement \u00e9talonn\u00e9s sur 100 mg de chlorpromazine, est d\u00e9sormais obsol\u00e8te pour les antipsychotiques atypiques et difficile \u00e0 \u00e9tablir en raison du profil d&#8217;effets secondaires tr\u00e8s diff\u00e9rent. Le groupe de travail suisse dirig\u00e9 par St. Kaiser et al. a n\u00e9anmoins inclus une telle \u00e9valuation d&#8217;\u00e9quivalence des antipsychotiques atypiques, mesur\u00e9e \u00e0 1 mg d&#8217;olanzapine, dans les recommandations de traitement 2016 <strong>(tab.&nbsp;2).<\/strong> La clozapine ne provoque pas d&#8217;EPMS, de dyskin\u00e9sies tardives ou d&#8217;augmentation de la prolactine. Son profil d&#8217;effets secondaires est par exemple associ\u00e9 \u00e0 une agranulocytose, \u00e0 une prise de poids ou \u00e0 une sialo-rh\u00e9e. Ainsi, la clozapine a \u00e9t\u00e9 la premi\u00e8re \u00e0 \u00eatre class\u00e9e dans le nouveau groupe des antipsychotiques atypiques.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12720 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab2_np6_s19.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1134;height:619px; width:600px\" width=\"1100\" height=\"1134\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Contrairement \u00e0 la psychiatrie europ\u00e9enne, notamment germanophone, le terme &#8220;antipsychotiques&#8221; s&#8217;est impos\u00e9 tr\u00e8s t\u00f4t dans les pays anglophones, au lieu de neuroleptiques. Depuis l&#8217;introduction de la clozapine aux \u00c9tats-Unis en 1990 au plus tard, on ne parle plus que d&#8217;antipsychotiques et on fait la distinction entre les substances typiques et atypiques. Synonymement, et surtout dans les manuels, les antipsychotiques sont class\u00e9s en antipsychotiques de premi\u00e8re g\u00e9n\u00e9ration (APG) ou en antipsychotiques de deuxi\u00e8me g\u00e9n\u00e9ration (APG). Il ne s&#8217;agit pas d&#8217;une classe unique de substances, car les nouveaux antipsychotiques ont une structure chimique tr\u00e8s diff\u00e9rente et un profil de r\u00e9cepteur tr\u00e8s diff\u00e9rent. En principe, dans la litt\u00e9rature scientifique anglophone, toutes les substances antipsychotiques introduites apr\u00e8s 1990 sont appel\u00e9es &#8220;antipsychotiques atypiques&#8221; (Maudsley Guidelines, 2018). Ces derni\u00e8res ann\u00e9es, le Coll\u00e8ge europ\u00e9en de neuropsychopharmacologie (ECNP) a promu une nouvelle nomenclature qui classe les substances en fonction de leur pharmacologie et de leur mode d&#8217;action : Neuroscience based Nomenclature (NbN2, 2018). L&#8217;avenir nous dira si cette classification sophistiqu\u00e9e s&#8217;imposera. Toujours est-il que dans leur manuel de psychiatrie standard, Kaplan Sadock (2015) qualifie les antipsychotiques typiques d&#8217;antagonistes de la dopamine et les substances atypiques d&#8217;antagonistes de la s\u00e9rotonine et de la dopamine, car ils ont ce principe d&#8217;action en commun (\u00e9volution de la nomenclature).<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img decoding=\"async\" class=\"size-full wp-image-12721 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/kasten_np6_s18.png\" style=\"--smush-placeholder-width: 1094px; --smush-placeholder-aspect-ratio: 1094\/1205;height:441px; width:400px\" width=\"1094\" height=\"1205\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"quel-est-linteret-de-ce-debat-academique-pour-le-patient\">Quel est l&#8217;int\u00e9r\u00eat de ce d\u00e9bat acad\u00e9mique pour le patient ?<\/h2>\n<p>Les patients sont g\u00e9n\u00e9ralement sceptiques\/critiques en premier lieu lorsqu&#8217;on leur prescrit des antipsychotiques. Ce qui leur importe avant tout, c&#8217;est une action efficace sans effets ind\u00e9sirables des m\u00e9dicaments.<\/p>\n<p>Faire ou garder de bons antipsychotiques du point de vue du patient (extrait) :<\/p>\n<ul>\n<li>Aucun sympt\u00f4me de crampe (EPMS)<\/li>\n<li>Pas d&#8217;agitation motrice (akathisie)<\/li>\n<li>Pas de langue lourde, pas de probl\u00e8mes de d\u00e9glutition (EPMS, dyskin\u00e9sies pr\u00e9coces)<\/li>\n<li>Poids corporel stable<\/li>\n<li>Pas de s\u00e9dation\/d&#8217;effet de surprise<\/li>\n<li>Puissance\/Libido<\/li>\n<li>Pas d&#8217;aplatissement des affects<\/li>\n<li>Pas de &#8220;d\u00e9pendance<\/li>\n<li>Pas de &#8220;dommage g\u00e9n\u00e9tique<\/li>\n<\/ul>\n<p>Lors du choix d&#8217;un antipsychotique, il convient donc de veiller \u00e0 une s\u00e9curit\u00e9 et \u00e0 une tol\u00e9rance optimales, ainsi qu&#8217;\u00e0 une bonne efficacit\u00e9 <strong>(tableau 2). <\/strong>Parall\u00e8lement, les crit\u00e8res susmentionn\u00e9s sont essentiels pour recommander le m\u00e9dicament le plus adapt\u00e9 \u00e0 chaque individu. Il est important de proc\u00e9der dans l&#8217;esprit de la prise de d\u00e9cision partag\u00e9e et de tenir compte des souhaits du patient.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12722 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/ubersicht2_np6_s19.png\" style=\"--smush-placeholder-width: 1099px; --smush-placeholder-aspect-ratio: 1099\/548;height:199px; width:400px\" width=\"1099\" height=\"548\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Chez les patients psychotiques pr\u00e9sentant un premier \u00e9pisode de psychose (FEP = First Episode Psychosis), la plupart des lignes directrices internationales recommandent l&#8217;administration d&#8217;un antipsychotique de la classe des antid\u00e9presseurs. 2\u00e8me g\u00e9n\u00e9ration, ceux de la 3\u00e8me g\u00e9n\u00e9ration peuvent \u00e9galement \u00eatre inclus dans cette cat\u00e9gorie. Cela vaut \u00e9galement pour les recommandations de traitement suisses (Kaiser et al. 2016\/18). Les antipsychotiques de 1\u00e8re g\u00e9n\u00e9ration (par exemple l&#8217;halop\u00e9ridol) sont aujourd&#8217;hui utilis\u00e9s en deuxi\u00e8me intention dans le traitement des troubles psychotiques. L&#8217;exception est l&#8217;utilisation dans le traitement du d\u00e9lire (Eich PH, Nick B. 2018).<\/p>\n<h2 id=\"-4\">&nbsp;<\/h2>\n<h2 id=\"-5\"><img decoding=\"async\" class=\"size-full wp-image-12723 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/fallbeispiele_np6_s20.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1176;height:641px; width:600px\" width=\"1100\" height=\"1176\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-6\">&nbsp;<\/h2>\n<h2 id=\"conclusion\">Conclusion<\/h2>\n<p>La pharmacoth\u00e9rapie moderne du trouble schizophr\u00e9nique doit remplir plusieurs fonctions, ce qui signifie que la perspective de traitement des patients est multifocale. Elle doit \u00e0 la fois<\/p>\n<ol>\n<li>Conna\u00eetre les antipsychotiques de premi\u00e8re g\u00e9n\u00e9ration et \u00eatre conscient de leurs avantages et inconv\u00e9nients.<\/li>\n<li>\u00catre efficace avec le moins d&#8217;effets ind\u00e9sirables (EI) possible<\/li>\n<li>\u00eatre personnalis\u00e9s, c&#8217;est-\u00e0-dire adapt\u00e9s aux personnes concern\u00e9es (si des indicateurs correspondants sont disponibles)<\/li>\n<li>\u00catre restitutif dans le but de restituer ad integrum, c&#8217;est-\u00e0-dire de pr\u00e9server la fonction et de r\u00e9habiliter<\/li>\n<li>S&#8217;inscrire dans une prise en charge de proximit\u00e9 et adapt\u00e9e aux besoins de chacun<\/li>\n<\/ol>\n<p>D&#8217;un point de vue clinique, les  <em>les antipsychotiques de la 2. et 3\u00e8me g\u00e9n\u00e9ration<\/em>  avantages \u00e9vidents par rapport aux substances typiques. En r\u00e9f\u00e9rence \u00e0 Hippocrate et \u00e0 son principe : &#8220;Primum non nocere &#8211; secundum cavere &#8211; tertium sanare&#8221; (premi\u00e8rement, ne pas nuire\/ne pas faire de mal &#8211; deuxi\u00e8mement, porter des pr\u00e9cautions &#8211; troisi\u00e8mement, soigner\/contribuer \u00e0 la gu\u00e9rison\/traduction<em> de l&#8217;auteur)<\/em>, les agonistes partiels de la dopamine, avec leur profil d&#8217;effets secondaires favorable, sont absolument des m\u00e9dicaments de premier choix.<\/p>\n<h2 id=\"messages-take-home\">Messages Take-Home<\/h2>\n<ul>\n<li>Les antipsychotiques restent aujourd&#8217;hui le principal pilier du traitement aigu et \u00e0 long terme des troubles schizophr\u00e9niques. Historiquement, nous avons actuellement un choix assez large de substances antipsychotiques modernes.<\/li>\n<li>La prescription d&#8217;un traitement pharmacologique est bas\u00e9e sur la psychopathologie et la souffrance des patients concern\u00e9s. Il convient de noter que plus le traitement antipsychotique est instaur\u00e9 t\u00f4t, plus les chances de contr\u00f4ler ou de stopper la progression de la psychose sont grandes.<\/li>\n<li>La non-adh\u00e9sion est le principal facteur de rechute.<\/li>\n<li>L&#8217;utilisation d&#8217;antipsychotiques doit \u00eatre discut\u00e9e dans le cadre d&#8217;une prise de d\u00e9cision partag\u00e9e ; une bonne connaissance du mode d&#8217;action et des EI potentiels est une condition pr\u00e9alable.<\/li>\n<li>Les antipsychotiques de 3e g\u00e9n\u00e9ration (aripiprazole, brexpiprazole et cariprazine) constituent un pas important dans la bonne direction.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature compl\u00e9mentaire :<\/p>\n<ul>\n<li>Citrome L : Current Psychiatry, 17(4), avril 2018<\/li>\n<li>Eich PH, Nick B : Num\u00e9ro sp\u00e9cial &#8220;Schizophr\u00e9nie&#8221;, Therapeutische Umschau, 01\/2018.<\/li>\n<li>Kaiser ST, et al. : Recommandations de traitement de la SSPP pour la schizophr\u00e9nie, version f\u00e9vrier 2016 ; www.psychiatrie.ch\/sgpp\/fachleute-und-kommissionen<\/li>\n<li>Kaiser ST, et al. : Recommandations de traitement de la SSPP concernant la schizophr\u00e9nie, Swiss Med Forum 2018 ; 18(25) : 532-539.<\/li>\n<li>Taylor D, et al. : The Maudsley Prescribing Guidelines in Psychiatry 13th edition, Wiley Blackwell, 2018.<\/li>\n<li>Neuroscience based Nomenclature (NbN-2R), publi\u00e9e par ECNP, 2018.<\/li>\n<li>Falkai P, Wittchen HU : Manuel diagnostique et statistique des troubles mentaux DSM-5, APA, 2013 ; Hogrefe 2015<\/li>\n<li>Kaplan &amp; Sadock&#8217;s Synopsis of Psychiatry, 11e \u00e9dition, Wolters Kluwer, 2015.<\/li>\n<li>M\u00f6ller HJ, Laux G, Deister A : Psychiatrie, psychosomatique et psychoth\u00e9rapie, 6e \u00e9dition, Thieme Verlag, 2015.<\/li>\n<li>Stahl ST : Essential Psychopharmacology, 4e \u00e9dition, Cambridge University Press, 2013.<\/li>\n<li>Woggon B : Traitement par psychotropes, 3e \u00e9dition, Huber Verlag, 2009.<\/li>\n<\/ul>\n<p>\n<em>InFo NEUROLOGIE &amp; PSYCHIATRIE 2019 ; 17(6) : 16-21<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les antipsychotiques sont le principal pilier du traitement aigu et \u00e0 long terme des troubles schizophr\u00e9niques. Plus le traitement antipsychotique est mis en place t\u00f4t, plus les chances de contr\u00f4ler&hellip;<\/p>\n","protected":false},"author":7,"featured_media":92524,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Nouveaut\u00e9s dans le traitement de la schizophr\u00e9nie","footnotes":""},"category":[11531,12075,11383,11464,11549],"tags":[26294,26289,13018],"powerkit_post_featured":[],"class_list":["post-334831","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formation-continue","category-formation-continue-avec-partenaire","category-neurologie-fr","category-pharmacologie-et-toxicologie","category-rx-fr","tag-agonistes-partiels-de-la-dopamine","tag-neuroleptiques","tag-schizophrenie-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:45:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":334853,"slug":"similitudini-e-differenze-degli-agonisti-parziali-della-dopamina","post_title":"Similitudini e differenze degli agonisti parziali della dopamina","href":"https:\/\/medizinonline.com\/it\/similitudini-e-differenze-degli-agonisti-parziali-della-dopamina\/"},"pt_PT":{"locale":"pt_PT","id":334942,"slug":"semelhancas-e-diferencas-entre-os-agonistas-parciais-da-dopamina","post_title":"Semelhan\u00e7as e diferen\u00e7as entre os agonistas parciais da dopamina","href":"https:\/\/medizinonline.com\/pt-pt\/semelhancas-e-diferencas-entre-os-agonistas-parciais-da-dopamina\/"},"es_ES":{"locale":"es_ES","id":334866,"slug":"similitudes-y-diferencias-entre-los-agonistas-parciales-de-la-dopamina","post_title":"Similitudes y diferencias entre los agonistas parciales de la dopamina","href":"https:\/\/medizinonline.com\/es\/similitudes-y-diferencias-entre-los-agonistas-parciales-de-la-dopamina\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/334831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=334831"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/334831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/92524"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=334831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=334831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=334831"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=334831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}