{"id":336557,"date":"2019-03-09T01:00:00","date_gmt":"2019-03-09T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/decalage-entre-les-donnees-probantes-et-les-donnees-empiriques\/"},"modified":"2019-03-09T01:00:00","modified_gmt":"2019-03-09T00:00:00","slug":"decalage-entre-les-donnees-probantes-et-les-donnees-empiriques","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/decalage-entre-les-donnees-probantes-et-les-donnees-empiriques\/","title":{"rendered":"D\u00e9calage entre les donn\u00e9es probantes et les donn\u00e9es empiriques"},"content":{"rendered":"<p><strong>Dans certains cas, les m\u00e9dicaments contenant des cannabino\u00efdes ont montr\u00e9 une efficacit\u00e9 consid\u00e9rable pour soulager les sympt\u00f4mes. Les r\u00e9sultats de certaines \u00e9tudes soutiennent \u00e9galement des effets positifs. Cependant, les preuves g\u00e9n\u00e9rales ne sont pas claires \u00e0 l&#8217;heure actuelle.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>L&#8217;utilisation du cannabis \u00e0 des fins m\u00e9dicales fait l&#8217;objet de controverses. La conclusion d&#8217;une m\u00e9ta-\u00e9tude command\u00e9e par l&#8217;OFSP et publi\u00e9e en 2015 est que les pr\u00e9parations m\u00e9dicales \u00e0 base de cannabino\u00efdes ont une efficacit\u00e9 prouv\u00e9e dans l&#8217;indication des douleurs chroniques et neuropathiques [1]. D&#8217;un point de vue statistique, l&#8217;effet n&#8217;est cependant pas tr\u00e8s important dans ce jeu de donn\u00e9es &#8211; une constatation qui a \u00e9t\u00e9 r\u00e9pliqu\u00e9e en 2017 [2]. En revanche, des rapports d&#8217;exp\u00e9riences de cas individuels dans lesquels la souffrance subjective a pu \u00eatre consid\u00e9rablement r\u00e9duite gr\u00e2ce \u00e0 des m\u00e9dicaments contenant du cannabis et le nombre de demandes d&#8217;autorisations exceptionnelles aupr\u00e8s de l&#8217;OFSP ne cesse d&#8217;augmenter.  &nbsp;<\/p>\n<h2 id=\"debat-sur-les-benefices-et-les-risques\">D\u00e9bat sur les b\u00e9n\u00e9fices et les risques<\/h2>\n<p>Dans une m\u00e9ta-\u00e9tude publi\u00e9e en 2018, des param\u00e8tres statistiques ont \u00e9t\u00e9 calcul\u00e9s pour \u00e9tablir un bilan b\u00e9n\u00e9fices\/risques concernant les m\u00e9dicaments contenant du cannabis [3]. Le nombre de personnes \u00e0 traiter (NNT) pour obtenir une r\u00e9duction d&#8217;au moins 30% de la douleur \u00e9tait de 24 ; en revanche, le nombre de personnes \u00e0 traiter avant l&#8217;apparition d&#8217;un effet secondaire n&#8217;est que de 6 [3]. Selon le PD Dr Konrad Maurer, directeur du service ambulatoire interdisciplinaire de la douleur \u00e0 l&#8217;h\u00f4pital universitaire de Zurich, cela implique un rapport d\u00e9s\u00e9quilibr\u00e9. D&#8217;un autre c\u00f4t\u00e9, les effets secondaires des produits \u00e0 base de cannabis (par exemple tachycardie, agitation) sont relativement faibles par rapport \u00e0 ceux d&#8217;autres m\u00e9dicaments contre la douleur et il n&#8217;y a pas de risque de mortalit\u00e9, m\u00eame \u00e0 fortes doses. En ce qui concerne les effets ind\u00e9sirables des produits \u00e0 base de cannabis, le d\u00e9bat sur les avantages m\u00e9dicaux doit \u00eatre distingu\u00e9 du d\u00e9bat sociopolitique. Le potentiel de d\u00e9pendance au cannabis est moins important qu&#8217;on ne le pense g\u00e9n\u00e9ralement.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-11471\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/03\/kasten_hp2_s36.png\" style=\"height:395px; width:600px\" width=\"1100\" height=\"724\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"thc-et-cbd-a-des-fins-medicales\">THC et CBD \u00e0 des fins m\u00e9dicales<\/h2>\n<p>Contrairement au THC (\u2206-9-t\u00e9trahydrocannabinol), le CBD (cannabidiol) n&#8217;a pas d&#8217;effet psychoactif. En Suisse, le spray buccal <sup>Sativex\u00ae<\/sup> (relaxant musculaire contenant du THC et du CBD) est actuellement le seul m\u00e9dicament contenant des principes actifs cannabino\u00efdes autoris\u00e9 par la loi sur les produits th\u00e9rapeutiques, mais uniquement comme traitement de deuxi\u00e8me ligne de la spasticit\u00e9 dans le cadre de la scl\u00e9rose en plaques. Pour le <sup>Marinol\u00ae<\/sup>, une pr\u00e9paration contenant du THC sous forme synth\u00e9tique (dronabinol), qui aurait des effets analg\u00e9siques et antispasmodiques et stimulerait l&#8217;app\u00e9tit, une demande m\u00e9dicale aupr\u00e8s de l&#8217;OFSP est n\u00e9cessaire. Les produits de chanvre non-m\u00e9dicaux qui ont une teneur en TCH inf\u00e9rieure \u00e0 1% ou qui contiennent uniquement du cannabino\u00efde CBD sont librement disponibles dans le commerce en Suisse. Toutefois, pour les m\u00e9dicaments contenant le principe actif CBD \u00e0 des fins m\u00e9dicales, une demande m\u00e9dicale doit \u00eatre soumise \u00e0 l&#8217;OFSP et il existe une obligation de d\u00e9clarer les effets secondaires \u00e0 Swissmedics.<\/p>\n<p>Dans un avenir proche, le d\u00e9bat tournera de plus en plus autour du CBD, a d\u00e9clar\u00e9 le Dr Maurer. La l\u00e9galisation des produits contenant du cannabis \u00e0 des fins m\u00e9dicales est pr\u00e9vue en Suisse, mais n&#8217;entrera probablement pas en vigueur avant 2022. Actuellement, les pr\u00e9parations \u00e0 base de cannabis ne sont rembours\u00e9es par l&#8217;assurance maladie que dans certains cas. Pour ceux qui payent eux-m\u00eames, le prix (environ 400-800 CHF par mois) peut \u00eatre un obstacle important, mais il s&#8217;agit d&#8217;un montant relativement faible par rapport \u00e0 d&#8217;autres m\u00e9dicaments rembours\u00e9s par l&#8217;assurance maladie.<br \/>\n&nbsp;<br \/>\n<em>Source : Symposium VZI, 31 janvier 2019, Zurich<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Whiting PF, et al. : Cannabinoids for Medical Use. A Systematic Review and Meta-analysis. JAMA 2015 ; 313(24) : 2456-2473.<\/li>\n<li>Meng H, et al. : Cannabino\u00efdes s\u00e9lectifs pour la douleur neuropathique chronique : une revue syst\u00e9matique et une m\u00e9ta-analyse. Anaesth Analg 2017 ; 125(5) : 1638-1652.  &nbsp;<\/li>\n<li>Stockings E, et al. : Cannabis et cannabino\u00efdes pour le traitement des personnes souffrant de douleurs chroniques non canc\u00e9reuses : une revue syst\u00e9matique et une m\u00e9ta-analyse des \u00e9tudes contr\u00f4l\u00e9es et observationnelles. PAIN 2018 ; 159 : 1932-1954.<\/li>\n<li>Baschoud A, Broers B : Cannabino\u00efdes et douleur au cabinet m\u00e9dical. Une option pour le traitement de la douleur chronique ? Prim Hosp Care Allg Inn Med 2018 ; 18(09) : 156-159. DOI: https:\/\/doi.org\/10.4414\/phc-d.2018.01728<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2019 ; 14(2) : 36<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans certains cas, les m\u00e9dicaments contenant des cannabino\u00efdes ont montr\u00e9 une efficacit\u00e9 consid\u00e9rable pour soulager les sympt\u00f4mes. Les r\u00e9sultats de certaines \u00e9tudes soutiennent \u00e9galement des effets positifs. Cependant, les preuves&hellip;<\/p>\n","protected":false},"author":7,"featured_media":87364,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Le cannabis en tant que m\u00e9dicament  ","footnotes":""},"category":[11527,11315,11535,11549],"tags":[24617,14016,23737,21337,14020],"powerkit_post_featured":[],"class_list":["post-336557","post","type-post","status-publish","format-standard","has-post-thumbnail","category-etudes","category-medecine-interne-generale","category-rapports-de-congres","category-rx-fr","tag-cannabidiol-fr","tag-cannabis-fr","tag-cbd-fr","tag-chanvre","tag-thc-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:28:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":336561,"slug":"discrepanza-tra-prove-ed-esperienza","post_title":"Discrepanza tra prove ed esperienza","href":"https:\/\/medizinonline.com\/it\/discrepanza-tra-prove-ed-esperienza\/"},"pt_PT":{"locale":"pt_PT","id":336566,"slug":"discrepancia-entre-provas-e-experiencia","post_title":"Discrep\u00e2ncia entre provas e experi\u00eancia","href":"https:\/\/medizinonline.com\/pt-pt\/discrepancia-entre-provas-e-experiencia\/"},"es_ES":{"locale":"es_ES","id":336591,"slug":"discrepancia-entre-las-pruebas-y-la-experiencia","post_title":"Discrepancia entre las pruebas y la experiencia","href":"https:\/\/medizinonline.com\/es\/discrepancia-entre-las-pruebas-y-la-experiencia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/336557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=336557"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/336557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/87364"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=336557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=336557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=336557"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=336557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}