{"id":336717,"date":"2019-02-16T01:00:00","date_gmt":"2019-02-16T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/les-inhibiteurs-de-pcsk9-tiennent-le-syndrome-coronarien-aigu-en-echec\/"},"modified":"2019-02-16T01:00:00","modified_gmt":"2019-02-16T00:00:00","slug":"les-inhibiteurs-de-pcsk9-tiennent-le-syndrome-coronarien-aigu-en-echec","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/les-inhibiteurs-de-pcsk9-tiennent-le-syndrome-coronarien-aigu-en-echec\/","title":{"rendered":"Les inhibiteurs de PCSK9 tiennent le syndrome coronarien aigu en \u00e9chec"},"content":{"rendered":"<p><strong>Il est bien connu qu&#8217;un faible taux de cholest\u00e9rol LDL r\u00e9duit le risque de maladies cardiovasculaires. Mais dans la pratique, c&#8217;est souvent plus facile \u00e0 dire qu&#8217;\u00e0 faire. Les inhibiteurs de PCSK9 sont-ils la solution ?<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La r\u00e9duction du taux de LDL-C fait partie int\u00e9grante de la r\u00e9duction du risque chez les patients ayant subi un infarctus du myocarde. Cependant, tr\u00e8s peu d&#8217;entre eux atteignent les valeurs cibles de 2,5&nbsp;mmol\/l ou de 1,8&nbsp;mmol\/l chez les patients \u00e0 haut risque, comme le pr\u00e9conisent les lignes directrices europ\u00e9ennes [1]. Pourtant, les statines ont clairement d\u00e9montr\u00e9 leur efficacit\u00e9 dans le traitement des dyslipid\u00e9mies. Cependant, la fr\u00e9quence des myalgies, qui touchent jusqu&#8217;\u00e0 10-25% des patients sous statines, a \u00e9t\u00e9 sous-estim\u00e9e jusqu&#8217;\u00e0 pr\u00e9sent [2]. L&#8217;administration d&#8217;inhibiteurs de PCSK-9 a donc \u00e9t\u00e9 \u00e9tudi\u00e9e comme option suppl\u00e9mentaire, avec succ\u00e8s.<\/p>\n<p>La proprot\u00e9ine convertase subtilisine\/kexine de type 9 (PCSK9) se lie aux r\u00e9cepteurs LDL et les marque pour les d\u00e9grader dans les lysosomes. Ainsi, la densit\u00e9 des r\u00e9cepteurs \u00e0 la surface des cellules diminue et le cholest\u00e9rol LDL circulant dans le sang augmente. En revanche, si le PCSK9 est inhib\u00e9, les r\u00e9cepteurs des LDL \u00e0 la surface des h\u00e9patocytes peuvent \u00eatre recycl\u00e9s plusieurs fois, ce qui leur permet de lier davantage de LDLC circulantes et de faire baisser le taux. Le profil lipidique global en b\u00e9n\u00e9ficie.<\/p>\n<h2 id=\"les-patients-a-haut-risque-en-beneficient\">Les patients \u00e0 haut risque en b\u00e9n\u00e9ficient<\/h2>\n<p>La sous-analyse [3] d&#8217;une \u00e9tude randomis\u00e9e \u00e0 grande \u00e9chelle, en double aveugle et contr\u00f4l\u00e9e par placebo [4] a montr\u00e9 que l&#8217;ajout de l&#8217;\u00e9volocumab, un inhibiteur de PCSK-9, a r\u00e9duit le taux de LDL-C de 59 \u00e0 61% de mani\u00e8re constante dans les trois groupes. La date du dernier infarctus, le nombre d&#8217;infarctus ou la pr\u00e9sence d&#8217;une maladie coronarienne multivisc\u00e9rale n&#8217;ont pas \u00e9t\u00e9 pris en compte. Les experts en ont conclu qu&#8217;un traitement par inhibiteurs de PCSK-9 est surtout indiqu\u00e9 chez les patients en pr\u00e9vention secondaire qui pr\u00e9sentent des caract\u00e9ristiques suppl\u00e9mentaires \u00e0 haut risque.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-11360\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/02\/abb1_cv1_s36.png\" style=\"height:425px; width:600px\" width=\"1100\" height=\"780\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"plus-cest-profond-mieux-cest\">Plus c&#8217;est profond, mieux c&#8217;est<\/h2>\n<p>La bonne r\u00e9ponse des patients au traitement hypolip\u00e9miant compl\u00e9mentaire a soulev\u00e9 une question qui n&#8217;avait jamais \u00e9t\u00e9 pos\u00e9e auparavant : o\u00f9 se situe la limite inf\u00e9rieure du LDL-C ? En effet, 10% des sujets ont pr\u00e9sent\u00e9 un taux de LDL-C de &lt;0,5&nbsp;mmol\/l (m\u00e9diane 0,36&nbsp;mmol\/l) apr\u00e8s quatre semaines de traitement. Peut-on s&#8217;attendre \u00e0 un b\u00e9n\u00e9fice clinique suppl\u00e9mentaire avec ces valeurs ? En effet, il s&#8217;est av\u00e9r\u00e9 que la r\u00e9duction du LDL-cholest\u00e9rol entra\u00eenait \u00e9galement une diminution du risque d&#8217;\u00e9v\u00e9nements cardiovasculaires tels que d\u00e9c\u00e8s d&#8217;origine cardiovasculaire, infarctus du myocarde, attaque c\u00e9r\u00e9brale, revascularisation coronarienne ou hospitalisation pour angine de poitrine instable<strong> (Fig.&nbsp;1). <\/strong>Ces r\u00e9sultats sugg\u00e8rent que m\u00eame les patients dont les taux sont d\u00e9j\u00e0 inf\u00e9rieurs aux valeurs cibles peuvent b\u00e9n\u00e9ficier d&#8217;une r\u00e9duction suppl\u00e9mentaire du LDL-C. Aucune augmentation des effets ind\u00e9sirables n&#8217;a \u00e9t\u00e9 observ\u00e9e. M\u00eame les valeurs &lt;0,5&nbsp;mmol\/l sont consid\u00e9r\u00e9es comme s\u00fbres par les auteurs sur la base des r\u00e9sultats [5], comme l&#8217;a expliqu\u00e9 le professeur Urs Fischer de l&#8217;H\u00f4pital universitaire de Berne dans une conf\u00e9rence.<\/p>\n<p><em>Source : Congr\u00e8s annuel de la Soci\u00e9t\u00e9 suisse d&#8217;attaque c\u00e9r\u00e9brale, 15-16 janvier 2019, Zurich<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>www.escardio.org\/Guidelines\/Clinical-Practice-Guidelines\/Dyslipidaemias-Management-of (dernier acc\u00e8s : 22.01.2019)<\/li>\n<li>Thompson PD, et al : Statin-Associated Side Effects. J Am Coll Cardiol. 2016 ; 67 : 2395-2410.<\/li>\n<li>Sabatine MS, et al : B\u00e9n\u00e9fice clinique de l&#8217;\u00e9volocumab par s\u00e9v\u00e9rit\u00e9 et extension de la maladie art\u00e9rielle coronarienne : une analyse de FOURIER. Circulation 2018 ; 138 : 756-766.<\/li>\n<li>Sabatine MS et al : Evolocumab and Clinical Outcomes in Patients with Cardiovascular Disease. N Engl J Med 2017 ; 376:1713-1722<\/li>\n<li>Giugliano RP et al : Cognitive Function in a Randomized Trial of Evolocumab. N Engl J Med 2017 ; 377 : 633-643.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2019 ; 18(1) : 36<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est bien connu qu&#8217;un faible taux de cholest\u00e9rol LDL r\u00e9duit le risque de maladies cardiovasculaires. Mais dans la pratique, c&#8217;est souvent plus facile \u00e0 dire qu&#8217;\u00e0 faire. Les inhibiteurs&hellip;<\/p>\n","protected":false},"author":7,"featured_media":86754,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"R\u00e9union annuelle de la Soci\u00e9t\u00e9 suisse d'attaque c\u00e9r\u00e9brale, Zurich","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11378,11527,11535,11549],"tags":[17959,20777,30322],"powerkit_post_featured":[],"class_list":["post-336717","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologie","category-etudes","category-rapports-de-congres","category-rx-fr","tag-cholesterol-ldl","tag-infarctus-du-myocarde-fr","tag-inhibition-de-pcsk9","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:43:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":336723,"slug":"gli-inibitori-della-pcsk9-tengono-a-bada-la-sindrome-coronarica-acuta","post_title":"Gli inibitori della PCSK9 tengono a bada la sindrome coronarica acuta","href":"https:\/\/medizinonline.com\/it\/gli-inibitori-della-pcsk9-tengono-a-bada-la-sindrome-coronarica-acuta\/"},"pt_PT":{"locale":"pt_PT","id":336729,"slug":"os-inibidores-pcsk9-mantem-a-sindrome-coronaria-aguda-a-distancia","post_title":"Os inibidores PCSK9 mant\u00eam a s\u00edndrome coron\u00e1ria aguda \u00e0 dist\u00e2ncia","href":"https:\/\/medizinonline.com\/pt-pt\/os-inibidores-pcsk9-mantem-a-sindrome-coronaria-aguda-a-distancia\/"},"es_ES":{"locale":"es_ES","id":336695,"slug":"los-inhibidores-de-la-pcsk9-mantienen-a-raya-el-sindrome-coronario-agudo","post_title":"Los inhibidores de la PCSK9 mantienen a raya el s\u00edndrome coronario agudo","href":"https:\/\/medizinonline.com\/es\/los-inhibidores-de-la-pcsk9-mantienen-a-raya-el-sindrome-coronario-agudo\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/336717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=336717"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/336717\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=336717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=336717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=336717"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=336717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}