{"id":337895,"date":"2018-06-17T02:00:00","date_gmt":"2018-06-17T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/de-nouvelles-donnees-sur-le-dossier-electronique-du-patient-temoignent-dun-nouveau-depart\/"},"modified":"2018-06-17T02:00:00","modified_gmt":"2018-06-17T00:00:00","slug":"de-nouvelles-donnees-sur-le-dossier-electronique-du-patient-temoignent-dun-nouveau-depart","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/de-nouvelles-donnees-sur-le-dossier-electronique-du-patient-temoignent-dun-nouveau-depart\/","title":{"rendered":"De nouvelles donn\u00e9es sur le dossier \u00e9lectronique du patient t\u00e9moignent d&#8217;un nouveau d\u00e9part"},"content":{"rendered":"<p><strong>Le nouveau Barom\u00e8tre eHealth 2018 a \u00e9t\u00e9 pr\u00e9sent\u00e9 dans le cadre du SWISS eHealth Forum \u00e0 Berne : Les choses bougent dans le domaine de la num\u00e9risation de la sant\u00e9. Les acteurs se mettent en r\u00e9seau, les parties prenantes du Dossier Patient Informatis\u00e9 sont r\u00e9ceptives.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La majorit\u00e9 des professionnels de la sant\u00e9 interrog\u00e9s recommanderaient aujourd&#8217;hui un DEP <strong>(Fig.&nbsp;1). <\/strong>La plupart des prestataires de soins interrog\u00e9s pensent que le DEP est une bonne chose, les pharmaciens se distinguant le plus, ce que Golder attribue \u00e0 la pression pr\u00e9coce de la num\u00e9risation dans ce secteur. Cette ouverture d&#8217;esprit joue un r\u00f4le important dans le succ\u00e8s du DEP aupr\u00e8s des patients. Avec le recentrage des pharmaciens sur leur r\u00f4le de coachs et de premiers interlocuteurs, ils ont gagn\u00e9 en pertinence en tant qu&#8217;\u00e9ventuels relais importants du DEP.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-10274\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/06\/abb1-hp5_s38.png\" style=\"height:448px; width:600px\" width=\"1100\" height=\"822\"><\/p>\n<p>&nbsp;<\/p>\n<p>En revanche, le r\u00e9sultat est l\u00e9g\u00e8rement diff\u00e9rent pour la population r\u00e9sidente. En premier lieu, le DEP n&#8217;a pas gagn\u00e9 en notori\u00e9t\u00e9 au cours de l&#8217;ann\u00e9e \u00e9coul\u00e9e, ce qui pourrait \u00eatre li\u00e9 \u00e0 l&#8217;affaiblissement du d\u00e9bat m\u00e9diatique sur le sujet, suppose Golder. La proportion de la population r\u00e9sidente qui pense que le DEP est en principe une bonne chose est de 50%, et 19% pensent m\u00eame que c&#8217;est une tr\u00e8s bonne chose. Cependant, si l&#8217;on filtre en fonction de la volont\u00e9 d&#8217;ouvrir un DEP, le nombre de personnes ouvertes se r\u00e9duit encore actuellement \u00e0 environ un tiers de la population r\u00e9sidente<strong> (graphique&nbsp;2),<\/strong> la volont\u00e9 \u00e9tant plus \u00e9lev\u00e9e parmi les personnes ayant le droit de vote que parmi les \u00e9trangers (33% contre 8%). Les Romands se montrent particuli\u00e8rement motiv\u00e9s (45%) par rapport aux Al\u00e9maniques (29%) et aux italophones (23%).<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-10275 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/06\/abb2_hp5_s38.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/890;height:485px; width:600px\" width=\"1100\" height=\"890\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Selon M. Golder, le moteur haptique de cette \u00e9volution est le smartphone : les applications, qui sont plus largement utilis\u00e9es, donnent l&#8217;impulsion au sein de la population, car elles sont tr\u00e8s concr\u00e8tement applicables, alors que l&#8217;utilit\u00e9 d&#8217;un DEP est encore un concept assez diffus, qui n&#8217;existe qu&#8217;en th\u00e9orie. &#8220;Mais un moteur essentiel est aussi la strat\u00e9gie &#8211; la LDEP. C&#8217;est aussi le point de vue des responsables cantonaux de la cybersant\u00e9 que nous avons interrog\u00e9s. En 2018, 26 responsables cantonaux ont particip\u00e9 \u00e0 l&#8217;enqu\u00eate. Cette enqu\u00eate exhaustive est une premi\u00e8re&#8221;. Entre-temps, les forces motrices repr\u00e9sentent une alliance entre les fournisseurs de prestations, les autorit\u00e9s cantonales et les parlements. &#8220;Un puissant effet d&#8217;allumage&#8221;, selon Golder.<\/p>\n<h2 id=\"lobjectif-semble-encore-loin\">L&#8217;objectif semble encore loin<\/h2>\n<p>Le degr\u00e9 de mise en r\u00e9seau interne concerne toutes les prestations et informations \u00e9chang\u00e9es en interne, le degr\u00e9 de mise en r\u00e9seau externe celles \u00e9chang\u00e9es avec des prestataires de services ext\u00e9rieurs \u00e0 l&#8217;institution. L&#8217;indice de connectivit\u00e9 a \u00e9t\u00e9 d\u00e9fini sur la base du Catalogue des performances de l&#8217;OCDE. En interne, l&#8217;indice couvre environ la moiti\u00e9 de tous les services imaginables de l&#8217;OCDE, ce qui signifie qu&#8217;environ 45% du potentiel est aujourd&#8217;hui exploit\u00e9 par l&#8217;ensemble des fournisseurs de services interrog\u00e9s. Dans les h\u00f4pitaux interrog\u00e9s, ce chiffre est d\u00e9j\u00e0 tr\u00e8s \u00e9lev\u00e9, de l&#8217;ordre de 75%. La valeur de l&#8217;indice de connectivit\u00e9 externe montre que l&#8217;objectif est encore loin d&#8217;\u00eatre atteint (19%) <strong>(Fig.&nbsp;3).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-10276 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/06\/abb3_hp5_s38.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/657;height:358px; width:600px\" width=\"1100\" height=\"657\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"le-role-du-corps-medical\">Le r\u00f4le du corps m\u00e9dical<\/h2>\n<p>Environ trois quarts des personnes qui pourraient envisager d&#8217;ouvrir un DEP sur recommandation aimeraient recevoir cette recommandation directement d&#8217;un m\u00e9decin. Cela d\u00e9crit le r\u00f4le important du m\u00e9decin en tant que catalyseur. Certes, les m\u00e9decins ont tendance \u00e0 \u00eatre un peu plus critiques quant \u00e0 la forme du DPE et \u00e0 leur volont\u00e9 de payer. Mais lorsqu&#8217;on demande \u00e0 la population r\u00e9sidente avec qui elle souhaite partager ses donn\u00e9es, c&#8217;est toujours le m\u00e9decin traitant qui vient en premier. Tous les autres aspects dans ce contexte qui sont consid\u00e9r\u00e9s comme b\u00e9n\u00e9fiques sont moins prioritaires. Le public formule \u00e9galement des exigences vis-\u00e0-vis des m\u00e9decins, par exemple la prise de rendez-vous en ligne ou la consultation en ligne.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img decoding=\"async\" class=\"size-full wp-image-10277 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/06\/kasten_hp5_s37.png\" style=\"--smush-placeholder-width: 877px; --smush-placeholder-aspect-ratio: 877\/1194;height:545px; width:400px\" width=\"877\" height=\"1194\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"attentes-dutilite-et-spirale-dutilisation\">Attentes d&#8217;utilit\u00e9 et spirale d&#8217;utilisation<\/h2>\n<p>L&#8217;int\u00e9r\u00eat pour le DEP de la part de la population r\u00e9sidente est d\u00e9clench\u00e9 par l&#8217;exp\u00e9rience avec les applications pour le fitness et l&#8217;activit\u00e9 physique. La majorit\u00e9 conna\u00eet ces applications, 47% ne les connaissent pas. Les jeunes sont encore plus nombreux \u00e0 utiliser des applications que leurs a\u00een\u00e9s. 73% de la population peut envisager d&#8217;utiliser une application ou l&#8217;utilise d\u00e9j\u00e0. &#8220;Si une telle utilisation suscite des sentiments positifs, de nouveaux besoins ne tarderont pas \u00e0 appara\u00eetre. A l&#8217;avenir, les donn\u00e9es du DPE seront certainement accessibles et utilisables via le smartphone. Cela cr\u00e9era \u00e9galement des besoins pour de nouveaux contextes d&#8217;utilisation&#8221;, pr\u00e9voit Golder avec optimisme, avant d&#8217;approfondir : L&#8217;\u00e9tude montre qu&#8217;il existe d\u00e9j\u00e0 trois attentes positives en termes d&#8217;avantages chez tous les prestataires de soins et les votants : La pr\u00e9vention des erreurs m\u00e9dicales, la pr\u00e9vention des traitements inutiles et l&#8217;acc\u00e8s rapide aux donn\u00e9es en cas de traitement d&#8217;urgence. La spirale de l&#8217;utilisation &#8211; la g\u00e9n\u00e9ration de nouvelles attentes d&#8217;utilisation gr\u00e2ce \u00e0 des exp\u00e9riences d&#8217;utilisation positives &#8211; continuera \u00e9galement \u00e0 stimuler l&#8217;utilisation des donn\u00e9es EPD. Cette logique s&#8217;est d\u00e9j\u00e0 manifest\u00e9e apr\u00e8s l&#8217;apparition des applications sur les smartphones, qui sont d\u00e9sormais ancr\u00e9es dans les habitudes de consommation et d&#8217;information de leurs propri\u00e9taires. La population attend de pouvoir consulter ses propres informations sur le traitement et d&#8217;ajouter elle-m\u00eame des donn\u00e9es. M\u00eame si le premier point est vu d&#8217;un \u0153il plus critique par les m\u00e9decins, de telles attentes positives en mati\u00e8re d&#8217;utilisation permettront d&#8217;enclencher une spirale d&#8217;innovation.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Plus d&#8217;informations et d&#8217;analyses :<\/strong><br \/>\nwww.e-healthforum.ch<\/em><\/p>\n<p><em>Coordonn\u00e9es de l&#8217;institut de recherche<br \/>\nLukas Golder<br \/>\ngfs.berne<br \/>\nlukas.golder@gfsbern.ch<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2018 ; 13(5) : 37-39<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau Barom\u00e8tre eHealth 2018 a \u00e9t\u00e9 pr\u00e9sent\u00e9 dans le cadre du SWISS eHealth Forum \u00e0 Berne : Les choses bougent dans le domaine de la num\u00e9risation de la sant\u00e9.&hellip;<\/p>\n","protected":false},"author":7,"featured_media":78562,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Barom\u00e8tre SWISS eHealth 2018","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11523,11527,11482,11535,11549],"tags":[15041,12578,15046],"powerkit_post_featured":[],"class_list":["post-337895","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-etudes","category-prevention-et-soins-de-sante","category-rapports-de-congres","category-rx-fr","tag-dossier-du-patient","tag-e-health-fr","tag-epd-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:44:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":337898,"slug":"nuovi-dati-sulla-partenza-del-documento-elettronico-della-cartella-clinica","post_title":"Nuovi dati sulla partenza del documento elettronico della cartella clinica","href":"https:\/\/medizinonline.com\/it\/nuovi-dati-sulla-partenza-del-documento-elettronico-della-cartella-clinica\/"},"pt_PT":{"locale":"pt_PT","id":337903,"slug":"novos-dados-sobre-o-documento-electronico-de-partida-do-processo-do-doente","post_title":"Novos dados sobre o documento electr\u00f3nico de partida do processo do doente","href":"https:\/\/medizinonline.com\/pt-pt\/novos-dados-sobre-o-documento-electronico-de-partida-do-processo-do-doente\/"},"es_ES":{"locale":"es_ES","id":337877,"slug":"nuevos-datos-sobre-la-salida-del-expediente-electronico-del-paciente","post_title":"Nuevos datos sobre la salida del expediente electr\u00f3nico del paciente","href":"https:\/\/medizinonline.com\/es\/nuevos-datos-sobre-la-salida-del-expediente-electronico-del-paciente\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/337895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=337895"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/337895\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=337895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=337895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=337895"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=337895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}