{"id":338892,"date":"2017-12-14T01:00:00","date_gmt":"2017-12-14T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/pourquoi-les-gliomes-de-faible-malignite-sont-actuellement-incurables\/"},"modified":"2017-12-14T01:00:00","modified_gmt":"2017-12-14T00:00:00","slug":"pourquoi-les-gliomes-de-faible-malignite-sont-actuellement-incurables","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/pourquoi-les-gliomes-de-faible-malignite-sont-actuellement-incurables\/","title":{"rendered":"Pourquoi les gliomes de faible malignit\u00e9 sont actuellement incurables"},"content":{"rendered":"<p><strong>Les gliomes de grade II ont tendance \u00e0 \u00eatre sous-estim\u00e9s dans leur malignit\u00e9 au stade pr\u00e9coce. Il n&#8217;existe pas de norme pour le traitement. Outre l&#8217;attentisme, une tactique chirurgicale agressive est de plus en plus souvent adopt\u00e9e. Il n&#8217;est toutefois pas possible d&#8217;obtenir une gu\u00e9rison avec cette m\u00e9thode.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Les gliomes de faible malignit\u00e9 de grade II de l&#8217;OMS infiltrent souvent le cortex et provoquent donc des crises d&#8217;\u00e9pilepsie dans 60 \u00e0 80% des cas, souvent comme premi\u00e8re manifestation [1,2]. C&#8217;est le lobe le plus grand du cerveau, le cerveau frontal, qui est le plus souvent touch\u00e9. Il en r\u00e9sulte des changements de personnalit\u00e9, des troubles de l&#8217;impulsion et de l&#8217;humeur, mais aussi une ataxie frontale. Si la r\u00e9gion fronto pr\u00e9-centrale \u00e0 post-centrale est touch\u00e9e, des crises focales motrices persistantes avec tendance \u00e0 la g\u00e9n\u00e9ralisation se produisent, mais aussi des h\u00e9mipar\u00e9sies spastiques et des troubles de la sensibilit\u00e9. En cas d&#8217;atteinte du lobe temporal, les crises partielles et complexes, voire les troubles du langage, dominent. Les troubles de l&#8217;appareil visuel sont rares, le plus probable \u00e9tant l&#8217;h\u00e9mianopsie homonyme en cas d&#8217;atteinte du tractus optique. Si le tronc c\u00e9r\u00e9bral est touch\u00e9, il en r\u00e9sulte des troubles neurologiques complexes des voies longues et de la fonction des nerfs cr\u00e2niens, pouvant aller jusqu&#8217;\u00e0 la paralysie bulbaire avec troubles de la d\u00e9glutition et de l&#8217;aspiration. Si le thalamus et les ganglions de la base sont atteints, des troubles extrapyramidaux ou des troubles de la m\u00e9moire apparaissent. Les fluctuations de la vigilance pouvant aller jusqu&#8217;\u00e0 la d\u00e9mence sont au premier plan. Mais souvent, m\u00eame en cas de processus tr\u00e8s importants, la personnalit\u00e9 est bien pr\u00e9serv\u00e9e pendant une p\u00e9riode prolong\u00e9e, car les cellules tumorales envahissent le tissu c\u00e9r\u00e9bral sain de mani\u00e8re diffuse sans le d\u00e9truire. Le lent d\u00e9placement des zones fonctionnelles par le tissu tumoral permet un d\u00e9placement de la fonction menac\u00e9e vers les zones voisines ou du c\u00f4t\u00e9 oppos\u00e9 (plasticit\u00e9), ce qui est visible sur l&#8217;IRM fonctionnelle.<\/p>\n<p><strong>La figure&nbsp;1<\/strong> montre une \u00e9volution typique d&#8217;un astrocytome de faible malignit\u00e9 de grade II de l&#8217;OMS.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9519\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8.jpg\" style=\"height:483px; width:600px\" width=\"1100\" height=\"885\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8-800x644.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8-120x97.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8-90x72.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8-320x257.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_oh6_s8-560x451.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"les-gliomes-manifestation-du-taux-de-mutation-spontanee\">Les gliomes : Manifestation du taux de mutation spontan\u00e9e ?<\/h2>\n<p>Rarement (&lt;5%), les tumeurs c\u00e9r\u00e9brales apparaissent de mani\u00e8re syndromique dans les cancers familiaux, par exemple dans le syndrome de Turcot avec d\u00e9faut g\u00e9n\u00e9tique &#8220;mismatch repair&#8221; ou dans le syndrome de Li-Fraumeni avec mutation p53 [3\u20135]. Plus rares encore sont les astrocytomes b\u00e9nins \u00e0 cellules g\u00e9antes, qui se manifestent chez l&#8217;enfant et de mani\u00e8re sporadique chez l&#8217;adulte, et qui sont la cons\u00e9quence d&#8217;une mutation cong\u00e9nitale des g\u00e8nes de la scl\u00e9rose tub\u00e9reuse TSC1 et TSC2, qui cor\u00e9gulent le complexe mTOR du m\u00e9tabolisme \u00e9nerg\u00e9tique. L&#8217;anomalie g\u00e9n\u00e9tique la plus fr\u00e9quemment associ\u00e9e aux maladies neurologiques est la mutation du g\u00e8ne de la neurofibromatose de type 1, avec une fr\u00e9quence de 1 pour 3000. Il s&#8217;agit de microd\u00e9l\u00e9tions intrag\u00e9niques qui, dans la moiti\u00e9 des cas, ne sont pas h\u00e9r\u00e9ditaires mais apparaissent spontan\u00e9ment. Le locus du g\u00e8ne NF1 sur le chromosome 17q11.2 est relativement instable. Le ph\u00e9notype Nf1 comprend les gliomes optiques b\u00e9nins. Des d\u00e9l\u00e9tions de Nf1 ont \u00e9t\u00e9 d\u00e9tect\u00e9es dans des sous-types de glioblastomes et contribuent \u00e0 la gliomagen\u00e8se en combinaison avec d&#8217;autres mutations. Dans les astrocytomes de grade II et dans le glioblastome secondaire, dont le pronostic est meilleur, on trouve souvent des mutations des g\u00e8nes de l&#8217;isocitrate d\u00e9shydrog\u00e9nase IDH1 et IDH2. Comme la co-d\u00e9l\u00e9tion 1p-19q dans l&#8217;oligodendrogliome, la mutation IDH marque un autre type d&#8217;origine biologique avec un meilleur pronostic.<\/p>\n<p>Le taux de mutation spontan\u00e9e est de 1:100&#8217;000 par division cellulaire. Un organisme passe par environ <sup>1014<\/sup> divisions cellulaires avant d&#8217;atteindre la diff\u00e9renciation compl\u00e8te. Au cours de la vie, d&#8217;innombrables erreurs de lecture se produisent dans chaque cellule lors de la division cellulaire &#8211; y compris dans le r\u00e9servoir de cellules souches &#8211; qui sont pour la plupart imm\u00e9diatement corrig\u00e9es par des m\u00e9canismes de r\u00e9paration intrins\u00e8ques \u00e0 la cellule. N\u00e9anmoins, il y a toujours des mutations qui ne sont pas d\u00e9tect\u00e9es ou qui ne sont pas prises en compte. ne sont pas r\u00e9par\u00e9es, ce qui contribue dans de rares cas au d\u00e9veloppement de tumeurs. Les gliomes font partie des maladies dites &#8220;orphelines&#8221;, c&#8217;est-\u00e0-dire tr\u00e8s rares, avec une incidence de moins de cinq cas pour 10 000 personnes par an.<\/p>\n<h2 id=\"classification-genetique-moleculaire\">Classification g\u00e9n\u00e9tique mol\u00e9culaire<\/h2>\n<p>Des tests g\u00e9n\u00e9tiques r\u00e9cemment d\u00e9velopp\u00e9s, qui balayent l&#8217;ensemble du g\u00e9nome, permettent un pronostic assez pr\u00e9cis de tous les types de gliomes et permettent de classer correctement les cas histologiquement incertains [6]. Il s&#8217;agit de balayer l&#8217;ensemble du g\u00e9nome \u00e0 la recherche de profils de m\u00e9thylation pathologiques. L&#8217;expression de nombreux g\u00e8nes qui contr\u00f4lent la prolif\u00e9ration des cellules tumorales et favorisent l&#8217;apoptose est r\u00e9gul\u00e9e par ce que l&#8217;on appelle les \u00eelots CpG dans la r\u00e9gion promotrice des g\u00e8nes, qui peuvent \u00eatre d\u00e9sactiv\u00e9s par m\u00e9thylation, par exemple dans la diff\u00e9renciation des organes, mais aussi dans les cellules canc\u00e9reuses. Un autre type d&#8217;inactivation g\u00e9nique est la d\u00e9l\u00e9tion \u00e0 long terme de bras chromosomiques, qui transforme une section h\u00e9t\u00e9rozygote en section monozygote, souvent avec une r\u00e9duplication. On peut alors cr\u00e9er un all\u00e9lotype sur tous les chromosomes afin de d\u00e9tecter la perte d&#8217;h\u00e9t\u00e9rozygotie. Par exemple, les monosomies 1p et 19q sont pathognomoniques pour les oligodendrogliomes \u00e0 croissance lente. Les oligodendrogliomes de type sauvage avec h\u00e9t\u00e9rozygotie 1p\/19q ont un comportement beaucoup plus agressif. Dans les glioblastomes, on trouve typiquement la monosomie du chromosome 10 et la trisomie du chromosome 7 avec amplification de l&#8217;EGFR. L&#8217;analyse combin\u00e9e de l&#8217;all\u00e9lotype et du m\u00e9thylome permet une classification tr\u00e8s pr\u00e9cise de tous les gliomes, en particulier dans les cas o\u00f9 l&#8217;histologie soul\u00e8ve des questions. Si des survivants \u00e0 long terme sont observ\u00e9s dans des \u00e9tudes sur le glioblastome, le diagnostic histologique devrait \u00eatre v\u00e9rifi\u00e9 par des tests mol\u00e9culaires, car le taux d&#8217;erreur histologique dans les \u00e9tudes \u00e0 grande \u00e9chelle peut atteindre 7% [7].<\/p>\n<h2 id=\"reduction-de-masse-retardee-lors-de-la-manifestation-des-symptomes\">R\u00e9duction de masse retard\u00e9e lors de la manifestation des sympt\u00f4mes<\/h2>\n<p>Comme la plupart des patients gliome de grade II sont en bon \u00e9tat clinique au moment du diagnostic, une phase d&#8217;observation est souvent choisie initialement [1,2]. De nombreux patients peuvent ainsi mener une vie normale relativement peu symptomatique pendant quelques ann\u00e9es. Dans le cadre de cette strat\u00e9gie, on n&#8217;intervient qu&#8217;en cas de transformation en un degr\u00e9 de malignit\u00e9 plus \u00e9lev\u00e9 (degr\u00e9 III ou IV) ou en cas d&#8217;\u00e9chec de l&#8217;intervention. si des sympt\u00f4mes neurologiques se manifestent jusqu&#8217;\u00e0 des signes de pression intracr\u00e2nienne (c\u00e9phal\u00e9es, troubles de la vigilance, naus\u00e9es \u00e0 vomissements). Une r\u00e9duction de masse est alors mise en place, suivie d&#8217;une radiochimioth\u00e9rapie, ou r\u00e9sign\u00e9e.<\/p>\n<h2 id=\"craniotomie-eveillee-et-neuromonitoring\">Cr\u00e2niotomie \u00e9veill\u00e9e et neuromonitoring<\/h2>\n<p>Dans les premi\u00e8res phases de la chirurgie du gliome, on a \u00e9galement tent\u00e9, dans des cas d\u00e9sesp\u00e9r\u00e9s, de contr\u00f4ler la tumeur par h\u00e9misph\u00e9rectomie, mais cela n&#8217;a pas pu aboutir en raison de la tendance \u00e0 l&#8217;infiltration diffuse des cellules tumorales. Ces derni\u00e8res ann\u00e9es, la chirurgie agressive des gliomes a connu une renaissance, mais en se limitant \u00e0 une r\u00e9duction de masse extensive par craniotomie \u00e0 l&#8217;\u00e9tat de veille et neuromonitoring [8]. La r\u00e9organisation corticale due \u00e0 la plasticit\u00e9 c\u00e9r\u00e9brale permet parfois de r\u00e9s\u00e9quer des zones fonctionnellement importantes sans entra\u00eener de d\u00e9ficits suppl\u00e9mentaires. Cette approche ne peut logiquement pas non plus aboutir \u00e0 une gu\u00e9rison, car des millions de cellules tumorales infiltrantes restent non d\u00e9tect\u00e9es. Un mod\u00e8le de calcul permet de le d\u00e9montrer : Un corps humain de 70&nbsp;kg est compos\u00e9 d&#8217;environ <sup>1014<\/sup> cellules. Une tumeur de 70&nbsp;g contient donc environ 1011 cellules tumorales. Lorsqu&#8217;une tumeur maligne infiltrante est r\u00e9s\u00e9qu\u00e9e \u00e0 99,9%, il reste encore environ 100 millions de cellules tumorales qui d\u00e9terminent le sort futur<strong> (fig.&nbsp;2). <\/strong>Un traitement moderne doit \u00e9liminer ces cellules r\u00e9siduelles ou les remplacer par d&#8217;autres. contr\u00f4ler.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9520 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10.png\" style=\"--smush-placeholder-width: 877px; --smush-placeholder-aspect-ratio: 877\/1323;height:603px; width:400px\" width=\"877\" height=\"1323\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10.png 877w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10-800x1207.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10-120x181.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10-90x136.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10-320x483.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb2_oh6_s10-560x845.png 560w\" data-sizes=\"(max-width: 877px) 100vw, 877px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"perspectives-therapeutiques\">Perspectives th\u00e9rapeutiques<\/h2>\n<p>De nombreux patients atteints d&#8217;astrocytome de grade II n&#8217;ont pas d\u00e9pass\u00e9 l&#8217;\u00e2ge de 50 ans&nbsp;ou ont \u00e9t\u00e9 diagnostiqu\u00e9s \u00e0 un stade pr\u00e9coce. seulement avec des d\u00e9ficits neurologiques croissants et sont expos\u00e9s \u00e0 la menace permanente d&#8217;une probabilit\u00e9 de 50 % de transformation en un niveau de malignit\u00e9 sup\u00e9rieur. Cela plaide en fait pour une intervention pr\u00e9coce. Bien que la r\u00e9section supramaximale n&#8217;entra\u00eene pas de gu\u00e9rison, elle r\u00e9duit le risque de transformation maligne. Les premi\u00e8res exp\u00e9riences d&#8217;irradiation cibl\u00e9e de cellules individuelles par des biomol\u00e9cules diffusibles qui se fixent sur des r\u00e9cepteurs sp\u00e9cifiques de cellules tumorales et qui portent comme effecteur un isotope de haute \u00e9nergie \u00e0 tr\u00e8s courte port\u00e9e ont conduit \u00e0 plusieurs reprises \u00e0 un contr\u00f4le tr\u00e8s long de la tumeur, bien au-del\u00e0 de la survie moyenne, sans toxicit\u00e9 importante [9,10]. D&#8217;autres m\u00e9dicaments viendront s&#8217;y ajouter \u00e0 l&#8217;avenir, qui bloqueront les circuits biologiques perturb\u00e9s et am\u00e9lioreront ainsi le pronostic [5].<\/p>\n<h2 id=\"messages-take-home\">Messages Take-Home<\/h2>\n<ul>\n<li>Environ 10 \u00e0 15% de tous les gliomes malins se pr\u00e9sentent principalement sous la forme d&#8217;astrocytomes de grade II de faible malignit\u00e9 ou, plus rarement, d&#8217;oligodendrogliomes. La survie moyenne est de sept \u00e0 dix ans pour les astrocytomes de grade II et de dix \u00e0 quinze ans pour les oligodendrogliomes de grade II.<\/li>\n<li>Compte tenu du pronostic mis\u00e9rable des glioblastomes plus fr\u00e9quents, les gliomes de grade II ont tendance \u00e0 \u00eatre sous-estim\u00e9s dans leur malignit\u00e9 \u00e0 la phase pr\u00e9coce.<\/li>\n<li>Les tumeurs c\u00e9r\u00e9brales sont probablement la cons\u00e9quence du taux de mutation spontan\u00e9e des processus cellulaires, en quelque sorte le revers de la recombinaison.<\/li>\n<li>La nouvelle classification de l&#8217;OMS des tumeurs c\u00e9r\u00e9brales sur la base du sch\u00e9ma de m\u00e9thylation et de l&#8217;all\u00e9lotype permet d&#8217;\u00e9tablir un pronostic fiable.<\/li>\n<li>Il n&#8217;existe pas de norme pour le traitement des gliomes de grade II. Outre l&#8217;attitude attentiste, une tactique chirurgicale agressive est de plus en plus souvent adopt\u00e9e. Cependant, en raison de l&#8217;infiltration des cellules tumorales dans les tissus c\u00e9r\u00e9braux sains, il n&#8217;est pas possible d&#8217;obtenir une gu\u00e9rison. Il existe de premi\u00e8res indications selon lesquelles la radioth\u00e9rapie cibl\u00e9e sur une seule cellule avec des biomol\u00e9cules diffusibles pourrait am\u00e9liorer consid\u00e9rablement le pronostic.<\/li>\n<\/ul>\n<p>\nLitt\u00e9rature :<\/p>\n<ol>\n<li>Merlo A, de Tribolet N : Tumeurs du cerveau et de la moelle \u00e9pini\u00e8re. In : Steck A, Hess CH (\u00e9d.) : Neurologische Pathophysiologie. Berne : \u00c9ditions Hans Huber 2003.<\/li>\n<li>Schneider T, et al : Gliomes chez l&#8217;adulte. Dtsch Arztebl Int 2010 ; 107(45) : 799-807.&nbsp;&nbsp; &nbsp;<\/li>\n<li>Merlo A, Rochlitz C, Scott R : Survival of patients with Turcot&#8217;s syndrome and glioblastoma [letter]. N Engl J Med 1996 ; 334(11) : 736-737.<\/li>\n<li>Merlo A, Bettler B : Glioblastomas on the move. Science STKE 2004 ; 2004(229) : pe18.<\/li>\n<li>Lino M, Merlo A : Translating Biology into Clinic : the case of glioblastoma. Curr Opin Cell Biol 2009 ; 21(2) : 311-316.<\/li>\n<li>Louis DN, et al : The 2016 World Health Organization Classification of Tumors of the Central Nervous System : a summary. Acta Neuropathol 2016 ; 131(6) : 803-820.<\/li>\n<li>Linz U : Commentary on Effects of Radiotherapy with concomitant and adjuvant temozolomide versus radiotherapy alone on survival in glioblastoma in a randomised phase III study : 5-year analysis of the EORTC-NCIC trial (Lancet Oncol. 2009;10:459-466). Cancer 2010 ; 116(8) : 1844-1846.<\/li>\n<li>Duffau H : The Rationale to Perform Early Resection in Incidental Diffuse Low-Grade Glioma : Toward a &#8220;Preventive Surgical Neurooncology&#8221;. World Neurosurgery 2013 ; 80(5) : e115-e117.<\/li>\n<li>Cordier D, et al : Traitement cibl\u00e9 par alpha-radionucl\u00e9ide des gliomes fonctionnellement critiqu\u00e9s avec la substance P de 213Bi-DOTAGA : un essai pilote. Eur J Nucl Med Mol Imaging 2010 ; 37(7) : 1335-1344.<\/li>\n<li>Cordier D, et al : Compos\u00e9s radiolabellis\u00e9s cibl\u00e9s dans le traitement du gliome. Semin Nucl Med 2016 ; 46(3) : 243-249.<br \/>\n\t&nbsp;<\/li>\n<\/ol>\n<p><em>InFo ONKOLOGIE &amp; H\u00c9MATOLOGIE 2017 ; 5(6) : 7-10<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les gliomes de grade II ont tendance \u00e0 \u00eatre sous-estim\u00e9s dans leur malignit\u00e9 au stade pr\u00e9coce. Il n&#8217;existe pas de norme pour le traitement. Outre l&#8217;attentisme, une tactique chirurgicale agressive&hellip;<\/p>\n","protected":false},"author":7,"featured_media":72980,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Pronostic et biologie des gliomes","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11531,11383,11389,11549],"tags":[35678,35686,30926,12373,16572,32614,35681,30925,35699,12573,35693],"powerkit_post_featured":[],"class_list":["post-338892","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formation-continue","category-neurologie-fr","category-oncologie","category-rx-fr","tag-astrocytomes","tag-biologie-fr","tag-chirurgie-fr","tag-classification-fr","tag-gliomes","tag-guerison","tag-oligodendrogliomes","tag-previsions-fr","tag-radiotherapie-a-cellules-uniques-avec-des-biomolecules-diffusibles","tag-therapie-fr","tag-tumeurs-cerebrales","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:52:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":338911,"slug":"perche-i-gliomi-poco-maligni-non-sono-attualmente-curabili","post_title":"Perch\u00e9 i gliomi poco maligni non sono attualmente curabili","href":"https:\/\/medizinonline.com\/it\/perche-i-gliomi-poco-maligni-non-sono-attualmente-curabili\/"},"pt_PT":{"locale":"pt_PT","id":338919,"slug":"porque-e-que-os-gliomas-de-baixo-malignidade-nao-sao-actualmente-curaveis","post_title":"Porque \u00e9 que os gliomas de baixo malignidade n\u00e3o s\u00e3o actualmente cur\u00e1veis","href":"https:\/\/medizinonline.com\/pt-pt\/porque-e-que-os-gliomas-de-baixo-malignidade-nao-sao-actualmente-curaveis\/"},"es_ES":{"locale":"es_ES","id":338922,"slug":"por-que-los-gliomas-poco-malignos-no-son-curables-en-la-actualidad","post_title":"Por qu\u00e9 los gliomas poco malignos no son curables en la actualidad","href":"https:\/\/medizinonline.com\/es\/por-que-los-gliomas-poco-malignos-no-son-curables-en-la-actualidad\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/338892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=338892"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/338892\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=338892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=338892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=338892"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=338892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}