{"id":339741,"date":"2017-05-31T02:00:00","date_gmt":"2017-05-31T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/qualite-et-centrage-sur-le-patient-dans-la-profession-de-medecin-generaliste\/"},"modified":"2017-05-31T02:00:00","modified_gmt":"2017-05-31T00:00:00","slug":"qualite-et-centrage-sur-le-patient-dans-la-profession-de-medecin-generaliste","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/qualite-et-centrage-sur-le-patient-dans-la-profession-de-medecin-generaliste\/","title":{"rendered":"Qualit\u00e9 et centrage sur le patient dans la profession de m\u00e9decin g\u00e9n\u00e9raliste"},"content":{"rendered":"<p><strong>Qu&#8217;est-ce que la qualit\u00e9 dans la pratique de la m\u00e9decine g\u00e9n\u00e9rale ? C&#8217;\u00e9tait l&#8217;une des questions directrices abord\u00e9es lors du 7e congr\u00e8s de l&#8217;association des jeunes m\u00e9decins de famille suisses \u00e0 Thoune. Que signifie &#8220;care&#8221; &#8211; un mot pour lequel la langue allemande propose toute une s\u00e9rie de traductions aux connotations diverses, qui permettent d&#8217;explorer les nombreuses facettes de la profession de m\u00e9decin g\u00e9n\u00e9raliste. Ce n&#8217;est pas un hasard si le slogan &#8220;Yes we care&#8221; s&#8217;inspire du slogan de campagne programmatique de Barack Obama.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Pr\u00e8s de 500 jeunes m\u00e9decins de bonne humeur se sont r\u00e9unis \u00e0 Thoune pour \u00e9changer, r\u00e9seauter et se former. En plus des apports pratiques sur la cr\u00e9ation et la gestion d&#8217;un cabinet m\u00e9dical et des nombreux s\u00e9minaires techniques, les participants ont discut\u00e9 intensivement de l&#8217;ambivalence de la profession de m\u00e9decin g\u00e9n\u00e9raliste entre l&#8217;engagement personnel et la vie priv\u00e9e, entre la responsabilit\u00e9 non d\u00e9l\u00e9gable en tant que m\u00e9decin et la bureaucratie, entre l&#8217;intuition et l&#8217;expertise.<\/p>\n<p>&#8220;Le mod\u00e8le de la m\u00e9decine fond\u00e9e sur les preuves (EBM) n&#8217;est finalement pas une garantie de qualit\u00e9 \u00e0 100%&#8221;, a introduit le Dr Bruno Kissling, Berne, lors du panel de discussion avec l&#8217;ethnologue Dr phil. Andrea Abraham, Zurich, de. L&#8217;exp\u00e9rience, l&#8217;expertise et l&#8217;intuition oscillent. &#8220;En m\u00e9decine de famille, la qualit\u00e9 n&#8217;est pas quantifiable, elle n&#8217;est perceptible que par le bien-\u00eatre du patient. Une notion de qualit\u00e9 qui suit la logique industrielle ne peut pas \u00eatre concili\u00e9e avec le travail quotidien dans un cabinet de m\u00e9decine g\u00e9n\u00e9rale&#8221;, a d\u00e9clar\u00e9 Kissling. Souvent, le patient a d&#8217;autres concepts de sant\u00e9 et veut \u00eatre per\u00e7u dans sa globalit\u00e9 pour pouvoir accepter les offres de traitement. &#8220;Il reste toujours un facteur d&#8217;incertitude &#8211; une caract\u00e9ristique essentielle que l&#8217;on ach\u00e8te avec cette profession&#8221;. L&#8217;intuition contribue de mani\u00e8re non n\u00e9gligeable au choix de la bonne th\u00e9rapie &#8211; toutefois, &#8220;en tant que m\u00e9decin, il faut d&#8217;abord pouvoir et savoir beaucoup de choses&#8221;.<\/p>\n<p>Le r\u00f4le de l&#8217;intuition a \u00e9t\u00e9 confirm\u00e9 par le Dr Hans Jakob Zehnder, co-m\u00e9decin-chef \u00e0 l&#8217;h\u00f4pital de Riggisberg, lors d&#8217;une table ronde sur le r\u00f4le du m\u00e9decin de famille dans la soci\u00e9t\u00e9. Les patients difficiles sont g\u00e9n\u00e9ralement des personnes qui ont peur. Le manque de coop\u00e9ration, les besoins d&#8217;attention particuliers ou les attentes des patients d&#8217;\u00eatre disponibles 24h\/24 et 7j\/7 poussent les m\u00e9decins g\u00e9n\u00e9ralistes \u00e0 leurs limites &#8211; il faut alors souvent se forcer \u00e0 changer de perspective. C&#8217;est en m\u00eame temps ce qui est satisfaisant dans le m\u00e9tier de m\u00e9decin g\u00e9n\u00e9raliste : en tant que m\u00e9decin g\u00e9n\u00e9raliste, on a la possibilit\u00e9 de suivre un patient sur une longue p\u00e9riode, de conna\u00eetre son contexte social et de se faire une id\u00e9e des conflits potentiels dans lesquels une personne \u00e9volue au travail, dans sa famille ou dans la communaut\u00e9 villageoise. Gr\u00e2ce \u00e0 ces connaissances, un m\u00e9decin g\u00e9n\u00e9raliste est mieux \u00e0 m\u00eame de comprendre les attitudes de ses patients et d&#8217;assurer une prise en charge globale de ces derniers. C&#8217;est la raison pour laquelle Zehnder accorde une grande importance aux visites \u00e0 domicile. On y apprendrait parfois plus sur le patient que lors de longs entretiens dans les locaux du cabinet.<\/p>\n<p>Pour Zehnder, la formation continue joue un r\u00f4le cl\u00e9 dans la comp\u00e9tence en mati\u00e8re de conseil. Bien entendu, il ne s&#8217;agit pas de pouvoir r\u00e9aliser soi-m\u00eame chaque op\u00e9ration, mais il faut savoir ce qui est important dans le traitement postop\u00e9ratoire et, en tant que confident m\u00e9dical du patient, il faut pouvoir le conseiller de mani\u00e8re ad\u00e9quate. Les m\u00e9decins devraient, si n\u00e9cessaire, sortir de l&#8217;ombre et demander le soutien de leurs coll\u00e8gues, y compris accepter les critiques de leurs jeunes coll\u00e8gues. Il met en garde contre le fait de faire quelque chose que l&#8217;on ne peut pas fondamentalement faire, rejoignant ainsi l&#8217;avertissement de Kissling.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-8656\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei.png\" style=\"height:180px; width:400px\" width=\"870\" height=\"391\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei.png 870w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei-800x360.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei-120x54.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei-90x40.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei-320x144.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/05\/literaturhinwei-560x252.png 560w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Cependant, le m\u00e9tier de m\u00e9decin g\u00e9n\u00e9raliste demande parfois du courage. Il y a quelques mois, Zehnder a ainsi \u00e9t\u00e9 affect\u00e9 \u00e0 environ 150 demandeurs d&#8217;asile fluctuants d&#8217;un centre de transit \u00e0 Riggisberg en tant que m\u00e9decin de premier recours. A cette \u00e9poque, il y avait peu de recommandations sur la mani\u00e8re de proc\u00e9der en ce qui concerne les premiers soins. Les personnes \u00e9taient issues de soci\u00e9t\u00e9s diff\u00e9rentes, parfois traumatis\u00e9es, et la communication \u00e9tait souvent impossible. Les indications les plus fr\u00e9quentes concernaient les maladies de peau, les probl\u00e8mes orthop\u00e9diques et les infections. Il y a eu quelques \u00e9nigmes \u00e0 r\u00e9soudre, mais c&#8217;est une question de formation &#8211; et d&#8217;une \u00e9quipe qui doit \u00e9galement avoir un haut niveau de qualification professionnelle.<\/p>\n<h2 id=\"ou-sont-les-limites\">O\u00f9 sont les limites ?<\/h2>\n<p>Dans la profession de m\u00e9decin, la question de la d\u00e9limitation est toujours importante. Zehnder s&#8217;est \u00e9galement beaucoup engag\u00e9 personnellement dans l&#8217;encadrement des r\u00e9fugi\u00e9s demandeurs d&#8217;asile, par exemple en mettant \u00e0 disposition sa propre maison comme possibilit\u00e9 d&#8217;h\u00e9bergement apr\u00e8s la fermeture du centre de transit. Les situations ont \u00e9t\u00e9 particuli\u00e8rement difficiles lorsque des patients gravement atteints dans leur sant\u00e9 ont \u00e9t\u00e9 renvoy\u00e9s \u00e0 l&#8217;\u00e9tranger. M. Zehnder a soulign\u00e9 \u00e0 quel point les m\u00e9decins traitants sont parfois impuissants face \u00e0 la mani\u00e8re dont les gens sont trimball\u00e9s par la bureaucratie, &#8220;comme des patates chaudes&#8221;. Cela concerne \u00e9galement les personnes qui ont un besoin urgent de s\u00e9curit\u00e9 et de continuit\u00e9 pour avoir une chance r\u00e9elle de survie.<\/p>\n<p>Zehnder a expliqu\u00e9 qu&#8217;en d\u00e9pit d&#8217;un engagement exceptionnel, des limites doivent \u00eatre fix\u00e9es en connaissance de cause. Il n&#8217;emm\u00e8ne pas ses patients dans la sph\u00e8re priv\u00e9e. La famille, les amis, les hobbies auraient leur importance, entre autres, dans le fait de marquer ces limites.<\/p>\n<p>Le Dr Heidi Zinggler Furrer, p\u00e9diatre \u00e0 Coire, a abord\u00e9 l&#8217;\u00e9quilibre entre ses r\u00f4les de m\u00e9decin, de femme et de m\u00e8re dans un expos\u00e9 tr\u00e8s personnel et \u00e9galement impressionnant. Elle a r\u00e9fl\u00e9chi \u00e0 la notion de &#8220;care&#8221; par rapport aux patients, \u00e0 son \u00e9quipe, \u00e0 ses enfants et \u00e0 elle-m\u00eame, et a \u00e9t\u00e9 tr\u00e8s claire : toutes les relations doivent \u00eatre \u00e9quilibr\u00e9es, chaque aspect de la vie doit \u00eatre pris en charge. Le &#8220;care&#8221; comprend \u00e9galement le soin de soi et donc parfois la capacit\u00e9 \u00e0 se distinguer.<\/p>\n<h2 id=\"le-medecin-generaliste-comme-pilote\">Le m\u00e9decin g\u00e9n\u00e9raliste comme pilote<\/h2>\n<p>Le professeur Thierry Carrel, de Berne, a soulign\u00e9 dans son message vid\u00e9o le r\u00f4le particulier du m\u00e9decin de famille en tant qu&#8217;accompagnateur \u00e0 long terme des patients. &#8220;Les sp\u00e9cialistes sont plut\u00f4t des passants, alors qu&#8217;un m\u00e9decin g\u00e9n\u00e9raliste est souvent plus \u00e0 m\u00eame de juger quel traitement convient \u00e0 un patient&#8221;, explique Carell. Zehnder a confirm\u00e9 ce r\u00f4le dans une note sceptique sur les centres de sant\u00e9 de plus en plus populaires aupr\u00e8s des jeunes m\u00e9decins g\u00e9n\u00e9ralistes : Pour les patients &#8220;temporaires&#8221;, un centre de sant\u00e9 est une solution viable, a-t-il ajout\u00e9. Cependant, les patients qui suivent des traitements plus longs et qui ont des attitudes complexes risquent d&#8217;\u00eatre &#8220;absorb\u00e9s&#8221; par les institutions de sant\u00e9. &#8220;De tels patients ont besoin d&#8217;\u00eatre guid\u00e9s par un conseiller m\u00e9dical central, et ce conseiller est le m\u00e9decin de famille&#8221;, d\u00e9clare clairement Zehnder.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Source : 7e Congr\u00e8s JHaS, 29 avril 2017, Thoune<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2017 ; 12(5) : 38-39<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&#8217;est-ce que la qualit\u00e9 dans la pratique de la m\u00e9decine g\u00e9n\u00e9rale ? C&#8217;\u00e9tait l&#8217;une des questions directrices abord\u00e9es lors du 7e congr\u00e8s de l&#8217;association des jeunes m\u00e9decins de famille suisses&hellip;<\/p>\n","protected":false},"author":7,"featured_media":66620,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"7e Congr\u00e8s JHaS, Thoune","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11315,11482,11535,11549],"tags":[33543,38329,38323],"powerkit_post_featured":[],"class_list":["post-339741","post","type-post","status-publish","format-standard","has-post-thumbnail","category-medecine-interne-generale","category-prevention-et-soins-de-sante","category-rapports-de-congres","category-rx-fr","tag-centre-sur-le-patient","tag-ebm-fr","tag-jhas-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:54:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":339750,"slug":"qualita-e-centralita-del-paziente-nella-professione-di-medico-generico","post_title":"Qualit\u00e0 e centralit\u00e0 del paziente nella professione di medico generico","href":"https:\/\/medizinonline.com\/it\/qualita-e-centralita-del-paziente-nella-professione-di-medico-generico\/"},"pt_PT":{"locale":"pt_PT","id":339759,"slug":"qualidade-e-centralidade-do-paciente-na-profissao-de-medico-de-clinica-geral","post_title":"Qualidade e centralidade do paciente na profiss\u00e3o de m\u00e9dico de cl\u00ednica geral","href":"https:\/\/medizinonline.com\/pt-pt\/qualidade-e-centralidade-do-paciente-na-profissao-de-medico-de-clinica-geral\/"},"es_ES":{"locale":"es_ES","id":339766,"slug":"calidad-y-atencion-al-paciente-en-la-profesion-de-medico-de-familia","post_title":"Calidad y atenci\u00f3n al paciente en la profesi\u00f3n de m\u00e9dico de familia","href":"https:\/\/medizinonline.com\/es\/calidad-y-atencion-al-paciente-en-la-profesion-de-medico-de-familia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/339741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=339741"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/339741\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=339741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=339741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=339741"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=339741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}