{"id":339746,"date":"2017-06-02T02:00:00","date_gmt":"2017-06-02T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/possibilites-de-traitement-par-le-chardon-marie\/"},"modified":"2017-06-02T02:00:00","modified_gmt":"2017-06-02T00:00:00","slug":"possibilites-de-traitement-par-le-chardon-marie","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/possibilites-de-traitement-par-le-chardon-marie\/","title":{"rendered":"Possibilit\u00e9s de traitement par le chardon-Marie"},"content":{"rendered":"<p><strong>Les \u00e9tudes pharmacologiques et cliniques soutiennent l&#8217;efficacit\u00e9 des extraits de chardon-Marie et de silymarine &#8211; un aper\u00e7u des maladies et des \u00e9tudes d&#8217;efficacit\u00e9<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Diff\u00e9rentes \u00e9tudes pharmacologiques et cliniques soutiennent l&#8217;efficacit\u00e9 des extraits de chardon-marie et, en premier lieu, de la silymarine, le principal principe actif du chardon-marie. Les pr\u00e9parations correspondantes se pr\u00eatent donc \u00e0 un traitement naturel et efficace des l\u00e9sions h\u00e9patiques d&#8217;origines diverses. Les principales maladies du foie sont les suivantes  &nbsp;<\/p>\n<ul>\n<li>H\u00e9patite aigu\u00eb<\/li>\n<li>h\u00e9patite C chronique<\/li>\n<li>Cirrhose du foie<\/li>\n<\/ul>\n<p><strong>H\u00e9patite A :<\/strong> L&#8217;h\u00e9patite A, transmise par voie f\u00e9co-orale, par exemple par des aliments contamin\u00e9s, est une maladie infectieuse du foie, mais contrairement aux h\u00e9patites B et C, elle ne devient pas chronique. La maladie dure g\u00e9n\u00e9ralement moins de deux mois, mais elle peut aussi durer plusieurs mois. Les sympt\u00f4mes typiques comprennent la jaunisse, le gonflement du foie, la fi\u00e8vre, les naus\u00e9es, la fatigue, les douleurs, les vomissements, le manque d&#8217;app\u00e9tit, les selles claires, l&#8217;urine fonc\u00e9e.<\/p>\n<p><strong>H\u00e9patite B :<\/strong> L&#8217;h\u00e9patite B est transmise par le sang, la salive ou le sperme, et pr\u00e9sente des sympt\u00f4mes similaires \u00e0 ceux de l&#8217;h\u00e9patite A. Elle peut \u00e9galement \u00eatre transmise par le sang, la salive ou le sperme. Contrairement \u00e0 l&#8217;h\u00e9patite A, l&#8217;h\u00e9patite B peut devenir chronique chez environ 5% des personnes touch\u00e9es et entra\u00eener de graves probl\u00e8mes h\u00e9patiques tels qu&#8217;une cirrhose, une insuffisance h\u00e9patique ou un carcinome h\u00e9patocellulaire.<br \/>\nH\u00e9patite C : Dans le cas de l&#8217;infection caus\u00e9e par le virus de l&#8217;h\u00e9patite C, la plupart des patients ne ressentent aucun sympt\u00f4me typique. La maladie se manifeste par de la fatigue, des naus\u00e9es, une perte d&#8217;app\u00e9tit, des douleurs musculaires et articulaires et une perte de poids. L&#8217;h\u00e9patite C est dangereuse \u00e0 long terme, car elle peut \u00e9voluer vers une cirrhose ou un cancer du foie et n\u00e9cessiter une transplantation.<\/p>\n<p><strong>Cirrhose du foie :<\/strong> La cirrhose du foie est une maladie du foie qui \u00e9volue de mani\u00e8re chronique et qui d\u00e9truit l&#8217;architecture lobaire et vasculaire par fibrose. Les patients concern\u00e9s sont fatigu\u00e9s et abattus, ressentent une pression dans la partie sup\u00e9rieure droite de l&#8217;abdomen, des naus\u00e9es, perdent du poids. On observe \u00e9galement de l&#8217;abattement et du m\u00e9t\u00e9orisme. L&#8217;alcool est souvent impliqu\u00e9.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-8659\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/mariendiste_hp5.jpg\" style=\"height:390px; width:400px\" width=\"897\" height=\"875\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"les-plantes-medicinales-pour-les-problemes-de-foie\">Les plantes m\u00e9dicinales pour les probl\u00e8mes de foie<\/h2>\n<p>Il existe un certain nombre de plantes m\u00e9dicinales qui peuvent \u00eatre utilis\u00e9es pour traiter les probl\u00e8mes de foie. Il s&#8217;agit principalement de l&#8217;artichaut (Cynara scolymus), du pissenlit (Taraxacum officinale), de la ch\u00e9lidoine (Chelidonium majus) et du chardon-Marie (Silybum marianum). Il existe \u00e9galement des applications possibles avec l&#8217;achill\u00e9e millefeuille (Achillea millefolium) et la chicor\u00e9e sauvage (Cichorium intybus).<\/p>\n<p>Le chardon-Marie (Silybum marianum) est une plante qui peut atteindre 150&nbsp;cm de haut et qui pousse de l&#8217;est du bassin m\u00e9diterran\u00e9en jusqu&#8217;au sud de la Russie et de l&#8217;Iran. Son ancien nom \u00e9tait Carduus marianus.<\/p>\n<h2 id=\"composants-pharmacologie-du-chardon-marie\">Composants, pharmacologie du chardon-marie<\/h2>\n<p>Le principal ingr\u00e9dient du chardon-Marie est la silymarine, un complexe de substances dont la silibinine (silybine) est la substance la plus active. L&#8217;effet principal est la stabilisation anti-h\u00e9patotoxique de la membrane cellulaire. Un autre effet du silybum marianum repose sur la stimulation de la capacit\u00e9 de r\u00e9g\u00e9n\u00e9ration des h\u00e9patocytes. De plus, la silymarine emp\u00eache la p\u00e9n\u00e9tration des toxines et la perte de composants cellulaires tels que les transaminases. Cela se fait en r\u00e9duisant les processus d&#8217;oxydation et de transport dans la membrane cellulaire. La silymarine stimule \u00e9galement la formation de nouveaux h\u00e9patocytes [1]. Les propri\u00e9t\u00e9s antiradicalaires de la silymarine semblent jouer un r\u00f4le important \u00e0 cet \u00e9gard [2].<\/p>\n<h2 id=\"etudes\">\u00c9tudes<\/h2>\n<p>Plusieurs \u00e9tudes pharmacologiques et cliniques ont port\u00e9 sur l&#8217;efficacit\u00e9 du chardon-marie ou de la silymarine dans le traitement de diverses maladies du foie. Un article de synth\u00e8se a \u00e9galement \u00e9t\u00e9 publi\u00e9 au d\u00e9but de cette ann\u00e9e [3]. Les r\u00e9sultats d&#8217;\u00e9tudes publi\u00e9es sont pr\u00e9sent\u00e9s ci-dessous.<\/p>\n<h2 id=\"hepatites-a-b-et-c\">H\u00e9patites A, B et C<\/h2>\n<p>Wei et al. ont publi\u00e9 en 2013 une m\u00e9ta-analyse sur l&#8217;efficacit\u00e9 des combinaisons de silymarine avec des agents antiviraux (lamivudine et interf\u00e9ron) dans le traitement de l&#8217;h\u00e9patite B chronique [4]. Les \u00e9tudes \u00e9valu\u00e9es ont montr\u00e9 une efficacit\u00e9 similaire de la silymarine et des antiviraux en termes de normalisation des taux s\u00e9riques d&#8217;AST et d&#8217;ALT, ainsi qu&#8217;en termes de taux de conversion n\u00e9gatif de l&#8217;AgHBs s\u00e9rique. La combinaison de silymarine et d&#8217;antiviraux \u00e9tait plus efficace que les antiviraux seuls.<\/p>\n<p>Dans une autre m\u00e9ta-analyse de Yang et al. En 2014 [5], l&#8217;efficacit\u00e9 de la silymarine a \u00e9t\u00e9 \u00e9tudi\u00e9e dans le cas de l&#8217;h\u00e9patite C chronique. Il a \u00e9t\u00e9 d\u00e9montr\u00e9 que la silymarine pouvait r\u00e9duire le taux s\u00e9rique d&#8217;ARN du virus de l&#8217;h\u00e9patite C, mais pas de mani\u00e8re significative. Cependant, pour obtenir cet effet, la silymarine devait \u00eatre administr\u00e9e \u00e0 la fois par voie orale et par voie intraveineuse.<\/p>\n<p>Ferenci et al. ont pu montrer en 2008 que la silybine, en bloquant la fonction de la polym\u00e9rase du VHC, peut r\u00e9duire la charge virale d&#8217;un logarithme de 3 \u00e0 4 chez les patients r\u00e9sistants \u00e0 l&#8217;interf\u00e9ron p\u00e9gyl\u00e9 [6].<\/p>\n<h2 id=\"lesions-hepatiques-liees-a-lalcool\">L\u00e9sions h\u00e9patiques li\u00e9es \u00e0 l&#8217;alcool<\/h2>\n<p>L&#8217;abus d&#8217;alcool est l&#8217;une des causes les plus fr\u00e9quentes d&#8217;h\u00e9patopathie dans le monde, en affectant le fonctionnement des mitochondries par la peroxydation des lipides et par l&#8217;accumulation intracellulaire d&#8217;ac\u00e9tald\u00e9hyde.<\/p>\n<p>Federico et al. ont montr\u00e9 en 2015, dans une \u00e9tude pharmacologique in vitro, qu&#8217;un complexe silybine-phosphatidylcholine avait un effet positif sur la vitalit\u00e9 cellulaire en \u00e9tat de stress oxydatif, en r\u00e9duisant \u00e0 la fois la peroxydation lipidique et la n\u00e9crose cellulaire [7].<\/p>\n<p>Plusieurs \u00e9tudes ont montr\u00e9 que la silymarine et le complexe silybine-phosphatidylcholine peuvent optimiser les processus m\u00e9taboliques mitochondriaux ainsi que le transport d&#8217;\u00e9lectrons [8\u201311]. Cela augmente la superoxyde dismutase intracellulaire et diminue l&#8217;activit\u00e9 de la MAO, ce qui entra\u00eene une diminution des compos\u00e9s oxyg\u00e9n\u00e9s r\u00e9actifs intracellulaires et donc une am\u00e9lioration de la fonction mitochondriale.<\/p>\n<h2 id=\"lesions-du-foie-non-liees-a-lalcool\">L\u00e9sions du foie non li\u00e9es \u00e0 l&#8217;alcool<\/h2>\n<p>Les l\u00e9sions h\u00e9patiques non li\u00e9es \u00e0 l&#8217;alcool (NAFLD) ont connu une croissance exponentielle dans l&#8217;h\u00e9misph\u00e8re occidental au cours des derni\u00e8res ann\u00e9es. Plusieurs \u00e9tudes ont tent\u00e9 d&#8217;expliquer le lien entre l&#8217;utilisation de la silymarine\/silybine et son efficacit\u00e9. La silymarine\/silybine exerce un antagonisme sur la progression des l\u00e9sions h\u00e9patiques non li\u00e9es \u00e0 l&#8217;alcool.<\/p>\n<p>Butorova et al. ont \u00e9tudi\u00e9 l&#8217;efficacit\u00e9 de la silymarine dans la NAFLD dans le cadre d&#8217;une \u00e9tude ouverte, randomis\u00e9e et en parall\u00e8le [12]. Les auteurs ont conclu qu&#8217;un traitement de 140&nbsp;mg de silymarine 3\u00d7\/jour \u00e9tait un h\u00e9patoprotecteur efficace et s\u00fbr dans le cas de la NAFLD et qu&#8217;il entra\u00eenait une am\u00e9lioration significative des param\u00e8tres cliniques et biochimiques.<\/p>\n<h2 id=\"cirrhose-du-foie\">Cirrhose du foie<\/h2>\n<p>Une fibrose avanc\u00e9e des cellules h\u00e9patiques est irr\u00e9versible. La silymarine interf\u00e8re cependant avec le processus fibrog\u00e9nique. Une \u00e9tude pharmacologique [13] a montr\u00e9 que chez des rats trait\u00e9s au CCl4, la silymarine peut r\u00e9duire la progression du processus fibrog\u00e9nique \u00e0 un stade pr\u00e9coce.<\/p>\n<p><strong>Conclusion : <\/strong>le chardon-Marie est une plante m\u00e9dicinale bien \u00e9tudi\u00e9e et efficace pour divers troubles h\u00e9patiques.<\/p>\n<h2 id=\"messages-take-home\">Messages Take-Home<\/h2>\n<ul>\n<li>Il existe plusieurs plantes m\u00e9dicinales ayant une tradition de m\u00e9decine populaire pour le traitement des maladies du foie. Il s&#8217;agit notamment de l&#8217;artichaut, du pissenlit et de la ch\u00e9lidoine. Le chardon-Marie, Silybum marianum, a \u00e9galement fait l&#8217;objet de recherches particuli\u00e8rement approfondies. Cet article offre un aper\u00e7u des maladies du foie et de leurs possibilit\u00e9s de traitement avec le chardon-marie.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Wellington K, Jarvis B : Silymarin ; a review of its clinical properties in the management of hepatic disorders. Bio Drugs 2001(7) ; 15 : 465-489.<\/li>\n<li>Iten F, et al. : La silymarine dans le traitement des maladies du foie, phytoth\u00e9rapie 2003(1) ; 3 : 18-24.<\/li>\n<li>Federico A, Dallio M, Loguercio C : Silymarine\/Silybine et Disparition chronique du foie : un mariage de plusieurs ann\u00e9es, Molecules. 2017(2) ; 22. pii : E191. doi : 10.3390\/molecules22020191<\/li>\n<li>Wei F, et al. : M\u00e9ta-analyse : Silymarin et son association pour le traitement de l&#8217;h\u00e9patite B chronique, Eur. J. Clin. Microbiol. Infect. Dis. 2013 ;&nbsp; 32 : 657-669.<\/li>\n<li>Yang Z, et al : Effects and tolerance of silymarin (milk thistle) in chronic hepatitis C virus infection patients : A meta-analysis of randomized control trials, Biomed. Res. Int. 2014, 2014, 941085.<\/li>\n<li>Ferenci P, et al : Silibinin is a potent antiviral agent in patients with chronic hepatitis C not responding tu pegylated interferon ribavirin therapy, Gastronenterology 2008 ; 135 : 1561-1567.<\/li>\n<li>Federico A. et al. : Silybin-Phosphatidylcholine Complex Protects Human Gastric and Liver Cells from Oxidative Stress, In Vivo 2015 ;<\/li>\n<li>29: 569-575.<\/li>\n<li>Rolo A.P. et al. : Protection against post-ischemic mitochondrial injury in rat liver by silymarin or TUDC, Hepatol. Res. 2003 ;<\/li>\n<li>26 : 217-224.<\/li>\n<li>Detaille D. et al. : Interrelation entre l&#8217;inhibition du flux glycolytique par la silibinine et la diminution de la production de ROS mitochondriales dans des h\u00e9patocytes de rat perfus\u00e9s, Life Sci. 2008 ; 82 : 1070-1076.<\/li>\n<li>Grattagliano I. et al. : A silybin-phospholipids complex counteracts rat fatty liver degeneration and mitochondrial oxidative changes, World J. Gastroenterol. 2013 ; 19 : 3007-3017<\/li>\n<li>Mazzio E.A. et al. : Food constituents attenuate monoamine oxidae activity and peroxide levels in C6 astrocyte cells, Plant Med. 1998 ; 64 : 603-606.<\/li>\n<li>Butorova L.I, et al. : Potential for the Use of Legalon\u00ae in Non-Alcoholic Fatty Liver Desease, Experimental and Clinical Gastroenterology 2010 ; 3 : 85-91.<\/li>\n<li>Clichici S, et al. : La silymarine inhibe la progression de la fibrose au stade pr\u00e9coce de la l\u00e9sion h\u00e9patique chez les rats trait\u00e9s au CCl4, J. Med. Food 2015 ; 18 : 290-298.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2017 ; 12(5) : 3-4<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9tudes pharmacologiques et cliniques soutiennent l&#8217;efficacit\u00e9 des extraits de chardon-Marie et de silymarine &#8211; un aper\u00e7u des maladies et des \u00e9tudes d&#8217;efficacit\u00e9<\/p>\n","protected":false},"author":7,"featured_media":66638,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Maladies du foie","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11523,11527,11414,11428,11315,11467,11549],"tags":[38332,15556,38345,38352,13030,15552,38356,24770,38339],"powerkit_post_featured":[],"class_list":["post-339746","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-etudes","category-gastro-enterologie-et-hepatologie","category-infectiologie","category-medecine-interne-generale","category-medecine-pharmaceutique","category-rx-fr","tag-chardon-marie","tag-cirrhose-du-foie","tag-dependance-au-gluten","tag-etudes-sur-le-chardon-marie","tag-fatigue-fr","tag-hepatite","tag-lesions-du-foie","tag-maladies-du-foie","tag-silybum-marianum-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:43:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":339760,"slug":"possibilita-di-trattamento-con-il-cardo-mariano","post_title":"Possibilit\u00e0 di trattamento con il cardo mariano","href":"https:\/\/medizinonline.com\/it\/possibilita-di-trattamento-con-il-cardo-mariano\/"},"pt_PT":{"locale":"pt_PT","id":339770,"slug":"possibilidades-de-tratamento-com-cardo-de-leite","post_title":"Possibilidades de tratamento com cardo de leite","href":"https:\/\/medizinonline.com\/pt-pt\/possibilidades-de-tratamento-com-cardo-de-leite\/"},"es_ES":{"locale":"es_ES","id":339775,"slug":"posibilidades-de-tratamiento-con-cardo-mariano","post_title":"Posibilidades de tratamiento con cardo mariano","href":"https:\/\/medizinonline.com\/es\/posibilidades-de-tratamiento-con-cardo-mariano\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/339746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=339746"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/339746\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=339746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=339746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=339746"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=339746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}