{"id":340201,"date":"2017-02-19T01:00:00","date_gmt":"2017-02-19T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/assurance-qualite-dans-la-prise-en-charge-de-lattaque-cerebrale-dans-toute-la-suisse\/"},"modified":"2017-02-19T01:00:00","modified_gmt":"2017-02-19T00:00:00","slug":"assurance-qualite-dans-la-prise-en-charge-de-lattaque-cerebrale-dans-toute-la-suisse","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/assurance-qualite-dans-la-prise-en-charge-de-lattaque-cerebrale-dans-toute-la-suisse\/","title":{"rendered":"Assurance qualit\u00e9 dans la prise en charge de l&#8217;attaque c\u00e9r\u00e9brale dans toute la Suisse"},"content":{"rendered":"<p><strong>L&#8217;Association suisse pour l&#8217;attaque c\u00e9r\u00e9brale (SHG) a f\u00eat\u00e9 son 20e anniversaire en 2016. En tant que soci\u00e9t\u00e9 interdisciplinaire, elle est ouverte \u00e0 tous les groupes professionnels impliqu\u00e9s dans le traitement des accidents vasculaires c\u00e9r\u00e9braux et encourage la coop\u00e9ration clinique et scientifique. Cette ann\u00e9e, l&#8217;assembl\u00e9e annuelle de l&#8217;ASH a eu lieu le 27 janvier \u00e0 B\u00e2le.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La r\u00e9union annuelle a toujours pour objectif de favoriser les \u00e9changes entre les experts des domaines de la neurologie, de la neuroradiologie, de la neurochirurgie, de la chirurgie vasculaire tels que les scientifiques, les infirmiers et les th\u00e9rapeutes. Cette ann\u00e9e encore, un congr\u00e8s scientifiquement instructif et pertinent pour la pratique a eu lieu, avec une formation continue de haut niveau dans un cercle interdisciplinaire et interprofessionnel.<\/p>\n<p>Le vaste \u00e9ventail de sujets d&#8217;actualit\u00e9 comprenait des sessions sur le &#8220;Bleeding intrac\u00e9r\u00e9bral&#8221;, la &#8220;Cytoprotection in acute stroke&#8221; et les &#8220;Imaging modalities in acute stroke&#8221;. Le programme a \u00e9t\u00e9 compl\u00e9t\u00e9 par le Swiss Stroke Trialists&#8217; Meeting et l&#8217;atelier pratique &#8220;Interventional neuroradiology in acute stroke&#8221; \u00e0 l&#8217;H\u00f4pital universitaire de B\u00e2le.  &nbsp;<\/p>\n<h2 id=\"groupes-de-travail-interdisciplinaires\">Groupes de travail interdisciplinaires<\/h2>\n<p>Le Swiss Stroke Trialists&#8217; Meeting a \u00e9t\u00e9 introduit en 2008 afin de discuter de projets scientifiques et de cr\u00e9er des consortiums. D\u00e8s le d\u00e9but, les objectifs de l&#8217;ASH \u00e9taient de transmettre et d&#8217;\u00e9changer des connaissances sur tous les sujets diagnostiques et th\u00e9rapeutiques li\u00e9s aux maladies c\u00e9r\u00e9brovasculaires. Pour ce faire, diff\u00e9rents groupes de travail interdisciplinaires ont \u00e9t\u00e9 mis en place, qui traitent par exemple du &#8220;traitement aigu de l&#8217;attaque c\u00e9r\u00e9brale&#8221;, des &#8220;h\u00e9morragies intracr\u00e2niennes&#8221; ou de la &#8220;prophylaxie secondaire m\u00e9dicamenteuse&#8221; et \u00e9laborent des directives m\u00e9dicales. En 2010, un groupe th\u00e9matique a \u00e9galement \u00e9t\u00e9 cr\u00e9\u00e9 pour promouvoir la rel\u00e8ve, g\u00e9r\u00e9 par les Swiss Young Stroke Physicians.<\/p>\n<p>La qualit\u00e9 des soins en mati\u00e8re d&#8217;AVC a pu \u00eatre consid\u00e9rablement am\u00e9lior\u00e9e en soutenant la cr\u00e9ation de stroke units et de stroke centers et leur certification en collaboration avec la Swiss Federation of Clinical Neurosocieties (SFCNS). Une liste de ces centres est disponible sur le site web de l&#8217;ASH, www.neurovasc.ch. Il est possible de cliquer sur les zones correspondantes sur une carte pour obtenir des informations concr\u00e8tes sur l&#8217;unit\u00e9 de soins intensifs concern\u00e9e. Les informations sont destin\u00e9es aux patients ainsi qu&#8217;aux m\u00e9decins r\u00e9f\u00e9rents.<\/p>\n<p>La 21e r\u00e9union annuelle de la SHG aura lieu le 25. et L&#8217;\u00e9v\u00e9nement aura lieu les 25 et 26 janvier 2018 au CHUV \u00e0 Lausanne.<\/p>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2017 ; 16(1) : 31<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Association suisse pour l&#8217;attaque c\u00e9r\u00e9brale (SHG) a f\u00eat\u00e9 son 20e anniversaire en 2016. En tant que soci\u00e9t\u00e9 interdisciplinaire, elle est ouverte \u00e0 tous les groupes professionnels impliqu\u00e9s dans le traitement&hellip;<\/p>\n","protected":false},"author":7,"featured_media":63987,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Soci\u00e9t\u00e9 suisse d'attaque c\u00e9r\u00e9brale SHG","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11523,11383,11549],"tags":[39423,39428],"powerkit_post_featured":[],"class_list":["post-340201","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-neurologie-fr","category-rx-fr","tag-shg-fr","tag-societe-des-coups-de-cerveau","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:14:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":340215,"slug":"garanzia-di-qualita-nella-cura-dellictus-in-tutta-la-svizzera","post_title":"Garanzia di qualit\u00e0 nella cura dell'ictus in tutta la Svizzera","href":"https:\/\/medizinonline.com\/it\/garanzia-di-qualita-nella-cura-dellictus-in-tutta-la-svizzera\/"},"pt_PT":{"locale":"pt_PT","id":340224,"slug":"garantia-de-qualidade-nos-cuidados-do-avc-em-toda-a-suica","post_title":"Garantia de qualidade nos cuidados do AVC em toda a Su\u00ed\u00e7a","href":"https:\/\/medizinonline.com\/pt-pt\/garantia-de-qualidade-nos-cuidados-do-avc-em-toda-a-suica\/"},"es_ES":{"locale":"es_ES","id":340230,"slug":"garantia-de-calidad-en-la-atencion-al-ictus-en-toda-suiza","post_title":"Garant\u00eda de calidad en la atenci\u00f3n al ictus en toda Suiza","href":"https:\/\/medizinonline.com\/es\/garantia-de-calidad-en-la-atencion-al-ictus-en-toda-suiza\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/340201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=340201"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/340201\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=340201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=340201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=340201"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=340201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}