{"id":341601,"date":"2016-04-28T02:00:00","date_gmt":"2016-04-28T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/diagnostic-et-options-de-traitement-des-lymphomes-non-hodgkiniens-indolents\/"},"modified":"2016-04-28T02:00:00","modified_gmt":"2016-04-28T00:00:00","slug":"diagnostic-et-options-de-traitement-des-lymphomes-non-hodgkiniens-indolents","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/diagnostic-et-options-de-traitement-des-lymphomes-non-hodgkiniens-indolents\/","title":{"rendered":"Diagnostic et options de traitement des lymphomes non hodgkiniens &#8220;indolents&#8221;."},"content":{"rendered":"<p><strong>Le terme de lymphomes indolents englobe un nombre croissant de lymphomes non hodgkiniens de faible malignit\u00e9 et de leuc\u00e9mies, principalement de la lign\u00e9e des cellules B. Les lymphomes indolents sont des tumeurs qui se d\u00e9veloppent \u00e0 partir de cellules souches. Ils sont diff\u00e9renci\u00e9s et class\u00e9s les uns des autres en fonction de leur constellation de marqueurs et de leur profil g\u00e9n\u00e9tique. Le traitement d\u00e9pend de l&#8217;ampleur ou de la dynamique de la maladie et des sympt\u00f4mes du patient. On assiste actuellement \u00e0 un glissement du traitement des chimioth\u00e9rapies classiques vers les inhibiteurs de signal et les immunoth\u00e9rapies. L&#8217;objectif principal du traitement est souvent de contr\u00f4ler la maladie le plus longtemps possible tout en maintenant une tol\u00e9rance acceptable au traitement.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Le terme de lymphome non hodgkinien indolent (LNHi) d\u00e9signe un groupe biologiquement h\u00e9t\u00e9rog\u00e8ne de lymphomes matures et \u00e0 petites cellules de la lign\u00e9e des cellules B ayant tendance \u00e0 avoir des manifestations leuc\u00e9miques. Auparavant, le terme &#8220;indolent&#8221; d\u00e9crivait un groupe de lymphomes &#8220;de faible malignit\u00e9&#8221; \u00e0 croissance lente, dont les sous-types \u00e9taient souvent difficiles \u00e0 s\u00e9parer les uns des autres et qui ne devaient pas toujours \u00eatre diff\u00e9renci\u00e9s en raison du manque de possibilit\u00e9s th\u00e9rapeutiques.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-7125\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0.png\" style=\"height:438px; width:400px\" width=\"883\" height=\"967\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0.png 883w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0-800x876.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0-120x131.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0-90x99.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0-320x350.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_oh2_s11_0-560x613.png 560w\" sizes=\"(max-width: 883px) 100vw, 883px\" \/><\/p>\n<p>Entre-temps, des donn\u00e9es immunoph\u00e9notypiques et mol\u00e9culaires \u00e9largies permettent une meilleure subdivision en entit\u00e9s de lymphome, qui devrait \u00eatre effectu\u00e9e selon la classification actuelle des lymphomes de l&#8217;OMS en 2008 <strong>(tab.&nbsp;1) <\/strong>[1]. Certains LNHI se transforment en lymphomes blastiques ou agressifs hautement malins au cours de la maladie, le lymphome folliculaire en t\u00eate, suivi de la leuc\u00e9mie lympho\u00efde chronique (LLC). En outre, il existe des entit\u00e9s telles que le lymphome \u00e0 cellules du manteau (MCL), dont la majorit\u00e9 (environ 90% de tous les cas) pr\u00e9sentent un comportement de croissance agressif et sont trait\u00e9es par immunochimioth\u00e9rapie intensive (\u00e9ventuellement avec une th\u00e9rapie \u00e0 haute dose et un remplacement de cellules souches autologues). Mais il existe aussi un sous-groupe indolent, qui se manifeste g\u00e9n\u00e9ralement chez les patients \u00e2g\u00e9s pr\u00e9sentant une atteinte de la moelle osseuse et de la rate. Il ne faut pas oublier les LNH typiques qui peuvent survenir dans un contexte clinique particulier, comme le MALT associ\u00e9 \u00e0 Helicobacter pylori ou le lymphome de la zone marginale associ\u00e9 au VHC.<br \/>\n&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-7126 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/469;height:341px; width:800px\" width=\"1100\" height=\"469\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12-800x341.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12-120x51.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12-90x38.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12-320x136.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab2_oh2_s12-560x239.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<h2 id=\"diagnostic-et-sous-types\">Diagnostic et sous-types<\/h2>\n<p>Le diagnostic est \u00e9tabli par une biopsie des ganglions lymphatiques et\/ou de la moelle osseuse, un (immuno)ph\u00e9notypage du sang et\/ou de la moelle osseuse et des analyses g\u00e9n\u00e9tiques et mol\u00e9culaires <strong>(tableau&nbsp;2). <\/strong>Ces tests sont standardis\u00e9s et s&#8217;appliquent \u00e0 toutes les pathologies du lymphome. Selon la classification de l&#8217;OMS, les entit\u00e9s suivantes font partie des iNHL :<\/p>\n<ul>\n<li>Leuc\u00e9mie lympho\u00efde chronique (LLC) ou leuc\u00e9mie \u00e0 tricholeucocytes (LT)&nbsp;  leur forme nodulaire (lymphome lymphocytaire \u00e0 petites cellules, SLL)<\/li>\n<li>Lymphome lymphoplasmocytaire (LPL ou maladie de Waldenstr\u00f6m)<\/li>\n<li>Lymphome de la zone marginale (LZM) <strong>(Fig.&nbsp;1)<\/strong> avec ses trois sous-formes : nodale, extranodale (par ex. comme MALT) et spl\u00e9nique<\/li>\n<li>Lymphome folliculaire (FL) <strong>(Fig.&nbsp;2)<\/strong><\/li>\n<li>La leuc\u00e9mie \u00e0 tricholeucocytes (HZL).<br \/>\n\t&nbsp;<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"size-full wp-image-7127 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1230;height:895px; width:800px\" width=\"1100\" height=\"1230\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13-800x895.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13-120x134.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13-90x101.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13-320x358.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_oh2_s13-560x626.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>\nLa LLC et la leuc\u00e9mie \u00e0 tricholeucocytes ne sont pas consid\u00e9r\u00e9es par tous les groupes de travail comme faisant partie du LNHI car, comme leur nom l&#8217;indique, elles se manifestent souvent en premier lieu par des modifications de la formule sanguine et n\u00e9cessitent parfois (cela concerne en particulier la leuc\u00e9mie \u00e0 tricholeucocytes) d&#8217;autres mesures th\u00e9rapeutiques. Le lymphome \u00e0 cellules du manteau (MCL) ne devrait plus \u00eatre class\u00e9 parmi les iNHL pour les raisons susmentionn\u00e9es, bien qu&#8217;il existe un sous-groupe indolent chez les patients \u00e2g\u00e9s.<br \/>\n&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-7128 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/991;height:721px; width:800px\" width=\"1100\" height=\"991\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13-800x721.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13-120x108.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13-90x81.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13-320x288.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb2_oh2_s13-560x505.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<h2 id=\"presentation-clinique-et-principes-therapeutiques\">\nPr\u00e9sentation clinique et principes th\u00e9rapeutiques<\/h2>\n<p>Les lymphomes indolents sont g\u00e9n\u00e9ralement une maladie de l&#8217;\u00e2ge avanc\u00e9. La grande majorit\u00e9 des patients (66%) se trouvent d\u00e9j\u00e0 dans les stades avanc\u00e9s III et IV (classification des stades selon Ann Arbor ou plus r\u00e9cemment Lugano) au moment du diagnostic et ne sont donc plus accessibles \u00e0 un traitement curatif [2]. L&#8217;\u00e9tablissement d&#8217;un diagnostic n&#8217;implique pas toujours la n\u00e9cessit\u00e9 de mettre en place imm\u00e9diatement un traitement. M\u00eame si les recommandations varient quelque peu selon les sous-types, il est toujours vrai que seules les maladies symptomatiques doivent \u00eatre trait\u00e9es. La d\u00e9finition d&#8217;une maladie symptomatique est rest\u00e9e largement inchang\u00e9e au cours des 30 derni\u00e8res ann\u00e9es et inclut les sympt\u00f4mes locaux dus \u00e0 la croissance du lymphome, \u00e0 l&#8217;alt\u00e9ration de la fonction normale des organes (par exemple, l&#8217;an\u00e9mie symptomatique), les sympt\u00f4mes B, la maladie extranodale symptomatique, d&#8217;autres cytop\u00e9nies ou une vitesse de croissance rapide d&#8217;une manifestation lymphatique. Ces crit\u00e8res sont tr\u00e8s \u00e9lastiques et offrent au patient et au m\u00e9decin une grande marge de d\u00e9cision. C&#8217;est pourquoi des efforts sont actuellement d\u00e9ploy\u00e9s pour \u00e9tablir une meilleure classification pronostique et donc une aide \u00e0 la d\u00e9cision au moyen de nouveaux marqueurs (mol\u00e9culaires). L&#8217;indice pronostique de la LLC (CLL-IPI), r\u00e9cemment pr\u00e9sent\u00e9, en est un exemple : il donne une recommandation quant au moment de commencer le traitement et au type de traitement [3].<\/p>\n<h2 id=\"la-radiotherapie-dans-les-stades-precoces-une-option-curative\">La radioth\u00e9rapie dans les stades pr\u00e9coces : une option curative ?<\/h2>\n<p>Au cours des derni\u00e8res d\u00e9cennies, la radioth\u00e9rapie a \u00e9t\u00e9 d\u00e9finie comme une option de traitement curatif des premiers stades de la maladie du lymphome folliculaire. 15-25% des patients diagnostiqu\u00e9s avec un lymphome folliculaire sont au stade I ou II et les directives nationales et internationales en vigueur recommandent toujours la radioth\u00e9rapie pour ces patients [4].<\/p>\n<p>La difficult\u00e9 d&#8217;une recommandation positive pour la mise en \u0153uvre de la radioth\u00e9rapie dans la pratique clinique quotidienne actuelle repose sur l&#8217;incertitude de savoir si les donn\u00e9es des anciennes \u00e9tudes (grandes surfaces d&#8217;irradiation, doses totales \u00e9lev\u00e9es, applications non sp\u00e9cifiques aux ganglions lymphatiques ou au champ d&#8217;involution) peuvent \u00eatre appliqu\u00e9es aux techniques d&#8217;irradiation actuelles. Il existe donc un grand dilemme : nous ne pouvons actuellement pas d\u00e9finir la valeur curative pr\u00e9sum\u00e9e de la radioth\u00e9rapie dans les lymphomes indolents (principalement le lymphome folliculaire) au stade pr\u00e9coce.<\/p>\n<h2 id=\"attendre-apres-le-diagnostic-est-ce-encore-valable\">Attendre apr\u00e8s le diagnostic : est-ce encore valable ?<\/h2>\n<p>Certains auteurs estiment qu&#8217;actuellement, environ 50% des patients n&#8217;ont toujours pas besoin d&#8217;un traitement imm\u00e9diat au moment du diagnostic. Le terme &#8220;watch &amp; wait&#8221; (w&amp;w) a \u00e9t\u00e9 invent\u00e9 il y a plus de 35 ans [5]. L&#8217;attente semblait justifi\u00e9e lorsque la maladie progressait lentement et que les sympt\u00f4mes \u00e9taient faibles ou inexistants &#8211; et aussi parce qu&#8217;il n&#8217;existait pas de traitement efficace. Ainsi, \u00e0 l&#8217;\u00e9poque, chez les patients FL, le d\u00e9lai m\u00e9dian avant le premier traitement \u00e9tait de 31 \u00e0 36 mois. Des analyses d&#8217;observation longitudinales ont montr\u00e9 qu&#8217;environ 20% des patients FL n&#8217;avaient pas besoin de traitement avec un suivi m\u00e9dian de 17 ans. Compar\u00e9 \u00e0 une cohorte de patients trait\u00e9s par chimioth\u00e9rapie au moment du diagnostic, aucune diff\u00e9rence n&#8217;a \u00e9t\u00e9 observ\u00e9e en termes de survie globale (SG) \u00e0 5 ans. L&#8217;OS moyen \u00e9tait de 11 ans et variait consid\u00e9rablement d&#8217;une histologie \u00e0 l&#8217;autre.<\/p>\n<p>La question de savoir si le w&amp;w est appropri\u00e9 concerne toutes les LNI, mais elle est principalement analys\u00e9e dans le cas du FL. Ainsi, dans une \u00e9tude multicentrique, 379 patients ont \u00e9t\u00e9 randomis\u00e9s dans trois bras de traitement : observation seule (w&amp;w), induction par rituximab seul (applications toutes les quatre semaines) ou induction par rituximab suivie d&#8217;un traitement d&#8217;entretien de deux ans (rituximab tous les deux mois) [6]. L&#8217;\u00e9tude a montr\u00e9 un avantage significatif en termes de survie sans progression (PFS) pour les deux bras de rituximab par rapport \u00e0 w&amp;w. L&#8217;\u00e9tude a \u00e9galement montr\u00e9 que le rituximab n&#8217;avait pas d&#8217;effets secondaires. La survie globale n&#8217;\u00e9tait toutefois pas diff\u00e9rente, de sorte qu&#8217;il n&#8217;y a toujours pas de raison imp\u00e9rieuse d&#8217;utiliser l&#8217;immunoth\u00e9rapie \u00e0 un stade pr\u00e9coce. Cela peut changer avec les nouveaux m\u00e9dicaments (immunoth\u00e9rapeutiques) et devrait donc toujours \u00eatre remis en question.<\/p>\n<h2 id=\"therapies-actuelles\">Th\u00e9rapies actuelles<\/h2>\n<p>Les possibilit\u00e9s de traitement du LNHi ont radicalement chang\u00e9 ces derni\u00e8res ann\u00e9es avec l&#8217;\u00e9tablissement de nouvelles th\u00e9rapies. Ils sont principalement bas\u00e9s sur les anticorps et l&#8217;inhibition de la tyrosine kinase <strong>(Fig.&nbsp;3). <\/strong>Jusqu&#8217;\u00e0 pr\u00e9sent, l&#8217;immunoth\u00e9rapie avec des anticorps sp\u00e9cifiques du CD20 en monoth\u00e9rapie ou en combinaison avec des agents chimioth\u00e9rapeutiques classiques domine le traitement de premi\u00e8re ligne. Il faut toujours partir du principe qu&#8217;une gu\u00e9rison n&#8217;est pas possible malgr\u00e9 les m\u00e9thodes th\u00e9rapeutiques modernes ; la seule exception est la transplantation allog\u00e9nique de cellules souches.<\/p>\n<h2 id=\"anticorps-monoclonaux-specifiques-du-cd20\">Anticorps monoclonaux sp\u00e9cifiques du CD20<\/h2>\n<p>L&#8217;exemple classique d&#8217;un anticorps sp\u00e9cifique du CD20 est le rituximab, qui fait d\u00e9sormais partie int\u00e9grante du traitement du lymphome \u00e0 cellules B et peut \u00eatre utilis\u00e9 dans diff\u00e9rentes entit\u00e9s, soit en monoth\u00e9rapie (par exemple FL), soit en association avec une chimioth\u00e9rapie (par exemple CLL). Les nouveaux anticorps anti-CD20 (par exemple l&#8217;obinutuzumab) ont une toxicit\u00e9 cellulaire directe (activit\u00e9 ADCC) parfois encore plus \u00e9lev\u00e9e et peuvent ainsi \u00e9liminer plus efficacement les cellules du lymphome [7]. Dans le traitement de la LLC, par exemple, cela se traduit par une augmentation du nombre de patients pr\u00e9sentant une maladie r\u00e9siduelle minimale (MRD) n\u00e9gative. Cela signifie que chez les patients trait\u00e9s par obinutuzumab + chimioth\u00e9rapie, la maladie &#8211; par rapport au traitement classique par rituximab + chimioth\u00e9rapie &#8211; est plus souvent ind\u00e9tectable (38 contre 3% dans le sang p\u00e9riph\u00e9rique), malgr\u00e9 des m\u00e9thodes de d\u00e9tection sensibles. On ne sait pas encore si l&#8217;augmentation du taux de n\u00e9gativit\u00e9 de la MRD se traduira par une survie prolong\u00e9e.<\/p>\n<h2 id=\"combinaison-danticorps-et-de-chimiotherapie\">Combinaison d&#8217;anticorps et de chimioth\u00e9rapie<\/h2>\n<p>Les anticorps sp\u00e9cifiques CD20 sont g\u00e9n\u00e9ralement utilis\u00e9s en combinaison avec le chlorambucil, la bendamustine ou le CHOP. Le chlorambucil est souvent utilis\u00e9 en combinaison avec l&#8217;obinutuzumab dans le traitement des patients \u00e2g\u00e9s atteints de LLC ou le rituximab dans le traitement du lymphome MALT [8]. En revanche, la bendamustine, associ\u00e9e au rituximab, est consid\u00e9r\u00e9e comme le standard de premi\u00e8re ligne dans le lymphome folliculaire (grades 1 et 2) [9] et dans la LLC (avec des r\u00e9serves sur la fludarabine-endoxan). Le rituximab avec CHOP est utilis\u00e9 un peu moins souvent qu&#8217;auparavant et est principalement utilis\u00e9 dans les variantes de lymphomes blasto\u00efdes ou de grade FL 3&nbsp;. En g\u00e9n\u00e9ral, le nombre de cycles de chimioth\u00e9rapie est souvent limit\u00e9 \u00e0 six (toutes les trois \u00e0 quatre semaines) et l&#8217;immunoth\u00e9rapie est administr\u00e9e pendant la m\u00eame dur\u00e9e ou encore en monoth\u00e9rapie pendant deux ans, dans le cadre d&#8217;un traitement d&#8217;entretien.<\/p>\n<h2 id=\"immunomodulateurs\">Immunomodulateurs<\/h2>\n<p>Les immunomodulateurs (IMID) sont de petites mol\u00e9cules (&#8220;small molecules&#8221;) qui sont g\u00e9n\u00e9ralement prises par voie orale. Les IMID comme le l\u00e9nalidomide ont \u00e9t\u00e9 utilis\u00e9s pour la premi\u00e8re fois avec succ\u00e8s dans le my\u00e9lome multiple et sont d\u00e9sormais test\u00e9s dans le lymphome avec des taux de r\u00e9ponse encourageants. L&#8217;association de l\u00e9nalidomide et de rituximab chez les patients atteints de FL de grade 3 et de maladie r\u00e9currente ou r\u00e9fractaire a permis d&#8217;obtenir un taux de r\u00e9ponse global (ORR) allant jusqu&#8217;\u00e0 86%. Lorsque la combinaison est utilis\u00e9e directement dans le traitement de premi\u00e8re ligne, des taux d&#8217;ORR allant jusqu&#8217;\u00e0 98% peuvent \u00eatre atteints avec des taux \u00e9lev\u00e9s de r\u00e9mission compl\u00e8te (RC) (87% de RC et de RC non confirm\u00e9es) et de n\u00e9gativit\u00e9 de la MRD. R\u00e9cemment, l&#8217;autorisation de mise sur le march\u00e9 a \u00e9galement \u00e9t\u00e9 obtenue pour le traitement du lymphome \u00e0 cellules du manteau (MCL). L&#8217;autorisation de mise sur le march\u00e9 est bas\u00e9e sur des \u00e9tudes portant sur la maladie MCL r\u00e9currente ou r\u00e9fractaire sur la base d&#8217;un ROR de 42-53% [10,11].<\/p>\n<h2 id=\"inhibition-de-la-voie-de-signalisation-du-recepteur-des-cellules-b-bcr\">Inhibition de la voie de signalisation du r\u00e9cepteur des cellules B (BCR)<\/h2>\n<p>Des taux de r\u00e9ponse encore plus \u00e9lev\u00e9s dans le traitement du MCL peuvent \u00eatre obtenus avec des substances qui inhibent la voie de signalisation en aval du BCR, par exemple les inhibiteurs de la tyrosine kinase de Bruton (BTK) ou de la kinase PI3 (PI3K) [12]. Ces deux kinases sont souvent actives de mani\u00e8re constitutive dans les cellules de lymphome et favorisent la prolif\u00e9ration ou la survie cellulaire.<\/p>\n<h2 id=\"inhibiteurs-de-btk\">Inhibiteurs de BTK<\/h2>\n<p>L&#8217;ibrutinib est le premier inhibiteur de BTK autoris\u00e9 qui se lie de mani\u00e8re irr\u00e9versible et covalente \u00e0 un r\u00e9sidu cyst\u00e9ine (Cys-481) de la tyrosine kinase, provoquant ainsi une inhibition puissante et durable de l&#8217;activit\u00e9 enzymatique. Dans la LLC, l&#8217;ibrutinib a montr\u00e9 une activit\u00e9 \u00e9lev\u00e9e. L&#8217;autorisation de mise sur le march\u00e9 repose sur une \u00e9tude comparative avec l&#8217;ofatumumab, un anticorps monoclonal sp\u00e9cifique du CD20 (\u00e9tude RESONATE), men\u00e9e chez 391 patients atteints de LLC\/SLL pr\u00e9trait\u00e9s [13]. Avec un suivi m\u00e9dian de 9,4 mois, l&#8217;ibrutinib (420&nbsp;mg\/d\/po) a significativement am\u00e9lior\u00e9 la PFS et l&#8217;OS. Apr\u00e8s 12 mois, l&#8217;OS \u00e9tait de 90% dans le groupe ibrutinib et de 81% dans le groupe ofatumumab. Le taux de r\u00e9ponse global \u00e9tait significativement plus \u00e9lev\u00e9 pour l&#8217;ibrutinib (42,6 vs. 4,1%, p &lt;0,001). Le taux et la dur\u00e9e de la r\u00e9ponse \u00e9taient ind\u00e9pendants de la pr\u00e9sence d&#8217;une <em>del17p<\/em> ou d&#8217;une r\u00e9sistance aux analogues des purines. Cela prouve la grande importance des inhibiteurs de BTK dans ce sous-groupe de patients atteints de LLC difficile \u00e0 traiter. Les \u00e9v\u00e9nements ind\u00e9sirables les plus fr\u00e9quents ont \u00e9t\u00e9 la diarrh\u00e9e, la fatigue, la fi\u00e8vre et les naus\u00e9es.<\/p>\n<p>La deuxi\u00e8me entit\u00e9 autoris\u00e9e en Suisse concerne le traitement du MCL r\u00e9cidivant. L&#8217;autorisation de mise sur le march\u00e9 a \u00e9t\u00e9 accord\u00e9e sur la base d&#8217;une \u00e9tude multicentrique de phase II \u00e0 un seul bras portant sur 111 patients atteints de MCL pr\u00e9trait\u00e9s et recevant une dose de 560&nbsp;mg d&#8217;ibrutinib une fois par jour. La publication compl\u00e8te fait \u00e9tat d&#8217;un ORR de 66% avec un taux de RC de 17% pour une dur\u00e9e m\u00e9diane de r\u00e9ponse (DOR) de 17,5 mois [4]. Il est int\u00e9ressant de noter que le taux de r\u00e9ponse a augment\u00e9 de mani\u00e8re continue au cours du traitement (ce que l&#8217;on appelle &#8220;incremental response under treatment&#8221;), de sorte que &#8211; contrairement aux chimioth\u00e9rapies classiques &#8211; des r\u00e9missions tardives peuvent \u00e9galement survenir si le traitement est poursuivi.<\/p>\n<h2 id=\"inhibiteurs-de-pi3k\">Inhibiteurs de PI3K<\/h2>\n<p>La famille PI3K est compos\u00e9e d&#8217;un certain nombre de s\u00e9rine\/thr\u00e9onine kinases qui r\u00e9gulent la croissance, la diff\u00e9renciation, le m\u00e9tabolisme, la survie et la prolif\u00e9ration dans diff\u00e9rentes cellules. Par exemple, l&#8217;inhibition de l&#8217;unit\u00e9 p110\u03b4 entra\u00eene une d\u00e9pl\u00e9tion significative des cellules B et un blocage de la voie de signalisation en aval du BCR. C&#8217;est pourquoi la plupart des approches th\u00e9rapeutiques dans le traitement du lymphome se focalisent sur un blocage direct de l&#8217;unit\u00e9 p110\u03b4. Le prototype de cette classe de substances est l&#8217;id\u00e9lalisib en tant qu&#8217;inhibiteur s\u00e9lectif de p110\u03b4.<\/p>\n<p>L&#8217;idelalisib a d&#8217;abord \u00e9t\u00e9 test\u00e9 dans une \u00e9tude randomis\u00e9e de phase III chez 220 patients atteints de LLC en r\u00e9cidive en association avec le rituximab [15]. Dans le bras de contr\u00f4le, les patients ont re\u00e7u du rituximab plus un placebo. Avec un pr\u00e9traitement m\u00e9dian de trois substances, le rituximab et un alkylant ou un analogue de nucl\u00e9otide pur avaient \u00e9t\u00e9 utilis\u00e9s au pr\u00e9alable dans presque tous les cas. Pr\u00e8s de 40% des patients atteints de LLC pr\u00e9sentaient \u00e9galement l&#8217;alt\u00e9ration g\u00e9n\u00e9tique d\u00e9favorable du g\u00e8ne p53.<\/p>\n<p>En termes d&#8217;efficacit\u00e9, on a observ\u00e9 un taux de r\u00e9ponse significativement plus \u00e9lev\u00e9 dans le bras rituximab + idelalisib (81 vs 13%), une prolongation significative de la SSP \u00e0 1 an (93 vs 46%, p&lt;0,001) et une prolongation significative de l&#8217;OS \u00e0 1 an (92 vs 80%, p=0,02). La sup\u00e9riorit\u00e9 de l&#8217;association rituximab + idelalisib a \u00e9t\u00e9 d\u00e9montr\u00e9e pour tous les sous-groupes.<\/p>\n<p>Les effets secondaires significatifs dans la pratique clinique quotidienne et d\u00e9passant le cadre de l&#8217;application du rituximab sont la diarrh\u00e9e pr\u00e9coce ou, dans certains cas, tardive. Mais si l&#8217;on compare son profil d&#8217;effets secondaires \u00e0 celui d&#8217;autres substances susceptibles d&#8217;\u00eatre utilis\u00e9es dans cette situation, comme l&#8217;ofatumumab, l&#8217;alemtuzumab ou les cytostatiques traditionnels, l&#8217;id\u00e9lalisib obtient certainement un r\u00e9sultat positif.<\/p>\n<p>En monoth\u00e9rapie, l&#8217;id\u00e9lalisib s&#8217;av\u00e8re tr\u00e8s efficace dans le traitement des LNHi en rechute. La mol\u00e9cule est approuv\u00e9e pour le traitement des patients FL avec une maladie r\u00e9currente ayant re\u00e7u deux lignes de traitement pr\u00e9c\u00e9dentes [16]. Dans l&#8217;\u00e9tude de phase II \u00e0 un bras sous-jacente portant sur 125 patients atteints de LNHi r\u00e9sistants au rituximab et aux alkylants, l&#8217;id\u00e9lalisib a \u00e9t\u00e9 administr\u00e9 \u00e0 raison de 150&nbsp;mg deux fois par jour jusqu&#8217;\u00e0 la progression de la maladie. Le d\u00e9lai m\u00e9dian de r\u00e9ponse \u00e9tait de 1,9 mois, la dur\u00e9e m\u00e9diane de r\u00e9ponse de 12,5 mois et la PFS m\u00e9diane de 11 mois. Les effets secondaires de grade 3 ou plus les plus fr\u00e9quents \u00e9taient la neutrop\u00e9nie (27% des patients), l&#8217;augmentation des aminotransf\u00e9rases (13%), la diarrh\u00e9e (13%) et la pneumonie (7%).<\/p>\n<h2 id=\"inhibiteurs-de-bcl-2\">Inhibiteurs de BCL-2<\/h2>\n<p>La prot\u00e9ine anti-apoptotique BCL-2 est surexprim\u00e9e dans les cellules de lymphome et contribue \u00e0 la r\u00e9sistance \u00e0 la chimioth\u00e9rapie. Les inhibiteurs s\u00e9lectifs de BCL-2 administr\u00e9s par voie orale, comme le v\u00e9n\u00e9toclax, stoppent la prolif\u00e9ration des cellules lymphomateuses et entra\u00eenent ainsi des r\u00e9missions tumorales dans des mod\u00e8les pr\u00e9cliniques. Dans une premi\u00e8re \u00e9tude clinique portant sur 106 patients atteints de MCL (n=28), de lymphome folliculaire (n=29), de lymphome diffus \u00e0 grandes cellules B (n=41) et d&#8217;autres sous-types de LNH (n=8), le v\u00e9n\u00e9toclax en monoth\u00e9rapie a montr\u00e9 un profil de s\u00e9curit\u00e9 acceptable \u00e0 la dose maximale tol\u00e9r\u00e9e de 1200&nbsp;mg\/j [17]. L&#8217;ORR \u00e9tait de 44% pour tous les sous-types, de 78% pour le MCL et de 38% pour le FL. La PFS m\u00e9diane \u00e9tait de 10 \u00e0 14 mois. Les effets ind\u00e9sirables li\u00e9s au traitement les plus fr\u00e9quents (EI \u226520%) ont \u00e9t\u00e9 les naus\u00e9es (48%), la diarrh\u00e9e (44%), la fatigue (41%), la diminution de l&#8217;app\u00e9tit (21%) et les vomissements (21%). La survenue d&#8217;un syndrome de lyse tumorale est importante, mais elle est survenue chez deux patients sans cons\u00e9quences cliniques.<br \/>\n&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-7129 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/782;height:569px; width:800px\" width=\"1100\" height=\"782\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14-800x569.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14-120x85.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14-90x64.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14-320x227.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_oh2_s14-560x398.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<h2 id=\"futures-therapies\">\nFutures th\u00e9rapies<\/h2>\n<p>Les th\u00e9rapies futures proviendront principalement de deux domaines<strong> (Fig.&nbsp;3) : <\/strong>Les inhibiteurs de la voie de signalisation, qui ciblent des mol\u00e9cules de commutation importantes de la cellule lymphomateuse et bloquent leur fonction (par exemple, les inhibiteurs CDK 4\/6), et les nouveaux m\u00e9dicaments d&#8217;immunoth\u00e9rapie. La d\u00e9couverte que le syst\u00e8me immunitaire contribue au contr\u00f4le des tumeurs r\u00e9volutionne actuellement les options de traitement h\u00e9mato-oncologique. Les inhibiteurs de blocage des points de contr\u00f4le, les anticorps bisp\u00e9cifiques et les cellules T reprogramm\u00e9es (CAR T cells) sont en cours de d\u00e9veloppement clinique, avec des r\u00e9sultats parfois impressionnants. Peut-\u00eatre parviendrons-nous un jour \u00e0 stimuler le syst\u00e8me immunitaire de telle sorte qu&#8217;il sera possible de contr\u00f4ler la tumeur \u00e0 long terme, voire de la gu\u00e9rir.<\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Swerdlow SH, et al. : IARC Press, Lyon, 2008.<\/li>\n<li>Brice P, et al : J Clin Oncol 1997 ; 15(3) : 1110-1117.<\/li>\n<li>Molica S, et al. : Abstract 498, pr\u00e9sent\u00e9 \u00e0 la <sup>57e<\/sup> r\u00e9union annuelle de l&#8217;Amercan Society of Hematology (ASH), 2015.<\/li>\n<li>Hiddemann W, et al. : Internist (Berl) 2016 ; 57(3) : 222-229.<\/li>\n<li>Morrison VA, Peterson BA : Leuk Lymphoma 1993 ; 10 Sup : 29-33.<\/li>\n<li>Adreshna KM, et al : Lancet Oncol 2014 ; 15(4) : 424-435.<\/li>\n<li>Goede V, et al. : NEJM 2014 ; 370(12) : 1101-1110.<\/li>\n<li>Zucca E, et al : J Clin Oncol 2013 ; 31(5) : 565-572.<\/li>\n<li>Rummel MJ, et al : Lancet 2013 ; 381(9873) : 1203-1210.<\/li>\n<li>Habermann TM, et al : Br J Haematol 2009 ; 145(3) : 344-349.<\/li>\n<li>Witzig TE, et al : Ann Oncol 2011 ; 22(7) : 1622-1627.<\/li>\n<li>Mato A, et al : Am J Hematol 2015 ; 90(7) : 657-664.<\/li>\n<li>Byrd JC, et al. : NEJM 2014 ; 371(3) : 213-223.<\/li>\n<li>Wang ML, et al. : NEJM 2013 ; 369(6) : 507-516.<\/li>\n<li>Furman RR, et al : NEJM 2014 ; 370(11) : 997-1007.<\/li>\n<li>Gopal AK, et al. : NEJM 2014 ; 370(11) : 1008-1018.<\/li>\n<li>Roberts AW, et al. : NEJM 2016 ; 374(4) : 311-322.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONKOLOGIE &amp; H\u00c4MATOLOGIE 2016 ; 4(2) : 11-15<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le terme de lymphomes indolents englobe un nombre croissant de lymphomes non hodgkiniens de faible malignit\u00e9 et de leuc\u00e9mies, principalement de la lign\u00e9e des cellules B. Les lymphomes indolents sont&hellip;<\/p>\n","protected":false},"author":7,"featured_media":56399,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"\"Watch and wait\", radioth\u00e9rapie ou th\u00e9rapie syst\u00e9mique ?","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11531,11373,11389,11549],"tags":[39216,20832,42533],"powerkit_post_featured":[],"class_list":["post-341601","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formation-continue","category-hematologie","category-oncologie","category-rx-fr","tag-cellules-b","tag-leucemie","tag-lymphome-non-hodgkinien","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:52:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":341612,"slug":"diagnosi-e-opzioni-di-trattamento-per-il-linfoma-non-hodgkin-indolente","post_title":"Diagnosi e opzioni di trattamento per il linfoma non-Hodgkin \"indolente\".","href":"https:\/\/medizinonline.com\/it\/diagnosi-e-opzioni-di-trattamento-per-il-linfoma-non-hodgkin-indolente\/"},"pt_PT":{"locale":"pt_PT","id":341618,"slug":"diagnostico-e-opcoes-de-tratamento-para-linfoma-indolente-nao-hodgkin","post_title":"Diagn\u00f3stico e op\u00e7\u00f5es de tratamento para linfoma \"indolente\" n\u00e3o-Hodgkin","href":"https:\/\/medizinonline.com\/pt-pt\/diagnostico-e-opcoes-de-tratamento-para-linfoma-indolente-nao-hodgkin\/"},"es_ES":{"locale":"es_ES","id":341623,"slug":"diagnostico-y-opciones-de-tratamiento-del-linfoma-no-hodgkin-indolente","post_title":"Diagn\u00f3stico y opciones de tratamiento del linfoma no Hodgkin \"indolente","href":"https:\/\/medizinonline.com\/es\/diagnostico-y-opciones-de-tratamiento-del-linfoma-no-hodgkin-indolente\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/341601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=341601"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/341601\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=341601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=341601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=341601"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=341601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}