{"id":341701,"date":"2016-04-04T02:00:00","date_gmt":"2016-04-04T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/prevention-des-chutes-chez-les-personnes-agees-10-questions-10-reponses\/"},"modified":"2016-04-04T02:00:00","modified_gmt":"2016-04-04T00:00:00","slug":"prevention-des-chutes-chez-les-personnes-agees-10-questions-10-reponses","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/prevention-des-chutes-chez-les-personnes-agees-10-questions-10-reponses\/","title":{"rendered":"Pr\u00e9vention des chutes chez les personnes \u00e2g\u00e9es &#8211; 10 questions, 10 r\u00e9ponses"},"content":{"rendered":"<p><strong>L&#8217;anamn\u00e8se des chutes chez les patients g\u00e9riatriques est g\u00e9n\u00e9ralement floue et peu pertinente. Dans la recherche des causes possibles d&#8217;une chute, l&#8217;\u00e9valuation structur\u00e9e de la d\u00e9marche est bien plus importante que les investigations techniques. Les d\u00e9ficits musculaires des mollets et des hanches sont des causes fr\u00e9quentes de troubles de la marche chez les patients g\u00e9riatriques. L&#8217;entra\u00eenement de l&#8217;\u00e9quilibre pour pr\u00e9venir les chutes est particuli\u00e8rement efficace si des t\u00e2ches cognitives suppl\u00e9mentaires sont propos\u00e9es. D&#8217;autres aspects importants de la pr\u00e9vention des chutes sont de bonnes chaussures, l&#8217;\u00e9limination des obstacles qui font tr\u00e9bucher, l&#8217;am\u00e9lioration de la vision et une alimentation riche en prot\u00e9ines. La valeur cible pour le taux de vitamine D dans le sang est de 75 nmol\/l.<\/strong><\/p>\n<div style=\"display: block;\">\n<div style=\"display: none;\">\n<div>\n<div>\n<table cellspacing=\"1\">\n<tbody>\n<tr>\n<td><strong>Reconna\u00eetre une langueAfrikaansAlbanaisArabeArm\u00e9nienAzerba\u00efdjanaisBasqueBengaliBosniaqueBulgareBirmanCebuanoChichewaChinois (ver)Chinois (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/strong><\/td>\n<td>\n<div id=\"SL_switch_b\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/switchb.png\") repeat scroll 0% 0%;\" title=\"Changer de langue\">&nbsp;<\/div>\n<\/td>\n<td>\n<div style=\"display: block;\">\n<div style=\"display: none;\">\n<div>\n<div>\n<table cellspacing=\"1\">\n<tbody>\n<tr>\n<td><strong><strong>AfrikaansAlbanaisArabeArm\u00e9nienAzerba\u00efdjanaisBasqueBengaliBosniaqueBulgareBirmanCebuanoChichewaChinois (ver)Chinois (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/strong><\/strong><\/td>\n<td>\n<div id=\"SL_TTS_voice\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/ttsvoice.png\") repeat scroll 0% 0%;\" title=\"\u00c9couter\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_copy\" id=\"SL_copy\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/copy.png\") repeat scroll 0% 0%;\" title=\"Copier\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_font_patch\">&nbsp;<\/div>\n<div class=\"SL_bbl_font\" id=\"SL_bbl_font\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/font.png\") repeat scroll 0% 0%;\" title=\"Taille de la police\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_help\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bhelp.png\") repeat scroll 0% 0%;\" title=\"Aide\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_pin_off\" id=\"SL_pin\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/pin-on.png\") repeat scroll 0% 0%;\" title=\"Clouer le traducteur pop-up\">&nbsp;<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<div id=\"SL_shadow_translation_result\" style=\"visibility: visible;\">&nbsp;<\/div>\n<div class=\"SL_loading\" id=\"SL_loading\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/loading.gif\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_player2\">&nbsp;<\/div>\n<div id=\"SL_alert100\"><strong><strong><strong>La fonction son est limit\u00e9e \u00e0 200 caract\u00e8res<\/strong><\/strong><\/strong><\/div>\n<div id=\"SL_Balloon_options\" style=\"background: rgb(255, 255, 255) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bg3.png\") repeat scroll 0% 0%;\">\n<div id=\"SL_arrow_down\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/down.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<table id=\"SL_tbl_opt\" style=\"width:100%\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td>\n<div id=\"SL_BBL_IMG\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bbl-logo.png\") repeat scroll 0% 0%;\" title=\"Bouton Afficher dans le traducteur 3 secondes\">&nbsp;<\/div>\n<\/td>\n<td><strong><strong><strong><a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?bbl\" target=\"_blank\" title=\"Afficher les options\" rel=\"noopener\">Options<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?hist\" target=\"_blank\" title=\"Historique de la traduction\" rel=\"noopener\">Histoire<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?feed\" target=\"_blank\" title=\"R\u00e9troaction\" rel=\"noopener\">R\u00e9troaction<\/a>: <a class=\"SL_options\" href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&amp;hosted_button_id=GD9D8CPW8HFA2\" target=\"_blank\" title=\"Contribuer\" rel=\"noopener\">Donate<\/a><\/strong><\/strong><\/strong><\/td>\n<td><strong><strong><strong>Fermer<\/strong><\/strong><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p> <!--more--> <\/p>\n<p><strong>Les mesures de pr\u00e9vention des chutes sont-elles utiles pour toutes les personnes \u00e2g\u00e9es ?<\/strong><\/p>\n<p>Oui, absolument. On sait depuis des ann\u00e9es qu&#8217;un entra\u00eenement r\u00e9gulier de l&#8217;\u00e9quilibre, comme le tai-chi [1], et la substitution de vitamine D ont un effet positif sur la fr\u00e9quence des chutes chez les seniors en bonne sant\u00e9 [2]. Toutefois, le clinicien ou le m\u00e9decin g\u00e9n\u00e9raliste se concentre g\u00e9n\u00e9ralement sur les patients qui pr\u00e9sentent d\u00e9j\u00e0 un risque accru de chute en raison d&#8217;un trouble de la marche ou qui ont d\u00e9j\u00e0 \u00e9t\u00e9 victimes de chutes.<\/p>\n<p><strong>Dans quelle mesure est-il utile, pour ces patients, de savoir pourquoi ils sont tomb\u00e9s en dernier ?<\/strong><\/p>\n<p>En principe, c&#8217;est tr\u00e8s important. Toutefois, l&#8217;exp\u00e9rience clinique montre que nous devons ici nous fier principalement \u00e0 l&#8217;anamn\u00e8se personnelle &#8211; et celle-ci n&#8217;est malheureusement que rarement pertinente pour une attribution \u00e9tiologique claire de la chute. En effet, l&#8217;\u00e9v\u00e9nement de la chute et son interpr\u00e9tation sonnent g\u00e9n\u00e9ralement un peu diff\u00e9remment lorsque le patient le d\u00e9crit \u00e0 plusieurs reprises. Ce ph\u00e9nom\u00e8ne s&#8217;accentue encore en cas de d\u00e9ficience cognitive. En outre, il faut s&#8217;attendre \u00e0 un effet suggestif \u00e9lev\u00e9, en particulier pour les questions relatives \u00e0 une \u00e9ventuelle br\u00e8ve perte de conscience.<br \/>\n<strong>&nbsp;<br \/>\nEst-ce que cela entra\u00eene trop d&#8217;investigations dans le sens d&#8217;une syncope ?<\/strong><\/p>\n<p>Absolument. La syncope comme cause de chute ne repr\u00e9sente qu&#8217;un faible pourcentage de la population \u00e2g\u00e9e. Selon une compilation de diff\u00e9rentes \u00e9tudes, il ne serait m\u00eame que de 0,3% ! Sur cette petite proportion, ce sont en outre les variantes orthostatiques et neurog\u00e8nes qui p\u00e8sent lourd, tandis que les syncopes cardiog\u00e9niques repr\u00e9sentent une proportion encore plus faible [3]. Conclusion : aujourd&#8217;hui encore, trop d&#8217;argent est d\u00e9pens\u00e9 dans des examens techniques dont les r\u00e9sultats ne sont pas tr\u00e8s utiles [4]. Le recensement syst\u00e9matique des facteurs de risque de chute, suivi de leur modification, est bien plus efficace que des examens techniques excessifs et un regard r\u00e9trospectif flou (anamn\u00e8se personnelle). L&#8217;\u00e9valuation structur\u00e9e d&#8217;un trouble de la marche et de l&#8217;\u00e9quilibre, qui r\u00e9sulte g\u00e9n\u00e9ralement de la superposition de diverses pathologies, est ici centrale.<\/p>\n<p><strong>Qu&#8217;est-ce qu&#8217;une \u00e9valuation structur\u00e9e des troubles de la marche et de l&#8217;\u00e9quilibre ?<\/strong><\/p>\n<p>Cela ne doit pas \u00eatre une perte de temps. Il suffit de regarder le patient se lever et marcher quelques m\u00e8tres. Il est important d&#8217;avoir en t\u00eate les crit\u00e8res d&#8217;observation pertinents <strong>(tableau&nbsp;1) <\/strong>et de savoir \u00e0 quoi devrait ressembler la marche normale <strong>(fig.&nbsp;1) <\/strong>[5]. Une fois que l&#8217;on a une id\u00e9e de cela, on identifie assez rapidement les anomalies et l&#8217;on peut proc\u00e9der \u00e0 d&#8217;autres tests cibl\u00e9s afin d&#8217;acc\u00e9der aux causes du trouble de la marche.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9887\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0.png\" style=\"height:451px; width:600px\" width=\"1100\" height=\"827\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0-800x600.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0-320x240.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0-300x225.png 300w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0-120x90.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0-90x68.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/tab1_hp3-16_0-560x420.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9888 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/517;height:282px; width:600px\" width=\"1100\" height=\"517\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quelles sont les causes fr\u00e9quentes des troubles de la marche chez les personnes \u00e2g\u00e9es (geriatric gait disorder) ?<\/strong><\/p>\n<p>Il s&#8217;agit souvent de d\u00e9ficits musculaires. Avec l&#8217;\u00e2ge, la force des muscles du mollet diminue souvent plus que la moyenne, alors qu&#8217;ils jouent justement un r\u00f4le \u00e9norme dans la g\u00e9n\u00e9ration des pas. Dans la d\u00e9marche, cela se traduit par une flexion excessive du genou dans les phases d&#8217;unijambiste, mais aussi par une longueur de pas trop faible et un rythme de marche lent. Si l&#8217;on soup\u00e7onne les muscles du mollet, on peut rapidement et facilement tester leur force en se tenant sur une jambe avec les orteils &#8211; le genou doit rester tendu <strong>(fig.&nbsp;2).<\/strong> Pour une d\u00e9marche normale chez les personnes \u00e2g\u00e9es, cet exercice doit, selon notre exp\u00e9rience, \u00eatre r\u00e9ussi au moins cinq fois (la norme pour un \u00e2ge moyen \u00e9tant d&#8217;au moins vingt fois) [5,8].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9889 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16.jpg\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/1417;height:630px; width:400px\" width=\"900\" height=\"1417\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16.jpg 900w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16-800x1260.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16-120x189.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16-90x142.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16-320x504.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb1_hp3-16-560x882.jpg 560w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>De m\u00eame, les abducteurs de la hanche sont souvent trop faibles, ce qui n&#8217;est pas rare apr\u00e8s l&#8217;implantation d&#8217;une proth\u00e8se totale de hanche. Cela se traduit par une d\u00e9marche tr\u00e8s typique, appel\u00e9e&nbsp; &#8220;signe de Trendelenburg&#8221;, un abaissement controlat\u00e9ral du bassin <strong>(fig.&nbsp;3, <\/strong>\u00e0 gauche). On observe souvent une inclinaison lat\u00e9rale compensatoire du haut du corps vers le c\u00f4t\u00e9 faible, appel\u00e9e &#8220;hochement de Duch\u00e8nne&#8221; <strong>(Fig.&nbsp;3,<\/strong> \u00e0 droite).<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9890 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0.png\" style=\"--smush-placeholder-width: 901px; --smush-placeholder-aspect-ratio: 901\/1352;height:600px; width:400px\" width=\"901\" height=\"1352\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0.png 901w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0-800x1200.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0-120x180.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0-90x135.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0-320x480.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb3_hp3_16_0-560x840.png 560w\" data-sizes=\"(max-width: 901px) 100vw, 901px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quels sont les programmes d&#8217;entra\u00eenement appropri\u00e9s pour la pr\u00e9vention des chutes ?<\/strong><\/p>\n<p>Si des d\u00e9ficits de force ont \u00e9t\u00e9 identifi\u00e9s, ils doivent certainement \u00eatre corrig\u00e9s par un entra\u00eenement cibl\u00e9. En mati\u00e8re de pr\u00e9vention des chutes, l&#8217;entra\u00eenement de l&#8217;\u00e9quilibre est le plus important. Les activit\u00e9s qui exigent une grande concentration et un contr\u00f4le physique se sont r\u00e9v\u00e9l\u00e9es particuli\u00e8rement efficaces. Dans ce cas, outre le Tai Chi et le Jacque Dalcroze Rhythmic, un entra\u00eenement cognitivo-moteur sp\u00e9cifique est int\u00e9ressant, par exemple sur un Step Plate <strong>(fig.&nbsp;4).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9891 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/04\/abb4_hp3-16.jpg\" style=\"--smush-placeholder-width: 901px; --smush-placeholder-aspect-ratio: 901\/1433;height:636px; width:400px\" width=\"901\" height=\"1433\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quelle est l&#8217;importance d&#8217;\u00e9liminer les pi\u00e8ges des chutes \u00e0 la maison ?<\/strong><\/p>\n<p>C&#8217;est tr\u00e8s important, car la plupart des chutes se produisent dans l&#8217;environnement domestique. Un bon programme de pr\u00e9vention des chutes comprend toujours une \u00e9valuation du logement [6]. Dans ce cas, il suffit souvent d&#8217;un entretien cibl\u00e9. Les tapis glissants ou un \u00e9clairage insuffisant sont des pi\u00e8ges classiques contre les chutes, par exemple. Ces deux \u00e9l\u00e9ments sont relativement faciles \u00e0 corriger. Dans ce contexte, il ne faut pas sous-estimer l&#8217;importance des chaussures.<\/p>\n<p><strong>Que sont les &#8220;bonnes&#8221; et les &#8220;mauvaises&#8221; chaussures ?<\/strong><\/p>\n<p>Tout d&#8217;abord, une chaussure doit \u00eatre bien adapt\u00e9e, c&#8217;est-\u00e0-dire ni trop grande ni trop petite, et doit \u00e9galement envelopper la zone du talon. Une pantoufle ouverte typique n&#8217;est pas adapt\u00e9e au pied g\u00e9riatrique. Si des troubles de la sensibilit\u00e9 sont d\u00e9j\u00e0 pr\u00e9sents, il est pr\u00e9f\u00e9rable d&#8217;opter pour une semelle plus ferme plut\u00f4t que pour une suspension trop importante, afin de mieux sentir le sol. Un petit talon aide souvent \u00e0 avancer et est plus appropri\u00e9 que des chaussures trop plates, par exemple en cas de faiblesse du mollet existante. Pour l&#8217;ext\u00e9rieur, une chaussure \u00e0 la cheville avec un bon profil donne le meilleur soutien.<\/p>\n<p><strong>Quel est le r\u00f4le de la vitamine D ?<\/strong><\/p>\n<p>Chez nos patients pr\u00e9sentant un risque accru de chute, nous visons une suppl\u00e9mentation quotidienne en vitamine D de (800-)1000&nbsp;UI par jour. Toutefois, une administration hebdomadaire de 7000&nbsp;UI est \u00e9galement possible, \u00e0 condition que l&#8217;administration soit ainsi simplifi\u00e9e et plus s\u00fbre. Ce n&#8217;est qu&#8217;en cas de suspicion d&#8217;une constellation \u00e0 haut risque (p. ex. fracture, d\u00e9mence) que nous d\u00e9terminons parfois le taux sanguin afin de pouvoir proc\u00e9der \u00e0 un dosage forc\u00e9 en cas de carence grave (p. ex. une fois par semaine 45 000&nbsp;UI pendant quatre \u00e0 six semaines). La valeur cible du taux sanguin est de 75&nbsp;nmol\/l (30&nbsp;ng\/ml) [7].<\/p>\n<p><strong>Quels sont les autres points de d\u00e9part pour la modification des risques ?<\/strong><\/p>\n<p>Ces points de d\u00e9part importants sont syst\u00e9matiquement enregistr\u00e9s lors de l&#8217;\u00e9valuation g\u00e9riatrique. Une diminution g\u00e9n\u00e9rale de la masse musculaire (sarcop\u00e9nie) est particuli\u00e8rement fr\u00e9quente. Il faut y rem\u00e9dier non seulement par l&#8217;entra\u00eenement, mais aussi par une meilleure alimentation riche en prot\u00e9ines. Les probl\u00e8mes sensoriels sont \u00e9galement tr\u00e8s pertinents, l&#8217;am\u00e9lioration de la vision \u00e9tant un objectif r\u00e9aliste. L&#8217;\u00e9valuation critique de la liste des m\u00e9dicaments, g\u00e9n\u00e9ralement longue, en vue de d\u00e9tecter les substances favorisant les chutes fait \u00e9galement toujours partie du processus.<\/p>\n<p>On sous-estime d&#8217;ailleurs l&#8217;influence des modifications c\u00e9r\u00e9brales d\u00e9g\u00e9n\u00e9ratives et microvasculaires diffuses sur le contr\u00f4le moteur central, sans qu&#8217;il y ait n\u00e9cessairement un tableau clinique neurologique typique. Ainsi, d\u00e8s les premiers stades de la maladie d&#8217;Alzheimer, on observe de discr\u00e8tes modifications de la d\u00e9marche (surtout lors de l&#8217;ex\u00e9cution d&#8217;une t\u00e2che cognitive suppl\u00e9mentaire !) et une augmentation des chutes. Cet exemple souligne qu&#8217;une \u00e9valuation cognitive fait toujours partie d&#8217;une \u00e9valuation de la marche bien fond\u00e9e, afin de pouvoir conseiller et traiter de mani\u00e8re optimale en cas de d\u00e9mence d\u00e9butante.<\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Wolf SL, et al. : Reducing frailty and falls in older persons : an investigation of Tai Chi and computerized balance training. Groupe FICSIT d&#8217;Atlanta. Frailty and Injuries : Cooperative Studies of Intervention Techniques. J Am Geriatr Soc 1996 ; 44(5) : 489-497.<\/li>\n<li>Moyer VA, et al : Prevention of falls in community-dwelling older adults : U.S. Preventive Services Task Force recommendation statement. Ann Intern Med 2012 ; 157(3) : 197-204.<\/li>\n<li>Rubenstein LZ, et al : The epidemiology of falls and syncope. Clin Geriatr Med 2002 ; 18 : 141-158.<\/li>\n<li>Mendu ML, et al : Yield of diagnostic tests in evaluating syncopal episodes in older patients. Arch Intern Med 2009 ; 169(14) : 1299-1305.<\/li>\n<li>G\u00f6tz-Neumann K : Comprendre la marche. Analyse de la marche en physioth\u00e9rapie. \u00c9ditions Georg Thieme, 2006.<\/li>\n<li>www.bfu.ch\/de\/fuer-fachpersonen\/sturzpr\u00e4vention.<\/li>\n<li>Lamy O, et al : Ost\u00e9omalacie et vitamine D. Swiss Medical Forum 2015 ; 15(48) : 1118-1121.<\/li>\n<li>Lunsford BR, Perry J : The Standing Heel-Rise Test for Ankle Plantar Flexion : Criterion for Normal. Physical Therapy 1995 ; 8 : 694-698.<\/li>\n<\/ol>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2016 ; 11(3) : 26-31<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;anamn\u00e8se des chutes chez les patients g\u00e9riatriques est g\u00e9n\u00e9ralement floue et peu pertinente. Dans la recherche des causes possibles d&#8217;une chute, l&#8217;\u00e9valuation structur\u00e9e de la d\u00e9marche est bien plus importante&hellip;<\/p>\n","protected":false},"author":7,"featured_media":75641,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Entra\u00eenement \u00e0 l'\u00e9quilibre, vitamine D et \u00e9valuation structur\u00e9e de la marche","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11531,11368,11505,11549],"tags":[42818,42821,34524,29327,34529,13141],"powerkit_post_featured":[],"class_list":["post-341701","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formation-continue","category-geriatrie-fr","category-rhumatologie","category-rx-fr","tag-chutes","tag-pieges-a-chutes","tag-prevention-des-chutes","tag-syncope","tag-trouble-de-la-demarche","tag-vitamine-d","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 22:09:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":341710,"slug":"prevenzione-delle-cadute-negli-anziani-10-domande-10-risposte","post_title":"Prevenzione delle cadute negli anziani - 10 domande, 10 risposte","href":"https:\/\/medizinonline.com\/it\/prevenzione-delle-cadute-negli-anziani-10-domande-10-risposte\/"},"pt_PT":{"locale":"pt_PT","id":341720,"slug":"prevencao-de-quedas-em-idosos-10-perguntas-10-respostas","post_title":"Preven\u00e7\u00e3o de quedas em idosos - 10 perguntas, 10 respostas","href":"https:\/\/medizinonline.com\/pt-pt\/prevencao-de-quedas-em-idosos-10-perguntas-10-respostas\/"},"es_ES":{"locale":"es_ES","id":341725,"slug":"prevencion-de-caidas-en-los-ancianos-10-preguntas-10-respuestas","post_title":"Prevenci\u00f3n de ca\u00eddas en los ancianos - 10 preguntas, 10 respuestas","href":"https:\/\/medizinonline.com\/es\/prevencion-de-caidas-en-los-ancianos-10-preguntas-10-respuestas\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/341701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=341701"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/341701\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=341701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=341701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=341701"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=341701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}