{"id":345739,"date":"2014-03-20T00:00:00","date_gmt":"2014-03-19T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/le-prochain-defi-vous-attend-deja\/"},"modified":"2014-03-20T00:00:00","modified_gmt":"2014-03-19T23:00:00","slug":"le-prochain-defi-vous-attend-deja","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/le-prochain-defi-vous-attend-deja\/","title":{"rendered":"Le prochain d\u00e9fi vous attend d\u00e9j\u00e0"},"content":{"rendered":"<p><strong>Pour la 16e fois, le traditionnel symposium sur l&#8217;\u00e9tat de l&#8217;art de la Soci\u00e9t\u00e9 suisse de la scl\u00e9rose en plaques s&#8217;est tenu \u00e0 Lucerne en janvier 2014. Cette fois, le th\u00e8me de la scl\u00e9rose en plaques progressive \u00e9tait au centre des expos\u00e9s des sp\u00e9cialistes nationaux et internationaux de la SEP. Il s&#8217;est av\u00e9r\u00e9 que de nombreuses questions restaient en suspens concernant cette forme de maladie. Il manque notamment un bon mod\u00e8le animal qui permettrait d&#8217;\u00e9clairer davantage la situation.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Patricia Monin, directrice de la Soci\u00e9t\u00e9 suisse de la scl\u00e9rose en plaques, a soulign\u00e9 dans ses paroles de bienvenue la grande importance de la scl\u00e9rose en plaques (SEP) progressive : &#8220;Beaucoup des questions qui nous parviennent chaque jour sont li\u00e9es \u00e0 cette forme de maladie. Les personnes atteintes sont d\u00e9sesp\u00e9r\u00e9es et nous demandent s&#8217;il existe un quelconque espoir pour elles et s&#8217;il y aura une option de traitement pour elles \u00e0 l&#8217;avenir&#8221;. Elle a donc encourag\u00e9 les chercheurs pr\u00e9sents \u00e0 concentrer leurs travaux sur ce domaine dans les ann\u00e9es \u00e0 venir. La Soci\u00e9t\u00e9 suisse de la scl\u00e9rose en plaques soutient plusieurs projets \u00e0 l&#8217;\u00e9chelle nationale qui traitent \u00e9galement de la scl\u00e9rose en plaques progressive.<\/p>\n<h2 id=\"pas-de-bon-modele-animal\">Pas de bon mod\u00e8le animal<\/h2>\n<p>La premi\u00e8re intervenante du symposium, le professeur Christine Stadelmann-Nessler, pathologiste \u00e0 G\u00f6ttingen, a expliqu\u00e9 pourquoi les recherches sur la SEP progressive sont si difficiles : &#8220;Nous savons que la phase progressive de la SEP est pathologiquement caract\u00e9ris\u00e9e par la pr\u00e9dominance de l\u00e9sions inactives ou chroniquement actives, par une d\u00e9my\u00e9linisation corticale \u00e9tendue, par une perte progressive d&#8217;axones et par un dysfonctionnement neuronal. R\u00e9cemment, il a \u00e9galement \u00e9t\u00e9 fait \u00e9tat d&#8217;une infiltration lymphocytaire m\u00e9ning\u00e9e importante associ\u00e9e \u00e0 cette phase de la maladie&#8221;. Malgr\u00e9 tout, les connaissances sur la pathogen\u00e8se de la SEP progressive restent limit\u00e9es. &#8220;Malheureusement, il n&#8217;existe pas de mod\u00e8le animal appropri\u00e9 qui serait vraiment bien adapt\u00e9 \u00e0 l&#8217;\u00e9tude de la d\u00e9my\u00e9linisation chronique, qu&#8217;il s&#8217;agisse de la substance blanche ou grise&#8221;, a-t-elle fait remarquer. Les efforts se sont r\u00e9cemment concentr\u00e9s sur le mod\u00e8le de d\u00e9my\u00e9linisation toxique [1]. &#8220;En utilisant ce mod\u00e8le, nous voulons \u00e9tudier l&#8217;effet d&#8217;une d\u00e9my\u00e9linisation prolong\u00e9e ou r\u00e9currente sur la fonction axonale&#8221;, a expliqu\u00e9 le professeur Stadelmann-Nessler. Des mod\u00e8les g\u00e9n\u00e9tiques &#8211; des souris ayant subi une d\u00e9l\u00e9tion cibl\u00e9e de g\u00e8nes de my\u00e9line pertinents &#8211; pourraient \u00e9galement fournir des informations importantes \u00e0 l&#8217;avenir.<\/p>\n<h2 id=\"de-nouveaux-progres-dans-les-techniques-dimagerie\">De nouveaux progr\u00e8s dans les techniques d&#8217;imagerie<\/h2>\n<p>L&#8217;IRM est une technique bien \u00e9tablie pour le diagnostic et le suivi de la SEP en raison de sa tr\u00e8s grande sensibilit\u00e9 aux changements li\u00e9s \u00e0 cette maladie. &#8220;Cependant, les param\u00e8tres IRM ne permettent pas d&#8217;expliquer de mani\u00e8re satisfaisante le statut clinique et la progression du handicap des patients atteints de SEP \u00e9tablie&#8221;, a d\u00e9clar\u00e9 l&#8217;intervenante suivante, le Dr Maria A. Rocca, Milan. Cela a conduit \u00e0 une utilisation accrue des technologies bas\u00e9es sur la r\u00e9sonance magn\u00e9tique afin de mieux \u00e9valuer la charge de morbidit\u00e9 des patients \u00e0 diff\u00e9rents stades de la maladie. &#8220;L&#8217;utilisation de ces techniques a permis de graduer les l\u00e9sions pathologiques h\u00e9t\u00e9rog\u00e8nes de la SEP in vivo, et ce non seulement pour les l\u00e9sions focales, mais aussi pour la substance blanche et grise d&#8217;apparence normale&#8221;, a expliqu\u00e9 le Dr Rocca. Depuis peu, d&#8217;autres aspects de la pathologie de la SEP sont \u00e9galement devenus quantifiables, notamment l&#8217;infiltration des macrophages et les d\u00e9p\u00f4ts de fer pathologiques. &#8220;En outre, les donn\u00e9es d&#8217;IRM fonctionnelle ont fourni des informations importantes sur la r\u00e9organisation corticale et son r\u00f4le potentiellement important dans la limitation des cons\u00e9quences cliniques des l\u00e9sions structurelles&#8221;, a poursuivi l&#8217;oratrice. La disponibilit\u00e9 croissante de scanners \u00e0 champ magn\u00e9tique ultra-\u00e9lev\u00e9 (7 teslas ou plus, au lieu de 1,5 teslas) permet d&#8217;obtenir des informations importantes sur la pathogen\u00e8se de la SEP. Les avantages de cette technique incluent une meilleure visualisation des l\u00e9sions de la substance blanche et de leurs caract\u00e9ristiques morphologiques, une am\u00e9lioration de la capacit\u00e9 \u00e0 visualiser et \u00e0 localiser les l\u00e9sions de la substance grise et la quantification de certains m\u00e9tabolites qui pourraient jouer un r\u00f4le dans la d\u00e9g\u00e9n\u00e9rescence axonale [2]. &#8220;Tous ces progr\u00e8s nous aident \u00e0 am\u00e9liorer constamment notre compr\u00e9hension de la scl\u00e9rose en plaques, y compris les facteurs associ\u00e9s \u00e0 la progression&#8221;, a conclu le Dr Rocca.<\/p>\n<h2 id=\"la-tomographie-par-coherence-optique-pour-detecter-objectivement-la-progression\">La tomographie par coh\u00e9rence optique pour d\u00e9tecter objectivement la progression ?<\/h2>\n<p>L&#8217;\u0153il est une &#8220;fen\u00eatre&#8221; unique et directe sur le cerveau, la r\u00e9tine \u00e9tant le seul moyen de voir directement les neurones et les axones. La technique de la tomographie par coh\u00e9rence optique (OCT) permet d&#8217;\u00e9valuer les diff\u00e9rentes couches de la r\u00e9tine. Axel Petzold, Amsterdam, a d\u00e9clar\u00e9 : &#8220;Nous utilisons cette technique pour mesurer l&#8217;\u00e9paisseur des diff\u00e9rentes couches de la r\u00e9tine. Il y a donc trois possibilit\u00e9s : Soit une couche est normale, soit elle est trop \u00e9paisse, soit elle est trop fine&#8221;. La pr\u00e9cision de la m\u00e9thode s&#8217;est av\u00e9r\u00e9e exceptionnellement \u00e9lev\u00e9e [3]. &#8220;L&#8217;OCT repr\u00e9sente la technique la plus pr\u00e9cise que j&#8217;ai rencontr\u00e9e au cours de ma carri\u00e8re scientifique&#8221;, a soulign\u00e9 l&#8217;orateur.<\/p>\n<p>L&#8217;utilisation de l&#8217;OCT a notamment permis de constater l&#8217;augmentation du volume de la macula sous traitement par fingolimod [4]. Gelfand et al. ont trouv\u00e9 un \u0153d\u00e8me maculaire microkystique (MMO) par OCT chez 15 des 318 (4,7%) patients atteints de SEP, alors qu&#8217;aucune modification n&#8217;a \u00e9t\u00e9 d\u00e9tect\u00e9e chez 52 t\u00e9moins sains [5]. Le MMO concernait principalement la couche granulaire interne (INL, &#8220;inner nuclear layer&#8221;) de la r\u00e9tine. Les patients atteints de SEP avec MMO \u00e9taient plus handicap\u00e9s (EDSS m\u00e9dian de 4) que les patients sans MMO (EDSS m\u00e9dian de 2) (p=0,0002). De plus, les patients atteints de MMO pr\u00e9sentaient un score MSSS (&#8220;Multiple Sclerosis Severity Score&#8221;) plus \u00e9lev\u00e9, une mesure de la progression de la maladie. Enfin, les modifications de la r\u00e9tine \u00e9taient plus fr\u00e9quentes dans les yeux pr\u00e9sentant une n\u00e9vrite optique ant\u00e9rieure (50 vs. 27%). &#8220;Mais ce sont les r\u00e9sultats des travaux de Saidha et al. qui me semblent les plus importants&#8221;, a poursuivi le Dr Petzold. &#8220;Ce groupe a pu montrer par OCT qu&#8217;il existe un lien entre l&#8217;augmentation de l&#8217;\u00e9paisseur des LIN et l&#8217;activit\u00e9 de la maladie&#8221; [6]. Si ces r\u00e9sultats sont confirm\u00e9s, l&#8217;\u00e9paisseur des LIN pourrait \u00eatre utilis\u00e9e comme un pr\u00e9dicteur utile de la progression de la maladie. Il faut toutefois se rappeler que l&#8217;\u0153d\u00e8me maculaire microkystique n&#8217;est pas sp\u00e9cifique \u00e0 la SEP et qu&#8217;il peut survenir dans le cadre d&#8217;un certain nombre d&#8217;autres maladies.<\/p>\n<p>Ces derni\u00e8res ann\u00e9es, plusieurs travaux ont \u00e9galement cherch\u00e9 \u00e0 savoir si les modifications r\u00e9tiniennes d\u00e9tect\u00e9es par OCT diff\u00e9raient selon les sous-types de SEP. Les r\u00e9sultats de ces enqu\u00eates ont \u00e9t\u00e9 en grande partie n\u00e9gatifs. Seuls deux travaux r\u00e9cents ont montr\u00e9 que les modifications r\u00e9tiniennes \u00e9taient plus marqu\u00e9es dans les formes progressives de SEP ou dans les stades plus avanc\u00e9s de la maladie [7, 8]. De plus, il a \u00e9t\u00e9 possible d&#8217;\u00e9tablir un lien entre une n\u00e9vrite optique ant\u00e9rieure et la s\u00e9v\u00e9rit\u00e9 des alt\u00e9rations. Gelfand et al. ont constat\u00e9 que la perte d&#8217;axones r\u00e9tiniens commence t\u00f4t dans l&#8217;\u00e9volution de la SEP [8]. Un travail qui vient d&#8217;\u00eatre publi\u00e9 en ligne conclut que les couches les plus internes de la r\u00e9tine (couche de fibres nerveuses et couche de cellules ganglionnaires) sont mieux pr\u00e9serv\u00e9es dans le cas d&#8217;une SEP primaire progressive et b\u00e9nigne par rapport \u00e0 une SEP-RR [9]. Les auteurs interpr\u00e8tent cette observation comme une sensibilit\u00e9 potentiellement limit\u00e9e de la r\u00e9tine \u00e0 la neurod\u00e9g\u00e9n\u00e9rescence et soulignent que cela pourrait \u00eatre important pour les futures \u00e9tudes sur la neurod\u00e9g\u00e9n\u00e9rescence chez les patients atteints de SEP primaire progressive.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3434\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736.png\" width=\"1100\" height=\"525\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736-800x382.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736-120x57.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736-90x43.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736-320x153.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abbildung_Info2_s34.png-89e4d7_1736-560x267.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<h2 id=\"unir-ses-forces-pour-la-recherche\">Unir ses forces pour la recherche<\/h2>\n<p>Soulignant \u00e9galement l&#8217;importance de la forme progressive de la maladie, le professeur Alan Thompson, Londres, a d\u00e9clar\u00e9 dans l&#8217;introduction de son expos\u00e9 : &#8220;Dans le domaine de la scl\u00e9rose en plaques, peu de d\u00e9fis ont un impact aussi \u00e9norme sur les patients que la progression&#8221;. Il est d&#8217;autant plus surprenant que, jusqu&#8217;\u00e0 r\u00e9cemment, cette forme de SEP suscitait plut\u00f4t peu d&#8217;int\u00e9r\u00eat scientifique et clinique. &#8220;Bien qu&#8217;il y ait eu quelques d\u00e9veloppements importants dans notre compr\u00e9hension de la pathologie de la progression, de nombreuses questions fondamentales restent sans r\u00e9ponse&#8221;. C&#8217;est pourquoi il est important de se tourner \u00e0 l&#8217;avenir moins vers l&#8217;immunosuppression, par exemple, et davantage vers le domaine de la neuroprotection et des m\u00e9canismes de r\u00e9paration. &#8220;Mais cela signifie \u00e9galement que nous avons besoin de nouveaux mod\u00e8les d&#8217;\u00e9tudes innovants pour atteindre notre objectif en moins de temps et avec un nombre de patients plus faible&#8221;, a fait remarquer le professeur Thompson. Dans ce contexte, le &#8220;Multiple Sclerosis Outcome Assessments Consortium&#8221; (MSOAC) a r\u00e9cemment \u00e9t\u00e9 cr\u00e9\u00e9 [10]. L&#8217;objectif de cette organisation est de faire progresser la recherche sur les nouvelles th\u00e9rapies en d\u00e9veloppant de nouveaux moyens d&#8217;enregistrer les effets des traitements dans les essais cliniques. Enfin, le professeur Thompson a \u00e9galement \u00e9voqu\u00e9 la cr\u00e9ation de la Task Force internationale &#8220;Progressive MS Alliance&#8221; (www.endprogressivems.org). Cette alliance de plusieurs organisations, dont la F\u00e9d\u00e9ration internationale de la scl\u00e9rose en plaques et plusieurs associations nationales de la SEP, s&#8217;efforce de mettre en r\u00e9seau les ressources et les experts du monde entier afin de d\u00e9velopper de nouvelles solutions pour lutter contre la SEP progressive. L&#8217;identification de mod\u00e8les exp\u00e9rimentaux et de m\u00e9canismes pathologiques est \u00e9galement l&#8217;une des principales priorit\u00e9s.<\/p>\n<p><em>Source : <sup>16th<\/sup> State of the Art Symposium, Soci\u00e9t\u00e9 suisse de la scl\u00e9rose en plaques, 11 janvier 2014, Lucerne&nbsp;<\/em><\/p>\n<h3 id=\"litterature\">Litt\u00e9rature :<\/h3>\n<ol>\n<li>Skripuletz T, et al : La d\u00e9my\u00e9linisation corticale est pro\u00e9minente dans le mod\u00e8le de cuprizone murin et est d\u00e9pendante du stress. Am J Pathol 2008 ; 172 : 1053-1061.<\/li>\n<li>Filippi M, et al : Ultra-high-\ufb01eld MR imaging in multiple sclerosis. J Neurol Neurosurg Psychiatry 2014 ; 85 : 60-66.<\/li>\n<li>Balk LJ, Petzold A : Influence de la fonction de suivi bas\u00e9e sur le suivi oculaire sur l&#8217;\u00e9paisseur de la couche de fibres du nerf r\u00e9tinien en utilisant la tomographie par coh\u00e9rence optique \u00e0 quatre domaines. Invest Ophthalmol Vis Sci 2013 ; 54 : 3045.<\/li>\n<li>Nolan R, et al : Le traitement par le fingolimod dans la scl\u00e9rose en plaques entra\u00eene une augmentation du volume maculaire. Neurology 2013 ; 80 : 139-144.<\/li>\n<li>Gelfand JM, et al : L&#8217;\u0153d\u00e8me maculaire microkystique dans la scl\u00e9rose en plaques est associ\u00e9 \u00e0 la s\u00e9v\u00e9rit\u00e9 de la maladie. Brain 2012 ; 135 : 1786-1793.<\/li>\n<li>Saidha S, et al : Microcystic macular oedema, thickness of the inner nuclear layer of the retina, and disease characteristics in multiple sclerosis : a retrospective study. Lancet Neurol 2012 ; 11 : 963-972.<\/li>\n<li>Oberwahrenbrock T, et al : Dommages r\u00e9tiniens dans les sous-types de scl\u00e9rose en plaques mesur\u00e9s par tomographie par coh\u00e9rence optique \u00e0 haute r\u00e9solution. Mult Scler Int 2012 ; 2012 : 530305.<\/li>\n<li>Gelfand JM, et al : La perte axonale r\u00e9tinienne commence t\u00f4t dans l&#8217;\u00e9volution de la scl\u00e9rose en plaques et est similaire entre les ph\u00e9notypes progressifs. PLoS One 2012 ; 7 : e36847.<\/li>\n<li>Balk L, et al : H\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 de l&#8217;\u00e9volution de la maladie et OCT dans la scl\u00e9rose en plaques. Mult Scler 2014 Jan 8. [Epub ahead of print].<\/li>\n<li>Rudick RA, et al : Multiple Sclerosis Outcome Assessments Consortium : Genesis and initial project plan. Mult Scler 2014 ; 20 : 12-17.<\/li>\n<\/ol>\n<p><em>InFo Neurologie &amp; Psychiatrie 2014, 12(2) : 32-35<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la 16e fois, le traditionnel symposium sur l&#8217;\u00e9tat de l&#8217;art de la Soci\u00e9t\u00e9 suisse de la scl\u00e9rose en plaques s&#8217;est tenu \u00e0 Lucerne en janvier 2014. Cette fois, le&hellip;<\/p>\n","protected":false},"author":4,"featured_media":42190,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Scl\u00e9rose en plaques progressive","footnotes":""},"category":[11383,11535,11549],"tags":[15599,12371],"powerkit_post_featured":[],"class_list":["post-345739","post","type-post","status-publish","format-standard","has-post-thumbnail","category-neurologie-fr","category-rapports-de-congres","category-rx-fr","tag-ms-fr","tag-sclerose-en-plaques","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:35:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":345743,"slug":"la-prossima-sfida-sta-gia-aspettando","post_title":"La prossima sfida sta gi\u00e0 aspettando","href":"https:\/\/medizinonline.com\/it\/la-prossima-sfida-sta-gia-aspettando\/"},"pt_PT":{"locale":"pt_PT","id":345746,"slug":"o-proximo-desafio-ja-esta-a-espera","post_title":"O pr\u00f3ximo desafio j\u00e1 est\u00e1 \u00e0 espera","href":"https:\/\/medizinonline.com\/pt-pt\/o-proximo-desafio-ja-esta-a-espera\/"},"es_ES":{"locale":"es_ES","id":345754,"slug":"el-proximo-reto-ya-esta-esperando","post_title":"El pr\u00f3ximo reto ya est\u00e1 esperando","href":"https:\/\/medizinonline.com\/es\/el-proximo-reto-ya-esta-esperando\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/345739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=345739"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/345739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/42190"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=345739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=345739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=345739"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=345739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}