{"id":345789,"date":"2014-03-06T00:00:00","date_gmt":"2014-03-05T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/ce-que-le-medecin-generaliste-doit-savoir-2\/"},"modified":"2014-03-06T00:00:00","modified_gmt":"2014-03-05T23:00:00","slug":"ce-que-le-medecin-generaliste-doit-savoir-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/ce-que-le-medecin-generaliste-doit-savoir-2\/","title":{"rendered":"Ce que le m\u00e9decin g\u00e9n\u00e9raliste doit savoir"},"content":{"rendered":"<p><strong>Lors du Great Update de la SSMI \u00e0 Interlaken, les probl\u00e8mes et les d\u00e9fis les plus fr\u00e9quents auxquels un m\u00e9decin g\u00e9n\u00e9raliste est confront\u00e9 lorsqu&#8217;il s&#8217;occupe de personnes atteintes d&#8217;un lymphome ont \u00e9t\u00e9 discut\u00e9s. Comment nommer les plus de 70 entit\u00e9s de lymphomes malins pour que cela reste compr\u00e9hensible pour le patient et sa famille ? Le diagnostic et le suivi sont \u00e9galement du ressort du m\u00e9decin de premier recours.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Le professeur Andreas Lohri de l&#8217;h\u00f4pital cantonal de B\u00e2le-Campagne a ouvert son expos\u00e9 par des donn\u00e9es \u00e9pid\u00e9miologiques : &#8220;Les registres suisses du cancer recensent environ 1600 lymphomes malins par an, dont un bon tiers des cas sont mortels. Ainsi, les lymphomes pris ensemble font certes partie des types de cancer les plus r\u00e9pandus, mais si l&#8217;on se r\u00e9f\u00e8re \u00e0 la classification de l&#8217;OMS, ce groupe se divise en plus de 70 entit\u00e9s diff\u00e9rentes&#8221;.<\/p>\n<p>Plus de 70% des personnes atteintes de lymphomes hodgkiniens sont indemnes de la maladie au bout de dix ans, alors que ce chiffre est de 40% pour les lymphomes \u00e0 cellules B, qui sont les lymphomes les plus fr\u00e9quents, et de seulement 20% pour les variantes \u00e0 cellules T. Les r\u00e9sultats de l&#8217;\u00e9tude montrent que les personnes atteintes de lymphomes hodgkiniens sont plus susceptibles de d\u00e9velopper la maladie que les autres. Entre 2001 et 2010, il y a eu au total 16 000 nouveaux cas de lymphome, dont environ 6000 patients ont surv\u00e9cu \u00e0 la maladie.<\/p>\n<p>&#8220;Si l&#8217;on veut nommer l&#8217;entit\u00e9 sp\u00e9cifique, cela devient difficile. Alors que la situation est encore relativement claire pour les lymphomes hodgkiniens, le m\u00e9decin g\u00e9n\u00e9raliste ne sait g\u00e9n\u00e9ralement pas quel nom donner aux lymphomes diffus \u00e0 grandes cellules B (DLBCL), par exemple, afin que le patient et sa famille puissent comprendre la maladie. La plupart du temps, il a recours au terme obsol\u00e8te de &#8220;lymphome non hodgkinien&#8221;. L&#8217;organisation suisse de patients pour les personnes atteintes de lymphomes et leurs proches fournit donc aux malades des informations sp\u00e9cifiques sur les douze lymphomes les plus fr\u00e9quents, y compris l&#8217;indication de leur nom&#8221;, explique le professeur Lohri.<\/p>\n<h2 id=\"reconnaitriez-vous-un-lymphome\">Reconna\u00eetriez-vous un lymphome ?<\/h2>\n<p>Les sympt\u00f4mes peuvent ne pas \u00eatre clairs ou aller dans la mauvaise direction. Une enqu\u00eate mondiale portant sur 1606 patients atteints de diff\u00e9rentes maladies lymphomateuses a montr\u00e9 qu&#8217;environ 50% d&#8217;entre eux ont consult\u00e9 leur m\u00e9decin pour la premi\u00e8re fois parce qu&#8217;ils avaient de toute fa\u00e7on un rendez-vous pour un check-up ou parce qu&#8217;ils ne se sentaient g\u00e9n\u00e9ralement pas bien. &#8220;Les premiers sympt\u00f4mes sont donc tout \u00e0 fait non sp\u00e9cifiques et l&#8217;enqu\u00eate a \u00e9galement montr\u00e9 que pour 30% des patients, il a fallu plus de cinq mois depuis la premi\u00e8re visite chez le m\u00e9decin avant que le diagnostic correct ne soit pos\u00e9&#8221;, a expliqu\u00e9 le professeur Lohri. &#8220;Environ la moiti\u00e9 des lymphomes sont extranodaux et pr\u00e9sentent une grande vari\u00e9t\u00e9 de sympt\u00f4mes : neurologiques comme les lymphomes du SNC, cutan\u00e9s comme les lymphomes \u00e0 cellules T, ou r\u00e9naux et cardiaques comme les lymphomes producteurs d&#8217;amylo\u00efde. Les sympt\u00f4mes B typiques se manifestent assez tard, mais avant cela, certains patients se plaignent d\u00e9j\u00e0 de fatigue et de d\u00e9pression&#8221;.<\/p>\n<p>Un diagnostic correct, de pr\u00e9f\u00e9rence en collaboration avec un sp\u00e9cialiste, est donc essentiel. En principe, cela inclut<\/p>\n<ul>\n<li>une anamn\u00e8se (sympt\u00f4mes B, ant\u00e9c\u00e9dents familiaux)<\/li>\n<li>un laboratoire (Hb, Lc, Tc, CRP, EBV, HBV, HCV, HIV, Toxoplasma, Bartonella)<\/li>\n<li>un statut (ganglions lymphatiques, stations, taille de la rate, foie, ORL, peau)<\/li>\n<li>une biopsie (diff\u00e9rents examens tissulaires sont disponibles : IHC, FACS, cytog\u00e9n\u00e9tique, PCR, FISH).<\/li>\n<li>une imagerie.<\/li>\n<\/ul>\n<p>&#8220;Le PET fournit de tr\u00e8s bonnes donn\u00e9es sur la progression de la maladie, donne des indications sur le pronostic et facilite la prise de d\u00e9cision en mati\u00e8re de traitement&#8221;, explique le professeur Lohri.<\/p>\n<h2 id=\"comment-le-medecin-generaliste-accompagne-t-il-le-traitement\">Comment le m\u00e9decin g\u00e9n\u00e9raliste accompagne-t-il le traitement ?<\/h2>\n<p>Une fois le diagnostic confirm\u00e9, le traitement est g\u00e9n\u00e9ralement administr\u00e9 par le sp\u00e9cialiste, le m\u00e9decin g\u00e9n\u00e9raliste pouvant se charger des analyses de sang int\u00e9rimaires et de l&#8217;administration des facteurs de croissance et des antibiotiques.<\/p>\n<p>&#8220;Les algorithmes th\u00e9rapeutiques devraient id\u00e9alement \u00eatre planifi\u00e9s dans le cadre d&#8217;une r\u00e9union interdisciplinaire. En principe, la th\u00e9rapie a pour but de gu\u00e9rir le patient avec un r\u00e9gime aussi non toxique que possible, qui n&#8217;entra\u00eene pas d&#8217;effets secondaires ult\u00e9rieurs. Cet objectif n&#8217;a pas \u00e9t\u00e9 atteint \u00e0 ce jour. De nouvelles voies de recherche sont donc n\u00e9cessaires pour optimiser davantage le traitement. Il ne faut cependant pas oublier les grands progr\u00e8s r\u00e9alis\u00e9s avec les sch\u00e9mas th\u00e9rapeutiques actuellement utilis\u00e9s (notamment le sch\u00e9ma ABVD pour le lymphome hodgkinien limit\u00e9 et le sch\u00e9ma BEACOPP pour le lymphome hodgkinien avanc\u00e9) <strong>(voir encadr\u00e9). <\/strong>Dans le cas des lymphomes \u00e0 cellules B et de nombreux autres lymphomes, le sch\u00e9ma R-CHOP (avec l&#8217;anticorps rituximab) s&#8217;est av\u00e9r\u00e9 tr\u00e8s efficace. Pour les formes indolentes, les combinaisons de bendamustine prennent de plus en plus d&#8217;importance. Ce m\u00e9dicament a un excellent index th\u00e9rapeutique, ses principales toxicit\u00e9s sont les cytop\u00e9nies et les \u00e9ruptions cutan\u00e9es. La radioth\u00e9rapie est aujourd&#8217;hui moins utilis\u00e9e dans le cadre d&#8217;un traitement curatif, car les cons\u00e9quences tardives peuvent \u00eatre importantes&#8221;, a expliqu\u00e9 le professeur Lohri.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3374\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696.jpg\" width=\"1100\" height=\"654\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696-800x476.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696-120x71.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696-90x54.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696-320x190.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Kasten_s37_HP3.jpg-06c110_1696-560x333.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<h2 id=\"combien-de-temps-faut-il-faire-des-examens-de-suivi\">Combien de temps faut-il faire des examens de suivi ?<\/h2>\n<p>Avant l&#8217;an 2000, de nombreux patients atteints de la maladie de Hodgkin recevaient des doses de radiation parfois importantes. Selon des \u00e9tudes r\u00e9centes, l&#8217;irradiation m\u00e9diastinale augmente consid\u00e9rablement le risque de maladie cardiaque 10 \u00e0 25 ans apr\u00e8s le traitement [1]. Comme le m\u00e9decin g\u00e9n\u00e9raliste prend en charge le suivi des &#8220;survivants du lymphome&#8221;, il a \u00e9galement un r\u00f4le d\u00e9cisif \u00e0 jouer dans la d\u00e9tection de ces complications tardives et dans l&#8217;\u00e9tablissement d&#8217;un diagnostic correct.<\/p>\n<p>Dans le cadre du suivi des patients irradi\u00e9s, l'&#8221;American College of Radiology&#8221; recommande un d\u00e9pistage par test d&#8217;effort et \u00e9chocardiographie en raison du risque cardiaque accru, et ce \u00e0 partir de cinq \u00e0 dix ans apr\u00e8s le traitement.<\/p>\n<p>Le risque de deuxi\u00e8me tumeur est \u00e9galement plus \u00e9lev\u00e9 apr\u00e8s la radioth\u00e9rapie : une \u00e9tude a montr\u00e9 qu&#8217;environ 10% des patientes irradi\u00e9es \u00e0 20 ans ont d\u00e9velopp\u00e9 un cancer du sein vers l&#8217;\u00e2ge de 50 ans [2]. Il est donc recommand\u00e9 de r\u00e9aliser une IRM des seins et une mammographie \u00e0 partir de dix ans apr\u00e8s l&#8217;irradiation.<\/p>\n<h2 id=\"regarder-vers-lavenir\">Regarder vers l&#8217;avenir<\/h2>\n<p>Enfin, le professeur Lohri a \u00e9voqu\u00e9 quelques nouveaut\u00e9s pertinentes dans le traitement et le diagnostic du lymphome :<\/p>\n<ul>\n<li>Le PET permettra \u00e0 l&#8217;avenir de gu\u00e9rir avec des traitements moins agressifs.<\/li>\n<li>La radioth\u00e9rapie sera d\u00e9sormais \u00e9vit\u00e9e dans le cadre d&#8217;un traitement curatif.<\/li>\n<li>De nombreux nouveaux m\u00e9dicaments mol\u00e9culaires et immunoth\u00e9rapeutiques sont en cours de d\u00e9veloppement : comme les inhibiteurs de tyrosine kinase (ibrutinib), les immunomodulateurs, les anticorps de deuxi\u00e8me g\u00e9n\u00e9ration.<\/li>\n<\/ul>\n<p>&#8220;Le m\u00e9decin g\u00e9n\u00e9raliste doit dans tous les cas garder le lymphome sur son radar diagnostique s&#8217;il constate une fatigue, un prurit chronique, une an\u00e9mie, des sympt\u00f4mes syst\u00e9miques en cas d&#8217;h\u00e9patite virale ou d&#8217;infection chronique par l&#8217;EBV ou le VIH. Il est \u00e9galement le principal interlocuteur dans la gestion \u00e0 long terme du patient lymphome gu\u00e9ri et joue ainsi un r\u00f4le important dans la d\u00e9tection pr\u00e9coce des s\u00e9quelles associ\u00e9es&#8221;, a conclu le professeur Lohri.<\/p>\n<p><em>Source : &#8220;Lymphomes : ce que le m\u00e9decin de famille doit savoir&#8221;, s\u00e9minaire au SGIM Great Update, 14-15 novembre 2013, Interlaken<\/em><\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Galper S, et al : Maladie cardiaque cliniquement significative chez les patients atteints de lymphome de Hodgkin trait\u00e9s par irradiation m\u00e9diastinale. Blood 2011 ; 117 : 412-418.<\/li>\n<li>Dores GM, et al : Second malignant neoplasms among long-term survivors of Hodgkin&#8217;s disease : a population-based evaluation over 25 years. J Clin Oncol 2002 ; 20(16) : 3484-3494.<\/li>\n<\/ol>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2014 ; 9(3) : 36-37<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors du Great Update de la SSMI \u00e0 Interlaken, les probl\u00e8mes et les d\u00e9fis les plus fr\u00e9quents auxquels un m\u00e9decin g\u00e9n\u00e9raliste est confront\u00e9 lorsqu&#8217;il s&#8217;occupe de personnes atteintes d&#8217;un lymphome&hellip;<\/p>\n","protected":false},"author":4,"featured_media":41851,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Lymphomes","footnotes":""},"category":[11373,11389,11535,11549],"tags":[12719,15551,17497,14864,14976,16373,30138,23437,13000,54375,54368,34123,14321,43145,13436,48860],"powerkit_post_featured":[],"class_list":["post-345789","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hematologie","category-oncologie","category-rapports-de-congres","category-rx-fr","tag-anemie","tag-biopsie-fr","tag-cancer-fr","tag-depistage","tag-depression-fr","tag-dlbcl-fr","tag-lymphome-fr","tag-lymphome-a-cellules-b","tag-lymphome-de-hodgkin","tag-lymphome-du-snc","tag-maligne-fr","tag-pet-fr","tag-prurit-chronique","tag-r-chop-fr","tag-rituximab-fr","tag-schema-abvd-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:47:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":345793,"slug":"cosa-deve-sapere-il-medico-di-famiglia-2","post_title":"Cosa deve sapere il medico di famiglia","href":"https:\/\/medizinonline.com\/it\/cosa-deve-sapere-il-medico-di-famiglia-2\/"},"pt_PT":{"locale":"pt_PT","id":345799,"slug":"o-que-o-medico-de-familia-precisa-de-saber-2","post_title":"O que o m\u00e9dico de fam\u00edlia precisa de saber","href":"https:\/\/medizinonline.com\/pt-pt\/o-que-o-medico-de-familia-precisa-de-saber-2\/"},"es_ES":{"locale":"es_ES","id":345803,"slug":"lo-que-el-medico-de-familia-debe-saber-2","post_title":"Lo que el m\u00e9dico de familia debe saber","href":"https:\/\/medizinonline.com\/es\/lo-que-el-medico-de-familia-debe-saber-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/345789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=345789"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/345789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/41851"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=345789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=345789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=345789"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=345789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}