{"id":346216,"date":"2014-02-17T00:00:00","date_gmt":"2014-02-16T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/vieillissement-chronologique-ou-premature\/"},"modified":"2014-02-17T00:00:00","modified_gmt":"2014-02-16T23:00:00","slug":"vieillissement-chronologique-ou-premature","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/vieillissement-chronologique-ou-premature\/","title":{"rendered":"Vieillissement chronologique ou pr\u00e9matur\u00e9 ?"},"content":{"rendered":"<p><strong>En raison de sa fonction protectrice particuli\u00e8re pour le corps, la peau constitue une exception dans le processus de vieillissement : En tant que fronti\u00e8re m\u00e9canique et biologique entre les organes internes et l&#8217;environnement, la peau est en outre expos\u00e9e quotidiennement \u00e0 une multitude d&#8217;agressions exog\u00e8nes, non seulement uniques et directes (blessures), mais aussi r\u00e9p\u00e9titives et \u00e0 forte latence. C&#8217;est pourquoi on distingue le vieillissement intrins\u00e8que et le vieillissement extrins\u00e8que de la peau.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>On parle souvent de vieillissement chronologique ou g\u00e9n\u00e9tique pour le vieillissement intrins\u00e8que, de vieillissement exog\u00e8ne ou pr\u00e9matur\u00e9 pour le vieillissement extrins\u00e8que et de photovieillissement si la lumi\u00e8re ultraviolette est la toxine exog\u00e8ne. Morphologiquement, le vieillissement intrins\u00e8que de la peau ne peut pas toujours \u00eatre s\u00e9par\u00e9 nettement du vieillissement extrins\u00e8que. Les deux processus sont parall\u00e8les et le vieillissement extrins\u00e8que de la peau peut se superposer au vieillissement intrins\u00e8que dans diff\u00e9rentes parties du corps, \u00e0 des degr\u00e9s divers.<\/p>\n<p>\u00c9tant donn\u00e9 que les m\u00e9canismes sous-jacents au vieillissement intrins\u00e8que et extrins\u00e8que sont similaires et que les caract\u00e9ristiques biochimiques, morphologiques et cliniques du vieillissement cutan\u00e9 peuvent \u00eatre directement d\u00e9duites des m\u00e9canismes pathologiques, nous allons d&#8217;abord pr\u00e9senter quelques aspects sp\u00e9cifiques. Certains facteurs extrins\u00e8ques sont examin\u00e9s s\u00e9par\u00e9ment.<\/p>\n<h2 id=\"limportance-des-especes-reactives-de-loxygene-1-2\">L&#8217;importance des esp\u00e8ces r\u00e9actives de l&#8217;oxyg\u00e8ne [1, 2]<\/h2>\n<p>Les esp\u00e8ces r\u00e9actives de l&#8217;oxyg\u00e8ne (&#8220;reactive oxygen species&#8221;, ROS) jouent un r\u00f4le central dans le vieillissement de la peau. Selon la th\u00e9orie des radicaux libres du vieillissement formul\u00e9e par Harman [1], la formation de telles mol\u00e9cules est continue au cours de la vie. Cela se produit en particulier dans les tissus \u00e0 forte consommation d&#8217;oxyg\u00e8ne, comme le cerveau, les muscles et le foie.<\/p>\n<p>Au niveau cellulaire, les mitochondries sont le lieu o\u00f9 le turnover des ROS est le plus \u00e9lev\u00e9. Dans le cadre de la production d&#8217;\u00e9nergie par la cha\u00eene respiratoire, du <sub>H2O2<\/sub> est produit au niveau de la membrane mitochondriale interne. Celui-ci est \u00e9galement produit dans le cadre du photovieillissement, o\u00f9 il est g\u00e9n\u00e9r\u00e9 par des superoxydes dismutases \u00e0 partir d&#8217;anions superoxydes. Un grand nombre d&#8217;\u00e9tudes ont montr\u00e9 que, dans le cadre du vieillissement extrins\u00e8que, <sub>H2O2<\/sub> et l&#8217;oxyg\u00e8ne singlet constituent les principaux ROS induits par les UVA. Les radicaux hydroxyles, en revanche, sont produits dans le cadre de la r\u00e9action physiologique de Fenton avec <sub>H2O2<\/sub> et constituent les principaux radicaux d&#8217;oxyg\u00e8ne lors du vieillissement extrins\u00e8que de la peau dans le cadre de l&#8217;exposition aux UVB.<\/p>\n<p>Les ROS jouent donc un r\u00f4le central dans le vieillissement intrins\u00e8que et extrins\u00e8que de la peau.<\/p>\n<p>Au cours de l&#8217;\u00e9volution, l&#8217;organisme a d\u00e9velopp\u00e9 plusieurs m\u00e9canismes de d\u00e9fense contre les ROS. Il s&#8217;agit notamment de la catalase, du cytochrome p450, du glutathion, etc. Lorsque la capacit\u00e9 des syst\u00e8mes de l&#8217;organisme \u00e0 neutraliser les ROS est d\u00e9pass\u00e9e, ces mol\u00e9cules hautement r\u00e9actives peuvent r\u00e9agir avec diff\u00e9rents composants de la cellule et les endommager. Par exemple, les macromol\u00e9cules cellulaires telles que l&#8217;ADN, les prot\u00e9ines et les lipoprot\u00e9ines peuvent \u00eatre directement endommag\u00e9es. La surcharge des m\u00e9canismes de d\u00e9fense de l&#8217;organisme par la formation continue de ROS entra\u00eene des mutations g\u00e9n\u00e9tiques et projette le vieillissement de la peau.<br \/>\nS&#8217;appuyant sur la th\u00e9orie des radicaux libres du vieillissement, une grande partie de la population &#8211; notamment caucasienne &#8211; tente aujourd&#8217;hui de limiter, voire d&#8217;emp\u00eacher la formation de ROS par voie syst\u00e9mique en prenant des compl\u00e9ments alimentaires et par voie topique en appliquant des produits contenant des antioxydants naturels et synth\u00e9tiques. Malheureusement, il s&#8217;est av\u00e9r\u00e9 que les exp\u00e9riences de Harman ne pouvaient pas \u00eatre enti\u00e8rement reproduites et qu&#8217;en fonction du dispositif exp\u00e9rimental, une pr\u00e9sence accrue de ROS chez les vers et les souris pouvait m\u00eame entra\u00eener un allongement de la dur\u00e9e de vie [3]. Il est postul\u00e9 que les ROS mettent en place un r\u00e9seau de r\u00e9paration cellulaire. On pense m\u00eame aujourd&#8217;hui que l&#8217;apport de doses \u00e9lev\u00e9es d&#8217;antioxydants sous forme de vitamines et d&#8217;autres compl\u00e9ments alimentaires peut \u00eatre inefficace, voire nuisible.<\/p>\n<h2 id=\"mutation-de-ladn-mitochondrial-4-5\">Mutation de l&#8217;ADN mitochondrial [4, 5]<\/h2>\n<p>La t\u00e2che principale des mitochondries est de fournir de l&#8217;\u00e9nergie sous forme d&#8217;ATP. Cela se fait par le biais de la cha\u00eene respiratoire, qui se d\u00e9roule au niveau de la membrane mitochondriale interne. Ce processus n&#8217;est pas toujours exempt d&#8217;erreurs. Des erreurs dans la cha\u00eene respiratoire peuvent entra\u00eener la production d&#8217;ERO, ce qui explique pourquoi la mitochondrie est l&#8217;endroit o\u00f9 le turnover des ERO est le plus \u00e9lev\u00e9 dans la cellule.<\/p>\n<p>Les mitochondries contiennent leur propre mat\u00e9riel g\u00e9n\u00e9tique (ADNmt). L&#8217;ADNmt se trouve \u00e0 proximit\u00e9 imm\u00e9diate de la cha\u00eene respiratoire et donc \u00e0 proximit\u00e9 imm\u00e9diate de l&#8217;influence n\u00e9faste des ROS qui se forment. Il a \u00e9t\u00e9 d\u00e9montr\u00e9 que les mutations de l&#8217;ADNmt s&#8217;accumulent au cours du processus de vieillissement normal et que la fonction de la cha\u00eene respiratoire diminue de mani\u00e8re inversement proportionnelle, ce qui entra\u00eene une baisse de la fourniture d&#8217;\u00e9nergie (th\u00e9orie mitochondriale du vieillissement). En outre, il a \u00e9t\u00e9 d\u00e9montr\u00e9 qu&#8217;au-del\u00e0 du vieillissement intrins\u00e8que mentionn\u00e9 ci-dessus, les mutations de l&#8217;ADNmt jouent \u00e9galement un r\u00f4le dans le vieillissement extrins\u00e8que de la peau (th\u00e9orie mitochondriale du photovieillissement). La peau expos\u00e9e de mani\u00e8re r\u00e9p\u00e9t\u00e9e aux UV a montr\u00e9 une induction de mutations de l&#8217;ADNmt, entra\u00eenant des troubles fonctionnels des mitochondries (consommation d&#8217;oxyg\u00e8ne, potentiel de la membrane mt, m\u00e9tabolisme \u00e9nerg\u00e9tique).<\/p>\n<h2 id=\"metalloproteases-matricielles-6-7\">M\u00e9talloprot\u00e9ases matricielles [6, 7]<\/h2>\n<p>Les marix m\u00e9talloprot\u00e9inases (MMP) constituent une famille d&#8217;enzymes dont la fonction est de d\u00e9grader de mani\u00e8re prot\u00e9olytique les prot\u00e9ines de la matrice dermique. Les principaux substrats des MMP sont les prot\u00e9ines structurelles du derme, telles que les collag\u00e8nes et la g\u00e9latine. La fonction des MMP est importante dans le cadre du remodelage tissulaire qui se produit lors de diff\u00e9rents processus biologiques tels que la morphogen\u00e8se, la cicatrisation des plaies, l&#8217;angiogen\u00e8se ou la croissance tumorale. En outre, les MMP ont d&#8217;autres fonctions dans le traitement des mol\u00e9cules de signalisation qui contr\u00f4lent le comportement cellulaire. Il existe des inhibiteurs sp\u00e9cifiques des MMP, appel\u00e9s inhibiteurs sp\u00e9cifiques des tissus des m\u00e9talloprot\u00e9inases matricielles (TIMP). Ils r\u00e9duisent l&#8217;activit\u00e9 des MMP et limitent ainsi, par exemple, une d\u00e9gradation excessive des prot\u00e9ines. L&#8217;interaction entre le MMP et le TIMP n&#8217;est pas encore tout \u00e0 fait claire.<br \/>\nUn grand nombre de travaux sugg\u00e8rent que les MMP jouent un r\u00f4le important dans le vieillissement extrins\u00e8que de la peau. Les MMP sont induites directement et indirectement par la lumi\u00e8re ultraviolette. La d\u00e9gradation des prot\u00e9ines de la matrice dermique ainsi induite entra\u00eene une alt\u00e9ration de la matrice extracellulaire qui contribue aux changements visibles cliniquement et histologiquement caract\u00e9ristiques de la peau photovieillie.<\/p>\n<p>Des \u00e9tudes indiquent que les r\u00e9tino\u00efdes ont un effet inhibiteur sur l&#8217;expression des MMP. L&#8217;enrichissement en nouveau collag\u00e8ne non fractionn\u00e9 peut ensuite entra\u00eener une am\u00e9lioration significative de l&#8217;aspect de la peau.<\/p>\n<h2 id=\"activation-des-facteurs-de-transcription-8-9\">Activation des facteurs de transcription [8, 9]<\/h2>\n<p>L&#8217;activation de facteurs de transcription par les UV entra\u00eene l&#8217;induction de MMP. L&#8217;exposition de la peau humaine aux UV entra\u00eene non seulement l&#8217;induction directe de la MMP, mais aussi l&#8217;induction des facteurs de transcription AP-1 et NF-\u03baB. Ces facteurs sont des activateurs des g\u00e8nes MMP. Cette voie d&#8217;activation indirecte des MMP dans la peau vieillie de mani\u00e8re extrins\u00e8que existe en plus de l&#8217;induction directe des MMP par les ROS.<\/p>\n<p>Les r\u00e9sultats d&#8217;\u00e9tudes en laboratoire et sur des animaux indiquent que l&#8217;induction des facteurs de transcription peut \u00eatre inhib\u00e9e par des extraits de plantes (magnolol).<\/p>\n<h2 id=\"advanced-glycation-endproducts-produits-finaux-avances-de-la-glycation-10-11\">&#8220;Advanced Glycation Endproducts&#8221; (produits finaux avanc\u00e9s de la glycation) [10, 11]<\/h2>\n<p>&#8220;Advanced Glycation Endproducts&#8221; (AGEs) se forment dans le cadre d&#8217;une r\u00e9action de Maillard par glycation et oxydation de diff\u00e9rentes prot\u00e9ines structurelles. Dans ce cas, les prot\u00e9ines (groupes amino libres) ou les lipides r\u00e9agissent de mani\u00e8re non enzymatique avec les glucides. Les AGE sont impliqu\u00e9s dans diff\u00e9rentes maladies li\u00e9es au vieillissement. La glycation est impliqu\u00e9e \u00e0 la fois dans le vieillissement cutan\u00e9 intrins\u00e8que et extrins\u00e8que (exposition aux UV) et modifie les processus de croissance et de diff\u00e9renciation ainsi que les activit\u00e9s enzymatiques (MMP) dans la matrice extracellulaire de la peau. L&#8217;augmentation de la teneur en AGE dans la peau modifie les propri\u00e9t\u00e9s m\u00e9caniques. Ils se caract\u00e9risent par une \u00e9lasticit\u00e9 r\u00e9duite et une rigidit\u00e9 accrue.<br \/>\nDes r\u00e9sultats d&#8217;\u00e9tudes en laboratoire indiquent que la formation d&#8217;AGE peut \u00eatre inhib\u00e9e par des extraits de plantes (pamplemousse rouge).<\/p>\n<h2 id=\"vitamine-d-12-15\">Vitamine D [12\u201315]<\/h2>\n<p>La vitamine D est une vitamine liposoluble qui est principalement produite par la peau humaine sous l&#8217;effet du rayonnement solaire (en particulier les UV-B). Il r\u00e9gule, entre autres, l&#8217;absorption du calcium et du phosphate par l&#8217;intestin et leur int\u00e9gration dans les os. La diminution de l&#8217;\u00e9paisseur de la peau li\u00e9e \u00e0 l&#8217;\u00e2ge entra\u00eene une baisse significative de la synth\u00e8se de la vitamine D dans la peau. De plus, chez les personnes \u00e2g\u00e9es et moins mobiles, la diminution de l&#8217;exposition au soleil a un effet n\u00e9gatif sur le statut en vitamine D. Les personnes \u00e2g\u00e9es sont plus susceptibles de souffrir d&#8217;une carence en vitamine D que les autres.<\/p>\n<p>L&#8217;importance de la vitamine D a suscit\u00e9 une grande attention ces derni\u00e8res ann\u00e9es et fait actuellement l&#8217;objet d&#8217;un vif d\u00e9bat. La revue syst\u00e9matique de Philippe Autier [15] du 6.12.13 montre clairement que les opinions souvent colport\u00e9es sur la vitamine D doivent \u00eatre nuanc\u00e9es. De nombreuses \u00e9tudes prospectives ont montr\u00e9 une association entre de faibles concentrations de 25(OH)vitamine D et un certain nombre de maladies aigu\u00ebs et chroniques. Cependant, un nombre similaire d&#8217;\u00e9tudes randomis\u00e9es n&#8217;a pas pu d\u00e9montrer que l&#8217;augmentation de la concentration en vitamine D permettait de pr\u00e9venir l&#8217;apparition de la maladie.<\/p>\n<h2 id=\"senescence-immunitaire-16\">S\u00e9nescence immunitaire  [16]<\/h2>\n<p>M\u00eame chez les personnes apparemment en bonne sant\u00e9, le syst\u00e8me immunitaire vieillissant subit des changements profonds et parfois irr\u00e9versibles qui conduisent \u00e0 une diminution progressive de la fonction immunitaire &#8211; l&#8217;immunos\u00e9nescence. Elle concerne tous les organes et cellules du syst\u00e8me immunitaire inn\u00e9 et acquis, y compris les cellules souches h\u00e9matopo\u00ef\u00e9tiques (CSH), les cellules prog\u00e9nitrices lympho\u00efdes (CLP) de la moelle osseuse et du thymus, les lymphocytes T et B matures des organes lymphatiques secondaires, ainsi que les phagocytes et les cellules pr\u00e9sentatrices d&#8217;antig\u00e8nes (APC) du syst\u00e8me immunitaire inn\u00e9. Au niveau de l&#8217;organisme dans son ensemble, ces changements li\u00e9s \u00e0 l&#8217;\u00e2ge se traduisent principalement par une plus grande propension aux infections et une moindre r\u00e9ponse aux vaccins. Les tumeurs et les maladies auto-immunes sont \u00e9galement plus fr\u00e9quentes. Nombre d&#8217;entre elles concernent la sp\u00e9cialit\u00e9 dermatologique comme les carcinomes \u00e9pith\u00e9liaux, le m\u00e9lanome malin, les lymphomes cutan\u00e9s, les collag\u00e9noses, les dermatoses bulleuses, l&#8217;herp\u00e8s zoster, les troubles de la cicatrisation et d&#8217;autres.<\/p>\n<p><strong>Vieillissement de l&#8217;immunit\u00e9 inn\u00e9e :<\/strong> les cellules du syst\u00e8me immunitaire inn\u00e9 sont en premi\u00e8re ligne dans la d\u00e9fense contre les agents pathog\u00e8nes. Il s&#8217;agit notamment des cellules phagocytaires et\/ou pr\u00e9sentatrices d&#8217;antig\u00e8nes telles que les neutrophiles, les macrophages et les cellules dendritiques (DC), mais aussi de celles qui sont \u00e0 la fronti\u00e8re de l&#8217;immunit\u00e9 acquise, comme les cellules NK. Certaines des modifications du syst\u00e8me immunitaire inn\u00e9 li\u00e9es au vieillissement sont r\u00e9sum\u00e9es dans le <strong>tableau&nbsp;1 <\/strong>.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3218\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601.jpg\" width=\"1100\" height=\"1184\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601-800x861.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601-120x129.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601-90x97.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601-320x344.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s6_DP1.jpg-44f67d_1601-560x603.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p><strong>Vieillissement de l&#8217;immunit\u00e9 acquise : <\/strong>contrairement \u00e0 l&#8217;immunit\u00e9 inn\u00e9e, l&#8217;immunit\u00e9 acquise est capable de fournir des r\u00e9ponses immunitaires sp\u00e9cifiques aux antig\u00e8nes, principalement par le biais des lymphocytes T et des lymphocytes B. Les lymphocytes T et les lymphocytes B sont les principaux acteurs de la r\u00e9ponse immunitaire. Celles-ci subissent \u00e9galement des modifications li\u00e9es au vieillissement qui, comme pour l&#8217;immunit\u00e9 inn\u00e9e, entra\u00eenent une diminution (ou un mauvais ciblage) de la force de frappe contre les agents pathog\u00e8nes. En outre, l&#8217;immunit\u00e9 acquise pr\u00e9sente une variabilit\u00e9 r\u00e9duite et donc une capacit\u00e9 d&#8217;adaptation r\u00e9duite aux antig\u00e8nes <strong>(tableau 2).<\/strong><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-3219 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602.jpg\" width=\"1100\" height=\"1529\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602-800x1112.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602-120x167.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602-90x125.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602-320x445.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab2_s7_DP1.jpg-470a6d_1602-560x778.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1529;\" \/><\/strong><\/p>\n<h2 id=\"modifications-de-la-peau-liees-a-lenvironnement\">Modifications de la peau li\u00e9es \u00e0 l&#8217;environnement<\/h2>\n<p>Les modifications de la peau dues \u00e0 l&#8217;environnement sont aujourd&#8217;hui principalement caus\u00e9es par le tabagisme et les rayons ultraviolets (UV-S).<br \/>\n<strong>le tabagisme [17, 18] : <\/strong>L&#8217;alt\u00e9ration des processus physiologiques de la peau par le tabagisme a \u00e9t\u00e9 bien \u00e9tudi\u00e9e. Le tabagisme affecte g\u00e9n\u00e9ralement la circulation sanguine des tissus, y compris celle de la peau. La peau des fumeurs est souvent terne et gris\u00e2tre, elle est \u00e9galement plus s\u00e8che et plus flasque et se ride plus t\u00f4t et plus fortement. Ces ph\u00e9nom\u00e8nes ont \u00e9t\u00e9 document\u00e9s de mani\u00e8re impressionnante dans certains travaux portant sur des jumeaux monozygotes. Ces ph\u00e9nom\u00e8nes se manifestent plus t\u00f4t et plus clairement chez les femmes que chez les hommes. Plusieurs processus physiologiques de la peau sont responsables de la formation accrue de rides chez les fumeurs, qui sont affect\u00e9s par les nombreux radicaux libres pr\u00e9sents dans la fum\u00e9e de tabac. Ainsi, la fum\u00e9e de tabac inhibe la formation de nouvelles fibres de collag\u00e8ne dans le derme tout en favorisant la d\u00e9gradation des fibres de collag\u00e8ne et d&#8217;\u00e9lastine. Le syst\u00e8me finement coordonn\u00e9 de formation et de d\u00e9gradation des fibres est alors d\u00e9s\u00e9quilibr\u00e9. L&#8217;exposition aux UV affecte \u00e9galement ces processus. En outre, la nicotine contenue dans la fum\u00e9e de tabac r\u00e9tr\u00e9cit les vaisseaux sanguins, de sorte que la peau est \u00e9galement insuffisamment irrigu\u00e9e, et le monoxyde de carbone r\u00e9duit le transport de l&#8217;oxyg\u00e8ne par les \u00e9rythrocytes.<\/p>\n<p><strong>Exposition aux UV [19\u201322]:<\/strong> L&#8217;alt\u00e9ration des processus physiologiques de la peau, notamment par une exposition extensive aux UV, a \u00e9galement \u00e9t\u00e9 bien \u00e9tudi\u00e9e <strong>(fig.&nbsp;1).<\/strong><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3220 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Abb1_s5_DP1.png-3f3bed_1600.png\" width=\"627\" height=\"1137\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Abb1_s5_DP1.png-3f3bed_1600.png 627w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Abb1_s5_DP1.png-3f3bed_1600-120x218.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Abb1_s5_DP1.png-3f3bed_1600-90x163.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Abb1_s5_DP1.png-3f3bed_1600-320x580.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Abb1_s5_DP1.png-3f3bed_1600-560x1016.png 560w\" data-sizes=\"(max-width: 627px) 100vw, 627px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 627px; --smush-placeholder-aspect-ratio: 627\/1137;\" \/><\/p>\n<p>Cela a \u00e9t\u00e9 particuli\u00e8rement bien illustr\u00e9 l&#8217;an dernier dans un article de Jennifer Gordon publi\u00e9 dans le New England Journal of Medicine [20]. La pr\u00e9sentation clinique montre un chauffeur de camion de 69 ans dont la peau du c\u00f4t\u00e9 gauche du visage s&#8217;est \u00e9paissie et rid\u00e9e de mani\u00e8re asymptomatique sur une p\u00e9riode de 25 ans de travail et qui pr\u00e9sentait des signes typiques de l\u00e9sions cutan\u00e9es associ\u00e9es aux UVA. On sait encore peu de choses sur le photovieillissement \u00e9pidermique et les processus mol\u00e9culaires qui conduisent aux troubles de la pigmentation &#8211; typiques des peaux endommag\u00e9es par la lumi\u00e8re &#8211; ne sont pas encore bien compris. Le photovieillissement dermique est beaucoup mieux \u00e9tudi\u00e9. En raison d&#8217;une activit\u00e9 accrue de la m\u00e9talloprot\u00e9inase matricielle, de la collag\u00e9nase, de la g\u00e9latinase 92 kd et de la strom\u00e9lysine, le collag\u00e8ne se d\u00e9grade davantage avec l&#8217;\u00e2ge. M\u00eame des quantit\u00e9s faibles ou intermittentes de lumi\u00e8re UV activent la m\u00e9talloprot\u00e9inase matricielle et entra\u00eenent une d\u00e9gradation du collag\u00e8ne et une inhibition de la synth\u00e8se du collag\u00e8ne. C&#8217;est \u00e9galement \u00e0 ce stade qu&#8217;intervient le traitement \u00e0 l&#8217;acide r\u00e9tino\u00efque, qui vise \u00e0 emp\u00eacher l&#8217;activation de la m\u00e9talloprot\u00e9inase matricielle induite par les UV. Des processus similaires sont \u00e9galement d\u00e9crits pour l&#8217;\u00e9lastine. L&#8217;interaction de ces processus conduit \u00e0 la formation de rides typiques li\u00e9es \u00e0 la lumi\u00e8re.<\/p>\n<p>Entre-temps, il existe \u00e9galement des travaux qui d\u00e9crivent de mani\u00e8re impressionnante l&#8217;importance de la pollution dans le vieillissement de la peau. Mais le tabac et les UV-S ne sont pas les seuls facteurs environnementaux. <strong>La gravit\u00e9, les expressions faciales et la position de sommeil <\/strong>sont \u00e9galement des facteurs extrins\u00e8ques qui contribuent de mani\u00e8re non n\u00e9gligeable aux changements visibles de la peau vieillissante : La pesanteur tire sans cesse sur notre corps et ses signes sont particuli\u00e8rement visibles apr\u00e8s 50 ans. Le nez, les oreilles, les paupi\u00e8res et les l\u00e8vres sont particuli\u00e8rement touch\u00e9s. Les rides nasog\u00e9niennes, les rides de la marionnette et les rides du cou sont consid\u00e9r\u00e9es comme des rides de gravit\u00e9 et sont dues \u00e0 un rel\u00e2chement des tissus cutan\u00e9s et sous-cutan\u00e9s.<\/p>\n<p>Les rides <em>du visage<\/em> se forment de plus en plus avec l&#8217;\u00e2ge. Les rides d&#8217;expression peuvent appara\u00eetre tr\u00e8s t\u00f4t dans le cadre d&#8217;une hyperactivit\u00e9 des muscles du visage. En gros, on peut les classer en rides de la patte d&#8217;oie, rides de col\u00e8re, rides frontales, rides de la bouche, rides des l\u00e8vres ou rides du fumeur, ainsi qu&#8217;en rides du menton ou du nez.<\/p>\n<p>Certaines <em>positions de sommeil<\/em> entra\u00eenent l&#8217;apparition de rides de sommeil typiques, g\u00e9n\u00e9ralement verticales, au niveau des joues et des tempes.<\/p>\n<p>On constate de grandes diff\u00e9rences ethniques dans la formation des rides li\u00e9es \u00e0 l&#8217;\u00e2ge. Ainsi, les femmes japonaises et sud-cor\u00e9ennes restent pratiquement sans rides jusqu&#8217;\u00e0 l&#8217;\u00e2ge de 50 ans, tandis que les femmes fran\u00e7aises ont des rides d&#8217;expression visibles d\u00e8s l&#8217;\u00e2ge de 20 \u00e0 30 ans. Cependant, apr\u00e8s 50 ans, la situation s&#8217;inverse \u00e0 nouveau en faveur des Europ\u00e9ennes.<\/p>\n<h2 id=\"genie-genetique-et-soins-de-la-peau-23\">G\u00e9nie g\u00e9n\u00e9tique et soins de la peau  [23]<\/h2>\n<p>Ces derni\u00e8res ann\u00e9es, les progr\u00e8s consid\u00e9rables r\u00e9alis\u00e9s dans le domaine du g\u00e9nie g\u00e9n\u00e9tique et le d\u00e9veloppement des &#8220;puces g\u00e9n\u00e9tiques&#8221; nous ont permis de mieux comprendre les \u00e9v\u00e9nements mol\u00e9culaires li\u00e9s au vieillissement de la peau. Les analyses d&#8217;expression g\u00e9nique ont permis d&#8217;identifier des voies de signalisation impliqu\u00e9es dans le processus de vieillissement et ces connaissances peuvent sans aucun doute contribuer au d\u00e9veloppement de nouvelles strat\u00e9gies de pr\u00e9vention et de traitement.<\/p>\n<p>Cependant, les rapports souvent enthousiastes sur l&#8217;effet de nouveaux ingr\u00e9dients (parfois connus de longue date) sur le processus de vieillissement ont \u00e9t\u00e9 r\u00e9alis\u00e9s <em>in vitro<\/em> et une transposition \u00e0 des situations &#8220;cliniques&#8221; quotidiennes reste \u00e0 faire. Ces principes actifs candidats sont n\u00e9anmoins souvent propos\u00e9s \u00e0 doses hom\u00e9opathiques, \u00e0 grand renfort de mots et de couleurs, dans des produits cosm\u00e9tiques dits hautement efficaces et innovants. Les vantardises autour des cellules souches sont particuli\u00e8rement impressionnantes depuis que Michelle Obama soigne son visage avec un s\u00e9rum contenant des cellules souches de la vari\u00e9t\u00e9 de pomme suisse \u00e0 longue dur\u00e9e de vie &#8220;Uttwiler Sp\u00e4tlauber&#8221;. Ainsi, on sugg\u00e8re au consommateur &#8211; avec l&#8217;appui de nombreuses c\u00e9l\u00e9brit\u00e9s &#8211; que ces produits rappellent aux cellules souches de la peau leur mission, \u00e0 savoir se rendre utiles et rajeunir la peau.<\/p>\n<h2 id=\"conclusion-pour-la-pratique\">Conclusion pour la pratique<\/h2>\n<ul>\n<li>Dans le cas du vieillissement intrins\u00e8que, on parle souvent de vieillissement chronologique ou g\u00e9n\u00e9tique, et dans le cas du vieillissement extrins\u00e8que, de vieillissement exog\u00e8ne ou pr\u00e9matur\u00e9.<\/li>\n<li>Les esp\u00e8ces r\u00e9actives de l&#8217;oxyg\u00e8ne (ROS) jouent un r\u00f4le central dans le vieillissement intrins\u00e8que et extrins\u00e8que de la peau.<\/li>\n<li>Les mutations de l&#8217;ADN mitochondrial s&#8217;accumulent au cours du processus de vieillissement normal. La fonction de la cha\u00eene respiratoire diminue de mani\u00e8re inversement proportionnelle, ce qui entra\u00eene une baisse de la fourniture d&#8217;\u00e9nergie (th\u00e9orie mitochondriale du vieillissement).<\/li>\n<li>Le tabagisme, les UV-S, la gravit\u00e9, les expressions faciales et la position de sommeil sont consid\u00e9r\u00e9s comme des facteurs environnementaux de vieillissement de la peau.<\/li>\n<\/ul>\n<p><strong>Prof. Dr. phil. nat. Christian Surber<\/strong><\/p>\n<h3 id=\"litterature\">Litt\u00e9rature :<\/h3>\n<ol>\n<li>Harman D : J Gerontol 1956 ; 11 : 298-30000. PMID 13332224.<\/li>\n<li>Fortmann SP, et al. : Ann Intern Med 2013 ; 159(12) : 824-834. doi:10.7326\/0003-4819-159-12-201312170-00729.<\/li>\n<li>Moyer MW : Sci Am 2013 Feb ; 308(2) : 62-67. PMID : 23367786.<\/li>\n<li>Berneburg M, et al : Photochem Photobiol Sci 2006 ; 5 : 190-198. PMID : 16465305.<\/li>\n<li>Kazachkova N, et al : Aging Dis 2013 ; 4(6) : 337-350. PMID : 24307967.<\/li>\n<li>Griffiths CE, et al : N Engl J Med 1993 ; 329(8) : 530-535. PMID : 8336752.<\/li>\n<li>Hern\u00e1ndez-P\u00e9rez M, et al : Am J Dermatopathol 2012 ; 34(6) : 565-579. doi : 10.1097\/DAD. 0b013e31821e8744.<\/li>\n<li>Muthusamy V, et al. : Arch Dermatol Res 2010 ; 302(1) : 5-17. doi : 10.1007\/s00403-009-0994-y.<\/li>\n<li>Tanaka K, et al. : Curr Drug Metab 2010 ; 11(5) : 431-435. PMID : 20540695.<\/li>\n<li>Crisan M, et al. : PLoS One 2013 ; 8(10) : e75003. doi : 10.1371\/journal.pone.0075003.<\/li>\n<li>Jariyapamornkoon et al. : BMC Complement and Altern Med 2013 ; 13 : 171. doi : 10.1186\/1472-6882-13-171.<\/li>\n<li>Tang JY, et al : J Am Acad Dermatol 2012 ; 67(5) : 803.e1-12, quiz 815-6. doi : 10.1016\/j.jaad.2012.05.044.<\/li>\n<li>Tang JY, et al : J Am Acad Dermatol 2012 ; 67 : 817.e1-11, quiz 827-8. doi : 10.1016\/j.jaad.2012.07.022.<\/li>\n<li>Reid IR, et al : Lancet 2013 Oct 10. pii : S0140-6736(13)61647-5. doi : 10.1016\/S0140-6736(13)61647-5.<\/li>\n<li>Autier P, et al : Vitamin D status and ill health : a systematic review. The Lancet Diabetes &amp; Endocrinology, Disponible en ligne le 6 d\u00e9cembre 2013. <a href=\"http:\/\/dx.doi.org\/10.1016\/S2213-8587(13)70165-7\" target=\"_blank\" rel=\"noopener\">http:\/\/dx.doi.org\/10.1016\/S2213-8587(13)70165-7<\/a>.<\/li>\n<li>Peters T : Hautarzt 2011 ; 62(8) : 598-606, doi : 10.1007\/s00105-011-2134-9.<\/li>\n<li>Morita A, et al. : J Invest Dermatol Symp Proc 2009 ; 14 : 53-55, doi:10.1038\/jidsymp.2009.13.<\/li>\n<li>Okada HC, et al : Plast Reconstr Surg 2013 ; 132 : 1085-1092, doi : 10.1097\/PRS.0b013e3182a4c20a.<\/li>\n<li>Gilchrest BA : J Invest Dermatol 2013 ; 133(E1) : E2\u2013E6, doi:10.1038\/skinbio.2013.176.<\/li>\n<li>Gordon JRS, et al : N Engl J Med 2012 ; 366 : e25, doi : 10.1056\/NEJMicm1104059.<\/li>\n<li>Valacchi G, et al : Ann NY Acad Sci 2012 ; 1271 : 75-81, doi : 10.1111\/j.1749-6632.2012.06724.x.<\/li>\n<li>Dennerstein L, et al : Menopause Int 2011 ; 17(3) : 96-101. doi : 10.1258\/mi.2011.011028.<\/li>\n<li>Tiesman JP : J Drugs Dermatol 2009 ; 8(7 Suppl) : s12-14. PMID : 19623779.<\/li>\n<\/ol>\n<p><em>Pratique de la dermatologie 2014 ; 24(1) : 4-8<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En raison de sa fonction protectrice particuli\u00e8re pour le corps, la peau constitue une exception dans le processus de vieillissement : En tant que fronti\u00e8re m\u00e9canique et biologique entre les&hellip;<\/p>\n","protected":false},"author":4,"featured_media":41240,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Processus de vieillissement de la peau","footnotes":""},"category":[11349,11362,11531,11368,11549],"tags":[57000,56995,57026,46192,16371,15553,14837,56938,56964,56932,12094,56978,55299,56969,57006,56921,56951,56973,12368,56990,27401,56958,56984,42320,19882,49198,57012,56914,49205,34094,20609,19264,57022,57016,56944,28463,13141],"powerkit_post_featured":[],"class_list":["post-346216","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allergologie-et-immunologie-clinique","category-dermatologie-et-venerologie","category-formation-continue","category-geriatrie-fr","category-rx-fr","tag-advanced-glycation-endproducts-produits-finaux-de-glycation-avances","tag-age-fr","tag-cellule-souche","tag-collagene-fr","tag-dermatose-fr","tag-dermis-fr","tag-enzyme-fr","tag-especes-oxygenees","tag-exposition-aux-uvb","tag-extrinseque","tag-fumer","tag-gelatine","tag-genetique-fr","tag-h2o2-fr","tag-immunenescence","tag-intrinseque","tag-lumiere","tag-lumiere-uva","tag-melanome","tag-metalloproteinase-matricielle","tag-mimique","tag-mitochondries","tag-mtdns-fr","tag-pattes-doie","tag-peau","tag-radicaux-libres","tag-rayonnement-ultraviolet","tag-reactif","tag-ros-fr","tag-serum-fr","tag-soins-de-la-peau","tag-systeme-immunitaire","tag-tissu-sous-cutane","tag-uv-s-fr","tag-vieillissement","tag-vieux","tag-vitamine-d","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:44:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":346228,"slug":"invecchiamento-cronologico-o-prematuro","post_title":"Invecchiamento cronologico o prematuro?","href":"https:\/\/medizinonline.com\/it\/invecchiamento-cronologico-o-prematuro\/"},"pt_PT":{"locale":"pt_PT","id":346230,"slug":"envelhecimento-cronologico-ou-prematuro","post_title":"Envelhecimento cronol\u00f3gico ou prematuro?","href":"https:\/\/medizinonline.com\/pt-pt\/envelhecimento-cronologico-ou-prematuro\/"},"es_ES":{"locale":"es_ES","id":346232,"slug":"envejecimiento-cronologico-o-prematuro","post_title":"\u00bfEnvejecimiento cronol\u00f3gico o prematuro?","href":"https:\/\/medizinonline.com\/es\/envejecimiento-cronologico-o-prematuro\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/346216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=346216"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/346216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/41240"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=346216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=346216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=346216"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=346216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}