{"id":347208,"date":"2013-09-19T00:00:00","date_gmt":"2013-09-18T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/nouvelles-lignes-directrices-sur-le-traitement-et-la-stratification-des-risques\/"},"modified":"2013-09-19T00:00:00","modified_gmt":"2013-09-18T22:00:00","slug":"nouvelles-lignes-directrices-sur-le-traitement-et-la-stratification-des-risques","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/nouvelles-lignes-directrices-sur-le-traitement-et-la-stratification-des-risques\/","title":{"rendered":"Nouvelles lignes directrices sur le traitement et la stratification des risques"},"content":{"rendered":"<p><strong>En pr\u00e9sentant les nouvelles recommandations dans la prise en charge de la polyarthrite rhumato\u00efde, les intervenants de l&#8217;EULAR de cette ann\u00e9e ont notamment \u00e9voqu\u00e9 le r\u00f4le de la trith\u00e9rapie combin\u00e9e avec les DMARD conventionnels. Selon le Dr Robert B.M. Landew\u00e9, d&#8217;Amsterdam, leur utilit\u00e9 par rapport \u00e0 une th\u00e9rapie \u00e9tendue avec un compl\u00e9ment biologique n&#8217;est pas claire. N\u00e9anmoins, les nouvelles lignes directrices sont un peu plus explicitement favorables \u00e0 cette forme de traitement qu&#8217;en 2010.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Il s&#8217;agissait tout d&#8217;abord de savoir comment les recommandations EULAR de 2010 avaient fait leurs preuves. &#8220;Nos recommandations concernant le traitement DMARD combin\u00e9 ont \u00e9t\u00e9 particuli\u00e8rement critiqu\u00e9es, car nous avons pr\u00e9f\u00e9r\u00e9 la monoth\u00e9rapie par DMARD conventionnels (csDMARDs) au traitement combin\u00e9 csDMARDs et parce que nous avons trouv\u00e9 peu convaincantes les \u00e9tudes portant exclusivement sur les traitements combin\u00e9s csDMARDs&#8221;, a constat\u00e9 le Dr. med. Robert B.M. Landew\u00e9, Amsterdam.&nbsp;  &#8220;Pour cela, il faut savoir comment mesurer la performance de telles recommandations. Une m\u00e9decine bas\u00e9e sur les preuves devrait prendre en compte les r\u00e9sultats de la recherche, les donn\u00e9es cliniques telles que l&#8217;exp\u00e9rience, les pr\u00e9f\u00e9rences, les habitudes locales et les valeurs individuelles des patients telles que les craintes et les perceptions&nbsp; afin d&#8217;aboutir \u00e0 une d\u00e9cision optimale pour une recommandation. La r\u00e9\u00e9valuation qui a lieu actuellement continue donc \u00e0 d\u00e9terminer s&#8217;il existe une utilisation pour le traitement combin\u00e9 csDMARD dans le traitement des patients atteints de PR&#8221;.<\/p>\n<h2 id=\"swefot\">Swefot<\/h2>\n<p>L&#8217;essai Swefot (2012) a examin\u00e9 la question suivante : &#8220;Que faire si une dose ad\u00e9quate de MTX ne se traduit pas par un DAS 28\u22643,2 apr\u00e8s trois mois : triple combinaison (ajout de sulfasalazine et d&#8217;hydroxychloroquine) ou ajout d&#8217;infliximab ?&#8221; Les auteurs concluent : un traitement biologique compl\u00e9mentaire est une option valide pour les patients en \u00e9chec avec un traitement MTX initial. Cependant, l&#8217;am\u00e9lioration des r\u00e9sultats cliniques \u00e0 12 mois et des r\u00e9sultats radiographiques \u00e0 24 mois doit \u00eatre mise en balance avec la diff\u00e9rence clinique trop peu convaincante \u00e0 24 mois et le co\u00fbt nettement plus \u00e9lev\u00e9&nbsp; [1]. Cette \u00e9tude suscite plusieurs r\u00e9serves : &#8220;Dans l&#8217;ensemble, elle n&#8217;est pas vraiment appropri\u00e9e pour envisager si la triple combinaison peut \u00eatre recommand\u00e9e avant une suppl\u00e9mentation avec un produit biologique&#8221;, a d\u00e9clar\u00e9 le Dr Landew\u00e9.<\/p>\n<h2 id=\"tear-et-treach\">TEAR et tREACH<\/h2>\n<p>L&#8217;essai TEAR (2012) a cherch\u00e9 \u00e0 d\u00e9terminer si les patients atteints de New-Onset-RA \u00e9taient mieux trait\u00e9s par un DMARD renforc\u00e9 ou par une association directe. Le plan factoriel 2\u00d72 a \u00e9t\u00e9 utilis\u00e9 pour r\u00e9partir les participants dans l&#8217;un des quatre groupes de traitement : traitement direct par MTX plus \u00e9tanercept, trith\u00e9rapie orale directe (MTX plus sulfasalazine plus hydroxychloroquine) ou monoth\u00e9rapie MTX augment\u00e9e \u00e0 l&#8217;une des th\u00e9rapies combin\u00e9es (MTX plus \u00e9tanercept ou MTX plus sulfasalazine plus hydroxychloroquine) \u00e0 la semaine 24, si DAS28-ESR \u22653,2 [2]. &#8220;Les auteurs concluent que la trith\u00e9rapie et la suppl\u00e9mentation en \u00e9tanercept sont comparables en termes de r\u00e9sultats cliniques&#8221;, a d\u00e9clar\u00e9 le Dr Landew\u00e9. &#8220;Mais cette \u00e9tude suscite \u00e9galement des r\u00e9serves, car elle a \u00e9t\u00e9 con\u00e7ue pour comparer une th\u00e9rapie directe \u00e0 une th\u00e9rapie progressive, et non pas en premier lieu pour comparer une trith\u00e9rapie \u00e0 un compl\u00e9ment biologique. Cette \u00e9tude n&#8217;est donc pas non plus d&#8217;une grande utilit\u00e9 pour d\u00e9terminer si la trith\u00e9rapie est utile dans le traitement de la PR&#8221;. Il en va de m\u00eame pour l&#8217;\u00e9tude tREACH de 2013 [3].<br \/>\n&#8220;En fin de compte, m\u00eame la science et les essais randomis\u00e9s contr\u00f4l\u00e9s (RCT) sont toujours sujets \u00e0 interpr\u00e9tation, car ils sont exerc\u00e9s par des personnes et non par des machines. Ils ne peuvent donc pas \u00eatre consid\u00e9r\u00e9s comme les seules r\u00e9f\u00e9rences pour une recommandation, un compl\u00e9ment d&#8217;avis d&#8217;experts et de patients est n\u00e9cessaire dans tous les cas&#8221;, a conclu le Dr Landew\u00e9.<\/p>\n<h2 id=\"recommandations-ra-2013-quoi-de-neuf\">Recommandations RA 2013 : quoi de neuf ?<\/h2>\n<p>&#8220;Les recommandations de 2010 n&#8217;avaient pas pour but d&#8217;affirmer que la combinaison de traitements csDMARD \u00e9tait erron\u00e9e, mais qu&#8217;elle n&#8217;\u00e9tait pas n\u00e9cessaire&#8221;, a d\u00e9clar\u00e9 le professeur Josef Smolen, Vienne. Mais de nouvelles donn\u00e9es permettent d\u00e9sormais de pr\u00e9coniser un peu plus explicitement ces th\u00e9rapies combin\u00e9es. Selon le professeur Smolen, il faut mettre en perspective les recommandations EULAR 2013. Par rapport aux recommandations de 2010 :<br \/>\nles recommandations EULAR 2013 continuent de mettre l&#8217;accent sur l&#8217;efficacit\u00e9 des csDMARDS, y compris le traitement combin\u00e9 (premi\u00e8re ligne).<br \/>\nils consid\u00e8rent que tous les agents biologiques sont aussi efficaces et s\u00fbrs pour une th\u00e9rapie biologique initiale (seconde ligne).<br \/>\nils r\u00e9p\u00e8tent la pr\u00e9f\u00e9rence pour l&#8217;utilisation de biologica en combinaison avec le MTX, plut\u00f4t que la monoth\u00e9rapie.<br \/>\nils ne recommandent en aucun cas l&#8217;utilisation de Biologica comme strat\u00e9gie de premier DMARD.<br \/>\nils se penchent sur les biosimilaires et le tofacitinib.<\/p>\n<p>Par rapport \u00e0 la mise \u00e0 jour ACR 2012 :<\/p>\n<ul>\n<li>les recommandations 2013 de l&#8217;EULAR sont de nature plus g\u00e9n\u00e9rale. Ils n&#8217;\u00e9num\u00e8rent pas des sc\u00e9narios individuels.<\/li>\n<li>ils traitent des glucocortico\u00efdes, mais pas de la minocycline.<\/li>\n<li>ils ne recommandent pas l&#8217;utilisation de produits biologiques comme strat\u00e9gie de premier traitement. En effet, l&#8217;efficacit\u00e9 d&#8217;une strat\u00e9gie de traitement par cible avec ajout de m\u00e9dicaments biologiques apr\u00e8s une r\u00e9ponse insuffisante au MTX pr\u00e9sente des niveaux de preuve \u00e9lev\u00e9s.<\/li>\n<li>ils ne recommandent pas une monoth\u00e9rapie avec des inhibiteurs du TNF ou d&#8217;autres produits biologiques.<\/li>\n<\/ul>\n<p>&#8220;Dans l&#8217;ensemble, la mise \u00e0 jour EULAR 2013 a \u00e9t\u00e9 con\u00e7ue pour un large public cible. Elle s&#8217;adresse bien s\u00fbr aux rhumatologues, aux patients, aux m\u00e9decins, aux scientifiques, mais aussi \u00e0 d&#8217;autres repr\u00e9sentants du syst\u00e8me de sant\u00e9 tels que les directeurs d&#8217;h\u00f4pitaux, les assureurs maladie et les politiciens. Nous nous appuyons sur trois principes g\u00e9n\u00e9raux : D&#8217;une part, nous voulons examiner les objectifs de traitement, d&#8217;autre part, nous voulons pr\u00e9senter des approches th\u00e9rapeutiques et \u00e9valuer les risques qu&#8217;elles comportent, en nous penchant toujours sur les traitements conventionnels, biologiques, synth\u00e9tiques cibl\u00e9s et biosimilaires.&nbsp;  DMARD&#8221;, conclut le professeur Smolen. &#8220;Nos recommandations sont bas\u00e9es sur trois revues syst\u00e9matiques de la litt\u00e9rature : La premi\u00e8re portait sur les DMARD conventionnels, la deuxi\u00e8me sur les DMARD biologiques et la troisi\u00e8me sur les aspects de s\u00e9curit\u00e9&#8221;.<\/p>\n<p><em>Source : &#8220;Update of EULAR Rheumatoid Arthritis Management Recommendations&#8221;, EULAR, 12-15 juin 2013, Madrid<\/em><\/p>\n<p><strong>Litt\u00e9rature :<\/strong><\/p>\n<ol>\n<li>Van Vollenhoven RF, et al : Conventional combination treatment versus biological treatment in methotrexate-refractory early rheumatoid arthritis : 2 year follow-up of the randomised, non-blind, parallel-group Swefot trial. Lancet . 2012 May 5 ; 379(9827) : 1712-1720.<\/li>\n<li>Moreland LW, et al : A randomized comparative effectiveness study of oral triple therapy versus etanercept plus methotrexate in early aggressive rheumatoid arthritis : the treatment of Early Aggressive Rheumatoid Arthritis Trial. Arthritis Rheum. 2012 Sep ; 64(9) : 2824-35.<\/li>\n<li>Porter DR, et al : Step-up therapy remains an appropriate option. Ann Rheum Dis&nbsp; 2013 ; 72 : 72-78.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>En pr\u00e9sentant les nouvelles recommandations dans la prise en charge de la polyarthrite rhumato\u00efde, les intervenants de l&#8217;EULAR de cette ann\u00e9e ont notamment \u00e9voqu\u00e9 le r\u00f4le de la trith\u00e9rapie combin\u00e9e&hellip;<\/p>\n","protected":false},"author":4,"featured_media":35158,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Polyarthrite rhumato\u00efde","footnotes":""},"category":[11373,11535,11505,11549],"tags":[61496,17864,61503,19181,30645,13774,14272,17072,61509,61512,25977],"powerkit_post_featured":[],"class_list":["post-347208","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hematologie","category-rapports-de-congres","category-rhumatologie","category-rx-fr","tag-biologique","tag-dmard-fr","tag-essai-randomise-de-controle","tag-eular-fr","tag-guidelines-fr","tag-mtx-fr","tag-polyarthrite-rhumatoide","tag-risque-fr","tag-rtl-fr","tag-targeted-fr","tag-therapie-combinee","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:44:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":347213,"slug":"nuove-linee-guida-per-il-trattamento-e-la-stratificazione-del-rischio","post_title":"Nuove linee guida per il trattamento e la stratificazione del rischio","href":"https:\/\/medizinonline.com\/it\/nuove-linee-guida-per-il-trattamento-e-la-stratificazione-del-rischio\/"},"pt_PT":{"locale":"pt_PT","id":347176,"slug":"novas-directrizes-para-o-tratamento-e-estratificacao-de-riscos","post_title":"Novas directrizes para o tratamento e estratifica\u00e7\u00e3o de riscos","href":"https:\/\/medizinonline.com\/pt-pt\/novas-directrizes-para-o-tratamento-e-estratificacao-de-riscos\/"},"es_ES":{"locale":"es_ES","id":347186,"slug":"nuevas-directrices-para-el-tratamiento-y-la-estratificacion-del-riesgo","post_title":"Nuevas directrices para el tratamiento y la estratificaci\u00f3n del riesgo","href":"https:\/\/medizinonline.com\/es\/nuevas-directrices-para-el-tratamiento-y-la-estratificacion-del-riesgo\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/347208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=347208"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/347208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/35158"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=347208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=347208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=347208"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=347208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}