{"id":347573,"date":"2013-09-11T00:00:00","date_gmt":"2013-09-10T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/augmenter-la-sensibilisation-la-conformite-et-ladhesion\/"},"modified":"2013-09-11T00:00:00","modified_gmt":"2013-09-10T22:00:00","slug":"augmenter-la-sensibilisation-la-conformite-et-ladhesion","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/augmenter-la-sensibilisation-la-conformite-et-ladhesion\/","title":{"rendered":"Augmenter la sensibilisation, la conformit\u00e9 et l&#8217;adh\u00e9sion !"},"content":{"rendered":"<p><strong>Bien que de nombreux patients hypertendus effectuent des mesures r\u00e9guli\u00e8res de leur tension art\u00e9rielle \u00e0 domicile, une grande partie d&#8217;entre eux &#8211; 51% dans l&#8217;\u00e9tude SWISSHYPE publi\u00e9e en 2011 [1] &#8211; ne sont pas trait\u00e9s ou trait\u00e9s de mani\u00e8re ad\u00e9quate. n&#8217;atteint pas les valeurs de pression art\u00e9rielle cibles Cela s&#8217;explique d&#8217;une part par le manque de compliance et d&#8217;adh\u00e9rence de nombreux patients, mais aussi souvent par un traitement qui n&#8217;est pas d\u00e9velopp\u00e9 de mani\u00e8re optimale.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Une \u00e9quipe de l&#8217;Institut de m\u00e9decine g\u00e9n\u00e9rale de Zurich a d\u00e9montr\u00e9 qu&#8217;une intervention tr\u00e8s simple et peu co\u00fbteuse, \u00e0 savoir l&#8217;abaissement de la pression art\u00e9rielle, permettait de r\u00e9duire la pression art\u00e9rielle.<br \/>\nLa pression art\u00e9rielle est un indicateur important de la qualit\u00e9 de vie. -14&nbsp;mmHg, diast. -8 mmHg) [2, 3]. Les patients et les m\u00e9decins doivent \u00eatre conscients de l&#8217;importance de la pr\u00e9vention, d&#8217;une part en augmentant l&#8217;observance et l&#8217;adh\u00e9sion, et d&#8217;autre part en am\u00e9liorant la prise de conscience des patients et des m\u00e9decins.<\/p>\n<p>Pour \u00e9valuer les patients souffrant d&#8217;hypertension art\u00e9rielle, la mesure de la pression art\u00e9rielle sur 24 heures est une mesure efficace en termes de co\u00fbts et de temps. Les lignes directrices du NICE recommandent d&#8217;en effectuer une en premier lieu chez tous les patients pr\u00e9sentant une pression art\u00e9rielle &gt;140\/90&nbsp;mmHg [4]. Si la pression art\u00e9rielle moyenne dans cette mesure est de 135-150\/85-95&nbsp;mmHg, il est recommand\u00e9, chez les patients sans l\u00e9sion des organes terminaux et sans risque cardiovasculaire \u00e9lev\u00e9 (celui-ci peut \u00eatre d\u00e9termin\u00e9 par exemple \u00e0 l&#8217;aide du calculateur de risque AGLA, www.agla.ch), de ne prendre dans un premier temps que des mesures de style de vie. Si le patient pr\u00e9sente d\u00e9j\u00e0 des l\u00e9sions des organes terminaux et\/ou un risque cardiovasculaire accru, ou si les valeurs &gt;150\/95&nbsp;mmHg, il convient de commencer un traitement m\u00e9dicamenteux en plus des mesures de style de vie [4]. Lors du congr\u00e8s de la SSMI \u00e0 B\u00e2le, le Dr Thilo Burkhard, B\u00e2le, a recommand\u00e9 de toujours commencer par un antagoniste des r\u00e9cepteurs de l&#8217;angiotensine (ARA) ou un inhibiteur de l&#8217;ECA chez les patients jeunes (&lt;55 ans) et par un antagoniste du calcium chez les patients plus \u00e2g\u00e9s<strong>(figure 1<\/strong>) [4].<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-1595\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378.jpg\" width=\"993\" height=\"1088\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378.jpg 993w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378-800x877.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378-120x131.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378-90x99.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378-320x351.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/Drucksache_2013_7_44.jpg-271462_378-560x614.jpg 560w\" sizes=\"(max-width: 993px) 100vw, 993px\" \/><\/p>\n<p>Si la monoth\u00e9rapie n&#8217;est pas suffisante, les ARA ou les AINS sont utilis\u00e9s en premier lieu. Les inhibiteurs de l&#8217;ECA et les antagonistes du calcium sont combin\u00e9s et un diur\u00e9tique n&#8217;est ajout\u00e9 que dans un troisi\u00e8me temps, si n\u00e9cessaire [4]. Selon le Dr Burkhard, la plupart des patients ont besoin d&#8217;un traitement combin\u00e9 pour atteindre durablement les valeurs cibles de pression art\u00e9rielle. Il a donc recommand\u00e9, chez les patients souffrant d&#8217;une hypertension de grade 2 ou en pr\u00e9sence de l\u00e9sions des organes terminaux &#8211; en plus des mesures de style de vie qui en font toujours partie ! &#8211; d&#8217;envisager une th\u00e9rapie combin\u00e9e d\u00e8s le d\u00e9but. Les associations \u00e0 dose fixe contribuent \u00e0 am\u00e9liorer consid\u00e9rablement l&#8217;observance, en particulier chez les patients qui doivent prendre des m\u00e9dicaments suppl\u00e9mentaires.<\/p>\n<p><em>Source : &#8220;Traitement de l&#8217;hypertension au cabinet du m\u00e9decin g\u00e9n\u00e9raliste &#8211; Bien, mais peut-on faire mieux ?&#8221; Symposium satellite de la soci\u00e9t\u00e9 A. Menarini AG, Congr\u00e8s de la SSMI, 29-31 mai 2013, B\u00e2le<\/em><\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Brenner R, et al. : Swiss Med Wkly 2011 ; 141 : w13169.<\/li>\n<li>Steurer-Stey C, et al : Trials 2010 ; 11 : 38.<\/li>\n<li>Rosemann T : R\u00e9sultats de l&#8217;\u00e9tude CoCo. Expos\u00e9 sur le congr\u00e8s annuel de la SSMI 2013.<\/li>\n<li>NICE : CG127, 2011.  <a href=\"http:\/\/guidance.nice.org.uk\/CG127\" target=\"_blank\" rel=\"noopener\">http:\/\/guidance.nice.org.uk\/CG127<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Bien que de nombreux patients hypertendus effectuent des mesures r\u00e9guli\u00e8res de leur tension art\u00e9rielle \u00e0 domicile, une grande partie d&#8217;entre eux &#8211; 51% dans l&#8217;\u00e9tude SWISSHYPE publi\u00e9e en 2011 [1]&hellip;<\/p>\n","protected":false},"author":4,"featured_media":33193,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Traitement de l'hypertension","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11378,11434,11535,11549],"tags":[57853,15225,14154,13458,62921,24094,12573],"powerkit_post_featured":[],"class_list":["post-347573","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologie","category-nephrologie-fr","category-rapports-de-congres","category-rx-fr","tag-adherence-fr-2","tag-conformite","tag-diagnostic-fr","tag-hypertension-fr","tag-objectifs-glycemiques","tag-pression-arterielle","tag-therapie-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:24:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":347574,"slug":"aumenta-la-consapevolezza-la-conformita-e-laderenza","post_title":"Aumenta la consapevolezza, la conformit\u00e0 e l'aderenza!","href":"https:\/\/medizinonline.com\/it\/aumenta-la-consapevolezza-la-conformita-e-laderenza\/"},"pt_PT":{"locale":"pt_PT","id":347548,"slug":"aumentar-a-consciencializacao-o-cumprimento-e-a-aderencia","post_title":"Aumentar a consciencializa\u00e7\u00e3o, o cumprimento e a ader\u00eancia!","href":"https:\/\/medizinonline.com\/pt-pt\/aumentar-a-consciencializacao-o-cumprimento-e-a-aderencia\/"},"es_ES":{"locale":"es_ES","id":347558,"slug":"aumente-la-concienciacion-el-cumplimiento-y-la-adherencia","post_title":"Aumente la concienciaci\u00f3n, el cumplimiento y la adherencia","href":"https:\/\/medizinonline.com\/es\/aumente-la-concienciacion-el-cumplimiento-y-la-adherencia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/347573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=347573"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/347573\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=347573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=347573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=347573"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=347573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}