{"id":361104,"date":"2023-07-08T14:00:00","date_gmt":"2023-07-08T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/le-time-in-range-et-les-systemes-aid-gagnent-en-importance\/"},"modified":"2023-06-23T23:33:36","modified_gmt":"2023-06-23T21:33:36","slug":"le-time-in-range-et-les-systemes-aid-gagnent-en-importance","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/le-time-in-range-et-les-systemes-aid-gagnent-en-importance\/","title":{"rendered":"Le &#8220;Time in Range&#8221; et les syst\u00e8mes AID gagnent en importance"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Les syst\u00e8mes de mesure continue du glucose (CGM) et l&#8217;insulinoth\u00e9rapie assist\u00e9e par capteur sont d\u00e9j\u00e0 largement r\u00e9pandus. Les dispositifs d&#8217;administration automatis\u00e9e d&#8217;insuline (AID), tels que les AID hybrides ou en boucle ferm\u00e9e, joueront un r\u00f4le de plus en plus important \u00e0 l&#8217;avenir. Un param\u00e8tre important dans le contexte des syst\u00e8mes CGM est le &#8220;Time in Range&#8221;. Celle-ci refl\u00e8te l&#8217;ampleur de la variabilit\u00e9 du glucose sur un ou plusieurs jours.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">L&#8217;utilisation de la mesure continue du glucose (&#8220;Continuous glucose monitoring&#8221;, CGM) joue un r\u00f4le de plus en plus important dans la gestion du diab\u00e8te [1]. Il existe aujourd&#8217;hui une grande vari\u00e9t\u00e9 de syst\u00e8mes CGM. Le taux de glucose dans le liquide interstitiel du tissu adipeux sous-cutan\u00e9 est mesur\u00e9 \u00e0 l&#8217;aide d&#8217;un fil de d\u00e9tection fin. Cela signifie que ce n&#8217;est pas la glyc\u00e9mie qui est mesur\u00e9e, mais la glyc\u00e9mie tissulaire. Les syst\u00e8mes CGM permettent notamment de d\u00e9terminer le temps dans la plage cible (&#8220;Time in Range&#8221;, TIR)<strong> (Fig. 1, Fig. 2).<\/strong> Alors que l&#8217;<sub>HbA1c<\/sub> est le param\u00e8tre \u00e9tabli du contr\u00f4le m\u00e9tabolique \u00e0 long terme, la TIR permet de mesurer le contr\u00f4le du glucose \u00e0 court et moyen terme.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34.jpg\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-1160x1014.jpg\" alt=\"\" class=\"wp-image-360831\" width=\"580\" height=\"507\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-1160x1014.jpg 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-800x700.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-120x105.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-90x79.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-320x280.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-560x490.jpg 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-240x210.jpg 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-180x157.jpg 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-640x560.jpg 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34-1120x979.jpg 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb1_HP6_s34.jpg 1481w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"le-cgm-permet-detablir-des-profils-de-glucose-differencies\" class=\"wp-block-heading\">Le CGM permet d&#8217;\u00e9tablir des profils de glucose diff\u00e9renci\u00e9s<\/h3>\n\n<p class=\"wp-block-paragraph\">Les effets de la mesure continue du glucose sont moins accentu\u00e9s chez les patients dont le diab\u00e8te est d\u00e9j\u00e0 tr\u00e8s bien contr\u00f4l\u00e9 que dans les cas o\u00f9 ce n&#8217;est pas le cas, mais &#8220;la grande majorit\u00e9 de nos patients en b\u00e9n\u00e9ficient en termes de qualit\u00e9 de vie&#8221;, a soulign\u00e9 le Dr Sebastian Petry, de l&#8217;h\u00f4pital universitaire de Giessen et Marburg [2]. L&#8217;utilisation d&#8217;un syst\u00e8me CGM rend inutile la tenue d&#8217;un journal d\u00e9taill\u00e9 de la glyc\u00e9mie, car les quantit\u00e9s d&#8217;insuline et de glucides sont automatiquement enregistr\u00e9es lors de l&#8217;utilisation d&#8217;un calculateur de bolus et les donn\u00e9es glyc\u00e9miques sont directement saisies par le capteur [3]. Ces donn\u00e9es sont pr\u00e9sent\u00e9es sous forme num\u00e9rique ou visualis\u00e9e.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36.png\"><img decoding=\"async\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36.png\" alt=\"\" class=\"wp-image-360832 lazyload\" width=\"370\" height=\"557\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36.png 740w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-120x181.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-90x135.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-320x482.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-560x843.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-240x361.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-180x271.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/06\/abb2_HP6_s36-640x963.png 640w\" data-sizes=\"(max-width: 370px) 100vw, 370px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 370px; --smush-placeholder-aspect-ratio: 370\/557;\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"le-temps-passe-dans-la-zone-cible-est-correle-aux-complications-associees-au-diabete\" class=\"wp-block-heading\">Le temps pass\u00e9 dans la zone cible est corr\u00e9l\u00e9 aux complications associ\u00e9es au diab\u00e8te<\/h3>\n\n<p class=\"wp-block-paragraph\">En utilisant la mesure continue du glucose, il est possible de d\u00e9finir des zones cibles individuelles et la TIR permet une meilleure repr\u00e9sentation des hypoglyc\u00e9mies et de la variabilit\u00e9 du glucose que l&#8217;<sub>HbA1c<\/sub>. Plus le TIR est bas, plus la variabilit\u00e9 du glucose est \u00e9lev\u00e9e et plus le risque de complications hypo- et hyperglyc\u00e9miques est important [4]. Des \u00e9tudes montrent qu&#8217;il existe un lien entre un faible &#8220;Time in Range&#8221; et la r\u00e9tinopathie, la microalbuminurie et la neuropathie associ\u00e9es au diab\u00e8te [5]. Il a \u00e9galement \u00e9t\u00e9 d\u00e9montr\u00e9 empiriquement qu&#8217;une bonne TIR est n\u00e9gativement corr\u00e9l\u00e9e \u00e0 la survenue de complications diab\u00e9tiques \u00e0 long terme [1].  <\/p>\n\n<p class=\"wp-block-paragraph\">Les directives internationales recommandent de viser une valeur TIR d&#8217;au moins 70%. Cela signifie que plus de 70% des valeurs de glyc\u00e9mie au cours d&#8217;une journ\u00e9e se situent dans la plage cible<strong> (Fig. 2)<\/strong> [6]. En ce qui concerne la pr\u00e9vention des hypoglyc\u00e9mies, les directives de consensus ont propos\u00e9 comme valeur de r\u00e9f\u00e9rence moins de 4% de la journ\u00e9e en dessous de 70 mg\/dl et moins de 1% en dessous de 54 mg\/dl [6]. Le Dr Petry a soulign\u00e9 que les amplitudes des valeurs de glucose varient consid\u00e9rablement d&#8217;un individu \u00e0 l&#8217;autre [7]. Dans ce contexte, la TIR joue un r\u00f4le de plus en plus important. 11 \u00e0 12% de temps suppl\u00e9mentaire dans la zone cible, cela signifie 2 heures par jour et environ 14 heures par semaine, a fait remarquer le conf\u00e9rencier. Une TIR de 70% correspond approximativement \u00e0 un taux d&#8217;<sub>HbA1c<\/sub> de 7,0% (53 mmol\/mol) [6].  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-background\" style=\"background-color:#abb7c25c\"><tbody><tr><td><strong>Administration d&#8217;insuline : outre les pompes et les stylos, il existe d\u00e9sormais des &#8220;stylos intelligents&#8221;.<\/strong><br\/>Les &#8220;stylos intelligents&#8221; sont des applications innovantes de l&#8217;insuline r\u00e9cemment approuv\u00e9es. Les donn\u00e9es g\u00e9n\u00e9r\u00e9es concernant la dose d&#8217;insuline, le moment de l&#8217;injection et le type d&#8217;insuline sont transf\u00e9r\u00e9es via Internet vers le cloud ou inject\u00e9es dans des applications sp\u00e9ciales. Les stylos intelligents utilisent diff\u00e9rentes technologies pour d\u00e9terminer la quantit\u00e9 d&#8217;insuline d\u00e9livr\u00e9e par le stylo et la quantit\u00e9 d&#8217;insuline restante dans la cartouche d&#8217;insuline int\u00e9gr\u00e9e au stylo. Les donn\u00e9es relatives au moment o\u00f9 les patients s&#8217;injectent quelle insuline et \u00e0 quelle dose peuvent \u00eatre utilis\u00e9es pour optimiser l&#8217;insulinoth\u00e9rapie, par exemple en administrant davantage d&#8217;insuline prandiale. Cela est particuli\u00e8rement utile pour les patients qui suivent une insulinoth\u00e9rapie conventionnelle intensive (ICT) avec plusieurs applications de diff\u00e9rents types d&#8217;insuline par jour. Cela comble une lacune importante dans la gestion du diab\u00e8te.  <\/td><\/tr><tr><td><em>vers  [13]<\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h3 id=\"les-diabetiques-de-type-1-et-de-type-2-peuvent-en-beneficier\" class=\"wp-block-heading\">Les diab\u00e9tiques de type 1 et de type 2 peuvent en b\u00e9n\u00e9ficier<\/h3>\n\n<p class=\"wp-block-paragraph\">Le taux d&#8217;utilisation de ces technologies avanc\u00e9es est particuli\u00e8rement \u00e9lev\u00e9 chez les patients p\u00e9diatriques atteints de diab\u00e8te de type 1. [3]. Environ 80% des diab\u00e9tiques utilisent des capteurs de glucose, a rapport\u00e9 le Dr Petry. [2]. Il a donn\u00e9 un bref aper\u00e7u du d\u00e9veloppement des technologies modernes de lutte contre le diab\u00e8te. La th\u00e9rapie par pompe assist\u00e9e par capteur a \u00e9t\u00e9 suivie par l&#8217;arr\u00eat automatique de l&#8217;hypoglyc\u00e9mie  <\/p>\n\n<p class=\"wp-block-paragraph\">\u00e0 titre indicatif, moins de 4% de la journ\u00e9e en dessous de 70 mg\/dl et moins de 1% en dessous de 54 mg\/dl sont propos\u00e9s [6]. Le Dr Petry a soulign\u00e9 que les amplitudes des valeurs de glucose varient consid\u00e9rablement d&#8217;un individu \u00e0 l&#8217;autre [7]. Dans ce contexte, la TIR joue un r\u00f4le de plus en plus important. Si 11 \u00e0 12% de temps suppl\u00e9mentaire est atteint dans la zone cible, cela signifie 2 h par jour et environ 14 h par semaine, a fait remarquer l&#8217;orateur. Une TIR de 70% correspond approximativement \u00e0 un taux d&#8217;<sub>HbA1c<\/sub> de 7,0% (53 mmol\/mol) [6].<\/p>\n\n<h3 id=\"les-diabetiques-de-type-1-et-de-type-2-peuvent-en-beneficier-2\" class=\"wp-block-heading\">Les diab\u00e9tiques de type 1 et de type 2 peuvent en b\u00e9n\u00e9ficier<\/h3>\n\n<p class=\"wp-block-paragraph\">Le taux d&#8217;utilisation de ces technologies avanc\u00e9es est particuli\u00e8rement \u00e9lev\u00e9 chez les patients p\u00e9diatriques atteints de diab\u00e8te de type 1 [3]. Environ 80% des diab\u00e9tiques utilisent des capteurs de glucose, a rapport\u00e9 le Dr Petry [2]. Il a donn\u00e9 un bref aper\u00e7u du d\u00e9veloppement des technologies modernes de lutte contre le diab\u00e8te. La th\u00e9rapie par pompe assist\u00e9e par capteur a \u00e9t\u00e9 suivie par l&#8217;arr\u00eat automatique de l&#8217;hypoglyc\u00e9mie et l&#8217;\u00e9tape suivante a consist\u00e9 \u00e0 d\u00e9velopper l&#8217;arr\u00eat pr\u00e9dictif de l&#8217;hypoglyc\u00e9mie. Cette derni\u00e8re interrompt l&#8217;administration d&#8217;insuline avant m\u00eame qu&#8217;un \u00e9v\u00e9nement hypoglyc\u00e9mique ne se produise.<\/p>\n\n<p class=\"wp-block-paragraph\">Le lancement des syst\u00e8mes AID hybrides a constitu\u00e9 une \u00e9tape importante. Il s&#8217;agit de syst\u00e8mes semi-ouverts dans lesquels la part d&#8217;insuline basale non alimentaire est administr\u00e9e automatiquement de mani\u00e8re adaptative, tandis que l&#8217;administration manuelle du bolus d&#8217;insuline se fait au moment des repas. Dans les AID &#8220;Advanced Hybrid&#8221;, le contr\u00f4le de l&#8217;insuline basale et de l&#8217;insuline de correction est automatis\u00e9. Et l&#8217;administration prandiale enti\u00e8rement automatique d&#8217;insuline est appel\u00e9e &#8220;boucle ferm\u00e9e&#8221;. Alors que des algorithmes PID ou MPC sont utilis\u00e9s pour les syst\u00e8mes semi-ouverts, des algorithmes plus complexes sont n\u00e9cessaires pour les syst\u00e8mes ferm\u00e9s, explique l&#8217;orateur.  <\/p>\n\n<p class=\"wp-block-paragraph\">Dans le diab\u00e8te de type 2, la variabilit\u00e9 glyc\u00e9mique et les hypoglyc\u00e9mies sont g\u00e9n\u00e9ralement moins prononc\u00e9es que dans le diab\u00e8te de type 1 [8]. Mais il existe de nombreux r\u00e9sultats d&#8217;\u00e9tudes qui montrent que les diab\u00e9tiques de type 2 b\u00e9n\u00e9ficient \u00e9galement des syst\u00e8mes CGM. Par exemple, dans une \u00e9tude randomis\u00e9e et contr\u00f4l\u00e9e, une r\u00e9duction significative de l&#8217;<sub>HbA1c<\/sub> a \u00e9t\u00e9 obtenue chez des diab\u00e9tiques de type 2 insulinod\u00e9pendants dont le diab\u00e8te \u00e9tait mal contr\u00f4l\u00e9 et qui utilisaient le rtCGM [9]. En ce qui concerne les patients DT2 sans insulinoth\u00e9rapie complexe, certaines \u00e9tudes indiquent une am\u00e9lioration du contr\u00f4le glyc\u00e9mique et du contr\u00f4le du poids gr\u00e2ce \u00e0 l&#8217;utilisation de syst\u00e8mes CGM [10,11].  <\/p>\n\n<p class=\"wp-block-paragraph\">Comme l&#8217;indiquent les recommandations de la SSED pour le traitement du diab\u00e8te de type 2, mises \u00e0 jour en 2023, un taux d&#8217;<sub>HbA1c<\/sub> satisfaisant est atteint dans la plupart des cas lorsque \u226570% des heures dans la plage cible <em>(Time in Range,<\/em> TIR) pr\u00e9sentent une valeur comprise entre 3,9 et 10 mmol\/l [12].  <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Congr\u00e8s : Congr\u00e8s de la DGIM  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Litt\u00e9rature :<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Harer C, Mader JK : &#8220;Time in range&#8221; (TIR) vs. glycoh\u00e9moglobine de type A1c (HbA1c) : qu&#8217;est-ce qui compte pour nos patients ? Diab\u00e9tologie 2022(18) : 894-901.  <\/li>\n\n\n\n<li>&#8220;Syst\u00e8mes ferm\u00e9s pour le traitement du diab\u00e8te sucr\u00e9&#8221;, Dr. med. Sebastian Petry, session : Applications num\u00e9riques en m\u00e9decine interne, Congr\u00e8s DGIM, 22.04.2023.<\/li>\n\n\n\n<li>Biester T, et al. : Syst\u00e8mes AID (&#8220;automated insulin delivery&#8221;) en diab\u00e9tologie. Diab\u00e9tologue 2021(17) : 627-637.  <\/li>\n\n\n\n<li>Sartore G, et al : L&#8217;importance de l&#8217;HbA1c et de la variabilit\u00e9 du glucose chez les patients atteints de diab\u00e8te de type 1 et de type 2 : r\u00e9sultats de la surveillance continue du glucose (CGM). Acta Diabetologica 2012 ; 49 (Suppl 1) : S153-60.  <\/li>\n\n\n\n<li>Smith-Palmer J, et al : Assessment of the association between glycemic variability and diabetes-related complications in type 1 and type 2 diabetes. Diabetes Res Clin Pract 2014 ; 105(3) : 273-284.  <\/li>\n\n\n\n<li>Battelino T, et al : Cibles cliniques pour l&#8217;interpr\u00e9tation des donn\u00e9es de surveillance continue du glucose : recommandations du consensus international sur le temps dans l&#8217;intervalle. Diabetes Care 2019 ; 42(8) : 1593-1603.<\/li>\n\n\n\n<li>Philip M, et al : Recommandations de consensus pour l&#8217;utilisation des technologies d&#8217;administration automatis\u00e9e d&#8217;insuline dans la pratique clinique. Endocr Rev 2023 ; 44(2) : 254-280.<\/li>\n\n\n\n<li>Rama Chandran S, et al : Beyond HbA1c : Comparing Glycemic Variability and Glycemic Indices in Predicting Hypoglycemia in Type 1 and Type 2 Diabetes. Diabetes Technol Ther 2018 ; 20 (5) : 353-362.  <\/li>\n\n\n\n<li>Martens T, et al : Effect of continuous glucose monitoring on glycemic control in patients with type 2 diabetes treated with basal insulin : a randomized clinical trial. JAMA 2021 ; 325(22) : 2262-2272.<\/li>\n\n\n\n<li>Taylor PJ, Thompson CH, Brinkworth GD : Efficacit\u00e9 et acceptabilit\u00e9 du monitoring continu du glucose pour la gestion du diab\u00e8te de type 2 : A narrative review. J Diabetes Investig 2018 ; 9(4) : 713-725.<\/li>\n\n\n\n<li>Pickup JC, et al : Contr\u00f4le glyc\u00e9mique pendant une perfusion continue d&#8217;insuline sous-cutan\u00e9e versus de multiples injections quotidiennes d&#8217;insuline dans le diab\u00e8te de type 2 : m\u00e9ta-analyse des donn\u00e9es individuelles des patients et m\u00e9ta-r\u00e9gression des essais contr\u00f4l\u00e9s randomis\u00e9s. Diabetes Care 2017. doi : 10.2337\/dc16-2201<\/li>\n\n\n\n<li>Gastaldi G, et al. : Recommandations de la Soci\u00e9t\u00e9 suisse d&#8217;endocrinologie et de diab\u00e9tologie (SGED\/SSED) pour le traitement du diab\u00e8te sucr\u00e9 de type 2, 2023, www.sgedssed.ch, (derni\u00e8re consultation 06.06.2023).  <\/li>\n\n\n\n<li>&#8220;Stylos intelligents : une nouvelle \u00e8re commence !&#8221;, <a href=\"http:\/\/www.diabetologie-online.de\/a\/kommentar-smart-pens-eine-neue-aera-beginnt-239601\" target=\"_blank\" rel=\"noreferrer noopener\">www.diabetologie-online.de\/a\/kommentar-smart-pens-eine-neue-aera-beginnt-2396013,<\/a>(derni\u00e8re consultation le 06.06.2023).<\/li>\n<\/ol>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>HAUSARZT PRAXIS 2023 ; 18(6) : 34-35 (publi\u00e9 le 23.6.23, ahead of print)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les syst\u00e8mes de mesure continue du glucose (CGM) et l&#8217;insulinoth\u00e9rapie assist\u00e9e par capteur sont d\u00e9j\u00e0 largement r\u00e9pandus. Les dispositifs d&#8217;administration automatis\u00e9e d&#8217;insuline (AID), tels que les AID hybrides ou en&hellip;<\/p>\n","protected":false},"author":7,"featured_media":361138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Traitement du diab\u00e8te adapt\u00e9 au patient  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11404,11527,11253,11535,11549],"tags":[13608,69616,69598,69626,35674,15500,69604,69621,69613,28163,25207,69610],"powerkit_post_featured":[],"class_list":["post-361104","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologie-et-diabetologie","category-etudes","category-non-classifiee","category-rapports-de-congres","category-rx-fr","tag-aid-fr","tag-aid-hybride","tag-boucle-fermee-fr","tag-cgm-fr","tag-complications-fr","tag-dgim-fr","tag-insulinotherapie-assistee-par-capteur","tag-mesure-continue-du-glucose","tag-systemes-aid","tag-time-in-range-fr","tag-traitement-du-diabete","tag-variabilite-du-glucose","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:44:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":361156,"slug":"il-time-in-range-e-i-sistemi-aid-stanno-acquisendo-importanza","post_title":"Il \"Time in Range\" e i sistemi AID stanno acquisendo importanza.","href":"https:\/\/medizinonline.com\/it\/il-time-in-range-e-i-sistemi-aid-stanno-acquisendo-importanza\/"},"pt_PT":{"locale":"pt_PT","id":360981,"slug":"os-sistemas-time-in-range-e-aid-estao-a-ganhar-importancia","post_title":"Os sistemas \"Time in Range\" e AID est\u00e3o a ganhar import\u00e2ncia","href":"https:\/\/medizinonline.com\/pt-pt\/os-sistemas-time-in-range-e-aid-estao-a-ganhar-importancia\/"},"es_ES":{"locale":"es_ES","id":361034,"slug":"los-sistemas-de-tiempo-en-el-campo-de-tiro-y-aid-ganan-en-importancia","post_title":"Los sistemas de \"tiempo en el campo de tiro\" y AID ganan en importancia","href":"https:\/\/medizinonline.com\/es\/los-sistemas-de-tiempo-en-el-campo-de-tiro-y-aid-ganan-en-importancia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/361104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=361104"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/361104\/revisions"}],"predecessor-version":[{"id":361151,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/361104\/revisions\/361151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/361138"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=361104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=361104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=361104"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=361104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}