{"id":364166,"date":"2023-09-17T14:00:00","date_gmt":"2023-09-17T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/prevenir-les-exacerbations-et-ameliorer-la-qualite-de-vie\/"},"modified":"2023-09-17T14:15:20","modified_gmt":"2023-09-17T12:15:20","slug":"prevenir-les-exacerbations-et-ameliorer-la-qualite-de-vie","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/prevenir-les-exacerbations-et-ameliorer-la-qualite-de-vie\/","title":{"rendered":"Pr\u00e9venir les exacerbations et am\u00e9liorer la qualit\u00e9 de vie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Pour obtenir une r\u00e9duction de la fr\u00e9quence des exacerbations &#8211; un objectif th\u00e9rapeutique prioritaire dans la BPCO &#8211; il est recommand\u00e9 d&#8217;adopter une approche th\u00e9rapeutique multimodale. En ce qui concerne les traitements bronchodilatateurs par inhalation, les SABA et les SAMA ne sont aujourd&#8217;hui recommand\u00e9s qu&#8217;en cas de besoin, le traitement \u00e0 long terme \u00e9tant assur\u00e9 par les LABA et les LAMA. Dans certains cas, une bith\u00e9rapie ou une trith\u00e9rapie \u00e0 base de cortisone peut \u00e9galement \u00eatre utile. L&#8217;\u00e9ducation des patients, l&#8217;arr\u00eat du tabac et la r\u00e9adaptation pulmonaire sont d&#8217;autres composantes importantes du traitement.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Les patients chez qui une BPCO <em>(maladie pulmonaire obstructive chronique)<\/em> est diagnostiqu\u00e9e dans le cadre de l&#8217;examen m\u00e9dical se plaignent le plus souvent d&#8217;un manque d&#8217;air. La dyspn\u00e9e est un sympt\u00f4me lourd de cons\u00e9quences. Il peut y avoir une r\u00e9duction de l&#8217;activit\u00e9 et un retrait social, accompagn\u00e9s d&#8217;une diminution des performances et d&#8217;un risque accru de sympt\u00f4mes d&#8217;anxi\u00e9t\u00e9 et de d\u00e9pression. &#8220;Il est important de briser cette spirale descendante \u00e0 un stade pr\u00e9coce&#8221;, explique le Dr Carolin Steinack, m\u00e9decin-chef, Clinique de pneumologie, H\u00f4pital universitaire de Zurich [1]. Selon l&#8217;OMS, la BPCO est aujourd&#8217;hui la quatri\u00e8me cause de mortalit\u00e9 dans le monde. &#8220;Un diagnostic et un traitement pr\u00e9coces sont certainement un objectif important&#8221;, a d\u00e9clar\u00e9 l&#8217;intervenante [1].  <\/p>\n\n<h3 id=\"arret-du-tabac-et-readaptation-pulmonaire-elementaires-mais-essentiels\" class=\"wp-block-heading\">Arr\u00eat du tabac et r\u00e9adaptation pulmonaire &#8211; \u00e9l\u00e9mentaires, mais essentiels  <\/h3>\n\n<p class=\"wp-block-paragraph\">Bien qu&#8217;il existe d&#8217;autres facteurs de risque, tels que des facteurs g\u00e9n\u00e9tiques, des \u00e9v\u00e9nements survenus dans la petite enfance, des infections subies et des facteurs environnementaux, la cigarette reste la cause la plus fr\u00e9quente de BPCO en Europe [2]. &#8220;Veuillez demander activement si vous fumez&#8221;, a soulign\u00e9 le Dr Steinack [1]. Cela vaut \u00e9galement pour les rechutes au cours du traitement. Les patients peuvent avoir besoin d&#8217;aide pour arr\u00eater de fumer. Mais la BPCO s&#8217;accompagne \u00e9galement d&#8217;atteintes extrapulmonaires. La r\u00e9adaptation pulmonaire &#8211; une autre mesure importante du mode de vie dans la BPCO &#8211; consiste \u00e9galement \u00e0 faire travailler les muscles et la condition physique afin de r\u00e9duire la dyspn\u00e9e et les limitations cardiovasculaires. Il est important que les patients atteints de BPCO soient encourag\u00e9s \u00e0 pratiquer des activit\u00e9s pr\u00e9coces pendant leur hospitalisation ou qu&#8217;ils puissent participer \u00e0 des programmes de r\u00e9\u00e9ducation en ambulatoire. Une m\u00e9ta-analyse publi\u00e9e en 2016, bas\u00e9e sur plusieurs \u00e9tudes randomis\u00e9es contr\u00f4l\u00e9es incluant la r\u00e9adaptation pulmonaire apr\u00e8s exacerbation, montre que cela en vaut la peine [3]. &#8220;Cette m\u00e9ta-analyse, qui a inclus une vingtaine d&#8217;\u00e9tudes portant sur plus de 1500 patients, a pu d\u00e9montrer que les patients qui b\u00e9n\u00e9ficient d&#8217;une r\u00e9\u00e9ducation ont un b\u00e9n\u00e9fice significatif par rapport \u00e0 ceux qui n&#8217;en b\u00e9n\u00e9ficient pas&#8221;, a rapport\u00e9 l&#8217;intervenante [1]. C&#8217;est ce que montrent les analyses concernant la qualit\u00e9 de vie<em> (St George&#8217;s Respiratory Questionnaire,<\/em> SGRQ) et le test de marche de 6 minutes. En outre, le risque de r\u00e9hospitalisation en raison d&#8217;une nouvelle exacerbation a pu \u00eatre massivement r\u00e9duit au cours de la premi\u00e8re ann\u00e9e suivant une exacerbation. En r\u00e9sum\u00e9, la r\u00e9adaptation pulmonaire contribue \u00e0 r\u00e9duire la morbidit\u00e9 et la mortalit\u00e9.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-table\"><table class=\"has-background\" style=\"background-color:#8dd2fc5e\"><tbody><tr><td><strong>Syst\u00e8mes d&#8217;inhalation et oxyg\u00e9noth\u00e9rapie &#8211; l&#8217;\u00e9ducation des patients est n\u00e9cessaire<\/strong><br \/>Dans l&#8217;accompagnement des patients atteints de BPCO, il s&#8217;agit \u00e0 chaque fois de pouvoir proposer un traitement adapt\u00e9 au stade du patient. Certains patients peuvent tirer un grand b\u00e9n\u00e9fice de l&#8217;oxyg\u00e9noth\u00e9rapie. L&#8217;oxyg\u00e8ne est consid\u00e9r\u00e9 comme un dispositif m\u00e9dical soumis \u00e0 prescription m\u00e9dicale. Si l&#8217;on prescrit une oxyg\u00e9noth\u00e9rapie, il convient d&#8217;effectuer de temps en temps une analyse des gaz du sang art\u00e9riel, car il faut \u00e9viter une<sub>augmentation du CO2<\/sub>. En ce qui concerne les th\u00e9rapies par inhalation, il existe aujourd&#8217;hui une large gamme de pr\u00e9parations et d&#8217;inhalateurs. De nombreux patients pr\u00e9f\u00e8rent les pr\u00e9parations combin\u00e9es afin de ne pas avoir \u00e0 utiliser plusieurs inhalateurs. &#8220;L&#8217;inhalation n&#8217;est pas du tout facile&#8221;, explique le Dr Steinack. L&#8217;instruction de la technique d&#8217;inhalation correcte est un \u00e9l\u00e9ment important de la th\u00e9rapie. Pour s&#8217;assurer que les mol\u00e9cules inhal\u00e9es atteignent r\u00e9ellement les poumons, les a\u00e9rosols-doseurs utilisent parfois certains accessoires, comme une chambre d&#8217;amor\u00e7age. &#8220;Chez les patients tr\u00e8s avanc\u00e9s, nous utilisons aussi volontiers des inhalateurs humides, appel\u00e9s n\u00e9buliseurs&#8221;, a rapport\u00e9 le m\u00e9decin-chef de la clinique de pneumologie de l&#8217;h\u00f4pital universitaire de Zurich. Ces n\u00e9buliseurs facilitent l&#8217;inhalation ad\u00e9quate pour les patients \u00e0 un stade avanc\u00e9 ou pendant les exacerbations.  <\/td><\/tr><tr><td><em>d&#8217;apr\u00e8s [1] <\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h3 id=\"les-exacerbations-sont-associees-a-une-deterioration-de-la-fonction-pulmonaire\" class=\"wp-block-heading\">Les exacerbations sont associ\u00e9es \u00e0 une d\u00e9t\u00e9rioration de la fonction pulmonaire  <\/h3>\n\n<p class=\"wp-block-paragraph\">Il faut toujours v\u00e9rifier chez chaque patient quel est le stade de la maladie et si un ajustement du traitement est n\u00e9cessaire. L&#8217;impact des exacerbations est consid\u00e9rable. Plus de 77% des patients souffrent d&#8217;une exacerbation s\u00e9v\u00e8re ou mod\u00e9r\u00e9e au cours des trois premi\u00e8res ann\u00e9es suivant le diagnostic de BPCO. En cas d&#8217;exacerbation grave, une hospitalisation est souvent n\u00e9cessaire et il existe un risque d&#8217;alt\u00e9ration persistante de la fonction pulmonaire. Les r\u00e9sultats des \u00e9tudes indiquent que la fonction pulmonaire est encore nettement inf\u00e9rieure \u00e0 la normale individuelle 8 semaines apr\u00e8s une exacerbation aigu\u00eb [4]. Chaque exacerbation peut r\u00e9duire le d\u00e9lai jusqu&#8217;\u00e0 la prochaine exacerbation grave ou jusqu&#8217;au d\u00e9c\u00e8s [5]. Les \u00e9osinophiles sanguins sont un trait traitable. &#8220;Les \u00e9osinophiles sanguins sont souvent associ\u00e9s \u00e0 des exacerbations plus graves et plus fr\u00e9quentes&#8221;, a expliqu\u00e9 le Dr Steinack [1]. Il s&#8217;agit d&#8217;un corr\u00e9lat de l&#8217;\u00e9tendue de l&#8217;inflammation dans les bronches. Dans le cadre d&#8217;un traitement individualis\u00e9, il serait judicieux de d\u00e9terminer les \u00e9osinophiles sanguins (ceux-ci sont corr\u00e9l\u00e9s aux \u00e9osinophiles sput\u00e9s) et d&#8217;envisager, le cas \u00e9ch\u00e9ant, une extension du traitement en cas d&#8217;\u00e9osinophilie \u00e9lev\u00e9e.  <\/p>\n\n<h3 id=\"therapie-par-inhalation-differencier-la-medication-a-la-demande-de-la-medication-de-base\" class=\"wp-block-heading\">Th\u00e9rapie par inhalation &#8211; diff\u00e9rencier la m\u00e9dication \u00e0 la demande de la m\u00e9dication de base  <\/h3>\n\n<p class=\"wp-block-paragraph\">Un algorithme th\u00e9rapeutique bas\u00e9 sur des preuves est pr\u00e9sent\u00e9 dans la<strong> figure 1 <\/strong> [12]. Les anticholinergiques \u00e0 courte dur\u00e9e d&#8217;action (SAMA) et les b\u00eata-agonistes (SABA) conviennent pour le traitement intermittent \u00e0 la demande dans les stades initiaux de la maladie et, le cas \u00e9ch\u00e9ant, comme m\u00e9dicament d&#8217;urgence en cas d&#8217;exacerbation, mais pas pour le traitement de fond [6]. Les bronchodilatateurs \u00e0 longue dur\u00e9e d&#8217;action sont recommand\u00e9s \u00e0 la place : Les anticholinergiques \u00e0 longue dur\u00e9e d&#8217;action <em>( <\/em>LAMA) et les b\u00eata-agonistes \u00e0 longue dur\u00e9e d&#8217;action <em>( <\/em>LABA) sont les m\u00e9dicaments de base chez les patients symptomatiques pr\u00e9sentant une obstruction l\u00e9g\u00e8re ou mod\u00e9r\u00e9e, avec ou sans exacerbations fr\u00e9quentes [6,7]. Les associations LAMA\/LABA sont autoris\u00e9es en Suisse en tant que traitement de deuxi\u00e8me ligne pour les patients qui continuent \u00e0 pr\u00e9senter des sympt\u00f4mes avec une monoth\u00e9rapie. Les associations LAMA\/LABA ont montr\u00e9 un effet suppl\u00e9mentaire mod\u00e9r\u00e9 par rapport \u00e0 une monoth\u00e9rapie bronchodilatatrice en termes de fonction pulmonaire, de qualit\u00e9 de vie et de pr\u00e9vention des exacerbations.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31.png\"><img decoding=\"async\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31.png\" alt=\"\" class=\"wp-image-363852 lazyload\" style=\"--smush-placeholder-width: 2183px; --smush-placeholder-aspect-ratio: 2183\/1873;width:500px\" width=\"500\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31.png 2183w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-800x686.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-1160x995.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-2048x1757.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-120x103.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-90x77.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-320x275.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-560x480.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-1920x1647.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-240x206.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-180x154.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-640x549.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-1120x961.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/08\/abb1_HP8_s31-1600x1373.png 1600w\" data-sizes=\"(max-width: 2183px) 100vw, 2183px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"qui-beneficie-dune-bitherapie-ou-dune-tritherapie-a-base-de-cortisone\" class=\"wp-block-heading\">Qui b\u00e9n\u00e9ficie d&#8217;une bith\u00e9rapie ou d&#8217;une trith\u00e9rapie \u00e0 base de cortisone ?  <\/h3>\n\n<p class=\"wp-block-paragraph\">L&#8217;association CSI\/LABA n&#8217;est indiqu\u00e9e chez les patients atteints de BPCO que dans certaines conditions : BPCO mod\u00e9r\u00e9e \u00e0 s\u00e9v\u00e8re avec au moins une exacerbation mod\u00e9r\u00e9e par an ou lorsqu&#8217;il existe un chevauchement asthme-BPCO. Chez les patients symptomatiques qui, malgr\u00e9 un traitement d&#8217;entretien par LAMA+LABA ou LABA+ICS, ont eu au moins une exacerbation s\u00e9v\u00e8re au cours des 12 derniers mois, le traitement par une triple association CSI\/LAMA\/LABA semble avoir un effet suppl\u00e9mentaire sur le taux d&#8217;exacerbation par rapport \u00e0 la double association [6]. C&#8217;est ce qui ressort notamment de l&#8217;\u00e9tude IMPACT [8,9]. Il s&#8217;agissait d&#8217;une \u00e9tude multicentrique randomis\u00e9e et contr\u00f4l\u00e9e en groupes parall\u00e8les (n=10 355) avec trois bras d&#8217;\u00e9tude. Les taux annuels d&#8217;exacerbation et de mortalit\u00e9 ont \u00e9t\u00e9 consid\u00e9rablement r\u00e9duits par la trith\u00e9rapie fluticasone furoate\/um\u00e9clidinium\/vilanterol par rapport \u00e0 l&#8217;um\u00e9clidinium\/vilanterol et au fluticasone furoate\/vilanterol chez les patients BPCO symptomatiques ayant eu au moins une exacerbation s\u00e9v\u00e8re au cours de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente [1,8,10,11]. Les cas n\u00e9cessitant une hospitalisation ont \u00e9t\u00e9 \u00e9valu\u00e9s comme exacerbation s\u00e9v\u00e8re. Par ailleurs, il existe des preuves que les patients pr\u00e9sentant une \u00e9osinophilie \u2265150 cellules\/\u03bcl \u00e0 la ligne de base b\u00e9n\u00e9ficient particuli\u00e8rement d&#8217;une trith\u00e9rapie \u00e0 base de cortisone.<\/p>\n\n<p class=\"wp-block-paragraph\">Litt\u00e9rature : <\/p>\n\n<ol class=\"wp-block-list\">\n<li>\u00abFr\u00fcher Behandlungsbeginn und relevante Eskalation im Management von COPD\u00bb, Dr. med. Carolin \u00adSteinack, FomF Fortbildung, WebUp, 15.06.2023.<\/li>\n\n\n\n<li>Stolz D, et al.: Towards the elimination of chronic obstructive pulmonary disease: a Lancet Commission. Lancet 2022; 400(10356): 921\u2013972.<\/li>\n\n\n\n<li>Puhan MA, et al.: Pulmonary rehabilitation following exacerbations of chronic obstructive pulmonary disease. Cochrane Database Syst Rev 2016 Dec 8;12(12): CD005305.<\/li>\n\n\n\n<li>Watz H, et al.: Spirometric changes during exacerbations of COPD: a post hoc analysis of the WISDOM trial. Respir Res 2018; 19(1): 251.<\/li>\n\n\n\n<li>Suissa S, Dell\u2019Aniello S, Ernst P: Long-term natural history of chronic obstructive pulmonary disease: severe exacerbations and mortality. Thorax 2012; 67(11): 957\u2013963.<\/li>\n\n\n\n<li>COPD, <a href=\"http:\/\/www.medix.ch\/wissen\/guidelines\/copd\" target=\"_blank\" rel=\"noopener\">www.medix.ch\/wissen\/guidelines\/copd,<\/a>(derni\u00e8re consultation 12.07.2023) <\/li>\n\n\n\n<li>Agust\u00ed A, et al.: Global Initiative for Chronic Obstructive Lung Disease 2023 Report: GOLD Executive Summary. Am J Respir Crit Care Med 2023; 207(7): 819\u2013837.<\/li>\n\n\n\n<li>Pascoe SJ, et al.: A phase III randomised controlled trial of single-dose triple therapy in COPD: the IMPACT protocol. Eur Respir J 2016; 48(2): 320\u2013330. <\/li>\n\n\n\n<li>Lipson DA, et al.: IMPACT Investigators. Once-Daily Single-Inhaler Triple versus Dual Therapy in Patients with COPD. N Engl J Med 2018; 378(18): 1671-1680.<\/li>\n\n\n\n<li>Lipson DA, et al.: Reduction in All-Cause Mortality with Fluticasone Furoate\/Umeclidinium\/Vilanterol in Pa\u00adtients with Chronic Obstructive Pulmonary Disease. Am J Respir Crit Care Med 2020; 201(12): 1508\u20131516.<\/li>\n\n\n\n<li>GOLD Report 2020, <a href=\"http:\/\/goldcopd.org\" target=\"_blank\" rel=\"noopener\">http:\/\/goldcopd.org<\/a>, (derni\u00e8re consultation 12.07.2023)<\/li>\n\n\n\n<li>Nationale Versorgungsleitlinie COPD, 2021,<br \/><a href=\"http:\/\/www.leitlinien.de\/themen\/copd\/2-auflage\/kapitel-5\" target=\"_blank\" rel=\"noopener\">www.leitlinien.de\/themen\/copd\/2-auflage\/kapitel-5<\/a>, (derni\u00e8re consultation 12.07.2023).<\/li>\n<\/ol>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>HAUSARZT PRAXIS 2023; 18(8): 30\u201331<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour obtenir une r\u00e9duction de la fr\u00e9quence des exacerbations &#8211; un objectif th\u00e9rapeutique prioritaire dans la BPCO &#8211; il est recommand\u00e9 d&#8217;adopter une approche th\u00e9rapeutique multimodale. En ce qui concerne&hellip;<\/p>\n","protected":false},"author":7,"featured_media":364192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"BPCO : mise \u00e0 jour pour le m\u00e9decin g\u00e9n\u00e9raliste  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11315,11477,11535,11549],"tags":[70494,70488,70482,70475,12093,70498,61938,11919,18866,6978,3173,70241,6756,6755,8647,8646],"powerkit_post_featured":[],"class_list":["post-364166","post","type-post","status-publish","format-standard","has-post-thumbnail","category-medecine-interne-generale","category-pneumologie-fr","category-rapports-de-congres","category-rx-fr","tag-anticholinergiques-a-courte-duree-daction","tag-anticholinergiques-a-longue-duree-daction","tag-beta-2-sympathomimetiques-a-action-prolongee","tag-beta-2-sympathomimetiques-a-courte-duree-daction","tag-bpco","tag-combinaison-double","tag-combinaison-triple","tag-corticosteroide","tag-exacerbations","tag-ics","tag-inhalation","tag-inhalatives","tag-laba","tag-lama","tag-saba","tag-sama","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 10:36:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":364201,"slug":"contrastare-le-esacerbazioni-e-migliorare-la-qualita-della-vita","post_title":"Contrastare le esacerbazioni e migliorare la qualit\u00e0 della vita","href":"https:\/\/medizinonline.com\/it\/contrastare-le-esacerbazioni-e-migliorare-la-qualita-della-vita\/"},"pt_PT":{"locale":"pt_PT","id":364046,"slug":"combata-as-exacerbacoes-e-melhore-a-qualidade-de-vida","post_title":"Combata as exacerba\u00e7\u00f5es e melhore a qualidade de vida","href":"https:\/\/medizinonline.com\/pt-pt\/combata-as-exacerbacoes-e-melhore-a-qualidade-de-vida\/"},"es_ES":{"locale":"es_ES","id":364101,"slug":"contrarrestar-las-exacerbaciones-y-mejorar-la-calidad-de-vida","post_title":"Contrarrestar las exacerbaciones y mejorar la calidad de vida","href":"https:\/\/medizinonline.com\/es\/contrarrestar-las-exacerbaciones-y-mejorar-la-calidad-de-vida\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/364166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=364166"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/364166\/revisions"}],"predecessor-version":[{"id":365980,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/364166\/revisions\/365980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/364192"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=364166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=364166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=364166"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=364166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}