{"id":376830,"date":"2024-03-27T00:01:00","date_gmt":"2024-03-26T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=376830"},"modified":"2024-03-27T09:10:50","modified_gmt":"2024-03-27T08:10:50","slug":"un-document-de-consensus-international-resume-les-faits-importants","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/un-document-de-consensus-international-resume-les-faits-importants\/","title":{"rendered":"Un document de consensus international r\u00e9sume les faits importants"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La D\u00e9claration de consensus international sur l&#8217;allergie et la rhinologie : rhinite allergique (ICAR : AR 2023) est un outil pr\u00e9cieux pour surmonter l&#8217;inertie th\u00e9rapeutique et obtenir les meilleurs r\u00e9sultats possibles dans le traitement des patients atteints de rhinite allergique. Par rapport \u00e0 l&#8217;\u00e9dition publi\u00e9e en 2018, 41 nouveaux th\u00e8mes ont \u00e9t\u00e9 ajout\u00e9s. En plus d&#8217;un r\u00e9sum\u00e9 des preuves actuelles, les lacunes dans les connaissances et les &#8220;besoins non satisfaits&#8221; sont \u00e9galement abord\u00e9s.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Le nombre de publications dans le domaine de la rhinite allergique (RA) a consid\u00e9rablement augment\u00e9 au cours des derni\u00e8res d\u00e9cennies, de sorte que la pr\u00e9c\u00e9dente \u00e9dition du document de consensus a d\u00fb \u00eatre r\u00e9vis\u00e9e [1]. Une recherche PubMed effectu\u00e9e en 2022 a r\u00e9v\u00e9l\u00e9 qu&#8217;un total de 7169 citations sur la RA ont \u00e9t\u00e9 publi\u00e9es entre 2018 et 2022 [2]. L&#8217;un des objectifs de la nouvelle \u00e9dition du ICAR:AR, qui sera publi\u00e9e en 2023, est de r\u00e9sumer de mani\u00e8re claire cette \u00e9norme quantit\u00e9 de nouveaux faits pour les cliniciens tr\u00e8s occup\u00e9s [3]. Plus de 120 auteurs ont \u00e9valu\u00e9 de mani\u00e8re critique les preuves relatives \u00e0 144 th\u00e8mes individuels de RA dans 10 grands domaines th\u00e9matiques autour de la rhinite allergique. Voici un aper\u00e7u concis de quelques points importants.  <\/p>\n\n<h3 id=\"epidemiologie\" class=\"wp-block-heading\">\u00c9pid\u00e9miologie <\/h3>\n\n<p class=\"wp-block-paragraph\">La pr\u00e9valence globale de la RA est estim\u00e9e \u00e0 5-50%. On observe une augmentation de l&#8217;incidence chez les enfants et les adolescents. La pr\u00e9valence varie en fonction de la r\u00e9gion g\u00e9ographique et de la latitude et s&#8217;av\u00e8re \u00eatre la plus \u00e9lev\u00e9e dans les pays anglophones. L&#8217;effet du changement climatique sur la pr\u00e9valence de la RA fait l&#8217;objet d&#8217;\u00e9tudes r\u00e9centes [4].  <\/p>\n\n<h3 id=\"diagnostic\" class=\"wp-block-heading\">Diagnostic <\/h3>\n\n<p class=\"wp-block-paragraph\">L&#8217;anamn\u00e8se est essentielle pour le diagnostic de la RA. Il existe plusieurs outils d&#8217;enqu\u00eate valid\u00e9s qui peuvent aider au diagnostic. L&#8217;examen physique comprend \u00e9galement, en option, une endoscopie nasale qui peut mettre en \u00e9vidence un \u0153d\u00e8me compartimental central (&#8220;compartment edema&#8221;) ou des modifications polypiques qui ont \u00e9t\u00e9 r\u00e9cemment associ\u00e9es aux allergies [5]. L&#8217;endoscopie nasale peut \u00e9galement permettre d&#8217;exclure d&#8217;autres diagnostics. Les tests de confirmation sont utiles lorsque des strat\u00e9gies d&#8217;\u00e9vitement cibl\u00e9es ou une immunoth\u00e9rapie allerg\u00e9nique sont envisag\u00e9es, ce qui peut \u00eatre b\u00e9n\u00e9fique lorsqu&#8217;un traitement m\u00e9dicamenteux symptomatique n&#8217;est pas satisfaisant.<\/p>\n\n<p class=\"wp-block-paragraph\">Un test de piq\u00fbre cutan\u00e9e <em>(Skin Prick Test) <\/em>est recommand\u00e9 lorsque le diagnostic de RA doit \u00eatre confirm\u00e9 ou chez un patient suspect\u00e9 de RA pour lequel un traitement m\u00e9dical empirique appropri\u00e9 a \u00e9chou\u00e9 et pour lequel une immunoth\u00e9rapie allerg\u00e9nique est envisag\u00e9e. Les techniques intradermiques et mixtes peuvent \u00eatre utilis\u00e9es pour confirmer une sensibilisation allergique. Les tests IgE s\u00e9riques sp\u00e9cifiques aux allerg\u00e8nes peuvent \u00eatre n\u00e9cessaires lorsque les patients pr\u00e9sentent des contre-indications relatives ou absolues aux tests cutan\u00e9s, telles que la prise de b\u00eatabloquants, un asthme non contr\u00f4l\u00e9 ou des m\u00e9dicaments susceptibles d&#8217;interf\u00e9rer avec la r\u00e9ponse aux tests cutan\u00e9s.<\/p>\n\n<h3 id=\"options-de-traitement\" class=\"wp-block-heading\">Options de traitement <\/h3>\n\n<p class=\"wp-block-paragraph\">Bien qu&#8217;elles soient fr\u00e9quemment utilis\u00e9es dans le cadre du traitement de la RA, les donn\u00e9es relatives aux strat\u00e9gies d&#8217;\u00e9vitement des allerg\u00e8nes sont mitig\u00e9es. Par cons\u00e9quent<br\/>\u00c9viter les animaux domestiques et les allerg\u00e8nes de pollen consid\u00e9r\u00e9s comme une intervention optionnelle.  <\/p>\n\n<p class=\"wp-block-paragraph\">Traitement <strong>m\u00e9dicamenteux symptomatique : <\/strong>une forte recommandation est \u00e9mise pour l&#8217;utilisation des options th\u00e9rapeutiques suivantes :  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>antihistaminiques oraux de nouvelle g\u00e9n\u00e9ration (\u00e0 distinguer de ceux de premi\u00e8re g\u00e9n\u00e9ration)  <\/li>\n\n\n\n<li>corticost\u00e9ro\u00efdes intranasaux  <\/li>\n\n\n\n<li>rin\u00e7age intranasal \u00e0 l&#8217;eau sal\u00e9e  <\/li>\n\n\n\n<li>Traitement combin\u00e9 par corticost\u00e9ro\u00efdes intranasaux et antihistaminiques pour les patients qui ne r\u00e9pondent pas \u00e0 une monoth\u00e9rapie.  <\/li>\n\n\n\n<li>Immunoth\u00e9rapie sous-cutan\u00e9e (SCIT) ou immunoth\u00e9rapie sublinguale (SLIT) chez les patients \u00e9ligibles.  <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">En outre, le document de consensus contient une forte recommandation contre l&#8217;utilisation de monoth\u00e9rapies d\u00e9congestionnantes orales et contre l&#8217;utilisation syst\u00e9matique de corticost\u00e9ro\u00efdes oraux dans la RA.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Immunoth\u00e9rapie : <\/strong>SCIT pour AR est une option de traitement avec une forte recommandation et un niveau \u00e9lev\u00e9 de preuves empiriques. La SCIT est une mesure th\u00e9rapeutique efficace qui peut entra\u00eener une am\u00e9lioration des sympt\u00f4mes et de la qualit\u00e9 de vie ainsi qu&#8217;une r\u00e9duction de l&#8217;utilisation des m\u00e9dicaments d&#8217;urgence. Le SLIT s&#8217;est \u00e9galement r\u00e9v\u00e9l\u00e9 efficace sur ces aspects. Dans les m\u00e9ta-analyses, la SCIT s&#8217;est av\u00e9r\u00e9e sup\u00e9rieure \u00e0 la SLIT en termes d&#8217;efficacit\u00e9, mais il convient de noter que ces r\u00e9sultats reposent en grande partie sur des comparaisons indirectes et que la SLIT pr\u00e9sente un avantage en termes de s\u00e9curit\u00e9.  <\/p>\n\n<p class=\"wp-block-paragraph\">Dans le groupe d&#8217;\u00e2ge des enfants et des adolescents, il est important de prendre en compte le facteur &#8220;marche atopique&#8221; et de recueillir des ant\u00e9c\u00e9dents familiaux d&#8217;atopie. Les prick-tests cutan\u00e9s sont g\u00e9n\u00e9ralement effectu\u00e9s de mani\u00e8re syst\u00e9matique chez les enfants. Bien que les options de traitement soient limit\u00e9es pour les tr\u00e8s jeunes enfants, l&#8217;immunoth\u00e9rapie allerg\u00e9nique peut r\u00e9duire le risque de d\u00e9velopper de l&#8217;asthme plus tard dans la vie chez les enfants atteints de RA.<\/p>\n\n<h3 id=\"comorbidites-associees\" class=\"wp-block-heading\">Comorbidit\u00e9s associ\u00e9es  <\/h3>\n\n<p class=\"wp-block-paragraph\">En raison de l&#8217;unit\u00e9 des voies respiratoires sup\u00e9rieures et inf\u00e9rieures (&#8220;unified airways&#8221;), il existe un lien reconnu entre l&#8217;asthme et l&#8217;AR et l&#8217;AR est consid\u00e9r\u00e9 comme un facteur de risque pour le d\u00e9veloppement de l&#8217;asthme. Chez les patients souffrant \u00e0 la fois d&#8217;AR et d&#8217;asthme, le traitement par immunoth\u00e9rapie allerg\u00e9nique peut am\u00e9liorer non seulement l&#8217;AR, mais aussi les sympt\u00f4mes de l&#8217;asthme. En outre, un lien entre la RA et diff\u00e9rentes formes de rhinosinusite chronique a \u00e9t\u00e9 \u00e9tudi\u00e9. Bien que les \u00e9tudes ne soient pas homog\u00e8nes, on pense que les allergies jouent un r\u00f4le dans la rhinosinusite fongique allergique et les maladies atopiques du compartiment central. Bien que des publications r\u00e9centes aient mis en \u00e9vidence une pr\u00e9valence accrue d&#8217;allergies m\u00e9di\u00e9es par les IgE dans les maladies respiratoires exacerb\u00e9es par l&#8217;aspirine par rapport aux rapports pr\u00e9c\u00e9dents, la physiopathologie primaire des maladies respiratoires exacerb\u00e9es par l&#8217;aspirine r\u00e9side davantage dans une alt\u00e9ration du m\u00e9tabolisme de l&#8217;acide arachidonique que dans une hypersensibilit\u00e9 m\u00e9di\u00e9e par les IgE. Il existe des donn\u00e9es relativement claires sur l&#8217;association de l&#8217;AR avec les troubles du sommeil, le <em> syndrome d&#8217;allergie <\/em>alimentaire au pollen (PFAS), la conjonctivite et la dermatite atopique.<\/p>\n\n<h3 id=\"futures-questions-de-recherche\" class=\"wp-block-heading\">Futures questions de recherche  <\/h3>\n\n<p class=\"wp-block-paragraph\">Outre les th\u00e8mes mentionn\u00e9s, le document de consensus contient une section sp\u00e9cifique sur COVID-19. En outre, selon le panel d&#8217;experts, il existe d&#8217;autres domaines de recherche li\u00e9s \u00e0 la RA qui n&#8217;ont pas encore \u00e9t\u00e9 suffisamment explor\u00e9s. Par exemple, les facteurs de risque pour le d\u00e9veloppement de la RA et la relation entre les facteurs de risque potentiels et les facteurs g\u00e9n\u00e9tiques restent peu connus. Il existe plusieurs projets de recherche en cours sur le r\u00f4le des facteurs climatiques et g\u00e9ographiques dans l&#8217;apparition de la RA.<\/p>\n\n<p class=\"wp-block-paragraph\">Des tests peu co\u00fbteux tels que les IgE sp\u00e9cifiques aux allerg\u00e8nes nasaux et les niveaux d&#8217;activation des mastocytes sont \u00e9galement \u00e9tudi\u00e9s. En ce qui concerne l&#8217;optimisation des options de traitement, il est n\u00e9cessaire d&#8217;\u00e9valuer les th\u00e9rapies combin\u00e9es et de comparer directement les co\u00fbts et l&#8217;efficacit\u00e9 des diff\u00e9rentes options (par exemple, SLIT et SCIT). En outre, une meilleure compr\u00e9hension des effets de la RA sur d&#8217;autres maladies ORL telles que les polypes nasaux, les maladies de l&#8217;oreille et les maladies de la voix est n\u00e9cessaire, selon une autre d\u00e9claration du document de consensus international.  <\/p>\n\n<p class=\"wp-block-paragraph\">Litt\u00e9rature :<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Wise SK, et al : International Consensus Statement on Allergy and Rhinology : Allergic Rhinitis. Int Forum Allergy Rhinol 2018 ; 8(2) : 108-352.<\/li>\n\n\n\n<li>&#8220;International Consensus Statement on Allergy and Rhinology : Allergic Rhinitis 2023&#8221;, <a href=\"https:\/\/bulletin.entnet.org\/clinical-patient-care\/article\/22861705\/icar-allergic-rhinitis-2023\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bulletin.entnet.org\/clinical-patient-care\/article\/22861705\/icar-allergic-rhinitis-2023,<\/a>(derni\u00e8re consultation 08.03.2024)  <\/li>\n\n\n\n<li>Wise SK, et al : International consensus statement on allergy and rhinology : Allergic rhinitis &#8211; 2023. Int Forum Allergy Rhinol 2023 ; 13(4) : 293-859.<\/li>\n\n\n\n<li>Wise SK, et al. : A Synopsis of Guidance for Allergic Rhinitis Diagnosis and Management From ICAR 2023. J Allergy Clin Immunol Pract 2023 ; 11(3) : 773-796.<\/li>\n\n\n\n<li>DelGaudio JM, et al : Maladie atopique du compartiment central. Am J Rhinol Allergy 2017 ; 31(4) : 228-234.  <\/li>\n<\/ol>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2024 ; 19(3) : 20-21<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La D\u00e9claration de consensus international sur l&#8217;allergie et la rhinologie : rhinite allergique (ICAR : AR 2023) est un outil pr\u00e9cieux pour surmonter l&#8217;inertie th\u00e9rapeutique et obtenir les meilleurs r\u00e9sultats&hellip;<\/p>\n","protected":false},"author":7,"featured_media":376836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Rhinite allergique ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11349,11527,11531,11315,11549],"tags":[75010,14844,75008,43998,75009,51235,12438,13463,13469],"powerkit_post_featured":[],"class_list":["post-376830","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allergologie-et-immunologie-clinique","category-etudes","category-formation-continue","category-medecine-interne-generale","category-rx-fr","tag-international-consensus-statement-on-allergy-and-rhinology-allergic-rhinitis-declaration-de-consensus-international-sur-lallergie-et-la-rhinologie-rhinite-allergique","tag-antihistaminique","tag-cisa-ar-2023","tag-corticosteroide-fr","tag-document-consensuel","tag-immunotherapie-fr-2","tag-rhinite-allergique","tag-scit-fr","tag-slit-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 06:07:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":376840,"slug":"il-documento-di-consenso-internazionale-riassume-i-fatti-importanti","post_title":"Il documento di consenso internazionale riassume i fatti importanti","href":"https:\/\/medizinonline.com\/it\/il-documento-di-consenso-internazionale-riassume-i-fatti-importanti\/"},"pt_PT":{"locale":"pt_PT","id":376855,"slug":"documento-de-consenso-internacional-resume-factos-importantes","post_title":"Documento de consenso internacional resume factos importantes","href":"https:\/\/medizinonline.com\/pt-pt\/documento-de-consenso-internacional-resume-factos-importantes\/"},"es_ES":{"locale":"es_ES","id":376744,"slug":"un-documento-de-consenso-internacional-resume-hechos-importantes","post_title":"Un documento de consenso internacional resume hechos importantes","href":"https:\/\/medizinonline.com\/es\/un-documento-de-consenso-internacional-resume-hechos-importantes\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/376830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=376830"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/376830\/revisions"}],"predecessor-version":[{"id":376838,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/376830\/revisions\/376838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/376836"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=376830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=376830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=376830"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=376830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}