{"id":381593,"date":"2024-07-11T22:45:19","date_gmt":"2024-07-11T20:45:19","guid":{"rendered":"https:\/\/medizinonline.com\/?p=381593"},"modified":"2024-10-03T16:04:17","modified_gmt":"2024-10-03T14:04:17","slug":"limportance-de-la-nutrition-dans-la-cicatrisation-des-plaies-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/limportance-de-la-nutrition-dans-la-cicatrisation-des-plaies-2\/","title":{"rendered":"L&#8217;importance de la nutrition dans la cicatrisation des plaies"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Pour une cicatrisation efficace, il est essentiel d&#8217;avoir une alimentation riche en \u00e9nergie et en substrats. Les personnes \u00e2g\u00e9es pr\u00e9sentent un risque particuli\u00e8rement \u00e9lev\u00e9 de troubles de la cicatrisation des plaies dus \u00e0 la malnutrition, de sorte que l&#8217;on peut s&#8217;attendre \u00e0 l&#8217;avenir \u00e0 une augmentation de la pr\u00e9valence des processus chroniques de cicatrisation des plaies dus \u00e0 la malnutrition en raison des changements d\u00e9mographiques. Dans ce contexte, la malnutrition est un facteur de risque qui contribue \u00e0 une \u00e9volution d\u00e9favorable de la maladie, ind\u00e9pendamment de sa gravit\u00e9, et qui augmente significativement les co\u00fbts de traitement dans tous les groupes d&#8217;\u00e2ge.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Pour une cicatrisation efficace, il est essentiel d&#8217;avoir une alimentation riche en \u00e9nergie et en substrats. Les personnes \u00e2g\u00e9es pr\u00e9sentent un risque particuli\u00e8rement \u00e9lev\u00e9 de troubles de la cicatrisation des plaies dus \u00e0 la malnutrition, de sorte que l&#8217;on peut s&#8217;attendre \u00e0 l&#8217;avenir \u00e0 une augmentation de la pr\u00e9valence des processus chroniques de cicatrisation des plaies dus \u00e0 la malnutrition en raison des changements d\u00e9mographiques. Dans ce contexte, la malnutrition est un facteur de risque qui contribue \u00e0 une \u00e9volution d\u00e9favorable de la maladie, ind\u00e9pendamment de sa gravit\u00e9, et qui augmente significativement les co\u00fbts de traitement dans tous les groupes d&#8217;\u00e2ge. Les co\u00fbts cons\u00e9cutifs \u00e0 la malnutrition sont estim\u00e9s \u00e0 plusieurs milliards d&#8217;euros par an rien qu&#8217;en Allemagne [1].<\/p>\n\n\n\n<h3 id=\"besoins-en-energie-et-en-substrat-pour-la-cicatrisation-des-plaies\" class=\"wp-block-heading\">Besoins en \u00e9nergie et en substrat pour la cicatrisation des plaies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Imm\u00e9diatement apr\u00e8s une blessure, des composants sanguins sont lib\u00e9r\u00e9s dans la plaie et forment un caillot qui constitue une matrice pour l&#8217;afflux de cellules inflammatoires. Cette phase d&#8217;inflammation se caract\u00e9rise par la migration de leucocytes dans la plaie. Les granulocytes neutrophiles \u00e9liminent en premier lieu les bact\u00e9ries, suivis par les monocytes, qui se diff\u00e9rencient ensuite en macrophages, lesquels exercent des fonctions pro-inflammatoires pr\u00e9coces et anti-inflammatoires tardives au cours du processus de gu\u00e9rison. Il s&#8217;ensuit le d\u00e9p\u00f4t de la matrice de fibrine nouvellement synth\u00e9tis\u00e9e et la formation de tissu de granulation ; ceux-ci sont ensuite remplac\u00e9s par du collag\u00e8ne et du tissu cicatriciel au cours des derni\u00e8res \u00e9tapes de la cicatrisation. La phase prolif\u00e9rative finale de la cicatrisation est caract\u00e9ris\u00e9e par une r\u00e9-\u00e9pith\u00e9lialisation, une n\u00e9ovascularisation et un d\u00e9p\u00f4t de matrice extracellulaire.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre du traitement des plaies chroniques, en particulier des escarres, l&#8217;\u00e9tat nutritionnel et la garantie d&#8217;un apport suffisant en nutriments rev\u00eatent une importance particuli\u00e8re. En cas de risque de malnutrition et de malnutrition manifeste, la cicatrisation des plaies est perturb\u00e9e et donc retard\u00e9e, ce qui est encore modifi\u00e9 par d&#8217;autres facteurs. Outre les perturbations primaires dues \u00e0 une maladie sous-jacente, d&#8217;origine vasculaire dans plus de 70% des cas, des perturbations locales secondaires telles que la persistance de la fibrine ou un d\u00e9faut de migration des cellules \u00e9pith\u00e9liales entravent la cicatrisation. Les facteurs tertiaires concomitants sont, outre l&#8217;\u00e2ge du patient, les facteurs environnementaux cytotoxiques et les m\u00e9dicaments [2].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cicatrisation des plaies passe g\u00e9n\u00e9ralement par quatre \u00e9tapes : la coagulation, l&#8217;inflammation, la prolif\u00e9ration et, enfin, la diff\u00e9renciation. C&#8217;est surtout pendant la phase inflammatoire que le stress de la plaie entra\u00eene de graves modifications m\u00e9taboliques. Ainsi, les hormones cataboliques telles que le cortisol et les cat\u00e9cholamines sont hautement r\u00e9gul\u00e9es, tandis que le m\u00e9tabolisme des graisses dans l&#8217;organisme est d&#8217;abord ralenti. Parall\u00e8lement, la d\u00e9pense \u00e9nerg\u00e9tique augmente, ce qui se traduit \u00e9galement par une hausse de la temp\u00e9rature corporelle. La demande en glucose augmente, de sorte que la glucon\u00e9ogen\u00e8se h\u00e9patique est la premi\u00e8re \u00e0 \u00eatre fortement stimul\u00e9e par la consommation du glycog\u00e8ne stock\u00e9 dans le foie et, plus tard, par la lib\u00e9ration de prot\u00e9ines par les muscles squelettiques. Durant cette phase, il est particuli\u00e8rement important d&#8217;avoir un apport \u00e9nerg\u00e9tique suffisant par le biais de l&#8217;alimentation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la prolif\u00e9ration et la diff\u00e9renciation, outre l&#8217;\u00e9nergie n\u00e9cessaire aux processus de nettoyage, il faut suffisamment de substrats pour la r\u00e9paration : Les glucides et les lipides fournissent de l&#8217;\u00e9nergie en tant que macronutriments, tandis que les prot\u00e9ines servent \u00e0 la construction de la structure. Les vitamines et les oligo-\u00e9l\u00e9ments ont un effet de soutien en tant que cofacteurs, entre autres dans la synth\u00e8se de l&#8217;ADN.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cas de manque de substrats \u00e9nerg\u00e9tiques ou structurels pendant la cicatrisation, le corps puise dans les r\u00e9serves disponibles dans la &#8220;masse maigre&#8221;, c&#8217;est-\u00e0-dire d&#8217;abord dans le glycog\u00e8ne h\u00e9patique, puis dans les muscles, et plus tard seulement dans le tissu adipeux. Ces processus de d\u00e9gradation produisent des c\u00e9tones et du glucose en tant que fournisseurs d&#8217;\u00e9nergie et des acides amin\u00e9s en tant qu&#8217;\u00e9l\u00e9ments structurels. Si la d\u00e9gradation des substances propres \u00e0 l&#8217;organisme pour produire de l&#8217;\u00e9nergie pr\u00e9domine, une situation de carence prot\u00e9ino-\u00e9nerg\u00e9tique se d\u00e9veloppe progressivement. Dans ces conditions m\u00e9taboliques, la cicatrisation de la plaie est progressivement ralentie au profit de la pr\u00e9servation de ses propres prot\u00e9ines. En cas de diminution critique de la masse maigre, on assiste \u00e0 un d\u00e9placement de la consommation de prot\u00e9ines pour la cicatrisation en faveur de la pr\u00e9servation des structures vitales, telles que les muscles respiratoires et les immunoglobulines. Une r\u00e9duction de 20% de la masse maigre entra\u00eene d\u00e9j\u00e0 un retard de cicatrisation, un amincissement de la peau et un risque accru d&#8217;infection. Une perte de 30% est associ\u00e9e au d\u00e9veloppement spontan\u00e9 d&#8217;escarres et \u00e0 une stagnation de la cicatrisation, elle-m\u00eame associ\u00e9e \u00e0 une mortalit\u00e9 de 50% <strong>(tableau 1)<\/strong> [2]. Les causes de d\u00e9c\u00e8s sont alors des infections, le plus souvent des pneumonies, qui ne peuvent plus \u00eatre ma\u00eetris\u00e9es par l&#8217;organisme en raison d&#8217;une d\u00e9ficience importante des d\u00e9fenses immunitaires (baisse des leucocytes et des immunoglobulines n\u00e9cessaires).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1800\" height=\"583\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17.png\" alt=\"\" class=\"wp-image-381003\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17.png 1800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-800x259.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-1160x376.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-120x39.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-90x29.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-320x104.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-560x181.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-240x78.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-180x58.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-640x207.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-1120x363.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab1_DP3_s17-1600x518.png 1600w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 id=\"micronutriments-et-cicatrisation-des-plaies\" class=\"wp-block-heading\">Micronutriments et cicatrisation des plaies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les micronutriments, <strong>la vitamine C <\/strong>(acide ascorbique) joue un r\u00f4le central dans le m\u00e9tabolisme des plaies gr\u00e2ce \u00e0 son implication dans la biosynth\u00e8se du collag\u00e8ne en tant que cofacteur dans l&#8217;hydroxylation des acides amin\u00e9s lysine et proline et dans la formation de fibrilles de collag\u00e8ne stables [3]. Ce biofacteur favorise la formation et la r\u00e9ticulation du collag\u00e8ne, le maintient \u00e9lastique et est important pour la r\u00e9g\u00e9n\u00e9ration des tissus, pour soutenir la gu\u00e9rison des plaies et la cicatrisation ainsi que pour un tissu conjonctif intact. La vitamine C a \u00e9galement un effet positif sur la cicatrisation des plaies en tant que composant du syst\u00e8me de protection antioxydant de l&#8217;organisme et en raison de son implication dans la synth\u00e8se des lymphocytes et des anticorps pour limiter l&#8217;inflammation [4]. Une \u00e9tude r\u00e9cente sur les effets anti-biofilm de la vitamine C recommande de prescrire syst\u00e9matiquement la vitamine C avec des antibiotiques pour le traitement des infections bact\u00e9riennes en milieu clinique [5]. Une revue syst\u00e9matique de Bechara et al. a \u00e9galement constat\u00e9 en 2022 que la suppl\u00e9mentation en vitamine C am\u00e9liorait les r\u00e9sultats de la cicatrisation, notamment en cas d&#8217;escarres [6].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les autres micronutriments, les vitamines liposolubles A, D et E sont essentielles \u00e0 la cicatrisation des plaies. <strong>La vitamine A<\/strong> est un micronutriment essentiel qui se pr\u00e9sente sous diff\u00e9rentes formes, dont les r\u00e9tinols, les r\u00e9tino\u00efdes et les acides r\u00e9tino\u00efques. Il s&#8217;agit d&#8217;un \u00e9l\u00e9ment essentiel de nombreuses fonctions biologiques importantes, y compris la reproduction, le d\u00e9veloppement embryologique, la diff\u00e9renciation cellulaire, la croissance, l&#8217;immunit\u00e9 et la vision. La vitamine A agit principalement via les r\u00e9cepteurs nucl\u00e9aires de l&#8217;acide r\u00e9tino\u00efque, les r\u00e9cepteurs X des r\u00e9tino\u00efdes et les r\u00e9cepteurs activ\u00e9s par les prolif\u00e9rateurs de peroxysomes. Les r\u00e9tino\u00efdes r\u00e9gulent la croissance et la diff\u00e9renciation de nombreux types de cellules dans la peau. En revanche, leur d\u00e9ficit entra\u00eene une k\u00e9ratinisation \u00e9pith\u00e9liale anormale. Dans les tissus bless\u00e9s, la vitamine A active le turnover \u00e9pidermique, augmente le taux de r\u00e9-\u00e9pith\u00e9lialisation et restaure la structure \u00e9pith\u00e9liale. Les r\u00e9tino\u00efdes ont la capacit\u00e9 unique d&#8217;inverser l&#8217;effet inhibiteur des st\u00e9ro\u00efdes anti-inflammatoires sur la cicatrisation des plaies. En plus de son r\u00f4le dans la phase inflammatoire de la cicatrisation, l&#8217;acide r\u00e9tino\u00efque augmente la production de composants de la matrice extracellulaire tels que le collag\u00e8ne de type I et la fibronectine, la prolif\u00e9ration des k\u00e9ratinocytes et des fibroblastes et diminue le niveau de m\u00e9talloprot\u00e9inases matricielles d\u00e9gradantes [7].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La vitamine D <\/strong>contribue \u00e0 la cicatrisation des plaies en se liant au r\u00e9cepteur de la vitamine D (VDR) via le calcitriol. Il r\u00e9gule la transcription dans diff\u00e9rentes cellules cibles, en stimulant la production de facteurs de croissance mitog\u00e8nes via des r\u00e9cepteurs tels que le facteur de croissance d\u00e9riv\u00e9 des plaquettes (PDGF), les r\u00e9cepteurs du facteur de croissance \u00e9pidermique (EGFR) et le r\u00e9cepteur du facteur de croissance des k\u00e9ratinocytes (KGFR). Ces effets sont en partie m\u00e9diatis\u00e9s par les k\u00e9ratinocytes induits par le calcitriol. On attribue aux propri\u00e9t\u00e9s anti-inflammatoires de la vitamine D un effet antiprolif\u00e9ratif sur la r\u00e9g\u00e9n\u00e9ration de la peau et des muqueuses avec suppression des monocytes et de l&#8217;inflammation m\u00e9di\u00e9e par les cellules de Langerhans. Il r\u00e9duit \u00e9galement les k\u00e9ratinocytes exprim\u00e9s par les cytokines pro-inflammatoires IL-1\u03b1, IL-6 et IL-8. Le calcitriol induit directement l&#8217;expression de plusieurs paires de peptides antimicrobiens, y compris la cath\u00e9licidine et la d\u00e9fensine \u03b22, et peut reconna\u00eetre le r\u00e9cepteur microbien Toll-like 2 (TLR2) et le cofacteur de CD14. Ces activit\u00e9s collectives ont un effet immunoprotecteur contre la colonisation par des organismes pathog\u00e8nes [8]. L&#8217;action intracellulaire de la vitamine D se produit presque toujours en m\u00eame temps que celle du r\u00e9cepteur nucl\u00e9aire de la vitamine A. Les vitamines A et D agissent alors comme des hormones st\u00e9ro\u00efdes sur le m\u00e9tabolisme cellulaire.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour d\u00e9tecter une carence en vitamine D, il est utile de d\u00e9terminer le taux de 25(OH)D dans le sang (forme de stockage de la vitamine D). La Soci\u00e9t\u00e9 allemande de nutrition (DGE) ainsi que l&#8217;<em>Institut national de la sant\u00e9<\/em> (NIH) consid\u00e8rent qu&#8217;une valeur limite de 50 nmol\/l dans le s\u00e9rum, correspondant \u00e0 20 ng\/ml, est suffisante. La vie quotidienne montre toutefois que ce seuil est rarement atteint. Selon Bischoff-Ferrari [9] et d&#8217;autres, un apport suffisant n&#8217;est m\u00eame assur\u00e9 qu&#8217;\u00e0 partir d&#8217;une valeur de 75 nmol\/l ou 30 ng\/ml. Pour atteindre ces niveaux de vitamine dans le s\u00e9rum, la production endog\u00e8ne de vitamine D par la peau + le rayonnement UV au nord du 50e parall\u00e8le doit \u00eatre r\u00e9guli\u00e8rement soutenue par un apport exog\u00e8ne, par exemple 800-1000 UI de vitamine D (25[OH]D) par jour <strong>(tableau 2). <\/strong> <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18.png\"><img decoding=\"async\" width=\"1106\" height=\"679\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18.png\" alt=\"\" class=\"wp-image-381004 lazyload\" style=\"--smush-placeholder-width: 1106px; --smush-placeholder-aspect-ratio: 1106\/679;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18.png 1106w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-800x491.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-120x74.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-90x55.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-320x196.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-560x344.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-240x147.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-180x111.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab2_DP3_s18-640x393.png 640w\" data-sizes=\"(max-width: 1106px) 100vw, 1106px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>La vitamine E<\/strong> est compos\u00e9e de deux groupes de compos\u00e9s aux propri\u00e9t\u00e9s physico-biochimiques, les tocoph\u00e9rols et les tocotri\u00e9nols, dont la structure diff\u00e8re l\u00e9g\u00e8rement, l&#8217;\u03b1-tocoph\u00e9rol \u00e9tant la forme la plus puissante et la plus abondante in vivo. Gr\u00e2ce \u00e0 son activit\u00e9 de pi\u00e9geage des radicaux libres, la vitamine E d\u00e9fend les membranes cellulaires et les lipides polyinsatur\u00e9s contre les attaques ROS en induisant l&#8217;activation de diff\u00e9rentes voies de transduction du signal. En outre, cette vitamine est importante pour le maintien de l&#8217;int\u00e9grit\u00e9 structurelle de pratiquement toutes les cellules du corps humain, en influen\u00e7ant la signalisation cellulaire. La vitamine E module \u00e9galement l&#8217;expression du facteur de croissance des tissus conjonctifs (CTGF) et r\u00e9gule l&#8217;expression et la transcription des g\u00e8nes, favorisant ainsi la protection des plaies contre les infections telles que le <em>Staphylococcus aureus <\/em> r\u00e9sistant \u00e0 la m\u00e9thicilline (SARM) [10].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les autres micronutriments, les <strong>oligo-\u00e9l\u00e9ments <\/strong>zinc et s\u00e9l\u00e9nium, entre autres, sont essentiels pour les processus de r\u00e9paration et doivent \u00eatre substitu\u00e9s s\u00e9par\u00e9ment si n\u00e9cessaire. Le zinc est un cofacteur important pour la fonction de plus de 10% des prot\u00e9ines cod\u00e9es par le g\u00e9nome humain (~3000 prot\u00e9ines\/enzymes). Les prot\u00e9ines d\u00e9pendantes du zinc jouent de nombreux r\u00f4les indispensables dans les cellules, tels que la r\u00e9gulation de la transcription, la r\u00e9paration de l&#8217;ADN, l&#8217;apoptose, le traitement m\u00e9tabolique, la r\u00e9gulation de la matrice extracellulaire et la d\u00e9fense antioxydante [11]. En tant qu&#8217;atome central dans de nombreuses enzymes, le s\u00e9l\u00e9nium est \u00e9galement impliqu\u00e9 de mani\u00e8re multidimensionnelle dans les processus de r\u00e9paration de la cicatrisation.  <\/p>\n\n\n\n<h3 id=\"gestion-de-la-nutrition-pour-favoriser-la-cicatrisation-des-plaies\" class=\"wp-block-heading\">Gestion de la nutrition pour favoriser la cicatrisation des plaies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La maltodextrine, par exemple, est un m\u00e9lange de diff\u00e9rents sucres \u00e0 cha\u00eene courte qui peut \u00eatre ajout\u00e9 \u00e0 divers aliments sans en modifier le go\u00fbt de mani\u00e8re significative.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afin de rendre l&#8217;offre de prot\u00e9ines alimentaires aussi efficace que possible pour la synth\u00e8se des prot\u00e9ines par l&#8217;organisme, les pr\u00e9parations en poudre au go\u00fbt neutre, qui peuvent \u00eatre facilement m\u00e9lang\u00e9es \u00e0 des soupes ou \u00e0 des plats laitiers, conviennent parfaitement. Ainsi, les principaux repas quotidiens devraient contenir au moins 20 g de prot\u00e9ines chacun. Cette quantit\u00e9 entra\u00eene une stimulation postprandiale significative de la synth\u00e8se des prot\u00e9ines, qui peuvent alors utiliser directement dans l&#8217;organisme les dipeptides et les acides amin\u00e9s lib\u00e9r\u00e9s par l&#8217;alimentation.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de la substitution de la vitamine C sous forme de compl\u00e9ments alimentaires, il est important de veiller \u00e0 ce que la gal\u00e9nique des pr\u00e9parations soit appropri\u00e9e. Seule une lib\u00e9ration lente de l&#8217;acide ascorbique, par exemple \u00e0 partir d&#8217;une g\u00e9lule, permet de ne pas d\u00e9passer le seuil d&#8217;excr\u00e9tion r\u00e9nale de la vitamine C et de garantir ainsi une disponibilit\u00e9 suffisante dans l&#8217;organisme. En cas de consommation de quantit\u00e9s sup\u00e9rieures \u00e0 100 mg de vitamine C en poudre dans une portion, la majeure partie du micronutriment est directement \u00e9limin\u00e9e par les reins et est donc perdue pour l&#8217;organisme. Pour am\u00e9liorer la biodisponibilit\u00e9 des vitamines liposolubles, il est essentiel de les consommer lors d&#8217;un repas riche en graisses, car c&#8217;est le seul moyen de les dissoudre et de les absorber par voie intestinale.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La substitution du zinc doit se faire principalement par voie orale, sous forme de comprim\u00e9s de zinc-histidine. L&#8217;application locale de pr\u00e9parations contenant du zinc en tant que produits externes pour la cicatrisation des plaies n&#8217;a qu&#8217;un effet limit\u00e9 sur la synth\u00e8se des prot\u00e9ines et la r\u00e9g\u00e9n\u00e9ration de l&#8217;\u00e9piderme. Au contraire, les p\u00e2tes contenant du zinc en particulier peuvent entraver la respiration de la peau et ne doivent \u00eatre utilis\u00e9es que pendant une courte p\u00e9riode et de mani\u00e8re tr\u00e8s cibl\u00e9e, surtout pour prot\u00e9ger les zones de peau intacte contre la mac\u00e9ration. Le s\u00e9l\u00e9nium peut \u00e9galement \u00eatre administr\u00e9 sous forme de comprim\u00e9s, souvent en combinaison avec le zinc. Les besoins quotidiens en micronutriments essentiels \u00e0 la cicatrisation des plaies sont indiqu\u00e9s dans <strong>le tableau 3<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19.png\"><img decoding=\"async\" width=\"1160\" height=\"1219\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-1160x1219.png\" alt=\"\" class=\"wp-image-381006 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-1160x1219.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-800x841.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-1949x2048.png 1949w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-120x126.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-90x95.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-320x336.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-560x589.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-1920x2018.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-240x252.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-180x189.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-640x673.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-1120x1177.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19-1600x1682.png 1600w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab3_DP3_s19.png 2195w\" data-sizes=\"(max-width: 1160px) 100vw, 1160px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1160px; --smush-placeholder-aspect-ratio: 1160\/1219;\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 id=\"lage-et-linappetence-comme-facteurs-de-risque-pour-la-cicatrisation-des-plaies\" class=\"wp-block-heading\">L&#8217;\u00e2ge et l&#8217;inapp\u00e9tence comme facteurs de risque pour la cicatrisation des plaies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En 2019, l&#8217;\u00e9quipe de Sieske et al. le lien possible entre l&#8217;inflammation, l&#8217;app\u00e9tit et la quantit\u00e9 de nourriture consomm\u00e9e par les patients \u00e2g\u00e9s hospitalis\u00e9s (n=200) [12]. L&#8217;analyse a montr\u00e9 que la prot\u00e9ine C-r\u00e9active (CRP), marqueur de l&#8217;inflammation, est un pr\u00e9dicteur majeur de la d\u00e9t\u00e9rioration de l&#8217;app\u00e9tit (p=0,003). L&#8217;inflammation (p=0,011) et la fragilit\u00e9 (p=0,023) se sont av\u00e9r\u00e9es \u00eatre les principaux pr\u00e9dicteurs d&#8217;une faible consommation de nourriture. L&#8217;\u00e2ge en soi constitue \u00e9galement un facteur de risque de retard de cicatrisation. La diminution g\u00e9n\u00e9rale de l&#8217;apport alimentaire avec l&#8217;\u00e2ge entra\u00eene un ralentissement de toutes les activit\u00e9s m\u00e9taboliques ainsi que de la cicatrisation des plaies [13]. L&#8217;une des principales causes est la modification de la r\u00e9gulation de l&#8217;app\u00e9tit par le syst\u00e8me nerveux central en fonction de l&#8217;\u00e2ge : les hormones qui augmentent l&#8217;app\u00e9tit, telles que la s\u00e9rotonine, la noradr\u00e9naline et le neuropeptide Y, sont r\u00e9gul\u00e9es \u00e0 la baisse, tandis que l&#8217;effet des hormones contraires, telles que la dopamine, la leptine ou la chol\u00e9cystokinine, qui provoquent la sati\u00e9t\u00e9, augmente. Les m\u00e9diateurs inflammatoires TNF-\u03b1 et IL-6, qui r\u00e9duisent l&#8217;app\u00e9tit, sont particuli\u00e8rement importants dans ce contexte.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des \u00e9tudes ont montr\u00e9 que plus la quantit\u00e9 d&#8217;\u00e9nergie alimentaire consomm\u00e9e est faible, plus la quantit\u00e9 de micronutriments (fer, vitamines <sub>B1<\/sub>, <sub>B2<\/sub> et <sub>B6<\/sub>) diminue de mani\u00e8re significative. En dessous d&#8217;un apport alimentaire de 1500 kcal\/jour, des d\u00e9ficits de l&#8217;ordre de &gt;2\/3 des valeurs de r\u00e9f\u00e9rence en vigueur ont \u00e9t\u00e9 constat\u00e9s chez 24% des hommes et 47% des femmes [14].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D&#8217;autres facteurs de risque de malnutrition, en particulier chez les personnes \u00e2g\u00e9es, concernent, outre les nombreuses maladies associ\u00e9es, des facteurs psychosociaux, regroup\u00e9s dans le mod\u00e8le DOMAP (Determinations of Malnutrition in Aged Persons) [15]. Ce concept distingue diff\u00e9rents niveaux de facteurs d&#8217;influence :  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>le niveau central (besoins \u00e9lev\u00e9s, faible absorption des nutriments, biodisponibilit\u00e9 r\u00e9duite des nutriments),  <\/li>\n\n\n\n<li>le deuxi\u00e8me niveau, qui affecte directement les m\u00e9canismes centraux (par exemple, probl\u00e8mes de mastication, hyperactivit\u00e9, inapp\u00e9tence, diarrh\u00e9e, r\u00e9gimes restrictifs),  <\/li>\n\n\n\n<li>le troisi\u00e8me niveau, dont les facteurs sont \u00e0 l&#8217;origine du deuxi\u00e8me niveau (par exemple, maladie tumorale, solitude, handicap physique, d\u00e9ficience cognitive, insuffisance cardiaque),<\/li>\n\n\n\n<li>enfin, les changements d&#8217;\u00e2ge et les aspects g\u00e9n\u00e9raux qui augmentent le risque de malnutrition (par exemple, la fragilit\u00e9, la polym\u00e9dication, l&#8217;institutionnalisation, le faible niveau d&#8217;\u00e9ducation).<\/li>\n<\/ul>\n\n\n\n<h3 id=\"diagnostic-de-la-malnutrition\" class=\"wp-block-heading\">Diagnostic de la malnutrition<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une personne hospitalis\u00e9e sur quatre dans les h\u00f4pitaux allemands souffre de malnutrition, comme l&#8217;a montr\u00e9 une enqu\u00eate men\u00e9e d\u00e8s 2006 (n=1886) [16]. Dans ce cas, les patients \u00e2g\u00e9s \u00e9taient principalement concern\u00e9s dans les sp\u00e9cialit\u00e9s de g\u00e9riatrie (56,2%), d&#8217;oncologie (37,6%) et de gastro-ent\u00e9rologie (32,6%). En raison de cette pr\u00e9valence \u00e9lev\u00e9e, un d\u00e9pistage syst\u00e9matique de la malnutrition \u00e0 l&#8217;admission \u00e0 l&#8217;h\u00f4pital, en particulier chez les patients de plus de 60 ans, est fortement indiqu\u00e9. Si une malnutrition est suspect\u00e9e dans le cadre d&#8217;un d\u00e9pistage, elle doit \u00eatre suivie d&#8217;une \u00e9valuation nutritionnelle approfondie, puis d&#8217;un plan alimentaire.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comment d\u00e9finir la malnutrition ? Selon la Soci\u00e9t\u00e9 allemande de m\u00e9decine nutritionnelle (DGEM), ce terme englobe les \u00e9tats de carence cliniquement significatifs qui r\u00e9sultent soit d&#8217;une r\u00e9duction de l&#8217;apport alimentaire, d&#8217;une malabsorption et d&#8217;une maldigestion, d&#8217;une catabolisation accrue des prot\u00e9ines ou d&#8217;une inflammation [17]. On distingue ici la malnutrition sp\u00e9cifique \u00e0 une maladie aigu\u00eb ou chronique avec inflammation ou la malnutrition sp\u00e9cifique \u00e0 une maladie sans inflammation. Une troisi\u00e8me option est la malnutrition sans lien direct avec la maladie. En 2018, la <em>Global Leadership Initiative on Malnutrition<\/em> (GLIM) a \u00e9labor\u00e9 des crit\u00e8res pour le d\u00e9pistage de la malnutrition chez les patients [18]. Pour cela, on tient compte d&#8217;une part d&#8217;aspects ph\u00e9notypiques tels que la perte de poids, un IMC bas et une masse musculaire r\u00e9duite. D&#8217;autre part, des crit\u00e8res \u00e9tiologiques tels qu&#8217;une faible quantit\u00e9 de nourriture, la malassimilation et l&#8217;inflammation sont enregistr\u00e9s. Si au moins un point de chacun des deux groupes est rempli, il y a malnutrition selon GLIM. Ce d\u00e9pistage peut \u00eatre mis en \u0153uvre rapidement et bri\u00e8vement et contribue certainement \u00e0 l&#8217;identification des personnes \u00e0 risque. Appliqu\u00e9 \u00e0 l&#8217;admission, il doit ensuite \u00eatre r\u00e9p\u00e9t\u00e9 \u00e0 intervalles r\u00e9guliers.<\/p>\n\n\n\n<h3 id=\"mesures-therapeutiques-en-cas-de-malnutrition-et-de-troubles-de-la-cicatrisation-des-plaies\" class=\"wp-block-heading\">Mesures th\u00e9rapeutiques en cas de malnutrition et de troubles de la cicatrisation des plaies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les directives du <em>European Pressure Ulcer Advisory Panel<\/em> (EPUAP) pour le traitement des escarres recommandent, en fonction du degr\u00e9 de l&#8217;escarre et en cas de risque simultan\u00e9 de malnutrition ou de malnutrition d\u00e9j\u00e0 manifeste, un apport \u00e9nerg\u00e9tique par jour allant jusqu&#8217;\u00e0 40 kcal\/kg de poids corporel (PC) (escarres de degr\u00e9 IV) et un apport prot\u00e9ique par jour allant jusqu&#8217;\u00e0 2,0 g\/kg PC (escarres de degr\u00e9 IV) <strong>(tableau 4)<\/strong> [19]. Des suppl\u00e9ments prot\u00e9iques hautement caloriques, contenant autant d&#8217;arginine, de zinc et d&#8217;antioxydants que possible, devraient \u00eatre propos\u00e9s aux personnes concern\u00e9es en compl\u00e9ment des repas et collations enrichis. Enfin, des mesures ent\u00e9rales et parent\u00e9rales peuvent \u00e9galement \u00eatre appliqu\u00e9es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20.png\"><img decoding=\"async\" width=\"1293\" height=\"705\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20.png\" alt=\"\" class=\"wp-image-381005 lazyload\" style=\"--smush-placeholder-width: 1293px; --smush-placeholder-aspect-ratio: 1293\/705;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20.png 1293w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-800x436.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-1160x632.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-120x65.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-90x49.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-320x174.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-560x305.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-240x131.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-180x98.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-640x349.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/tab4_DP3_s20-1120x611.png 1120w\" data-sizes=\"(max-width: 1293px) 100vw, 1293px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le guide S3 sur le traitement local des plaies difficiles \u00e0 cicatriser et\/ou chroniques dues \u00e0 une maladie art\u00e9rielle p\u00e9riph\u00e9rique, au diab\u00e8te sucr\u00e9 ou \u00e0 une insuffisance veineuse chronique, publi\u00e9 en 2023, a \u00e9galement abord\u00e9 l&#8217;importance de la nutrition comme mesure adjuvante. Pour des recommandations plus d\u00e9taill\u00e9es, les guides S3 &#8220;Nutrition clinique en chirurgie&#8221; et &#8220;Nutrition clinique en g\u00e9riatrie&#8221; sont disponibles. Cette derni\u00e8re est actuellement en cours de mise \u00e0 jour. Pour les professionnels de la sant\u00e9, il existe \u00e9galement la norme d&#8217;experts &#8220;Prise en charge nutritionnelle pour assurer et promouvoir l&#8217;alimentation orale dans les soins&#8221; [20].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Messages Take-Home<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les patients atteints de plaies chroniques ont besoin d&#8217;un traitement nutritionnel adapt\u00e9 \u00e0 leurs besoins, en plus du traitement causal et du traitement de base. Il faut tenir compte de l&#8217;augmentation des besoins \u00e9nerg\u00e9tiques, mais aussi des besoins accrus en prot\u00e9ines, vitamines et oligo-\u00e9l\u00e9ments.  <\/li>\n\n\n\n<li>La pr\u00e9sence d&#8217;un risque ou d&#8217;une malnutrition manifeste chez un patient souffrant d&#8217;un trouble de la cicatrisation doit \u00eatre syst\u00e9matiquement \u00e9valu\u00e9e par un d\u00e9pistage, suivi le cas \u00e9ch\u00e9ant d&#8217;une \u00e9valuation nutritionnelle, afin qu&#8217;un traitement nutritionnel personnalis\u00e9 puisse \u00eatre mis en place rapidement.<\/li>\n\n\n\n<li>La th\u00e9rapie nutritionnelle commence par l&#8217;am\u00e9lioration de l&#8217;absorption orale des aliments gr\u00e2ce \u00e0 des collations et \u00e0 un enrichissement cibl\u00e9 des repas en macro et micronutriments. Enfin, des mesures de nutrition ent\u00e9rale et parent\u00e9rale peuvent encore \u00eatre appliqu\u00e9es.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Litt\u00e9rature :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Frejer K, Tan SS, Koopmmanschap MA, et al.: The economic costs of disease related malnutrition. Clin Nutrition 2013; 32: 136\u2013141.<\/li>\n\n\n\n<li>Demling RH: Nutrition, Anabolism, and the Wound Healing Process: An Overview. J Plast Surg 2009; 9: 65\u201394.<\/li>\n\n\n\n<li>Moores J: Vitamin C: a wound healing perspective. Br J Community Nurs 2013; 6: 8\u201311.<\/li>\n\n\n\n<li>Schols JM, et al.: Nutritional support in the treatment and prevention of pressure ulcers: an overview of studies with an arginine enriched oral nutritional supplement. J Tissue Viability 2009; 18(3): 72\u201379.<\/li>\n\n\n\n<li>Abdelraheem WM, et al.: Assessment of Antibacterial and Anti-biofilm Effects of Vitamin C Against Pseudomonas aeruginosa Clinical Isolates. Front Microbiol 2020; 13: 847449; doi: 10.3389\/fmicb.2022.847449.<\/li>\n\n\n\n<li>Bechara N, et al.: A Systematic Review on the Role of Vitamin C in Tissue Healing. Antioxidants 2022; 11: 1605; doi: 10.3390\/antiox11081605.<\/li>\n\n\n\n<li>Polcz ME, et al.: The Role of Vitamin A in Wound Healing. Nutr Clin Pract 2019; 34(5): 695\u2013700; doi: 10.1002\/ncp.10376.<\/li>\n\n\n\n<li>Siregar FD, et al.: The Role of Vitamin D on the Wound Healing Process: A Case Series. International Medical Case Reports Journal 2023: 16: 227-232.<\/li>\n\n\n\n<li>Bischoff-Ferrari HA, et al.: Estimation of optimal serum concentrations of 25-hydroxyvitamin D f\u00fcr multiple health outcomes. Am J Clin Nutr 2006; 84(1): 18\u201328.<\/li>\n\n\n\n<li>Hobson R.: Vitamin E and wound healing: an evidence-based review. Int Wound J 2016; 13: 331-335.<\/li>\n\n\n\n<li>Lin PH, et al.: Zinc in wound healing modulation. Nutrients 2018; 10: 16; doi: 10.3390\/nu10010016.<\/li>\n\n\n\n<li>Sieske L, et al.: Inflammation, appetite and food intake in older hospitalized patients. Nutrients 2019; 11(9): 1986. <\/li>\n\n\n\n<li>Robinson SM, et al.: Does nutrition play a role in the prevention and management of sarcopenia? Clin Nutr 2018; 37(4): 1121\u20131132. <\/li>\n\n\n\n<li>De Groot CP, van den Broek T, van Staveren W: Energy intake and micronutrient intake in elderly Europeans: seeking the minimum requirement in the SENECA study. Age and ageing 1999; 28(5): 469\u2013474.<\/li>\n\n\n\n<li>Volkert D, Kiesswetter E, Visser M: DoMAP \u2013 ein Determinanten-Modell zur Entstehung von Mangelern\u00e4hrung im Alter. Ern\u00e4hrungsUmschau 2020; 67: M530\u2013M535; doi: 10.4455\/eu.2020.047.<\/li>\n\n\n\n<li>Pirlich M, et al.: The German hospital malnutrition study. Clin Nutr 2006; 25(4): 563\u2013572. <\/li>\n\n\n\n<li>Valentini L, et al.: DGEM Terminologie in der klinischen Ern\u00e4hrung. Aktuel Ernahrungsmed 2013; 38: 97\u2013111. <\/li>\n\n\n\n<li>Cederholm T, et al.: GLIM criteria for the diagnosis of malnutrition \u2013 a consensus report from the Global Clinical Nutrition Community. Clin Nutr 2019; 38(1): 1\u20139.<\/li>\n\n\n\n<li>European Pressure Ulcer Advisory Panel, National Pressure Injury Advisory Panel and Pan Pacific Pressure Injury Alliance: Prevention and Treatment of Pressure Ulcers\/Injuries: Quick Reference Guide. Emily Haesler (Ed.). EPUAP\/NPIAP\/PPPIA 2019.<\/li>\n\n\n\n<li>Expertenstandard \u00abErn\u00e4hrungsmanagement zur Sicherung und F\u00f6rderung der oralen Ern\u00e4hrung in der Pflege \u2013 1. Aktualisierung 2017\u00bb. Schriftenreihe des Deutschen Netzwerks f\u00fcr Qualit\u00e4tsentwicklung in der Pflege. Osnabr\u00fcck; ISBN: 978-3-00-025800-8.<\/li>\n\n\n\n<li>Veitl V: Prophylaxe und Therapie der Wundheilungsst\u00f6rung \u2013 Bedeutung der Ern\u00e4hrung 2009; 41\u201351.<\/li>\n\n\n\n<li>Rosen C, Abrams SA, Aloia JF, et al.: IOM Committee Members Respond to Endocrine Society Vitamin D Guideline. Clin Endocrinol Metab 2012; 97(4): 1146\u20131152; doi: 10.1210\/jc.2011-2218.<\/li>\n\n\n\n<li>Recommandations pour l&#8217;apport en vitamines pour les adultes en bonne sant\u00e9 (mise \u00e0 jour : juin 2021)<a href=\"http:\/\/verbraucherzentrale.de\" target=\"_blank\" rel=\"noopener\">(verbraucherzentrale.de<\/a>) ; dernier acc\u00e8s : 12.05.2024.<\/li>\n\n\n\n<li>www.verbraucherzentrale.de\/sites\/default\/files\/2021-08\/empfehlungen_mineralstoffe_bf.pdf <a href=\"http:\/\/www.verbraucherzentrale.de\/sites\/default\/files\/2021-08\/empfehlungen_mineralstoffe_bf.pdf\" target=\"_blank\" rel=\"noopener\">;<\/a> dernier acc\u00e8s : 12.05.2024.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>HAUSARZT PRAXIS 2024; 19(6): 12\u201317<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour une cicatrisation efficace, il est essentiel d&#8217;avoir une alimentation riche en \u00e9nergie et en substrats. Les personnes \u00e2g\u00e9es pr\u00e9sentent un risque particuli\u00e8rement \u00e9lev\u00e9 de troubles de la cicatrisation des&hellip;<\/p>\n","protected":false},"author":7,"featured_media":381606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Traitement des plaies","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11549,11362,11404,11527,22616,11368,11428,11410],"tags":[76876,19831,21178,19527,12908,76877,68068,12902,76879,13705,70449],"powerkit_post_featured":[],"class_list":["post-381593","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-fr","category-dermatologie-et-venerologie","category-endocrinologie-et-diabetologie","category-etudes","category-formation-continue-cme","category-geriatrie-fr","category-infectiologie","category-nutrition-fr","tag-besoin-en-substrat","tag-cicatrisation-des-plaies","tag-escarres","tag-gestion-de-la-nutrition","tag-malnutrition-fr","tag-masse-maigre","tag-micronutriments-fr","tag-nutrition","tag-oligo-elements","tag-plaies-chroniques","tag-vitamines","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:46:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":381594,"slug":"limportanza-della-nutrizione-per-la-guarigione-delle-ferite-2","post_title":"L'importanza della nutrizione per la guarigione delle ferite","href":"https:\/\/medizinonline.com\/it\/limportanza-della-nutrizione-per-la-guarigione-delle-ferite-2\/"},"pt_PT":{"locale":"pt_PT","id":381595,"slug":"a-importancia-da-nutricao-para-a-cicatrizacao-de-feridas-2","post_title":"A import\u00e2ncia da nutri\u00e7\u00e3o para a cicatriza\u00e7\u00e3o de feridas","href":"https:\/\/medizinonline.com\/pt-pt\/a-importancia-da-nutricao-para-a-cicatrizacao-de-feridas-2\/"},"es_ES":{"locale":"es_ES","id":381596,"slug":"la-importancia-de-la-nutricion-para-la-cicatrizacion-de-heridas-2","post_title":"La importancia de la nutrici\u00f3n para la cicatrizaci\u00f3n de heridas","href":"https:\/\/medizinonline.com\/es\/la-importancia-de-la-nutricion-para-la-cicatrizacion-de-heridas-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/381593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=381593"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/381593\/revisions"}],"predecessor-version":[{"id":387414,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/381593\/revisions\/387414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/381606"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=381593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=381593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=381593"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=381593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}