{"id":397402,"date":"2025-03-17T13:54:48","date_gmt":"2025-03-17T12:54:48","guid":{"rendered":"https:\/\/medizinonline.com\/module-cancer-de-loesophage-et-de-lestomac\/"},"modified":"2025-03-18T09:37:30","modified_gmt":"2025-03-18T08:37:30","slug":"module-cancer-de-loesophage-et-de-lestomac","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/module-cancer-de-loesophage-et-de-lestomac\/","title":{"rendered":"Module Cancer de l&#8217;\u0153sophage et de l&#8217;estomac"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L&#8217;oncologie est en constante \u00e9volution, avec de nouvelles m\u00e9thodes de diagnostic, des m\u00e9thodes chirurgicales innovantes et des concepts th\u00e9rapeutiques constamment mis \u00e0 jour. Cela vaut \u00e9galement pour le traitement des cancers de l&#8217;\u0153sophage et de l&#8217;estomac, pour lesquels les directives et les donn\u00e9es d&#8217;\u00e9tudes actuelles jouent un r\u00f4le central.<br>Ce module de <em>Swiss Oncology in Motion<\/em> est consacr\u00e9 aux derniers d\u00e9veloppements dans le traitement de ces tumeurs. Anim\u00e9 par le PD Dr Ralph Fritsch (USZ Zurich), le PD Dr Alexander Reinhard Siebenh\u00fcner (Hirslanden Zurich) et le PD Dr Thomas Winder (Hirslanden Zurich), il offre un aper\u00e7u approfondi des possibilit\u00e9s de traitement actuelles et des connaissances scientifiques.  <\/strong><\/p>\n\n\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/fr\/mon-compte\/paquets\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/fr\/se-connecter\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Ffr%2Fmodule-cancer-de-loesophage-et-de-lestomac%2F\">Connectez-vous ici<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>L&#8217;oncologie est en constante \u00e9volution, avec de nouvelles m\u00e9thodes de diagnostic, des m\u00e9thodes chirurgicales innovantes et des concepts th\u00e9rapeutiques constamment mis \u00e0 jour. Cela vaut \u00e9galement pour le traitement des&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/fr\/mon-compte\/paquets\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/fr\/se-connecter\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Ffr%2Fmodule-cancer-de-loesophage-et-de-lestomac%2F\">Connectez-vous ici<\/a><\/div><\/div><\/div>","protected":false},"author":14,"featured_media":397413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"L'oncologie suisse en mouvement","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11549,11345,11389],"tags":[12006],"powerkit_post_featured":[],"class_list":["post-397402","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-fr","category-contenu-des-partenaires","category-oncologie","tag-loncologie-suisse-en-mouvement","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:30:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/397402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=397402"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/397402\/revisions"}],"predecessor-version":[{"id":397428,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/397402\/revisions\/397428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/397413"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=397402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=397402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=397402"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=397402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}