{"id":460114,"date":"2026-02-01T00:03:00","date_gmt":"2026-01-31T23:03:00","guid":{"rendered":"https:\/\/medizinonline.com\/ouvrir-de-nouveaux-horizons-grace-aux-therapies-combinees\/"},"modified":"2026-01-31T23:26:47","modified_gmt":"2026-01-31T22:26:47","slug":"ouvrir-de-nouveaux-horizons-grace-aux-therapies-combinees","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/ouvrir-de-nouveaux-horizons-grace-aux-therapies-combinees\/","title":{"rendered":"Ouvrir de nouveaux horizons gr\u00e2ce aux th\u00e9rapies combin\u00e9es"},"content":{"rendered":"\n<p><strong>Cette ann\u00e9e, le congr\u00e8s de l&#8217;<em>European Society for Medical Oncology, qui <\/em>s&#8217;est tenu \u00e0 Berlin du 17 au 21 octobre 2025, a propos\u00e9 une vari\u00e9t\u00e9 impressionnante de sujets sur de nombreuses entit\u00e9s tumorales et approches th\u00e9rapeutiques. Ceux-ci ont \u00e9t\u00e9 pr\u00e9sent\u00e9s sous diff\u00e9rents formats. Parmi ceux-ci figuraient des formats interactifs tels que les sessions &#8220;Challenge your Expert&#8221;, au cours desquelles le public pouvait poser des questions, apporter des commentaires critiques et confronter les experts \u00e0 des d\u00e9fis pratiques. Dans la session &#8220;Challenge your Expert-Gynae-Cancers&#8221;, David M. Gershenson a pr\u00e9sent\u00e9 de nouvelles approches th\u00e9rapeutiques du cancer s\u00e9reux de l&#8217;ovaire de bas grade (LGSOC). Sa pr\u00e9sentation s&#8217;est concentr\u00e9e sur le d\u00e9veloppement de th\u00e9rapies combin\u00e9es innovantes qui vont au-del\u00e0 des normes actuelles de chimioth\u00e9rapie et d&#8217;hormonoth\u00e9rapie et qui ouvrent de nouveaux horizons pour le traitement de cette entit\u00e9 tumorale rare.    <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/fr\/mon-compte\/paquets\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/fr\/se-connecter\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Ffr%2Fouvrir-de-nouveaux-horizons-grace-aux-therapies-combinees%2F\">Connectez-vous ici<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e, le congr\u00e8s de l&#8217;European Society for Medical Oncology, qui s&#8217;est tenu \u00e0 Berlin du 17 au 21 octobre 2025, a propos\u00e9 une vari\u00e9t\u00e9 impressionnante de sujets sur de&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/fr\/mon-compte\/paquets\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/fr\/se-connecter\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Ffr%2Fouvrir-de-nouveaux-horizons-grace-aux-therapies-combinees%2F\">Connectez-vous ici<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":460118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Cancer s\u00e9reux de l'ovaire de bas grade (LGSOC)  ","footnotes":"[{\"id\":\"46876782-286c-41fd-8c90-a1b266efa121\",\"content\":\"Selon la classification actuelle de l'OMS, les tumeurs borderline de l'ovaire (ou tumeurs \\u00e0 faible potentiel malin, LMP) sont des tumeurs \\u00e9pith\\u00e9liales de l'ovaire qui se situent morphologiquement entre les cystad\\u00e9nomes b\\u00e9nins et les carcinomes invasifs. Elles se caract\\u00e9risent par des atypies \\u00e9pith\\u00e9liales et une prolif\\u00e9ration, mais pas d'invasion destructrice du stroma [3]. Ces tumeurs apparaissent g\\u00e9n\\u00e9ralement chez des patientes jeunes, \\u00e2g\\u00e9es de 40 \\u00e0 55 ans, pr\\u00e9sentent un pronostic nettement plus favorable que les carcinomes invasifs et peuvent, dans certains cas, \\u00eatre consid\\u00e9r\\u00e9es comme des l\\u00e9sions pr\\u00e9curseurs du carcinome ovarien s\\u00e9reux de bas grade (LGSOC), comme l'expliquent Kurman et Shih dans leur travail fondamental sur la pathogen\\u00e8se des carcinomes ovariens \\u00e9pith\\u00e9liaux [4].  \"}]"},"category":[11527,11422,11389,11535,11549],"tags":[13668,87980,87983,87981,87991,87978,87984,49949,37794,46492,87985,22920,87989,87989,87987,87979,38738,25977,20774,21754,87977],"powerkit_post_featured":[],"class_list":{"0":"post-460114","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"category-etudes","7":"category-gynecologie","8":"category-oncologie","9":"category-rapports-de-congres","10":"category-rx-fr","11":"tag-braf-fr","12":"tag-cancer-sereux-de-lovaire-de-bas-grade-lgsoc","13":"tag-inhibiteur-de-cdk4-6-2","14":"tag-chimiotherapie-letrozole-versus-letrozole","15":"tag-etude-internationale-de-phase-ii-iii-gog-0281","16":"tag-etude-johns-hopkins","17":"tag-inhibiteur-de-braf-2","18":"tag-inhibiteur-de-braf","19":"tag-inhibiteur-de-cdk4-6","20":"tag-inhibiteur-mek","21":"tag-inhibiteur-mek-2","22":"tag-kras-fr","23":"tag-md-anderson-cancer-center-mdacc","25":"tag-medecine-moleculaire-de-precision","26":"tag-mutation-de-la-voie-de-signalisation-map-kinase","27":"tag-nras-fr","28":"tag-therapie-combinee","29":"tag-therapie-dentretien","30":"tag-therapie-hormonale","31":"tag-tumeurs-mixtes-lgsoc-et-hgsoc","32":"pmpro-level-required","33":"pmpro-level-1","34":"pmpro-no-access"},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:48:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":460117,"slug":"aprire-nuovi-orizzonti-attraverso-le-terapie-di-combinazione","post_title":"Aprire nuovi orizzonti attraverso le terapie di combinazione","href":"https:\/\/medizinonline.com\/it\/aprire-nuovi-orizzonti-attraverso-le-terapie-di-combinazione\/"},"pt_PT":{"locale":"pt_PT","id":460120,"slug":"abrir-novos-horizontes-atraves-de-terapias-combinadas","post_title":"Abrir novos horizontes atrav\u00e9s de terapias combinadas","href":"https:\/\/medizinonline.com\/pt-pt\/abrir-novos-horizontes-atraves-de-terapias-combinadas\/"},"es_ES":{"locale":"es_ES","id":460123,"slug":"abrir-nuevos-horizontes-mediante-terapias-combinadas","post_title":"Abrir nuevos horizontes mediante terapias combinadas","href":"https:\/\/medizinonline.com\/es\/abrir-nuevos-horizontes-mediante-terapias-combinadas\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/460114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=460114"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/460114\/revisions"}],"predecessor-version":[{"id":460119,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/460114\/revisions\/460119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/460118"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=460114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=460114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=460114"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=460114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}