{"id":461290,"date":"2026-03-03T23:03:16","date_gmt":"2026-03-03T22:03:16","guid":{"rendered":"https:\/\/medizinonline.com\/utiliser-les-effets-pleiotropiques-cardioprotecteurs-et-nephroprotecteurs-du-sglt-2-i-et-du-glp-1-ra\/"},"modified":"2026-01-28T14:06:53","modified_gmt":"2026-01-28T13:06:53","slug":"utiliser-les-effets-pleiotropiques-cardioprotecteurs-et-nephroprotecteurs-du-sglt-2-i-et-du-glp-1-ra","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/utiliser-les-effets-pleiotropiques-cardioprotecteurs-et-nephroprotecteurs-du-sglt-2-i-et-du-glp-1-ra\/","title":{"rendered":"Utiliser les effets pl\u00e9iotropiques cardioprotecteurs et n\u00e9phroprotecteurs du SGLT-2-i et du GLP-1-RA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Selon les connaissances actuelles, le diab\u00e8te de type 2 est une maladie multisyst\u00e9mique, dont le pronostic est largement influenc\u00e9 par la pathologie cardiaque et r\u00e9nale. C&#8217;est pourquoi une approche th\u00e9rapeutique pr\u00e9coce et multimodale, qui va au-del\u00e0 du simple contr\u00f4le de la glyc\u00e9mie, est importante. Il est d\u00e9sormais empiriquement prouv\u00e9 que les inhibiteurs du SGLT-2 et les agonistes des r\u00e9cepteurs du GLP-1 offrent des avantages en termes de cardioprotection et de n\u00e9phroprotection, et des \u00e9tudes r\u00e9centes ont montr\u00e9 que leur utilisation combin\u00e9e permettait d&#8217;obtenir des effets synergiques.    <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/fr\/mon-compte\/paquets\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/fr\/se-connecter\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Ffr%2Futiliser-les-effets-pleiotropiques-cardioprotecteurs-et-nephroprotecteurs-du-sglt-2-i-et-du-glp-1-ra%2F\">Connectez-vous ici<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Selon les connaissances actuelles, le diab\u00e8te de type 2 est une maladie multisyst\u00e9mique, dont le pronostic est largement influenc\u00e9 par la pathologie cardiaque et r\u00e9nale. C&#8217;est pourquoi une approche th\u00e9rapeutique&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/fr\/mon-compte\/paquets\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/fr\/se-connecter\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Ffr%2Futiliser-les-effets-pleiotropiques-cardioprotecteurs-et-nephroprotecteurs-du-sglt-2-i-et-du-glp-1-ra%2F\">Connectez-vous ici<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":461285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Diab\u00e8te de type 2 - contr\u00f4le glyc\u00e9mique et pr\u00e9vention des complications","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11549,11378,11404,11527,11434,11535],"tags":[15907,12050,65614,88197,88196,18589],"powerkit_post_featured":[],"class_list":["post-461290","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-fr","category-cardiologie","category-endocrinologie-et-diabetologie","category-etudes","category-nephrologie-fr","category-rapports-de-congres","tag-controle-glycemique","tag-diabete-de-type-2","tag-glp-1-ra-fr-2","tag-maladies-secondaires-cardioprotectrices","tag-nephroprotecteur-2","tag-sglt-2-i-fr","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:52:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":461533,"slug":"sfruttare-gli-effetti-pleiotropici-cardio-e-nefroprotettivi-di-sglt-2-i-e-glp-1-ra","post_title":"Sfruttare gli effetti pleiotropici cardio- e nefroprotettivi di SGLT-2-i e GLP-1-RA","href":"https:\/\/medizinonline.com\/it\/sfruttare-gli-effetti-pleiotropici-cardio-e-nefroprotettivi-di-sglt-2-i-e-glp-1-ra\/"},"pt_PT":{"locale":"pt_PT","id":461530,"slug":"utilizacao-dos-efeitos-pleiotropicos-cardio-e-nefroprotectores-do-sglt-2-i-e-do-glp-1-ra","post_title":"Utiliza\u00e7\u00e3o dos efeitos pleiotr\u00f3picos cardio e nefroprotectores do SGLT-2-i e do GLP-1-RA","href":"https:\/\/medizinonline.com\/pt-pt\/utilizacao-dos-efeitos-pleiotropicos-cardio-e-nefroprotectores-do-sglt-2-i-e-do-glp-1-ra\/"},"es_ES":{"locale":"es_ES","id":461527,"slug":"utilizacion-de-los-efectos-pleiotropicos-cardioprotectores-y-nefroprotectores-de-sglt-2-i-y-glp-1-ra","post_title":"Utilizaci\u00f3n de los efectos pleiotr\u00f3picos cardioprotectores y nefroprotectores de SGLT-2-i y GLP-1-RA","href":"https:\/\/medizinonline.com\/es\/utilizacion-de-los-efectos-pleiotropicos-cardioprotectores-y-nefroprotectores-de-sglt-2-i-y-glp-1-ra\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/461290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=461290"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/461290\/revisions"}],"predecessor-version":[{"id":461291,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/461290\/revisions\/461291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/461285"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=461290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=461290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=461290"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=461290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}