{"id":98278,"count":1,"description":"","link":"https:\/\/medizinonline.com\/fr\/tag\/modele-times-devaluation-immunologique-spatiale-dans-le-cas-des-cholangiocarcinomes\/","name":"Mod\u00e8le TIMES d'\u00e9valuation immunologique spatiale dans le cas des cholangiocarcinomes","slug":"modele-times-devaluation-immunologique-spatiale-dans-le-cas-des-cholangiocarcinomes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags\/98278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts?tags=98278"},{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/article_rx?tags=98278"},{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/post_dl?tags=98278"},{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tribe_events?tags=98278"},{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tec_calendar_embed?tags=98278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}