{"id":260965,"date":"2022-12-28T01:00:00","date_gmt":"2022-12-28T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/quali-sono-gli-standard-di-qualita-piu-importanti-per-la-colonscopia\/"},"modified":"2023-01-11T03:10:05","modified_gmt":"2023-01-11T02:10:05","slug":"quali-sono-gli-standard-di-qualita-piu-importanti-per-la-colonscopia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/quali-sono-gli-standard-di-qualita-piu-importanti-per-la-colonscopia\/","title":{"rendered":"Quali sono gli standard di qualit\u00e0 pi\u00f9 importanti per la colonscopia?"},"content":{"rendered":"<p><strong>La colonscopia \u00e8 una procedura di screening importante per individuare e rimuovere adenomi e polipi che possono potenzialmente portare al cancro del colon-retto. Da alcuni anni, un alto tasso di rilevamento dell&#8217;adenoma \u00e8 considerato un criterio importante per la colonscopia di screening. Per valutare la qualit\u00e0 della pulizia intestinale, si pu\u00f2 utilizzare la Scala di preparazione intestinale di Boston.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Il carcinoma del colon o del retto (carcinoma colorettale) \u00e8 il terzo tumore pi\u00f9 comune negli uomini e il secondo pi\u00f9 comune nelle donne in Svizzera [1]. Ogni anno, in questo Paese, a 4300 persone viene diagnosticato il cancro al colon; la maggior parte delle persone colpite ha pi\u00f9 di 50 anni [1]. In Svizzera, l&#8217;assicurazione sanitaria obbligatoria copre due colonscopie a intervalli di \u226510 anni o un test delle feci per la ricerca di sangue occulto (test immunochimico fecale, FIT) a intervalli di \u22652 anni tra i 50 e i 69 anni. In caso di riscontro positivo nel FIT, \u00e8 necessario eseguire un esame endoscopico dell&#8217;intero colon. La colonscopia di screening viene utilizzata per la diagnosi precoce del cancro all&#8217;intestino e per la resezione dei polipi intestinali. In caso di pazienti ad alto rischio e\/o di sintomi sospetti <span style=\"font-family:franklin gothic demi\">(panoramica&nbsp;1) <\/span>, la colonscopia pu\u00f2 essere indicata anche al di fuori di questo intervallo di et\u00e0 [2]. La colonscopia con prelievo di biopsie ha la pi\u00f9 alta sensibilit\u00e0 e specificit\u00e0 di tutti gli esami e rappresenta quindi il gold standard diagnostico. Che la colonscopia possa ridurre l&#8217;incidenza del cancro del colon-retto e i tassi di mortalit\u00e0 \u00e8 stato dimostrato, ad esempio, nello studio non randomizzato di &#8220;coorte chiusa&#8221; nei cantoni svizzeri di montagna [3]. In Germania, la prevalenza del cancro del colon-retto \u00e8 diminuita in modo significativo nella fascia di et\u00e0 55-84 anni, dall&#8217;introduzione delle colonscopie di screening approvate dall&#8217;assicurazione sanitaria nel 2002: del 17-20% negli uomini e del 20-26% nelle donne [4].<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-20271\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/ubersicht1_hp11_s35.png\" style=\"height:225px; width:400px\" width=\"752\" height=\"423\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"tasso-di-rilevamento-delladenoma-adr\">Tasso di rilevamento dell&#8217;adenoma (ADR)<\/h2>\n<p>Secondo l&#8217;OMS, le misure di screening efficaci dovrebbero essere documentate attraverso la garanzia di qualit\u00e0 [5,6]. Un documento di posizione della Societ\u00e0 Europea di Endoscopia Gastrointestinale (ESGE) elenca le &#8220;misure di performance attualmente raccomandate per l&#8217;endoscopia gastrointestinale inferiore&#8221; [7]. Si tratta di parametri che hanno dimostrato di essere associati a esiti migliori. In grandi studi di coorte, il tasso di rilevamento degli adenomi (ADR) in particolare \u00e8 stato associato a una minore incidenza e mortalit\u00e0 del cancro del colon-retto [8,9]. L&#8217;ADR target \u00e8 del 25%, in base al fatto che un valore di cut-off del 24,6% \u00e8 stato associato alla pi\u00f9 bassa mortalit\u00e0 per cancro colorettale [10,11].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-20272 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s35.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/286;height:156px; width:600px\" width=\"1100\" height=\"286\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"qualita-della-preparazione-scala-di-preparazione-dellintestino-di-boston-bbps\">Qualit\u00e0 della preparazione: &#8220;Scala di preparazione dell&#8217;intestino di Boston&#8221; (BBPS).<\/h2>\n<p>Il rilevamento degli adenomi dipende essenzialmente dalla visualizzazione dell&#8217;intera mucosa colonica. Pertanto, oltre a un&#8217;ADR elevata, \u00e8 importante ottenere una qualit\u00e0 di preparazione adeguata e un tasso di raggiungimento cecale sufficiente. A questo scopo, si raccomanda l&#8217;uso di un sistema di punteggio convalidato, come la <em>Boston Bowel Preparation Scale<\/em><span style=\"font-family:franklin gothic demi\">(box<\/span> ) [12,13]. La qualit\u00e0 della preparazione del colon valutato deve essere almeno moderata [8, 14]. Si raccomanda di puntare a un&#8217;alta percentuale di colonscopie con pre-scansione del cieco, poich\u00e9 una bassa percentuale di raggiungimento del cieco \u00e8 associata a una maggiore incidenza di carcinoma colorettale (sia distale che prossimale) [15]. Attualmente, lo standard minimo \u00e8 un tasso di raggiungimento cecale \u226590%, con un tasso \u226595% considerato ottimale [16]. Per garantire che i polipi siano completamente ablati, l&#8217;ESGE specifica un tasso di ablazione conforme alle linee guida di almeno l&#8217;80%. Ci\u00f2 significa che i polipi &lt;di 10 mm devono essere rimossi con il rasoio a freddo e \u226510 mm con il rasoio a caldo [17]. Una tecnica di ablazione dei polipi inadeguata \u00e8 responsabile fino al 25% dei casi di cancro colorettale post-colonscopia (PCCRC) [18].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-20273 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/kasten_hp11_s35.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/411;height:224px; width:600px\" width=\"1100\" height=\"411\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"follow-up-dopo-la-polipectomia\">Follow-up dopo la polipectomia<\/h2>\n<p>La colonscopia \u00e8 considerata una procedura molto sicura. Gli studi indicano un tasso di complicanze di circa 0,3-0,5 per 1000 esami [19]. Le complicazioni che si verificano durante l&#8217;esame e gli eventi che si verificano dopo la colonscopia, come il ricovero ospedaliero o la mortalit\u00e0 a 30 giorni, devono essere documentati secondo l&#8217;ESGE [16]. In termini di compliance del paziente, \u00e8 importante ridurre al minimo il dolore e il disagio durante la colonscopia. Anche se attualmente non esiste uno standard fisso per la soddisfazione del paziente, l&#8217;esperienza ha dimostrato che pratiche di sedazione efficaci durante la colonscopia possono contribuire a migliorare l&#8217;esperienza del paziente [20]. Dopo la colonscopia di screening, \u00e8 essenziale una gestione corretta con eventuali colonscopie di follow-up. Questo perch\u00e9 solo con un adeguato follow-up dopo la polipectomia \u00e8 possibile rimuovere eventuali polipi cresciuti di nuovo o resecati in modo incompleto. La <em>Societ\u00e0 Europea di Endoscopia Gastrointestinale&nbsp;<\/em>raccomanda ai pazienti con polipi ad alto rischio di sottoporsi a un&#8217;altra colonscopia dopo 3 anni. Nei pazienti senza polipi ad alto rischio, un&#8217;ulteriore colonscopia dopo 10 anni \u00e8 considerata ragionevole. La definizione di polipi ad alto rischio \u00e8 stata aggiornata nel 2020 [21]. Di conseguenza, il follow-up deve essere effettuato solo nei pazienti che hanno almeno un adenoma con displasia di alto grado o una dimensione \u226510 mm o nei pazienti che hanno \u22655 adenomi o che hanno almeno un polipo dentellato con displasia o una dimensione \u226510 mm.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Screening del cancro in Svizzera, www.swisscancerscreening.ch, (ultimo accesso 03.11.2022)<\/li>\n<li>&#8220;Rilevare precocemente il cancro all&#8217;intestino: Cosa ha senso?&#8221;. Prof. Dr. med. Benjamin Misselwitz, Clinica di chirurgia e medicina viscerale, Inselspital di Berna, 07.05.2022<\/li>\n<li>Manser CN, et al: Lo screening con colonscopia riduce notevolmente l&#8217;insorgenza di carcinomi del colon e di decessi correlati al carcinoma: uno studio di coorte chiuso. Gastrointest Endosc 2012; 76(1): 110-117.<\/li>\n<li>Brenner H, et al: Declino dell&#8217;incidenza e della mortalit\u00e0 del cancro colorettale in Germania. Dtsch Arztebl Int 2016; 113: 101-106; DOI: 10.3238\/arztebl.2016.0101<\/li>\n<li>OMS, https:\/\/apps.who.int\/iris\/handle\/10665\/330829, (ultimo accesso 03.11.2022)<\/li>\n<li>Zessner-Spitzenberg J, Waldmann E, Ferlitsch M: Garanzia di qualit\u00e0 nella colonscopia di screening in Austria e a livello europeo. J Gastroenterol Hepatol Erkr 2022, https:\/\/doi.org\/10.1007\/s41971-022-00137-w<\/li>\n<li>Kaminski MF, et al: Misure di performance per l&#8217;endoscopia gastrointestinale inferiore: un&#8217;iniziativa di miglioramento della qualit\u00e0 della Societ\u00e0 Europea di Endoscopia Gastrointestinale (ESGE). United European Gastroenterol j 2017; 5: 309-334.<\/li>\n<li>Kaminski MF, et al: Indicatori di qualit\u00e0 per la colonscopia e il rischio di cancro dell&#8217;intervallo. N Engl J Med 2010; 362: 1795-1803.<\/li>\n<li>Corley DA, et al: Tasso di rilevamento dell&#8217;adenoma e rischio di cancro colorettale e di morte. N Engl J Med 2014; 370: 1298-1306.<\/li>\n<li>Rembacken B, et al.: Qualit\u00e0 nella colonscopia di screening: dichiarazione di posizione della Societ\u00e0 europea di endoscopia gastrointestinale (ESGE). Endoscopia 2012; 44: 957-968.<\/li>\n<li>Kaminski MF, et al: L&#8217;aumento del tasso di rilevamento dell&#8217;adenoma si associa a un rischio ridotto di cancro del colon-retto e di morte. Gastroenterologia 2017; 153: 98-105.<\/li>\n<li>Calderwood AH, Jacobson BC: Convalida completa della scala di preparazione intestinale di Boston. Gastrointest Endosc 2010; 72: 686-692.<\/li>\n<li>Aronchick C, et al: Validazione di uno strumento per valutare la pulizia del colon. Am J Gastroenterol 1999; 94: 2667.<\/li>\n<li>Clark BT, et al: Quantificazione della preparazione intestinale adeguata per la colonscopia di screening o di sorveglianza negli uomini. Gastroenterologia 2016; 150:396-e315.<\/li>\n<li>Baxter NN, et al: L&#8217;analisi dei dati amministrativi rileva misure di qualit\u00e0 dell&#8217;endoscopista associate al cancro colorettale postcolonoscopico. Gastroenterologia 2011; 140: 65-72.<\/li>\n<li>Kaminski MF, et al: Misure di performance per l&#8217;endoscopia gastrointestinale inferiore: un&#8217;iniziativa di miglioramento della qualit\u00e0 della Societ\u00e0 Europea di Endoscopia Gastrointestinale (ESGE). Endoscopia 2017; 49: 378-397.<\/li>\n<li>Ferlitsch M, et al: Polipectomia colorettale e resezione endoscopica mucosa (EMR): linea guida clinica della Societ\u00e0 Europea di Endoscopia Gastrointestinale (ESGE). Endoscopia 2017; 49: 270-297.<\/li>\n<li>Robertson DJ, et al: Tumori del colon-retto subito dopo la colonscopia: un&#8217;analisi multicoorte in pool. Gut 2014; 63: 949-956.<\/li>\n<li>Reumkens A, et al: Complicazioni post-colonscopia: una revisione sistematica, tendenze temporali e meta-analisi di studi basati sulla popolazione. Am J Gastroenterol 2016; 111: 1092-1101.<\/li>\n<li>Harewood GC, Wiersema MJ, Melton JL III: Una valutazione prospettica e controllata dei fattori che influenzano l&#8217;accettazione della colonscopia di screening. Am J Gastroenterol 2002; 97(12): 3186-3194.<\/li>\n<li>Hassan C, et al: Sorveglianza della colonscopia post-polipectomia: aggiornamento delle linee guida della Societ\u00e0 Europea di Endoscopia Gastrointestinale (ESGE) 2020. Endoscopia 2020: 52: 687-700.<\/li>\n<li>Boston Bowel Preparation Scale (BBPS),&nbsp;www.gastropraxis-sh.ch\/fur-aerzte\/bbps.pdf,&nbsp;(ultimo accesso 03.11.2022).<\/li>\n<li>Lai EJ, et al: La scala di preparazione intestinale di Boston: uno strumento valido e affidabile per la ricerca orientata alla colonscopia. Gastrointest Endosc 2009; 69(3 Pt 2): 620-625.<\/li>\n<li>Strum WB: Adenomi colorettali. N Engl J Med 2016; 374: 1065-1075.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATICA GP 2022; 17(10): 35-36<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La colonscopia \u00e8 una procedura di screening importante per individuare e rimuovere adenomi e polipi che possono potenzialmente portare al cancro del colon-retto. Da alcuni anni, un alto tasso di&hellip;<\/p>\n","protected":false},"author":7,"featured_media":126934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Screening del cancro all'intestino","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11401,11306,11376,11473,11550,11515],"tags":[11579,11580,11578],"powerkit_post_featured":[],"class_list":["post-260965","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-gastroenterologia-ed-epatologia","category-medicina-interna-generale","category-oncologia-it","category-prevenzione-e-assistenza-sanitaria","category-rx-it","category-studi","tag-cancro-del-colon-retto","tag-colonscopia","tag-disposizione","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:57:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":260989,"slug":"quais-sao-os-padroes-de-qualidade-mais-importantes-para-a-colonoscopia","post_title":"Quais s\u00e3o os padr\u00f5es de qualidade mais importantes para a colonoscopia?","href":"https:\/\/medizinonline.com\/pt-pt\/quais-sao-os-padroes-de-qualidade-mais-importantes-para-a-colonoscopia\/"},"es_ES":{"locale":"es_ES","id":260963,"slug":"cuales-son-las-normas-de-calidad-mas-importantes-para-la-colonoscopia","post_title":"\u00bfCu\u00e1les son las normas de calidad m\u00e1s importantes para la colonoscopia?","href":"https:\/\/medizinonline.com\/es\/cuales-son-las-normas-de-calidad-mas-importantes-para-la-colonoscopia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/260965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=260965"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/260965\/revisions"}],"predecessor-version":[{"id":323719,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/260965\/revisions\/323719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/126934"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=260965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=260965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=260965"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=260965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}