{"id":324851,"date":"2022-09-05T14:00:00","date_gmt":"2022-09-05T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-moderna-gestione-della-spondiloartrite-assiale\/"},"modified":"2022-09-05T14:00:00","modified_gmt":"2022-09-05T12:00:00","slug":"la-moderna-gestione-della-spondiloartrite-assiale","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/la-moderna-gestione-della-spondiloartrite-assiale\/","title":{"rendered":"La moderna gestione della spondiloartrite assiale"},"content":{"rendered":"<p><strong>Per i pazienti con spondiloartrite assiale (axSpA), per i quali la terapia con farmaci antinfiammatori non steroidei non \u00e8 stata efficace, oggi sono disponibili diversi principi attivi appartenenti alle classi di sostanze dei biologici e degli inibitori JAK. Oltre all&#8217;efficacia, un importante criterio di selezione \u00e8 il profilo di sicurezza del DMARD. Inoltre, si devono prendere in considerazione le preferenze del paziente. Le raccomandazioni ASAS-EULAR forniscono anche indicazioni su come procedere quando si cambia terapia.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Al <em>Meeting annuale dell&#8217;EULAR<\/em> di quest&#8217;anno, esperti di fama hanno discusso le ultime scoperte sulla diagnosi e sul trattamento della spondiloartrite assiale (axSpA). L&#8217;AxSpA \u00e8 una malattia infiammatoria della colonna vertebrale di tipo reumatico che pu\u00f2 essere accompagnata da varie manifestazioni muscolo-scheletriche ed extrascheletriche [1]. Il sintomo principale dell&#8217;axSpA \u00e8 il dolore infiammatorio alla schiena. Il work-up diagnostico comprende la radiografia e la risonanza magnetica della colonna lombare (LS) e delle articolazioni sacroiliache, nonch\u00e9 uno screening di laboratorio che include i marcatori infiammatori (VES, CRP) e il test per l&#8217;HLA-B27 [2]. Oltre alle manifestazioni extra-articolari, l&#8217;anamnesi deve includere anche l&#8217;esplorazione degli stress psicosociali\/lavorativi. I criteri di classificazione ASAS (&#8220;Assessment of SpondyloArthritis International Society&#8221;) sono stati stabiliti per confermare la diagnosi <span style=\"font-family:franklin gothic demi\">(Fig. 1)<\/span> [3]. Questi richiedono una prova obbligatoria dell&#8217;HLA-B27; un ulteriore criterio \u00e8 la sacroileite rilevabile con la diagnostica per immagini. I pazienti senza alterazioni strutturali sono definiti come SpA assiale non radiografica, mentre i pazienti con alterazioni strutturali nelle articolazioni sacroiliache sono classificati come affetti da spondiloartrite anchilosante (spondilite anchilosante). Oltre ai risultati dell&#8217;esame clinico, della diagnostica per immagini e di laboratorio, per registrare l&#8217;attivit\u00e0 della malattia sono disponibili il BASDAI <em>(Bath Ankylosing Spondylitis Disease Activity Index) <\/em>e il pi\u00f9 recente ASDAS<em> (Ankylosing Spondylitis Disease Activity Score)<\/em>, che si basa su alcune domande del BASDAI e include la CRP [4\u20137]. L&#8217;attivit\u00e0 della malattia deve essere controllata a intervalli regolari &#8211; di solito ogni 3-6 mesi &#8211; utilizzando i punteggi clinici compositi [3,5].<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-19574\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16.png\" style=\"height:425px; width:600px\" width=\"1100\" height=\"780\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16-800x567.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16-120x85.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16-90x64.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16-320x227.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/abb1_hp8_s16-560x397.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"concetto-di-trattamento-multimodale\">Concetto di trattamento multimodale<\/h2>\n<p>Per il trattamento dei pazienti con axSpA, si raccomanda una combinazione di misure non farmacologiche (ad esempio, terapia di esercizio) e terapia farmacologica [1]. Oltre alla riduzione del dolore, l&#8217;obiettivo \u00e8 mantenere il funzionamento fisico e prevenire le lesioni strutturali [5,8,9]. Gli obiettivi del trattamento farmacologico sono principalmente la riduzione dell&#8217;attivit\u00e0 della malattia e il raggiungimento della remissione clinica. Questo include la riduzione del dolore, la riduzione dei processi infiammatori e l&#8217;inibizione della progressione radiografica. I farmaci antinfiammatori non steroidei (FANS) sono ancora considerati la terapia di prima linea per la SpA assiale [5]. A causa del profilo di sicurezza dei preparati FANS, il dosaggio e la durata della terapia devono essere continuamente rivisti. I farmaci <em>antireumatici modificanti la malattia<\/em> (DMARD) possono essere utilizzati nei pazienti che non ottengono una riduzione sufficiente dell&#8217;attivit\u00e0 infiammatoria della malattia con la terapia standard con FANS.<\/p>\n<h2 id=\"biologici-e-inibitori-jak-qual-e-lo-stato-attuale-delle-conoscenze\">Biologici e inibitori JAK: qual \u00e8 lo stato attuale delle conoscenze?<\/h2>\n<p>La Prof. Dr med. D\u00e9sir\u00e9e van der Heijde, Leiden University Medical Center (NL), ha fornito un aggiornamento sui bDMARD e tsDMARD come opzioni di trattamento per l&#8217;axSpA [10]. Una delle novit\u00e0 delle raccomandazioni ASAS-EULAR per la gestione dell&#8217;axSpA, aggiornate nel 2022, \u00e8 che i criteri ASDAS <span style=\"font-family:franklin gothic demi\">(Fig. 1) <\/span>sono utilizzati principalmente per valutare il decorso della malattia, mentre i criteri BASDAI sono diventati meno importanti. In caso di persistenza di un&#8217;attivit\u00e0 patologica elevata nonostante la terapia con FANS, con un punteggio ASDAS \u22652,1, si suggerisce di iniziare una terapia con un inibitore del TNF\u03b1 (TNF\u03b1-i), un inibitore dell&#8217;IL-17 (IL-17-i) o un inibitore della Janus chinasi (JAK-i). Sebbene i dati di efficacia dei biologici e di JAK-i siano simili, in genere si consiglia di provare prima il TNF\u03b1-i o l&#8217;IL-17-i. &#8220;Gli aspetti di sicurezza sono prevalentemente decisivi per la preferenza degli inibitori del TNF\u03b1 e degli inibitori dell&#8217;IL-17 rispetto agli inibitori della JAK&#8221;, spiega il relatore.<\/p>\n<p>Per quanto riguarda l&#8217;IL-17-i secukinumab, i dati della fase di estensione degli studi controllati randomizzati mostrano un basso tasso di infezioni gravi, tumori maligni ed eventi cardiovascolari. I dati su ixekizumab, anch&#8217;esso un IL-17-i, sono limitati. Questo vale anche per JAK-i, dove sono disponibili solo i dati di RCT a breve termine.<\/p>\n<p>Nei pazienti con artrite reumatoide (RA) e determinati fattori di rischio, i dati dello studio <em>Oral Surveillance<\/em> indicano che le JAK-i sono associate ad un aumento del rischio di eventi cardiovascolari (MACE) e di neoplasie. L&#8217;oratore ha sottolineato che la popolazione di pazienti RA non \u00e8 la stessa della popolazione axSpA [10,14]. Tuttavia, invita anche alla cautela nei pazienti con SpA assiale e alcuni fattori di rischio, data la scarsit\u00e0 di dati relativi a JAK-i. In ogni caso, i benefici e i rischi devono essere valutati attentamente in ogni singolo caso.<\/p>\n<p>La <span style=\"font-family:franklin gothic demi\">Tabella 1<\/span> riassume l&#8217;efficacia dei bDMARD e dei tsDMARD sulle diverse manifestazioni dell&#8217;axSpA. Gli studi osservazionali indicano che adalimumab, infliximab, golimumab e certolizumab pegol hanno un&#8217;efficacia maggiore nei confronti dell&#8217;uveite rispetto a secukinumab ed etanercept [11]. Non sono disponibili dati sugli inibitori JAK tofacitinib e upadacitinib.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-19575 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/406;height:221px; width:600px\" width=\"1100\" height=\"406\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0-800x295.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0-120x44.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0-90x33.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0-320x118.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1_hp8_s17_0-560x207.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"il-tentativo-di-trattamento-con-una-dmard-e-fallito-cosa-fare\">Il tentativo di trattamento con una DMARD \u00e8 fallito &#8211; cosa fare?<\/h2>\n<p>Sulla questione di cosa fare se il trattamento con un bDMARD non \u00e8 stato efficace, il Prof. van der Heijde consiglia: &#8220;La prima cosa da fare \u00e8 riconsiderare la diagnosi&#8221;. Questo \u00e8 particolarmente vero quando i pazienti con dolore alla schiena non hanno risposto alla terapia con TNF\u03b1-i o IL-17-i. Se l&#8217;attivit\u00e0 della malattia \u00e8 elevata, bisogna chiedersi se ci sono altre comorbidit\u00e0 o caratteristiche del paziente che possono influenzare questo dato. In questi casi, si raccomanda una risonanza magnetica per determinare se ci sono prove di infiammazione nella colonna vertebrale. Qual \u00e8 la raccomandazione specifica delle raccomandazioni ASAS-EULAR aggiornate su questo tema? Questo stabilisce che dopo un primo tentativo di trattamento fallito con un bDMARD o un tsDMARD, si dovrebbe passare a un altro bDMARD (TNF\u03b1-i o IL-17-i) o a un JAK-i. Nel complesso, i dati sul cambiamento di terapia dopo un tentativo di trattamento fallito con uno o pi\u00f9 bDMARD o tsDMRAD sono piuttosto limitati al momento, ha detto il relatore. Ci sono dati sul secukinumab che dimostrano che si ottengono buoni tassi di risposta nei pazienti che hanno avuto un tentativo fallito di trattamento con TNF\u03b1-i, anche se i tassi di risposta tendevano ad essere migliori nei pazienti biologicamente na\u00efve [12]. Lo stesso schema \u00e8 stato visto negli studi corrispondenti su ixekizumab [13].<\/p>\n<p>Il docente ha sottolineato che \u00e8 sempre importante prendere in considerazione i principi generali di terapia nel trattamento dei pazienti con axSpA. Il processo decisionale per la migliore opzione terapeutica possibile deve essere fatto insieme al paziente (&#8220;processo decisionale condiviso&#8221;). Si devono prendere in considerazione anche i criteri individuali e sociali. Se necessario, la forma di applicazione (sc, iv, orale) pu\u00f2 essere un criterio per selezionare il trattamento pi\u00f9 adatto in ogni caso, oltre all&#8217;efficacia, alla sicurezza e al fattore costo.<\/p>\n<p><em>Congresso:&nbsp;Riunione annuale EULAR<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Kiltz U, et al: Versione lunga della linea guida S3 Spondiloartrite assiale, inclusa la spondilite anchilosante e le forme precoci, aggiornamento, Z Rheumatol 2019(78): 3-64.<\/li>\n<li>Rudwaleit M: Spondiloartriti. Z Rheumatol 2017; 76(10): 889-903.<\/li>\n<li>Holak G: Diagnosi e terapia della spondiloartrite assiale. Studi di letteratura DFP 2021, www.pains.at\/wp-content\/uploads\/SN-1-21-DFP-Diagnose-und-Therapie-der-axialen-Spondyloarthritis_komprimiert.pdf, (ultimo accesso 14.07.2022)<\/li>\n<li>Rudwaleit M, et al: Lo stadio iniziale della malattia nella spondiloartrite assiale: risultati della German Spondyloarthritis Inception Cohort. Arthritis Rheum 2009; 60(3): 717-727.<\/li>\n<li>Spondiloartrite assiale, compresa la spondilite anchilosante e le forme precoci, Numero di registro delle linee guida AWMF: 060\/003, Fase di sviluppo: S3 Versione: 2019.<\/li>\n<li>Garrett S, et al: Un nuovo approccio per definire lo stato di malattia nella spondilite anchilosante: il Bath Ankylosing Spondylitis Disease Activity Index. J Rheumatol 1994; 21(12): 2286-2291.<\/li>\n<li>van der Heijde D, et al: ASDAS, un punteggio di attivit\u00e0 di malattia altamente discriminatorio approvato dall&#8217;ASAS nei pazienti con spondilite anchilosante. Ann Rheum Dis 2009; 68(12): 1811-1818.<\/li>\n<li>van der Heijde D, et al: Core set preliminari per gli endpoint nella spondilite anchilosante. Gruppo di lavoro Valutazioni nella Spondilite Anchilosante. J Rheumatol 1997; 24(11): 2225-2229; 321.<\/li>\n<li>van der Heijde D, et al: Spondilite anchilosante: discussione plenaria e risultati della votazione sulla selezione dei domini e di alcuni strumenti specifici. J Rheumatol 1999; 26(4): 1003-1005.<\/li>\n<li>&#8220;DMARD mirati sintetici o biologici nella spondiloartrite assiale&#8221;, Prof. D\u00e9sir\u00e9e van der Heijde, MD, EULAR, 04.06.2022<\/li>\n<li>Lindstr\u00f6m U, et al: Uveite anteriore in pazienti con spondiloartrite trattati con secukinumab o inibitori del fattore di necrosi tumorale nell&#8217;assistenza di routine: la scelta della terapia biologica \u00e8 importante? Ann Rheum Dis 2021; 80(11): 1445-1452.<\/li>\n<li>Kivitz AJ, et al: Efficacia e sicurezza del Secukinumab 150 mg con e senza regime di carico nella Spondilite Anchilosante: risultati a 104 settimane dello studio MEASURE 4. Rheumatol Ther 2018; 5(2): 447-462.<\/li>\n<li>Deodhar A: Gruppo di studio COAST-W. Efficacia e sicurezza di Ixekizumab nel trattamento della spondiloartrite assiale radiografica: risultati di sedici settimane di uno studio di Fase III randomizzato, in doppio cieco, controllato con placebo, in pazienti con precedente risposta inadeguata o intolleranza agli inibitori del fattore di necrosi tumorale. Arthritis Rheumatol 2019; 71(4): 599-611.<\/li>\n<li>Kragstrup TW, et al: In attesa dei dati sulla sicurezza degli inibitori JAK. RMD Open 2022 Feb; 8(1): e002236.<\/li>\n<li>Haller C: Spondiloartrite assiale, www.kssg.ch\/system\/files\/media_document\/2022-05\/Axiale%20Spondyloarthritis.pdf, (ultimo accesso 14.07.2022).<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATICA GP 2022; 17(8): 16-17<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per i pazienti con spondiloartrite assiale (axSpA), per i quali la terapia con farmaci antinfiammatori non steroidei non \u00e8 stata efficace, oggi sono disponibili diversi principi attivi appartenenti alle classi&hellip;<\/p>\n","protected":false},"author":7,"featured_media":124175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Malattie reumatiche","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11306,11522,11494,11550,11515],"tags":[13798,13795,14138],"powerkit_post_featured":[],"class_list":["post-324851","post","type-post","status-publish","format-standard","has-post-thumbnail","category-medicina-interna-generale","category-rapporti-del-congresso","category-reumatologia-it","category-rx-it","category-studi","tag-artrite","tag-reumatismo","tag-spondiloartrite-assiale","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:33:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":324862,"slug":"gestao-moderna-da-espondiloartrose-axial","post_title":"Gest\u00e3o moderna da espondiloartrose axial","href":"https:\/\/medizinonline.com\/pt-pt\/gestao-moderna-da-espondiloartrose-axial\/"},"es_ES":{"locale":"es_ES","id":324869,"slug":"tratamiento-moderno-de-la-espondiloartritis-axial","post_title":"Tratamiento moderno de la espondiloartritis axial","href":"https:\/\/medizinonline.com\/es\/tratamiento-moderno-de-la-espondiloartritis-axial\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/324851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=324851"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/324851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/124175"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=324851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=324851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=324851"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=324851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}