{"id":326767,"date":"2022-01-15T01:00:00","date_gmt":"2022-01-15T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/medicina-traslazionale-e-analisi-omiche-focus-su-approcci-terapeutici-collaudati-e-nuovi\/"},"modified":"2022-01-15T01:00:00","modified_gmt":"2022-01-15T00:00:00","slug":"medicina-traslazionale-e-analisi-omiche-focus-su-approcci-terapeutici-collaudati-e-nuovi","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/medicina-traslazionale-e-analisi-omiche-focus-su-approcci-terapeutici-collaudati-e-nuovi\/","title":{"rendered":"Medicina traslazionale e analisi omiche: focus su approcci terapeutici collaudati e nuovi"},"content":{"rendered":"<p><strong>Nell&#8217;artrite reumatoide, il sistema immunitario attacca la membrana sinoviale della sinovia. Se non viene trattata, c&#8217;\u00e8 il rischio di una graduale distruzione dell&#8217;articolazione. I DMARD sono quindi utilizzati per i cicli gravi. Le analisi omiche dei singoli tipi di cellule forniscono nuove conoscenze sul processo della malattia. Tra le altre cose, l&#8217;attenzione \u00e8 rivolta alla ricerca sull&#8217;attivit\u00e0 delle cellule T e sui diversi tipi di macrofagi tissutali come base per nuove strategie di trattamento. Le scoperte attuali e i risultati dello studio sono stati presentati in occasione della conferenza annuale&nbsp;della Societ\u00e0 tedesca di reumatologia (DGRh).<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Per una comprensione differenziata della malattia e delle opzioni terapeutiche che ne derivano, la ricerca sui complessi eventi molecolari che si verificano a livello cellulare \u00e8 molto istruttiva. I progressi delle tecnologie high-throughput (&#8220;omiche&#8221;) hanno reso possibili le osservazioni a livello genomico, trascrittomico e regolatorio di varie molecole biologiche <span style=\"font-family:franklin gothic demi\">(riquadro)<\/span>. L&#8217;ulteriore sviluppo di approcci terapeutici contro l&#8217;artrite reumatoide ha tratto grande beneficio dai risultati della ricerca di base degli ultimi decenni. &#8220;I reumatologi possono ora influenzare bene il decorso della malattia iniettando o infondendo vari anticorpi biologici, da Abatacept a Rituximab&#8221;, spiega il portavoce del gruppo di lavoro della Rete di Competenza sul Reumatismo, Prof. Ulf Wagner, MD, dell&#8217;Ospedale Universitario di Lipsia [1]. Pi\u00f9 recentemente, sono stati aggiunti farmaci sintetici come il baricitinib o il tofacitinib, che possono essere assunti in compresse. &#8220;I nuovi farmaci rendono il trattamento pi\u00f9 sopportabile per molti pazienti&#8221;, afferma l&#8217;esperto.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18099\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0.png\" style=\"height:293px; width:600px\" width=\"1100\" height=\"537\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0-800x391.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0-120x59.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0-90x44.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0-320x156.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_sg2_s24_0-560x273.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"sviluppare-ulteriormente-il-principio-terapeutico-della-modulazione-dellattivita-delle-cellule-t\">Sviluppare ulteriormente il principio terapeutico della modulazione dell&#8217;attivit\u00e0 delle cellule T.<\/h2>\n<p>L&#8217;attivazione delle cellule T autoreattive \u00e8 di importanza patogenetica centrale nelle malattie autoimmuni come l&#8217;artrite reumatoide. Sono coinvolte nella cascata infiammatoria, influenzando altre cellule immunitarie e producendo una serie di citochine proinfiammatorie. Sulla base di queste scoperte, sono stati sviluppati diversi concetti per il blocco terapeutico delle cellule T. Queste mirano a eliminare in gran parte le cellule T dal processo patologico o a influenzare la loro funzione in modo tale da rallentare i loro effetti patogeni. Abatacept (Orencia\u00ae) \u00e8 un modulatore dell&#8217;attivit\u00e0 delle cellule T che viene utilizzato terapeuticamente da qualche tempo. Il meccanismo d&#8217;azione consiste nel bloccare in modo specifico la via di segnalazione CD28-CD80\/CD86 [2,3]. Il CD28 \u00e8 una delle molecole costimolatorie pi\u00f9 importanti, espressa da circa la met\u00e0 delle cellule T. Il CD28 ha due ligandi, il CD80 e il CD86, che sono espressi sulla superficie di varie cellule presentanti l&#8217;antigene in modo dipendente dall&#8217;attivazione. Inoltre, l&#8217;antigene 4 associato ai linfociti T citotossici (CTLA-4) \u00e8 espresso anche sulle cellule T in modo dipendente dall&#8217;attivazione e si lega anche a CD80 e CD86. Tuttavia, a differenza del CD28, il CTLA-4 rallenta l&#8217;attivazione delle cellule T attraverso l&#8217;inibizione della proliferazione e della produzione di citochine e pu\u00f2 quindi essere considerato un antagonista del CD28.<\/p>\n<p>La modulazione delle cellule T dannose \u00e8 anche il fulcro di una nuova strategia di trattamento attualmente in fase di ricerca. &#8220;Attualmente riteniamo che all&#8217;inizio della malattia ci sia una perdita di auto-tolleranza, che normalmente impedisce alle cellule T di attaccare le cellule dell&#8217;organismo nella membrana sinoviale&#8221;, afferma il Prof. Ulf Wagner, MD [1]. &#8220;I linfociti T iniziano ad attaccare le cellule sinoviali e inducono i linfociti B a produrre anticorpi, di cui il fattore reumatoide \u00e8 l&#8217;esempio pi\u00f9 noto&#8221;. Secondo l&#8217;esperto, gli studi omici mostrano che il metabolismo delle cellule T cambia completamente nel corso della malattia. Ad esempio, la fornitura di energia passa dalla glicolisi alla via del pentoso fosfato. &#8220;Questi processi metabolici alterati possono fornire possibilit\u00e0 completamente nuove per influenzare terapeuticamente le malattie autoimmuni infiammatorie croniche&#8221;, spiega il Prof. Wagner. &#8220;Il nostro obiettivo dovrebbe essere quello di trasformare le cellule T &#8216;cattive&#8217; in cellule T &#8216;buone&#8217; e fermare il processo della malattia proprio all&#8217;inizio&#8221;. Il futuro mostrer\u00e0 se questo approccio terapeutico si affermer\u00e0 e porter\u00e0 al lancio sul mercato di sostanze attive corrispondenti.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-18100 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/564;height:308px; width:600px\" width=\"1100\" height=\"564\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0-800x410.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0-120x62.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0-90x46.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0-320x164.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_sg2_s30_0-560x287.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"i-macrofagi-tissutali-come-parte-della-cascata-infiammatoria\">I macrofagi tissutali come parte della cascata infiammatoria<\/h2>\n<p>Gli anticorpi biologici e i farmaci sintetici approvati finora bloccano le citochine o i loro recettori, che vengono rilasciati dalle cellule del sistema immunitario nell&#8217;ambito dei processi infiammatori <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1 e 2). <\/span>La ricerca di base si \u00e8 nel frattempo rivolta alle diverse cellule infiammatorie che producono queste citochine. I metodi omici pi\u00f9 recenti, come il sequenziamento dell&#8217;RNA di una singola cellula, il profilo dei ribosomi o la spettrometria di massa, consentono di conoscere per la prima volta le singole cellule. &#8220;Le indagini mostrano quali gruppi di cellule si comportano in modo diverso nei pazienti reumatici rispetto alle persone sane e quali sono quindi probabilmente coinvolti nel processo della malattia&#8221;, spiega il Prof. Wagner [1]. Combinando diverse tecnologie omiche, si pu\u00f2 ottenere un quadro pi\u00f9 completo dell&#8217;espressione genica, della quantit\u00e0 di proteine o di vari processi intracellulari. Uno degli attori centrali dell&#8217;artrite reumatoide sono i macrofagi tissutali, che sono presenti anche nella membrana sinoviale delle persone sane. &#8220;La ricerca vuole chiarire cosa fa s\u00ec che queste cellule rilascino le citochine infiammatorie e come si possa prevenire&#8221;, dice l&#8217;esperto.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-18101 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb2_sg2_s31.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1026;height:560px; width:600px\" width=\"1100\" height=\"1026\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"macrofagi-tissutali-mertk-negativi-e-cd206-negativi-come-target\">Macrofagi tissutali MerTK-negativi e CD206-negativi come target<\/h2>\n<p>I ricercatori di base hanno scoperto, ad esempio, che esistono due gruppi di macrofagi tissutali che si distinguono per i marcatori di superficie MerTK e CD206. Un recente studio pubblicato su Nature Medicine ha rilevato che i macrofagi tissutali MerTK-negativi e CD206-negativi producono una serie di citochine pro-infiammatorie e allarmine, promuovendo le risposte infiammatorie nella membrana sinoviale [4]. Al contrario, i macrofagi tissutali MerTK-positivi e CD206-positivi sembrano inibire le risposte infiammatorie. Queste cellule si trovano soprattutto nei pazienti la cui infiammazione si \u00e8 completamente attenuata. Il Prof. Wagner spiega: &#8220;L&#8217;idea di un approccio terapeutico sarebbe quella di utilizzare farmaci per mettere i macrofagi tissutali in uno stato di quiescenza permanente e quindi fermare la malattia a lungo termine&#8221;.<\/p>\n<p><em>Congresso:&nbsp;Conferenza annuale della DGRh<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>&#8220;Artrite reumatoide: l&#8217;analisi di singole cellule consente nuove conoscenze sul processo della malattia &#8211; si prevedono nuovi approcci terapeutici&#8221;, Congresso tedesco di reumatologia, 16.09.2021<\/li>\n<li>Swissmedicinfo: Orencia\u00ae, www.swissmedicinfo.ch (ultimo accesso 18.11.2021)<\/li>\n<li>Graninger W, Emminger W, Scheinecker C: J Med Drug Rev 2013; 3: 44-60.<\/li>\n<li>Alivernini S, et al: Nat Med 2020; 26(8): 1295-1306.<\/li>\n<li>Rosenstiel P, Franke A, Schreiber S: Prevedere e trattare individualmente l&#8217;infiammazione cronica. www.systembiologie.de (ultima chiamata 18.11.2021)<\/li>\n<li>Mihai C: Workshop sul reumatismo, Carmen-Marina Mihai, MD, 23.09.2021; www.usz.ch\/app\/uploads\/2021\/09\/CMihai_NW-Biologika_RheumaWorkshop_Sept21.pdf (ultimo accesso 18.11.2021)<\/li>\n<li>Tamborrini G: Rischio di infezione con DMARD e steroidi, Weekly 2021, www.rheuma-schweiz.ch (ultimo accesso 18.11.2021).<\/li>\n<li>Riley TR, et al: Rischio di infezioni con glucocorticoidi e DMARD nei pazienti con artrite reumatoide, RMD Open 2021: online.<\/li>\n<li>Gianfrancesco M, et al: Ann Rheum Dis 2020; 79: 859-866.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo PAIN &amp; GERIATURE 2021; 3(2): 30-31<br \/>\nPRATICA GP 2021; 16(12): 20-22<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;artrite reumatoide, il sistema immunitario attacca la membrana sinoviale della sinovia. Se non viene trattata, c&#8217;\u00e8 il rischio di una graduale distruzione dell&#8217;articolazione. I DMARD sono quindi utilizzati per i&hellip;<\/p>\n","protected":false},"author":7,"featured_media":114638,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Artrite reumatoide","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11355,11522,11494,11550,11515],"tags":[14293,12293,17691,13795],"powerkit_post_featured":[],"class_list":["post-326767","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geriatria-it","category-rapporti-del-congresso","category-reumatologia-it","category-rx-it","category-studi","tag-artrite-reumatoide","tag-biologici","tag-omics-it","tag-reumatismo","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:15:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":326778,"slug":"medicina-translacional-e-analises-omicas-enfoque-em-abordagens-terapeuticas-comprovadas-e-novas","post_title":"Medicina translacional e an\u00e1lises \u00f3micas: enfoque em abordagens terap\u00eauticas comprovadas e novas","href":"https:\/\/medizinonline.com\/pt-pt\/medicina-translacional-e-analises-omicas-enfoque-em-abordagens-terapeuticas-comprovadas-e-novas\/"},"es_ES":{"locale":"es_ES","id":326785,"slug":"medicina-traslacional-y-analisis-omicos-centrarse-en-enfoques-terapeuticos-probados-y-nuevos","post_title":"Medicina traslacional y an\u00e1lisis \u00f3micos: centrarse en enfoques terap\u00e9uticos probados y nuevos","href":"https:\/\/medizinonline.com\/es\/medicina-traslacional-y-analisis-omicos-centrarse-en-enfoques-terapeuticos-probados-y-nuevos\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/326767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=326767"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/326767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/114638"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=326767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=326767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=326767"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=326767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}