{"id":326833,"date":"2022-01-13T01:00:00","date_gmt":"2022-01-13T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-terapia-proattiva-con-schiuma-spray-per-la-psoriasi-vulgaris-rimane-efficace\/"},"modified":"2022-01-13T01:00:00","modified_gmt":"2022-01-13T00:00:00","slug":"la-terapia-proattiva-con-schiuma-spray-per-la-psoriasi-vulgaris-rimane-efficace","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/la-terapia-proattiva-con-schiuma-spray-per-la-psoriasi-vulgaris-rimane-efficace\/","title":{"rendered":"La terapia proattiva con schiuma spray per la psoriasi vulgaris rimane efficace."},"content":{"rendered":"<p><strong>La gestione proattiva con la combinazione fissa in schiuma spray di calcipotriolo e betametasone dipropionato ha portato a un minor numero di ricadute e a un migliore controllo dei sintomi a lungo termine rispetto a una strategia di trattamento reattiva con un profilo di sicurezza comparabile. Questa \u00e8 la conclusione dello studio randomizzato, controllato con veicolo, PSO-LONG.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Lo scopo dello studio di fase III \u00e8 stato quello di indagare l&#8217;efficacia e la sicurezza a lungo termine della terapia proattiva bisettimanale con la combinazione fissa di calcipotriolo 0,005% e betametasone dipropionato 0,064% come schiuma spray rispetto alla terapia reattiva per la psoriasi vulgaris <span style=\"font-family:franklin gothic demi\">(fig.&nbsp;1)<\/span> [1]. Nel complesso, sono stati raggiunti pi\u00f9 giorni di remissione e meno ricadute con il regime di trattamento proattivo con la combinazione fissa.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-17976\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2.png\" style=\"height:435px; width:600px\" width=\"1100\" height=\"797\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2-800x580.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2-120x87.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2-90x65.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2-320x232.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/abb1_dp6_s26_2-560x406.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"disegno-dello-studio\">Disegno dello studio<\/h2>\n<p>In una fase iniziale di 4 settimane in aperto, la schiuma spray calcipotriolo (Cal)\/betametasone dipropionato (BD) (Enstilar\u00ae) \u00e8 stata utilizzata 1\u00d7 al giorno in tutti i pazienti [2]. 545 pazienti che hanno raggiunto un punteggio Physician&#8217;s Global Assessment (PGA) di 0 (senza aspetto) o 1 (quasi senza aspetto) erano idonei a partecipare alla successiva fase di mantenimento di 52 settimane e sono stati assegnati in modo randomizzato 1:1 ai bracci di studio Gestione proattiva (Cal\/BD in schiuma spray, n=272) o Gestione reattiva (veicolo in schiuma spray, n=273), ciascuno 2x\/settimana o come terapia al bisogno 1\u00d7\/die per 4 settimane in caso di ricaduta.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img decoding=\"async\" class=\"size-full wp-image-17977 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/01\/kasten_dp6_26.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/530;height:289px; width:600px\" width=\"1100\" height=\"530\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"punti-finali-di-efficacia\">Punti finali di efficacia<\/h2>\n<p>L&#8217;endpoint primario era il tempo alla prima ricaduta. 251 pazienti (46,1%) hanno completato la fase di mantenimento di 52 settimane. L&#8217;uso proattivo della schiuma spray Cal\/BD ha ridotto significativamente il rischio di prima ricaduta del 43% rispetto alla terapia reattiva (HR 0,57; 95% CI, 47-69%; p&lt;0,001). Il tempo mediano alla prima ricaduta \u00e8 stato di 56 giorni con il regime proattivo e di 30 giorni con la terapia reattiva. Per il 50% dei pazienti, il tempo alla prima ricaduta \u00e8 raddoppiato rispetto alla terapia reattiva. Inoltre, l&#8217;uso proattivo ha avuto un impatto positivo sulla durata della remissione. Nell&#8217;arco di un anno*, i pazienti del braccio proattivo sono rimasti in remissione per una media di 41 giorni in pi\u00f9 rispetto al gruppo di controllo trattato in modo reattivo (p&lt;0,001), con 37,5 giorni di trattamento in pi\u00f9 all&#8217;anno. Il tasso di ricaduta \u00e8 diminuito del 46% con il trattamento proattivo con la schiuma spray Cal\/BD (95% CI: 37-54%; p&lt;0,001).<\/p>\n<p><span style=\"font-size:11px\"><em>* Ricadute per anno di esposizione<\/em><\/span><br \/>\n&nbsp;<\/p>\n<h2 id=\"dati-di-sicurezza\">Dati di sicurezza<\/h2>\n<p>Il profilo di sicurezza e tollerabilit\u00e0 del trattamento proattivo con schiuma spray Cal\/BD \u00e8 stato favorevole per tutto il periodo di studio. L&#8217;incidenza degli eventi avversi \u00e8 stata paragonabile nei due bracci di studio, cos\u00ec come i fenomeni di rimbalzo (6 e 7 rimbalzi, rispettivamente).&nbsp;  Anche il tasso di interruzione a causa di eventi avversi era simile tra la terapia proattiva e quella reattiva (0,7% e 0,4%, rispettivamente). I risultati di questo nuovo studio sono promettenti e indicano che la gestione proattiva con Enstilar\u00ae spray foam porta a un migliore controllo a lungo termine della psoriasi a placche rispetto alla strategia di trattamento reattivo convenzionale.<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Lebwohl M, et al: J Am Acad Dermatol 2021; 84(5): 1269-1277.<\/li>\n<li>Informazioni sui farmaci, www.swissmedicinfo.ch, ultimo accesso 06.11.2021<\/li>\n<li>Calzavara-Pinton P, et al.: Abstract 70, Innovations in Dermatology 2021.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATICA DERMATOLOGICA 2021; 31(6): 26<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gestione proattiva con la combinazione fissa in schiuma spray di calcipotriolo e betametasone dipropionato ha portato a un minor numero di ricadute e a un migliore controllo dei sintomi&hellip;<\/p>\n","protected":false},"author":7,"featured_media":114188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Combinazione fissa di calcipotriolo e betametasone dipropionato  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11351,11519,11537,11550,11515],"tags":[17902,17899,17896,17911,17903,17893,17918,13964,17907,17909,17915,17091,17906],"powerkit_post_featured":[],"class_list":["post-326833","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-e-venereologia","category-formazione-continua","category-mercato-e-medicina","category-rx-it","category-studi","tag-betametasone","tag-calcipotriolo","tag-combinazione-fissa","tag-controllo-dei-sintomi","tag-dipropionato","tag-enstilar-it","tag-pso-lungo","tag-psoriasi-it","tag-schiuma-spray","tag-schiuma-spray-it","tag-strategia-di-trattamento-reattivo","tag-studio","tag-terapia-proattiva","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:18:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":326859,"slug":"terapia-proactiva-com-espuma-de-pulverizacao-para-psoriase-vulgaris-persistentemente-eficaz","post_title":"Terapia proactiva com espuma de pulveriza\u00e7\u00e3o para psor\u00edase vulgaris persistentemente eficaz","href":"https:\/\/medizinonline.com\/pt-pt\/terapia-proactiva-com-espuma-de-pulverizacao-para-psoriase-vulgaris-persistentemente-eficaz\/"},"es_ES":{"locale":"es_ES","id":326877,"slug":"la-terapia-proactiva-con-espuma-en-aerosol-para-la-psoriasis-vulgar-sigue-siendo-eficaz","post_title":"La terapia proactiva con espuma en aerosol para la psoriasis vulgar sigue siendo eficaz","href":"https:\/\/medizinonline.com\/es\/la-terapia-proactiva-con-espuma-en-aerosol-para-la-psoriasis-vulgar-sigue-siendo-eficaz\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/326833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=326833"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/326833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/114188"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=326833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=326833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=326833"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=326833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}