{"id":328701,"date":"2021-06-26T01:00:00","date_gmt":"2021-06-25T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/il-ruolo-degli-autoanticorpi-nelle-polineuropatie\/"},"modified":"2023-01-12T13:51:16","modified_gmt":"2023-01-12T12:51:16","slug":"il-ruolo-degli-autoanticorpi-nelle-polineuropatie","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/il-ruolo-degli-autoanticorpi-nelle-polineuropatie\/","title":{"rendered":"Il ruolo degli autoanticorpi nelle polineuropatie"},"content":{"rendered":"\n<p><strong>Le neuropatie immunomediate variano nella presentazione clinica, nel decorso e nella patogenesi. Negli ultimi anni, sono stati rilevati autoanticorpi contro le proteine nodali e paranodali dell&#8217;anello di Ranvier. Gli autoanticorpi possono causare danni assonali e portare alla demielinizzazione.<\/strong><\/p>\n\n<!--more-->\n\n<p>Le neuropatie immunomediate variano nella presentazione clinica, nel decorso e nella patogenesi e rappresentano circa il 9% di tutte le polineuropatie [1]. Negli ultimi anni, sono stati rilevati autoanticorpi contro le proteine nodali e paranodali dell&#8217;anello di Ranvier. Gli autoanticorpi contro la neurofascina (NF), la contactina 1 (CNTN1) o la proteina associata alla contactina 1 (CASPR1) sono stati rilevati nel 10% dei pazienti con polineuropatia demielinizzante infiammatoria cronica (CIDP) [2]. Gli autoanticorpi possono causare danni assonali e portare alla demielinizzazione [4]. I pazienti sieropositivi con CIDP differiscono dai pazienti sieronegativi nel fenotipo clinico, nei risultati elettrofisiologici e nella risposta alla terapia standard [2].<\/p>\n\n<p>Il rilevamento di autoanticorpi nodali e paranodali specifici pu\u00f2 aiutare a trovare terapie efficaci. Oltre alla CIDP, gli autoanticorpi associati alla malattia sono noti anche in altre neuropatie immuno-mediate, come la sindrome di Guillain-Barr\u00e9 (GBS) con i sottotipi polineuropatia demielinizzante infiammatoria acuta (AIDP), neuropatia assonale motoria acuta (AMAN) e neuropatia assonale motoria e sensoriale acuta (AMSAN), Sindrome di Miller-Fisher (MFS), neuropatia motoria multifocale (MMN), neuropatia anti-MAG MGUS (neuropatia paraproteinemica), neuronopatia sensibile nelle malattie immunitarie sistemiche e polineuropatie paraneoplastiche.<\/p>\n\n<h2 id=\"\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"-2\" class=\"wp-block-heading\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-16541\" style=\"height: 271px; width: 600px;\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19.png\" alt=\"\" width=\"1100\" height=\"496\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19-800x361.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19-120x54.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19-90x41.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19-320x144.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab1_np3_s19-560x253.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/h2>\n\n<h2 id=\"-3\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"fisiopatologia-e-cambiamenti-elettrofisiologici-delle-nodo-e-paranodopatie\" class=\"wp-block-heading\">Fisiopatologia e cambiamenti elettrofisiologici delle nodo- e paranodopatie<\/h2>\n\n<p>Le polineuropatie sono tradizionalmente suddivise in neuropatie demielinizzanti e assonali in base ai criteri dell&#8217;elettrofisiologia <span style=\"font-family: franklin gothic demi;\">(Tab. 1)<\/span>. Si prevede che la patologia di base sia a livello della cellula mielinica\/swan o dell&#8217;assone. Le proteine della regione nodale o paranodale dell&#8217;anello di Ranvier sono giunzioni tra la mielina\/microvilli della cellula di Schwan e l&#8217;assone <span style=\"font-family: franklin gothic demi;\">(Fig. 1) <\/span>. Nelle neuropatie dovute ad autoanticorpi contro le proteine nodali e paranodali, non \u00e8 possibile una chiara assegnazione a un modello demielinizzante o assonale, a causa del patomeccanismo sottostante. Il termine nodo- e paranodopatie \u00e8 stato proposto da Uncini, Susuki e Yuki nel 2013 [8,9].<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"843\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19.png\" alt=\"\" class=\"wp-image-16542 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19-800x613.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19-120x92.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19-90x68.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19-320x245.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/abb1_np3_s19-560x429.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/843;\" \/><\/figure>\n\n<p><strong>Le caratteristiche della nodo- e della paranodopatia sono  <\/strong><\/p>\n\n<ol class=\"wp-block-list\">\n<li>Gli anticorpi contro le proteine nodali e paranodali hanno eziologie diverse, ma tutti portano a disfunzioni nella regione nodale dell&#8217;anello di Ranvier.<\/li>\n\n\n\n<li>Il continuum patologico va dal blocco di conduzione transitorio alla degenerazione assonale.<\/li>\n\n\n\n<li>Blocco di conduzione dovuto al distacco della mielina dall&#8217;assone, all&#8217;allargamento della regione nodale o alla disfunzione\/interruzione dei canali del sodio (alta densit\u00e0 nella regione nodale per la conduzione saltatoria) con polarizzazione segmentaria anomala dell&#8217;assolema.<\/li>\n\n\n\n<li>Il blocco di conduzione pu\u00f2 essere rapidamente reversibile senza la comparsa di una dispersione temporale significativa; il blocco di conduzione pu\u00f2 anche persistere.<\/li>\n\n\n\n<li>La degenerazione assonale dipende dalla malattia specifica e dalla sua gravit\u00e0, eventualmente seguita da un blocco di conduzione.<\/li>\n\n\n\n<li>La diagnosi pu\u00f2 essere fatta con esami elettrofisiologici ripetuti:<\/li>\n<\/ol>\n\n<ul class=\"wp-block-list\">\n<li>a. nella malattia acuta, nel caso di un blocco di conduzione o di una riduzione della velocit\u00e0 di conduzione nervosa rapidamente reversibile, senza una marcata dispersione temporale o una progressione del blocco di conduzione verso la degenerazione assonale;<\/li>\n\n\n\n<li>b. nelle malattie croniche con blocco di conduzione persistente e ulteriori segni di degenerazione assonale.<\/li>\n<\/ul>\n\n<p>L&#8217;uso del termine nodo- e paranodopatie pone l&#8217;attenzione sulla localizzazione del danno nervoso primario e aiuta a classificare meglio la neuropatia demielinizzante segmentale, il paradosso del danno assonale reversibile e la buona prognosi, nonostante le anomalie assonali in elettrofisiologia [9].<\/p>\n\n<h2 id=\"autoanticorpi-nella-polineuropatia-demielinizzante-infiammatoria-cronica-cidp\" class=\"wp-block-heading\">Autoanticorpi nella polineuropatia demielinizzante infiammatoria cronica (CIDP)<\/h2>\n\n<p>Localizzazione: nella regione paranodale, il complesso di contattina 1 e CASPR1 sull&#8217;assone e di neurofascina 155 sulla cellula gliale della guaina mielinica consolida il contatto tra i processi mielinici e l&#8217;assone<span style=\"font-family: franklin gothic demi;\"> (Fig. 1)<\/span> [10].<\/p>\n\n<p><strong>Anti Contactina 1 (CNTN1) IgG<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: il 20 &#8211; 49% presenta un esordio subacuto della malattia. \u00c8 noto un esordio dei sintomi aggressivo simile alla GBS, con paresi ad esordio subacuto <span style=\"font-family: franklin gothic demi;\">(casistica)<\/span>. \u00c8 tipica una neuropatia prevalentemente motoria e spesso si osserva un&#8217;atassia sensoriale. La comparsa di tremore \u00e8 pi\u00f9 frequente che nella CIDP sieronegativa, ma meno frequente che nella CIPD anti NF155-positiva. L&#8217;et\u00e0 di insorgenza \u00e8 di circa 50-60 anni. Anno di vita. Complessivamente, \u00e8 stata descritta un&#8217;et\u00e0 pi\u00f9 alta all&#8217;esordio della malattia per i pazienti CIDP anti-CNTN1-positivi rispetto ai pazienti CIDP sieronegativi [2].<\/li>\n\n\n\n<li>Risultati: Gli esami elettroneurografici rivelano cambiamenti assonali all&#8217;inizio del decorso della malattia <span style=\"font-family: franklin gothic demi;\">(Tab. 1) <\/span>.  <\/li>\n\n\n\n<li>Implicazioni per il trattamento: I pazienti rispondono in modo inadeguato alle immunoglobuline per via endovenosa (IVIg). I corticosteroidi hanno un buon effetto. Se la risposta alla terapia standard \u00e8 insufficiente, la terapia di deplezione delle cellule B con rituximab \u00e8 efficace [14]. Va notato che \u00e8 importante mantenere la durata della malattia il pi\u00f9 breve possibile, in modo da minimizzare il danno assonale [8]. In caso di immunoterapia efficace, i titoli sierici di anti CNTN1 diminuiscono [11].<\/li>\n<\/ul>\n\n<p><strong>Proteina 1 associata alla contattina (CASPR1) IgG<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: Nei pazienti sieropositivi anti CASPR1 \u00e8 stato descritto un dolore neuropatico pronunciato. I sintomi di solito iniziano in modo subacuto con un&#8217;espressione grave e sono inizialmente enfatizzati a livello motorio. Gli anti CASPR1 sono stati rilevati nei pazienti con CIDP e GBS. L&#8217;esordio della malattia \u00e8 riportato in un caso clinico intorno ai 30 anni.<\/li>\n\n\n\n<li>Risultati: I blocchi di conduzione reversibili possono essere rilevati nelle indagini elettrofisiologiche [11].<\/li>\n\n\n\n<li>Implicazioni per il trattamento: \u00c8 stata descritta la mancanza di risposta all&#8217;IVIg e al metilprednisolone. Il rituximab ha dimostrato un&#8217;ottima efficacia. Il dolore neuropatico associato migliora con una terapia efficace [2].<\/li>\n<\/ul>\n\n<p><strong>Anti Neurofascina 155 (NF155) IgG<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: in genere, un&#8217;alta percentuale di pazienti CIDP NF155-positivi presenta una debolezza enfatizzata a livello distale. Altri sintomi possono includere tremore ad alta ampiezza e bassa frequenza e atassia sensoriale con segni cerebellari. L&#8217;associazione con HLA-DRB1*15 \u00e8 stata descritta [12]. L&#8217;et\u00e0 di insorgenza \u00e8 significativamente pi\u00f9 giovane rispetto alla CIPD sieronegativa, con un&#8217;et\u00e0 di insorgenza intorno ai 20-30 anni.<\/li>\n\n\n\n<li>Risultati: L&#8217;esame elettrofisiologico mostra un modello demielinizzante con un chiaro prolungamento delle latenze distali e delle latenze delle onde F <span style=\"font-family: franklin gothic demi;\">(Tab. 1)<\/span>. Nel liquido cerebrospinale \u00e8 stato rilevato un forte aumento della proteina [13].<\/li>\n\n\n\n<li>Implicazioni per il trattamento: La risposta all&#8217;IVIg \u00e8 scarsa. \u00c8 stato descritto un miglioramento parziale con i corticosteroidi. Ci si pu\u00f2 aspettare un buon successo terapeutico con rituximab e plasmaferesi [14]. I titoli sierici di anti NF155 diminuiscono in caso di immunoterapia efficace ed \u00e8 stata dimostrata una correlazione con il miglioramento clinico [11].<\/li>\n<\/ul>\n\n<p><strong>Anti Neurofascina 140\/186 (NF 140\/186) IgG<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: I pazienti presentano -una poli-culopatia sensomotoria simmetrica con un decorso grave. Possono verificarsi anche atassia sensoriale e coinvolgimento dei nervi cranici. Alcuni pazienti presentavano una malattia autoimmune concomitante. L&#8217;et\u00e0 di insorgenza \u00e8 di circa 50-60 anni. descritto durante il primo anno di vita [2].<\/li>\n\n\n\n<li>Risultati: L&#8217;elettroneurografia ha rivelato risultati demielinizzanti con blocchi di conduzione (in 3\/5 pazienti) e caratteristiche assonali (in 2\/5 pazienti) [15].<\/li>\n\n\n\n<li>Implicazioni per il trattamento: Con IVIg e corticosteroidi, i sintomi sono parzialmente migliorati. \u00c8 stata descritta una risposta potenzialmente buona al rituximab [14].<\/li>\n<\/ul>\n\n<h2 id=\"autoanticorpi-nelle-polineuropatie-infiammatorie-acute-sindrome-di-guillain-barre-gbs-con-i-sottotipi-aidp-aman-e-amsan\" class=\"wp-block-heading\">Autoanticorpi nelle polineuropatie infiammatorie acute &#8211; sindrome di Guillain-Barr\u00e9 (GBS) con i sottotipi AIDP, AMAN e AMSAN<\/h2>\n\n<p>Localizzazione: i canali ionici dell&#8217;anello di Ranvier sono stabilizzati dai gangliosidi, glicosfingolipidi contenuti nella membrana cellulare delle regioni nodali e paranodali [16]. I diversi sottotipi della sindrome di Guillain-Barr\u00e9 sono ciascuno associato ad autoanticorpi contro gangliosidi diversi e differiscono nei risultati elettrofisiologici.<\/p>\n\n<p>La <strong>polineuropatia demielinizzante infiammatoria acuta (AIDP)<\/strong> \u00e8 il sottotipo pi\u00f9 comune di GBS in Europa e in Nord America. Di solito, in questo caso non si rilevano autoanticorpi specifici.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: La malattia \u00e8 spesso preceduta da un&#8217;infezione gastrointestinale o respiratoria. All&#8217;inizio si verificano ipoestesia, parestesia, paresi e dolore alle estremit\u00e0. Le paresi sono bilaterali, simmetriche e progressive. I sintomi motori si sviluppano da 12 ore a 28 giorni, fino alla tetraparesi con coinvolgimento dei muscoli respiratori. Inoltre, possono verificarsi deficit dei nervi cranici e disfunzioni autonomiche [4].<\/li>\n\n\n\n<li>Risultati: questo sottotipo demielinizzante di polineuropatia infiammatoria acuta \u00e8 caratterizzato da una marcata riduzione della velocit\u00e0 di conduzione nervosa, da un aumento delle latenze motorie distali, da blocchi di conduzione, da una dispersione temporale anomala, da latenze delle onde F prolungate o dall&#8217;assenza di onde F [17].<\/li>\n<\/ul>\n\n<p><strong>Anti LM1 (sialosilneolactotetraosilceramide)<\/strong><\/p>\n\n<p>Gli autoanticorpi contro LM1 (sialosilneolactotetraosilceramide) causano una polineuropatia demielinizzante infiammatoria acuta (AIDP) se sono monospecifici. Sono stati descritti casi in cui gli anticorpi IgG anti LM1 causano una reazione incrociata con gangliosidi come GM1, GalNAc-GD1a, GD1b e GQ1b, per cui in questo caso si pu\u00f2 fare la diagnosi di AMAN o AMSAN.<\/p>\n\n<p><strong>Anti GalC (galattocerebroside)<\/strong><\/p>\n\n<p>Autoanticorpi contro i galattocerebrosidi (GalC) sono stati rilevati nei bambini con polineuropatia demielinizzante acuta grave associata a M. pneumoniae (AIDP) [18].<\/p>\n\n<p><strong>Anti Neurofascina 186, Anti Gliomedina, Anti NrCAM, Anti CNTN1, Anti Neurofascina 155, Anti CASPR1 e Anti CASPR2<\/strong><\/p>\n\n<p>Negli studi sono stati rilevati gli autoanticorpi nodali anti neurofascina 186, anti gliomedina e anti NrCAM, e gli autoanticorpi paranodali anti CNTN1, anti neurofascina 155 e anti CASPR1 (vedere sopra nella sezione CIDP) nei pazienti adulti con GBS. Autoanticorpi juxtaparanodali contro CASPR2 sono stati descritti in 2 casi di GBS nei bambini.<\/p>\n\n<p>La <strong>neuropatia assonale motoria acuta (AMAN) <\/strong>si verifica principalmente in Asia [19].<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: corrispondenti all&#8217;AIDP (vedere sopra) senza disturbi sensoriali.<\/li>\n\n\n\n<li>Risultati: questo sottotipo assonale di polineuropatia infiammatoria acuta \u00e8 caratterizzato da una marcata riduzione dell&#8217;ampiezza del potenziale d&#8217;azione cumulativo motorio (CMAP) e dal cosiddetto &#8220;fallimento reversibile della conduzione&#8221;, vale a dire che l&#8217;ampiezza ridotta del CMAP e i blocchi di conduzione possono improvvisamente riprendersi con esami elettroneurografici ripetuti, senza evidenza di dispersione temporale come segno di rimielinizzazione.  [16].<\/li>\n<\/ul>\n\n<p><strong>Anti-GM1 IgG, Anti-GM2, Anti-GD1b IgG, Anti-GT1b, Anti- GM3, Anti-GD1a IgG e Anti-GalNac-GD1a  <\/strong><\/p>\n\n<p>Gli anticorpi gangliosidi anti-GM1 IgG, anti-GM2, anti-GD1b, anti-GT1b, anti-GM3, anti-GD1a IgG e anti-GalNac-GD1a possono essere rilevati in circa l&#8217;80% dei pazienti con AMAN. Questi autoanticorpi possono presentarsi singolarmente o in combinazione.<\/p>\n\n<p><strong>Neuropatia assonale acuta motoria e sensoriale (AMSAN)<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: vedere AIDP<\/li>\n\n\n\n<li>Risultati: stessi criteri di AMAN pi\u00f9 riduzione dell&#8217;ampiezza del potenziale d&#8217;azione del nervo sensoriale (Unicini et al. 2018).<\/li>\n<\/ul>\n\n<p><strong>IgG anti-GM1, anti-GM1b, IgG anti-GD1a<\/strong><\/p>\n\n<p>Gli anticorpi ganglioside anti-GM1, anti-GM1b, anti-GD1a sono rilevabili nella neuropatia assonale acuta motoria e sensoriale (ASMAN) [19].<\/p>\n\n<h2 id=\"autoanticorpi-nella-sindrome-di-miller-fisher-mfs\" class=\"wp-block-heading\">Autoanticorpi nella sindrome di Miller Fisher (MFS)<\/h2>\n\n<p>Localizzazione: il ganglioside GQ1b si trova principalmente nella mielina paranodale dei nervi cranici che forniscono i muscoli oculari [19].<\/p>\n\n<p><strong>Anti GQ1b IgG<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: L&#8217;oftalmoplegia acuta, la neuropatia atassica acuta e l&#8217;areflessia sono i sintomi principali della sindrome di Miller-Fisher. Nell&#8217;encefalite del tronco encefalico di Bickerstaff, si verificano oftalmoplegia e atassia, alterazione della coscienza e di solito iperreflessia.<\/li>\n<\/ul>\n\n<p>Gli autoanticorpi GQ1b possono essere rilevati nel 90% dei pazienti con sindrome di Miller Fisher (MFS). La sindrome di Miller-Fisher e l&#8217;encefalite del tronco encefalico di Bickerstaff sono associate agli anticorpi anti-GQ1b, quindi Shahrizaila e Yuki raggruppano le malattie come sindrome da anticorpi anti-GQ1b [20].<\/p>\n\n<h2 id=\"autoanticorpi-nella-neuropatia-motoria-multifocale-mmn\" class=\"wp-block-heading\">Autoanticorpi nella neuropatia motoria multifocale (MMN)<\/h2>\n\n<p>Localizzazione: il ganglioside GM1 \u00e8 localizzato principalmente nella regione nodale dell&#8217;anello di Ranvier. Gli autoanticorpi si legano alla regione nodale e attivano il complemento, influenzando il raggruppamento dei canali del sodio.<\/p>\n\n<p><strong>IgM anti GM1 e complesso anti GM1-galattocerebroside<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: \u00e8 caratteristica una paresi delle estremit\u00e0 in lento aumento, per lo pi\u00f9 asimmetrica, che spesso inizia dagli arti superiori. Non sono stati riscontrati deficit sensibili. Inoltre, possono verificarsi tremori di tenuta, fascicolazioni e crampi.<\/li>\n\n\n\n<li>Risultati: gli anticorpi IgM anti-GM1 sono rilevabili nel 50% di tutti i pazienti con MMN [21]. I blocchi di conduzione possono essere rilevati negli esami elettrofisiologici. L&#8217;attivazione del complemento pu\u00f2 causare un danno assonale.<\/li>\n\n\n\n<li>Implicazioni per il trattamento: Buona risposta all&#8217;IVIg. Il rilevamento degli autoanticorpi pu\u00f2 supportare la diagnosi di MMN se non sono soddisfatti tutti i criteri e aiutare a iniziare una terapia efficace con IVIg. Clinicamente, si tratta di una malattia del secondo motoneurone, che rende la MMN un&#8217;importante diagnosi differenziale della sclerosi laterale amiotrofica [11].<\/li>\n<\/ul>\n\n<h2 id=\"autoanticorpi-nella-polineuropatia-mgus-mgus-p\" class=\"wp-block-heading\">Autoanticorpi nella polineuropatia MGUS (MGUS-P)<\/h2>\n\n<p>Localizzazione: la glucoproteina associata alla mielina (MAG) \u00e8 localizzata nella mielina della regione paranodale.<\/p>\n\n<p><strong>Anti MAG (glucoproteina associata alla mielina) IgM<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: \u00e8 caratteristica una polineuropatia distale atassica lentamente progressiva, prevalentemente sensibile. Le estremit\u00e0 distali superiori sono spesso colpite [11]. La maggior parte dei pazienti ha un&#8217;et\u00e0 inferiore ai 50 anni.<\/li>\n\n\n\n<li>Risultati: Un modello demielinizzante \u00e8 rilevabile nell&#8217;esame elettrofisiologico. L&#8217;immunofissazione rivela una gammopatia monoclonale IgM. Gli anticorpi anti MAG IgM sono positivi nel 50% dei pazienti con MGUS-P. Il livello del titolo anticorpale non sembra essere correlato alla gravit\u00e0 della malattia e alla risposta alla terapia. Il rilevamento degli autoanticorpi anti MAG \u00e8 necessario solo per la diagnosi.<\/li>\n\n\n\n<li>Implicazioni per il trattamento: Alcuni studi hanno dimostrato una risposta alla plasmaferesi, alla ciclofosfamide, all&#8217;IVIg e al rituximab. Ci sono prove che la deplezione precoce delle cellule B con rituximab pu\u00f2 influenzare la progressione [11].<\/li>\n<\/ul>\n\n<h2 id=\"autoanticorpi-associati-alle-malattie-immunitarie-sistemiche\" class=\"wp-block-heading\">Autoanticorpi associati alle malattie immunitarie sistemiche<\/h2>\n\n<p><strong>Anticorpi SSA (Ro) e SSB (La), anticorpi antineuronali, anticorpo FGFR3 (recettore 3 del fattore di crescita dei fibroblasti)<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sintomi: Nei pazienti (pi\u00f9 giovani) con un decorso progressivo, acuto o subacuto della neuropatia\/neuronopatia sensoriale, \u00e8 utile la ricerca della sindrome di Sj\u00f6gren o lo screening delle malattie autoimmuni [22].<\/li>\n\n\n\n<li>Risultati: Nel liquor c&#8217;\u00e8 un lieve aumento delle proteine con una conta cellulare normale. Elettrofisiologicamente, sono rilevabili anomalie nei nervi sensibili che non dipendono dalla lunghezza. La perdita estesa o la bassa ampiezza dei potenziali d&#8217;azione del nervo sensoriale \u00e8 tipica, cos\u00ec come la distribuzione clinica asimmetrica (&#8220;a chiazze&#8221;). Occasionalmente, i nervi sensibili delle braccia possono essere pi\u00f9 colpiti di quelli delle gambe [23].<\/li>\n\n\n\n<li>Implicazioni terapeutiche: La malattia di base deve essere trattata.<\/li>\n<\/ul>\n\n<h2 id=\"-4\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"-5\" class=\"wp-block-heading\"><img decoding=\"async\" class=\"size-full wp-image-16543 lazyload\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/589;height: 321px; width: 600px;\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0.png\" alt=\"\" width=\"1100\" height=\"589\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0-800x428.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0-120x64.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0-90x48.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0-320x171.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab2_np3_s22_0-560x300.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/h2>\n\n<h2 id=\"-6\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"in-quale-presentazione-clinica-si-dovrebbe-pensare-a-una-genesi-mediata-da-autoanticorpi\" class=\"wp-block-heading\">In quale presentazione clinica si dovrebbe pensare a una genesi mediata da autoanticorpi?<\/h2>\n\n<p>Il test per gli autoanticorpi nodali e paranodali deve essere eseguito nei pazienti con un decorso acuto, subacuto o cronico della polineuropatia demielinizzante acquisita associata a sintomi aggiuntivi come tremore, coinvolgimento distale o scarsa risposta all&#8217;IVIg [11] <span style=\"font-family: franklin gothic demi;\">(Tabella 3)<\/span>.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"1317\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23.png\" alt=\"\" class=\"wp-image-16544 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23-800x958.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23-120x144.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23-90x108.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23-320x383.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab3_np3_s23-560x670.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1317;\" \/><\/figure>\n\n<h2 id=\"perche-la-terapia-standard-e-spesso-inadeguata-per-la-polineuropatia-demielinizzante-infiammatoria-cronica-sieropositiva\" class=\"wp-block-heading\">Perch\u00e9 la terapia standard \u00e8 spesso inadeguata per la polineuropatia demielinizzante infiammatoria cronica sieropositiva?<\/h2>\n\n<p>Gli studi hanno dimostrato che gli autoanticorpi nodali e paranodali appartengono a diverse sottoclassi di IgG <span style=\"font-family: franklin gothic demi;\">(Tabella 4) <\/span>. Le IgG2 e le IgG3 sono state riscontrate nella GBS monofasica anti CNTN1 e CASPR1 sieropositiva, le IgG4 solo nei decorsi cronici. Da Appeltshauser et al. \u00c8 stato descritto che nel corso della malattia pu\u00f2 verificarsi un cambiamento di classe da IgG3 a IgG4 nella neuropatia sieropositiva anti CNTN1 e anti CASPR1 [25]. Attualmente, le sottoclassi IgG degli autoanticorpi nodali e paranodali vengono determinate solo nei laboratori di ricerca.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"459\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25.png\" alt=\"\" class=\"wp-image-16545 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25-800x334.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25-120x50.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25-90x38.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25-320x134.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/06\/tab4_np3_s25-560x234.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/459;\" \/><\/figure>\n\n<p>Le neuropatie IgG3-mediate rispondono bene alla terapia standard con IVIg. L&#8217;IVIg \u00e8 efficace nelle polineuropatie infiammatorie, in particolare attraverso l&#8217;inibizione del complemento e la neutralizzazione degli anticorpi. I pazienti con anticorpi IgG2 e IgG4 non mostrano alcun miglioramento con le infusioni di IVIg oppure la risposta diminuisce nel corso della malattia. La scarsa o assente risposta all&#8217;IVIg nelle malattie IgG4-mediate \u00e8 attribuita alla bassa capacit\u00e0 di legare i recettori Fc\u03b3IIb e alla mancanza di attivazione del complemento [14]. Nelle malattie autoimmuni neurologiche e non neurologiche mediate da IgG4, come la miastenia gravis positiva agli anti-muscoli, la pancreatite autoimmune e la colangite sclerosante, l&#8217;efficacia del rituximab \u00e8 stata dimostrata in numerosi studi. L&#8217;effetto di deplezione delle cellule B del rituximab \u00e8 fondamentale nella malattia IgG4-mediata. \u00c8 stata riportata una risposta parziale dei pazienti con anticorpi IgG4 nodali e paranodali ai corticosteroidi [14]. Nelle neuropatie autoanticorpo-positive, \u00e8 necessaria una terapia rapida ed efficace prima che si verifichi un danno irreversibile. In assenza di risposta alla terapia standard (IVIg e steroidi) per la polineuropatia demielinizzante infiammatoria cronica, si deve prendere in considerazione la terapia con rituximab.<\/p>\n\n<h2 id=\"messaggi-da-portare-a-casa\" class=\"wp-block-heading\">Messaggi da portare a casa<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Nell&#8217;ambito delle neuropatie immuno-mediate, le nodo-\/paranodopatie devono essere prese in considerazione per la diagnosi differenziale, poich\u00e9 in questo caso esistono opzioni terapeutiche efficaci.<\/li>\n\n\n\n<li>La chimica di laboratorio pu\u00f2 rilevare autoanticorpi contro le proteine nodali e paranodali dell&#8217;anello di Ranvier nelle nodo- e paranodopatie.<\/li>\n\n\n\n<li>Le caratteristiche elettroneurografiche sono definite per le nodo- e le paranodopatie.<\/li>\n\n\n\n<li>La base della diagnosi delle neuropatie associate ad autoanticorpi sono gli esami elettroneurografici (modello demielinizzante o assonale, caratteristiche delle nodo- e paranodopatie) e la diagnostica di laboratorio e del liquor (esclusione di diagnosi differenziali rilevanti, rilevamento della dissociazione della citalbumina nel liquor); \u00e8 utile anche l&#8217;ecografia del nervo (modello di rigonfiamento del nervo).<\/li>\n\n\n\n<li>Esaminare gli autoanticorpi nodali e paranodali dal siero (nessuna produzione intratecale e titoli bassi nel liquor).<\/li>\n\n\n\n<li>In assenza di miglioramento con la terapia di prima linea (IVIg, steroidi) e nei pazienti con un decorso acuto o subacuto di polineuropatia demielinizzante acquisita con sintomi aggiuntivi come tremore, atassia e coinvolgimento distale (vedere <strong>Tabella 2:<\/strong> bandiere rosse nella CIDP), considerare la determinazione degli autoanticorpi e, se necessario, la terapia con rituximab.<\/li>\n\n\n\n<li>Selezione degli autoanticorpi in base ai sintomi clinici <strong>(Tab. 3)<\/strong>.<\/li>\n<\/ul>\n\n<p>Letteratura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Visser NA: Incidenza della polineuropatia a Utrecht, Paesi Bassi. Neurologia 2015, 20 gennaio; 84(3): 259-264.<\/li>\n\n\n\n<li>Vural A, Doppler K: Autoanticorpi contro il nodo di Ranvier nella polineuropatia demielinizzante infiammatoria cronica sieropositiva: rilevanza diagnostica, patogenetica e terapeutica. Anteriore. Immunol. 2018, 14 maggio; 9: 1029<\/li>\n\n\n\n<li>Stathopoulos P: Bersagli antigenici autoimmuni nel nodo di Ranvier nei disturbi demielinizzanti. Nat Rev Neurol. 2015 Mar; 11(3): 143-156.<\/li>\n\n\n\n<li>Kieseier BC, Mathey EK, Sommer C: Neuropatie immunomediate. Nat Rev Dis Primers 2018 4, 31.<\/li>\n\n\n\n<li>Svennerholm L: Designazione dei gangliosidi. Adv Exp Med Biol. 1980; 125: 11<\/li>\n\n\n\n<li>Grether NB, et al: Diagnostica delle polineuropatie immuno-mediate. DGNeurologia 2020; 3 (2): 147-158.<\/li>\n\n\n\n<li>Uncini A, Kuwabara S: Criteri elettrodiagnostici per la sindrome di Guillain-Barre: una revisione critica e la necessit\u00e0 di un aggiornamento. Clin Neurophysiol, 2012, 123(8), 1487-1495.<\/li>\n\n\n\n<li>Uncini A, Kuwabara S: Nodopatie del nervo periferico: un concetto emergente. J Neurol Neurosurg Psychiatry, 2015, 86(11), 1186-1195.<\/li>\n\n\n\n<li>Uncini A, Susuki K, Yuki N: Nodo-paranodopatia: oltre la classificazione demielinizzante e assonale nelle neuropatie mediate da anticorpi anti-ganglioside. Clin Neurophysiol, 2013, 124(10), 1928-1934.<\/li>\n\n\n\n<li>Poliak S, Peles E: La differenziazione locale degli assoni mielinizzati nei nodi di Ranvier. Nat Rev Neurosci, 2003, 4(12), 968-980.<\/li>\n\n\n\n<li>Querol L: Autoanticorpi nelle neuropatie infiammatorie croniche: implicazioni diagnostiche e terapeutiche, Nat Rev Neurol. Neurologia, 2017, settembre; 13(9): 533-547.<\/li>\n\n\n\n<li>Martinez-Martinez L: La poliradiculoneuropatia demielinizzante infiammatoria cronica anti-NF155 si associa fortemente all&#8217;HLA-DRB15. J Neuroinflammation 2017; 14: 224.<\/li>\n\n\n\n<li>Kadoya M: Anticorpi IgG4 anti-neurofascina155 nella poliradiculoneuropatia demielinizzante infiammatoria cronica: significato clinico e utilit\u00e0 diagnostica di un test convenzionale. Journal of Neuroimmunology 2016 Dec 15; 301: 16-22.<\/li>\n\n\n\n<li>Bunschoten C: Progressi nella diagnosi e nel trattamento della poliradiculoneuropatia demielinizzante cronica infiammatoria, Lancet Neurology 2019; 18: 784-94.<\/li>\n\n\n\n<li>Delmont E, Manso C, Querol L, et al: Autoanticorpi contro le isoforme nodali della neurofascina nella polineuropatia demielinizzante infiammatoria cronica. Cervello. 2017 Jul 1;140(7): 1851-1858.<\/li>\n\n\n\n<li>Susuki K: I gangliosidi contribuiscono alla stabilit\u00e0 delle giunzioni paranodali e dei cluster di canali ionici nelle fibre nervose mielinizzate. Glia, 2007a, 55(7): 746-757.<\/li>\n\n\n\n<li>Uncini A, Kuwabara S: L&#8217;elettrodiagnosi dei sottotipi della sindrome di Guillain-Barr\u00e9: A che punto siamo? Neurofisiologia clinica. 2018 Dec; 129(12): 2586-2593.<\/li>\n\n\n\n<li>Meyer Sauteur PM: Mycoplasma pneumoniae che scatena la sindrome di Guillain-Barr\u00e9: uno studio caso-controllo, Ann Neurol 2016 Oct; 80(4): 566-580.<\/li>\n\n\n\n<li>Pei S: Varianti assonali della sindrome di Guillain-Barr\u00e9: un aggiornamento. Springer Nature 2020 marzo.<\/li>\n\n\n\n<li>Shahrizaila N, Yuki N: Encefalite del tronco encefalico di Bickerstaff e sindrome di Fisher: sindrome da anticorpi anti-GQ1b. J Neurol Neurosurg Psychiatry 2013, 84: 576-583.<\/li>\n\n\n\n<li>Van Asseldonk JT: Neuropatia motoria multifocale. Lancet Neurol, 2005, 4(5): 309-319.<\/li>\n\n\n\n<li>Heuss D: Diagnostik bei Polyneuropathien, S1-Leitlinie, 2019, in: Deutsche Gesellschaft f\u00fcr Neurologie (Hrsg.), Leitlinien f\u00fcr Diagnostik und Therapie in der Neurologie. Online: www.dgn.org\/leitlinien. (recuperato il 01.04.2021).<\/li>\n\n\n\n<li>Sghirlanzoni A: Malattie dei neuroni sensoriali. The Lancet Neurology. 2005; 4(6): 349-361<\/li>\n\n\n\n<li>Sun X: Anticorpi anti-SOX1 nella sindrome neurologica paraneoplastica. J Clin Neurol. 2020 Oct;16(4):530-546.<\/li>\n\n\n\n<li>Appeltshauser L: Anticorpi antiparanodali e sottoclassi IgG nella neuropatia acuta autoimmune. Neurol Neuroimmunol Neuroinflamm. 2020 Jul 24; 7(5): e 817.<\/li>\n\n\n\n<li>Ilyas A: Distribuzione della sottoclasse di immunoglobuline G degli autoanticorpi contro i gangliosidi nei pazienti con sindrome di Giullain-Barre. Res Commun Mol Pathol Pharmacol. 2001 Jul; 109(1-2): 115-123.<\/li>\n\n\n\n<li>Lardone RD: Gli anticorpi IgG anti-glicosfingolipidi associati ai disturbi neurologici mostrano una distribuzione differenziata delle sottoclassi IgG. Sci Rep. 2020 Aug 4;10(1): 13074.<\/li>\n<\/ol>\n\n<p><em>InFo NEUROLOGIA &amp; PSICHIATRIA 2021; 19(3): 19-25.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le neuropatie immunomediate variano nella presentazione clinica, nel decorso e nella patogenesi. Negli ultimi anni, sono stati rilevati autoanticorpi contro le proteine nodali e paranodali dell&#8217;anello di Ranvier. Gli autoanticorpi&hellip;<\/p>\n","protected":false},"author":7,"featured_media":108434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Neuropatie immunomediate","footnotes":""},"category":[11519,22617,11371,11550],"tags":[20175,11750,20176,20177],"powerkit_post_featured":[],"class_list":["post-328701","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-formazione-ecm","category-neurologia-it","category-rx-it","tag-autoanticorpi","tag-formazione-ecm","tag-neuropatia","tag-neuropatia-immunomediata","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:27:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":328703,"slug":"o-papel-dos-auto-anticorpos-nas-polineuropatias","post_title":"O papel dos auto-anticorpos nas polineuropatias","href":"https:\/\/medizinonline.com\/pt-pt\/o-papel-dos-auto-anticorpos-nas-polineuropatias\/"},"es_ES":{"locale":"es_ES","id":328705,"slug":"el-papel-de-los-autoanticuerpos-en-las-polineuropatias","post_title":"El papel de los autoanticuerpos en las polineuropat\u00edas","href":"https:\/\/medizinonline.com\/es\/el-papel-de-los-autoanticuerpos-en-las-polineuropatias\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/328701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=328701"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/328701\/revisions"}],"predecessor-version":[{"id":328702,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/328701\/revisions\/328702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/108434"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=328701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=328701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=328701"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=328701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}