{"id":329055,"date":"2021-05-14T14:00:00","date_gmt":"2021-05-14T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/prima-sostanza-mirata-per-la-mutazione-kras-e-limmunoterapia-bispecifica\/"},"modified":"2021-05-14T14:00:00","modified_gmt":"2021-05-14T12:00:00","slug":"prima-sostanza-mirata-per-la-mutazione-kras-e-limmunoterapia-bispecifica","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/prima-sostanza-mirata-per-la-mutazione-kras-e-limmunoterapia-bispecifica\/","title":{"rendered":"Prima sostanza mirata per la mutazione KRAS e l&#8217;immunoterapia bispecifica"},"content":{"rendered":"<p><strong>Mentre le terapie mirate per il carcinoma polmonare non a piccole cellule (NSCLC) sono in aumento da anni, manca ancora un&#8217;opzione del genere per i tumori <em>mutati in KRAS<\/em>. L&#8217;inibitore di piccole molecole Sotorasib, che ha come bersaglio KRASG12C, potrebbe presto colmare questa lacuna. C&#8217;\u00e8 anche qualcosa in cantiere per il carcinoma polmonare a piccole cellule (SCLC). In questo caso, l&#8217;attenzione \u00e8 rivolta all&#8217;immunoterapia con i cosiddetti <em>&#8220;ingaggiatori di cellule T bispecifici&#8221;<\/em> (BiTE), tra le altre cose.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Pi\u00f9 del 10% di tutti i casi di cancro e un buon 20% di tutti i decessi associati a malignit\u00e0 sono dovuti al cancro ai polmoni. O, per dirla in modo pi\u00f9 chiaro: ogni 18 secondi, una persona muore a causa di questa malattia in tutto il mondo, di cui 1200 ogni giorno in Europa. Anche se negli ultimi anni sono stati raggiunti alcuni successi nella terapia, c&#8217;\u00e8 ancora molto spazio per l&#8217;innovazione. Non solo c&#8217;\u00e8 un grande bisogno di nuovi approcci diagnostici e terapeutici, ma anche la loro attuazione nella pratica ha urgente bisogno di essere migliorata.<\/p>\n<h2 id=\"kras-come-bersaglio-terapeutico\"><em>KRAS<\/em> come bersaglio terapeutico<\/h2>\n<p>Le alterazioni genetiche sono molto diffuse nel cancro al polmone <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1) <\/span>. In tutti i sottotipi, la proteina G <em>KRAS<\/em> rappresenta la molecola pi\u00f9 frequentemente mutata e potenzialmente attaccabile. Ad esempio, circa il 27% di tutti gli adenocarcinomi del polmone presenta una mutazione del <em>gene KRAS<\/em>. Tuttavia, mentre altre mutazioni, come quelle dei <em>geni<\/em> <em>EGFR<\/em> e <em>ALK<\/em>, vengono gi\u00e0 prese di mira a livello terapeutico, il <em>KRAS<\/em> \u00e8 stato a lungo considerato un &#8220;bersaglio nonruggibile&#8221;. In particolare, le dimensioni ridotte, la superficie liscia e l&#8217;assenza di tasche di legame adatte rendono difficile l&#8217;attacco selettivo.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-16175\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0.png\" style=\"height:436px; width:600px\" width=\"1100\" height=\"800\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0-800x582.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0-120x87.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0-90x65.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0-320x233.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s30_0-560x407.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Con lo sviluppo dell&#8217;inibitore a piccola molecola Sotorasib, \u00e8 stato raggiunto per la prima volta un blocco clinicamente applicabile delle <em>proteine KRAS<\/em> <em>mutate G12C<\/em>. Circa il 50% dei NSCLC <em>mutati in KRAS<\/em> presenta questo sottotipo di mutazione. Il nuovo composto si lega in modo selettivo e irreversibile al bersaglio che prima si pensava fosse impossibile e quindi, in una certa misura, ha dato il via a un cambiamento di paradigma nella terapia mirata, non solo nel cancro al polmone. Da quando \u00e8 stata somministrata la prima dose nel 2018, sono gi\u00e0 stati pubblicati alcuni risultati promettenti della sperimentazione clinica. Per esempio, nello studio di fase II CodeBreaK 100, che ha incluso 126 pazienti con almeno una terapia precedente, il controllo della malattia \u00e8 stato riscontrato in oltre l&#8217;80% dei casi quando la monoterapia \u00e8 stata somministrata con soterasib, e tre pazienti hanno addirittura avuto una risposta completa. In 43 pazienti, il volume del tumore \u00e8 diminuito di almeno il 30%. La risposta mediana \u00e8 durata dieci mesi ed \u00e8 stata rilevabile dopo 1,4 mesi. Al momento del cut-off dei dati, il 43% dei responder era ancora in trattamento con sororasib. Anche la sopravvivenza mediana libera da progressione (PFS) \u00e8 stata convincente nell&#8217;analisi dei dati. La durata del trattamento con Sotorasib \u00e8 stata di 6,8 mesi.<\/p>\n<p>Rispetto alle precedenti opzioni di terapia di seconda linea per questa popolazione di pazienti, la nuova sostanza rappresenta un&#8217;alternativa significativamente migliore sulla base dei dati attuali. Con gli attuali regimi di trattamento, la sopravvivenza libera da progressione dopo il fallimento della terapia di prima linea \u00e8 di circa 4,5 mesi, con tassi di risposta massimi del 20% alla seconda linea di terapia. Non solo nell&#8217;ambito dell&#8217;efficacia, il sororasib \u00e8 stato in grado di suscitare qualche speranza finora, ma anche nella sicurezza e nella tolleranza. Le reazioni avverse segnalate sono state generalmente lievi e non ci sono stati decessi dovuti al farmaco. Solo il 7,1% dei pazienti ha dovuto interrompere il trattamento a causa degli effetti collaterali. In questo caso, l&#8217;attenzione principale era rivolta alla diarrea e alla nausea. Inoltre, in alcuni casi si sono verificati aumenti degli enzimi epatici e affaticamento.<\/p>\n<p>Attualmente sono in corso numerosi studi clinici per l&#8217;applicazione del nuovo agente, sia in linee avanzate di terapia che in prima linea <span style=\"font-family:franklin gothic demi\">(Tab.&nbsp;1).<\/span> Finora, soterasib \u00e8 l&#8217;<em>inibitore di KRASG12C<\/em> pi\u00f9 studiato. Nuovi dati sono attesi gi\u00e0 quest&#8217;anno, in particolare dallo studio CodeBreaK 101 di fase Ib per l&#8217;uso come terapia combinata di prima linea nel NSCLC e nel cancro del colon-retto. Una richiesta di approvazione per il trattamento di seconda linea del NSCLC avanzato con <em>mutazione KRASG12C<\/em> \u00e8 gi\u00e0 stata presentata all&#8217;Agenzia Europea dei Medicinali (EMA).<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-16176 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/326;height:178px; width:600px\" width=\"1100\" height=\"326\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0-800x237.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0-120x36.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0-90x27.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0-320x95.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/tab1_oh2_s31_0-560x166.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"speranza-tranquilla-anche-per-la-piccola-cellula\">Speranza tranquilla anche per la piccola cellula<\/h2>\n<p>Come in assenza di mutazioni bersagliabili nel NSCLC, i farmaci oncologici mirati non svolgono attualmente un ruolo nel carcinoma polmonare a piccole cellule (SCLC). Questo tipo di cancro al polmone rappresenta circa il 13% di tutti i casi e ha ancora una prognosi sfavorevole. Per oltre quarant&#8217;anni, la chemioterapia \u00e8 stata al centro del trattamento; gli approcci immunoterapeutici non sono stati finora convincenti. Tuttavia, questo potrebbe presto cambiare con lo sviluppo di anticorpi bispecifici, i cosiddetti <em>&#8220;ingaggiatori di cellule T bi-specifici&#8221;<\/em> (BiTE).<\/p>\n<p>L&#8217;immunoterapia con le BiTE si basa sull&#8217;attivazione del potenziale citotossico delle cellule T dell&#8217;organismo. A questo scopo, gli <em>ingaggiatori di cellule T<\/em> hanno due domini anticorpali variabili: uno \u00e8 diretto contro un antigene tumorale e varia a seconda dell&#8217;entit\u00e0, l&#8217;altro lega il CD3 sulla superficie delle cellule T citotossiche. Finora, oltre 3000 pazienti sono gi\u00e0 stati trattati con la tecnologia. La ricerca \u00e8 in corso a pieno ritmo nel campo dei tumori maligni sia ematologici che solidi. Attualmente, l&#8217;interesse si concentra sull&#8217;uso nel carcinoma prostatico, nel carcinoma polmonare a piccole cellule, nel mieloma multiplo e nel carcinoma gastrico. Si stanno testando anche vari trattamenti combinati e sequenziali per prevenire la potenziale resistenza. Attualmente, solo una terapia BiTE \u00e8 approvata a livello mondiale e in Svizzera per il trattamento della leucemia linfoblastica acuta: Blinatumomab (Blincyto\u00ae).<\/p>\n<p>Nel carcinoma polmonare a piccole cellule, il dominio variabile del BiTE denominato AMG 757 \u00e8 diretto contro la molecola di superficie DLL3, che \u00e8 upregolata sulle cellule maligne. Gli studi di fase I sono attualmente in corso. I dati iniziali mostrano un tasso di controllo della malattia del 37% dopo un follow-up di undici mesi. I dati a lungo termine restano da vedere, ma potrebbe esserci un movimento nel prossimo futuro in un&#8217;area che \u00e8 stata tranquilla per molto tempo.<\/p>\n<h2 id=\"verifica-nel-mondo-reale-standard-non-uniformi-disponibilita-non-garantita\">Verifica nel mondo reale: standard non uniformi, disponibilit\u00e0 non garantita<\/h2>\n<p>Per quanto innovative, avanzate ed efficaci possano essere le nuove terapie, spesso \u00e8 difficile implementarle nella pratica clinica quotidiana. Con approcci terapeutici pi\u00f9 complessi, una moltitudine di studi clinici e diversi biomarcatori, le richieste di gestione dei pazienti con cancro al polmone sono in aumento. La malattia, che viene ancora trattata in molti luoghi senza test genetici pi\u00f9 precisi, sta assumendo sempre pi\u00f9 volti diversi grazie all&#8217;identificazione di sempre pi\u00f9 bersagli che possono essere utilizzati nella terapia. A causa della percezione del tumore al polmone come un modello di malattia eterogeneo dal punto di vista istologico, genetico e fenotipico, stanno emergendo nuove opzioni terapeutiche a un ritmo rapido. Spesso \u00e8 difficile integrarli nella routine clinica, spiega la dottoressa Anne-Marie Baird, Presidente dell&#8217;organizzazione di pazienti <em>Lung Cancer Europe<\/em> (LUCE). La medicina personalizzata non corrisponde ancora alla realt\u00e0 in gran parte dell&#8217;Europa. Pertanto, gli sviluppi positivi nel campo delle sostanze disponibili oggi, purtroppo, non servono a tutti coloro che sono stati colpiti da lontano. Secondo questo, il 31-50% dei pazienti in Europa non sa se si \u00e8 sottoposto al test dei biomarcatori. Secondo Baird, esistono differenze regionali significative non solo nell&#8217;area della diagnostica standard, ma anche nella disponibilit\u00e0 di farmaci efficaci.<\/p>\n<p>I rapidi cambiamenti nel panorama terapeutico del tumore al polmone portano a disparit\u00e0 nella gestione e sollevano molte domande sulla procedura ottimale nella pratica clinica. Spesso non \u00e8 chiaro chi deve essere sottoposto al test per cosa e quando. Inoltre, la scelta del farmaco giusto e della sequenza migliore pu\u00f2 rappresentare oggi una sfida importante. Oltre ad ampliare l&#8217;accesso alla diagnostica e alla terapia, Baird cita la ricerca di solidi marcatori predittivi e lo sviluppo di linee guida chiare sui test genetici come obiettivi per i prossimi anni. Se si riuscir\u00e0 a implementare queste soluzioni, i pazienti affetti da tumore al polmone potrebbero presto beneficiare di terapie ancora pi\u00f9 potenti, idealmente indipendentemente dal luogo in cui vivono. \u00c8 molto probabile che anche il soterasib e le BiTE giochino un ruolo in questo senso.<\/p>\n<p><em>Amgen Europa<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:<\/p>\n<ol>\n<li>Briefing per i media &#8220;Trasformare la cura mirata del cancro al polmone&#8221;, 01.02.2021, Amgen Europe Corporate Affairs<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGIA &amp; EMATOLOGIA 2021; 9(2): 30-31<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre le terapie mirate per il carcinoma polmonare non a piccole cellule (NSCLC) sono in aumento da anni, manca ancora un&#8217;opzione del genere per i tumori mutati in KRAS. L&#8217;inibitore&hellip;<\/p>\n","protected":false},"author":7,"featured_media":106429,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Novit\u00e0 dalla pipeline del cancro al polmone","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11405,11537,11376,11468,11550,11515],"tags":[18876,20514],"powerkit_post_featured":[],"class_list":["post-329055","post","type-post","status-publish","format-standard","has-post-thumbnail","category-genetica-it","category-mercato-e-medicina","category-oncologia-it","category-pneumologia","category-rx-it","category-studi","tag-carcinoma-polmonare","tag-sclc-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:55:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":329062,"slug":"primeira-substancia-visada-para-mutacao-kras-e-imunoterapia-bi-especifica","post_title":"Primeira subst\u00e2ncia visada para muta\u00e7\u00e3o KRAS e imunoterapia bi-espec\u00edfica","href":"https:\/\/medizinonline.com\/pt-pt\/primeira-substancia-visada-para-mutacao-kras-e-imunoterapia-bi-especifica\/"},"es_ES":{"locale":"es_ES","id":329066,"slug":"primera-sustancia-dirigida-para-la-mutacion-kras-e-inmunoterapia-biespecifica","post_title":"Primera sustancia dirigida para la mutaci\u00f3n KRAS e inmunoterapia biespec\u00edfica","href":"https:\/\/medizinonline.com\/es\/primera-sustancia-dirigida-para-la-mutacion-kras-e-inmunoterapia-biespecifica\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/329055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=329055"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/329055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/106429"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=329055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=329055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=329055"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=329055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}