{"id":329223,"date":"2021-04-28T14:00:00","date_gmt":"2021-04-28T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/vaccinazione-pneumococcica-utile-per-quali-gruppi-a-rischio\/"},"modified":"2021-04-28T14:00:00","modified_gmt":"2021-04-28T12:00:00","slug":"vaccinazione-pneumococcica-utile-per-quali-gruppi-a-rischio","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/vaccinazione-pneumococcica-utile-per-quali-gruppi-a-rischio\/","title":{"rendered":"Vaccinazione pneumococcica &#8211; utile per quali gruppi a rischio?"},"content":{"rendered":"<p><strong>Durante la pandemia della corona, in Svizzera c&#8217;\u00e8 stata una carenza di vaccino contro lo pneumococco. Pertanto, \u00e8 stata emessa una raccomandazione di vaccinazione sostitutiva. La copertura vaccinale dei bambini piccoli ha portato a una diminuzione significativa dei casi di pneumococco grave. La vaccinazione \u00e8 ancora fortemente raccomandata per questo gruppo a rischio. Come seconda priorit\u00e0, le persone con determinate malattie di base possono essere vaccinate indipendentemente dall&#8217;et\u00e0.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La piattaforma informativa sulle vaccinazioni in Svizzera (Infovac) raccomanda la vaccinazione contro gli pneumococchi con Prevenar13\u00ae per i bambini dai 2 mesi ai 5 anni di et\u00e0, per proteggersi dalle malattie pneumococciche come meningite, polmonite e avvelenamento del sangue [1]. A seconda dell&#8217;et\u00e0 del bambino, sono necessarie da 1 a 3 dosi. &nbsp;Come seconda priorit\u00e0, la vaccinazione con 1 dose di Prevenar13\u00ae \u00e8 raccomandata alle persone che presentano un rischio maggiore di infezione pneumococcica invasiva a causa di alcune patologie di base, indipendentemente dall&#8217;et\u00e0. Il Piano di vaccinazione svizzero mostra a quali malattie si applica [9]. Per poter continuare a fornire assistenza ai gruppi pi\u00f9 a rischio in Svizzera, \u00e8 fondamentale attenersi alle indicazioni raccomandate dalla&nbsp; Commissione federale per le vaccinazioni (EKIF) e dall&#8217;Ufficio federale della sanit\u00e0 pubblica (UFSP) [9].<\/p>\n<h2 id=\"laumento-della-domanda-porta-a-colli-di-bottiglia-nellofferta-di\">L&#8217;aumento della domanda porta a colli di bottiglia nell&#8217;offerta di&nbsp;.<\/h2>\n<p>In relazione alla pandemia COVID 19, \u00e8 stata segnalata una carenza di vaccini contro lo pneumococco in Svizzera [2,3]. L&#8217;EKIF e l&#8217;UFSP hanno quindi pubblicato delle raccomandazioni sostitutive temporanee per l&#8217;uso del vaccino Prevenar 13\u00ae <span style=\"font-family:franklin gothic demi\">(box)<\/span>. Questo indica che il vaccino \u00e8 disponibile, ma solo in quantit\u00e0 limitata. Pertanto, la priorit\u00e0 dovrebbe essere data alla vaccinazione dei bambini piccoli per prevenire la malattia pneumococcica invasiva, che \u00e8 comune e pericolosa in questi gruppi di et\u00e0, e in secondo luogo ad altri pazienti a maggior rischio di infezione pneumococcica a causa di malattie croniche. In Svizzera, la procedura di annullamento delle raccomandazioni di vaccinazione sostitutiva \u00e8 coordinata con l&#8217;Ufficio federale per l&#8217;approvvigionamento economico nazionale [2].<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"5\" cellspacing=\"1\" style=\"width:500px\">\n<tbody>\n<tr>\n<td>\n<p><strong>Raccomandazione sostitutiva temporanea per la vaccinazione contro gli pneumococchi<\/strong><\/p>\n<p>La raccomandazione sulla vaccinazione sostitutiva propone la seguente priorit\u00e0 (stato dell&#8217;informazione: 10.03.21) [5]: &#8220;L&#8217;Ufficio federale della sanit\u00e0 pubblica (UFSP) e la Commissione federale per le questioni relative alle vaccinazioni (EKIF) raccomandano che, fino a quando la disponibilit\u00e0 \u00e8 limitata, la prima priorit\u00e0 dovrebbe essere quella di vaccinare tutti i neonati di 2, 4 e 12 mesi. Ci\u00f2 corrisponde alla vaccinazione pneumococcica di base raccomandata nel Piano di vaccinazione 2020, con la seconda priorit\u00e0 di vaccinare con una dose di Prevenar13\u00ae le persone appartenenti ai gruppi di rischio definiti per l&#8217;infezione pneumococcica invasiva, identificati sulla base di malattie di base predisponenti. La vaccinazione nei soggetti a rischio (bambini &gt;5 anni e adulti) consiste in una singola dose; non sono indicate vaccinazioni di richiamo. Per le persone al di fuori di questi due gruppi di indicazioni, non c&#8217;\u00e8 alcuna indicazione alla vaccinazione&#8221;.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2 id=\"prevenar13-ha-unelevata-efficacia-contro-gli-pneumococchi\">Prevenar13\u00ae ha un&#8217;elevata efficacia contro gli pneumococchi<\/h2>\n<p>I dati statistici mostrano che il numero di casi di pneumococco invasivo \u00e8 diminuito nel corso degli anni e questa diminuzione \u00e8 correlata all&#8217;aumento della copertura vaccinale contro lo pneumococco [4]. Il tasso di malattia \u00e8 diminuito maggiormente nei gruppi di et\u00e0 inferiori ai 2 anni e dai 2 ai 4 anni. Il vaccino 13-valente (Prevenar13\u00ae) utilizzato in Svizzera dal 2011 protegge da un totale di 13 specie di pneumococco. Queste sono responsabili del 75-90% di tutte le malattie gravi nei neonati.&nbsp; Il vaccino coniugato contro gli pneumococchi ha un&#8217;efficacia molto elevata (&gt;95%), \u00e8 stato sviluppato appositamente per i neonati ed \u00e8 generalmente ben tollerato [1]. Alcuni effetti collaterali spiacevoli ma innocui, come la febbre o le reazioni locali (gonfiore, dolore e arrossamento) sono sproporzionati rispetto ai benefici della vaccinazione pneumococcica. Gli effetti collaterali gravi dopo la vaccinazione sono estremamente rari (da 1:100.000 a 1:1.000.000).<\/p>\n<h2 id=\"la-vaccinazione-contro-lo-pneumococco-non-puo-prevenire-il-decorso-grave-del-covid-19\">La vaccinazione contro lo pneumococco non pu\u00f2 prevenire il decorso grave del COVID-19<\/h2>\n<p>In relazione alle attuali carenze di approvvigionamento, l&#8217;UFSP sottolinea che la vaccinazione con Prevenar13<sup>\u00ae<\/sup>  protegge in modo molto efficace contro gli pneumococchi, ma non pu\u00f2 prevenire un decorso grave di COVID-19 [6]: &#8220;Tale decorso non si sviluppa a causa di infezioni batteriche secondarie causate da pneumococchi, ma nel contesto delle reazioni infiammatorie polmonari e sistemiche causate dal virus SARS-CoV-2&#8221;. L&#8217;Ufficio statale bavarese per la salute e la sicurezza alimentare (Bayerisches Landesamt f\u00fcr Gesundheit und Lebensmittelsicherheit), basato sull&#8217;Istituto Robert Koch (RKI), ha annunciato che la protezione vaccinale completa \u00e8 importante durante la pandemia coronale, soprattutto per le persone a rischio con determinate malattie precedenti [7,9]. La vaccinazione contro lo pneumococco protegge dalla polmonite causata dagli pneumococchi, che stressa e indebolisce il sistema immunitario e i polmoni, favorendo cos\u00ec ulteriori infezioni, come ad esempio il nuovo coronavirus SARS-CoV-2. Inoltre, la malattia pneumococcica pu\u00f2 richiedere che i pazienti siano assistiti in ospedale o in un&#8217;unit\u00e0 di terapia intensiva. Le raccomandazioni di vaccinazione che si applicano in Germania non sono del tutto congruenti con quelle della Svizzera.<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Infovac.ch: Pneumokokken, 14.10.20, www.infovac.ch, (ultimo accesso 10.03.2021)<\/li>\n<li>EKIF: Verbale dell&#8217;81esima Sessione Plenaria. 16.09.2020 (ultima chiamata 10.03.2021)<\/li>\n<li>UFSP: Vaccinazioni durante la pandemia COVID 19. Stato: 06.04.2020, (ultima chiamata 10.03.2021)<\/li>\n<li>Infovac.ch: Malattie invasive da pneumococco 2013-2017, www.infovac.ch, (ultimo accesso 10.03.2021)<\/li>\n<li>BORSA: Raccomandazioni per la sostituzione: Prevenar13\u00ae: disponibilit\u00e0 limitata A partire dal: 20.03.2020, www.bag.admin.ch, (ultimo accesso 10.03.2021)<\/li>\n<li>BAG: Coronavirus: domande frequenti (FAQ) www.bag.admin.ch, (ultimo accesso 10.03.2021)<\/li>\n<li>Ufficio statale bavarese per la salute e la sicurezza alimentare (LGL), www.lgl.bayern.de\/gesundheit, (ultimo accesso 10.03.2021)<\/li>\n<li>RKI: Bollettino epidemiologico 47\/2020, 19.11.2020, www.rki.de, (ultimo accesso 10.03.2021).<\/li>\n<li>UFSP: Piano di vaccinazione svizzero 2020,<\/li>\n<li>www.bag.admin.ch (ultima chiamata 10.03.2021)<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATICA GP 2021; 16(4): 31<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la pandemia della corona, in Svizzera c&#8217;\u00e8 stata una carenza di vaccino contro lo pneumococco. Pertanto, \u00e8 stata emessa una raccomandazione di vaccinazione sostitutiva. La copertura vaccinale dei bambini&hellip;<\/p>\n","protected":false},"author":7,"featured_media":106127,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Raccomandazioni di vaccinazione","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11415,11306,11443,11473,11550],"tags":[20688,15074,20687,12000],"powerkit_post_featured":[],"class_list":["post-329223","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-infettivologia","category-medicina-interna-generale","category-pediatria-it","category-prevenzione-e-assistenza-sanitaria","category-rx-it","tag-infovac-it","tag-pneumococco","tag-prevenire","tag-vaccinazione","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:56:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":329178,"slug":"vacinacao-pneumococica-util-para-que-grupos-de-risco","post_title":"Vacina\u00e7\u00e3o pneumoc\u00f3cica - \u00fatil para que grupos de risco?","href":"https:\/\/medizinonline.com\/pt-pt\/vacinacao-pneumococica-util-para-que-grupos-de-risco\/"},"es_ES":{"locale":"es_ES","id":329195,"slug":"vacunacion-antineumococica-util-para-que-grupos-de-riesgo","post_title":"Vacunaci\u00f3n antineumoc\u00f3cica: \u00bf\u00fatil para qu\u00e9 grupos de riesgo?","href":"https:\/\/medizinonline.com\/es\/vacunacion-antineumococica-util-para-que-grupos-de-riesgo\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/329223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=329223"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/329223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/106127"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=329223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=329223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=329223"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=329223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}