{"id":330531,"date":"2020-12-27T13:30:00","date_gmt":"2020-12-27T12:30:00","guid":{"rendered":"https:\/\/medizinonline.com\/il-principio-della-riduzione-del-danno-per-il-tabacco-unalternativa-reale-o-una-vetrina\/"},"modified":"2020-12-27T13:30:00","modified_gmt":"2020-12-27T12:30:00","slug":"il-principio-della-riduzione-del-danno-per-il-tabacco-unalternativa-reale-o-una-vetrina","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/il-principio-della-riduzione-del-danno-per-il-tabacco-unalternativa-reale-o-una-vetrina\/","title":{"rendered":"Il principio della riduzione del danno per il tabacco: un&#8217;alternativa reale o una vetrina?"},"content":{"rendered":"<p><strong>Le malattie legate al fumo sono tra i maggiori problemi di salute del 21\u00b0 secolo. Si stima che circa un miliardo di persone morir\u00e0 a causa delle conseguenze del consumo di tabacco entro il 2099 [1]. L&#8217;assistenza sanitaria preventiva \u00e8 attiva, si stanno sviluppando campagne contro il fumo &#8211; eppure molti non riescono a farne a meno. Nel frattempo, sono state sviluppate delle alternative alla sigaretta classica. Potrebbero essere la soluzione?<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La nicotina \u00e8 una sostanza psicoattiva responsabile della dipendenza dalle sigarette. Una strategia di riduzione del danno per i fumatori consiste nel passare a un servizio alternativo di somministrazione di nicotina. Questi includono prodotti come il tabacco senza fumo, le sigarette elettroniche o i prodotti di tabacco riscaldato. Per i fumatori di sigarette convenzionali, questo significa sostituire un prodotto molto dannoso con uno molto meno dannoso.<\/p>\n<p>Questa forma di sostituzione non \u00e8 un&#8217;idea nuova, ma \u00e8 nota da molto tempo nel trattamento di altri intossicanti e sostanze che creano dipendenza ed \u00e8 stata dimostrata in alcuni casi. La Svizzera occupa la prima posizione in un confronto europeo per quanto riguarda le misure di riduzione dei danni. Sono disponibili diverse opzioni, come le terapie sostitutive, lo scambio di siringhe e i controlli antidroga. Pertanto, il numero di decessi legati alla droga si \u00e8 notevolmente ridotto negli ultimi 20 anni <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1)<\/span> [2].<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-14952\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb1-hp11_s32.png\" style=\"height:300px; width:600px\" width=\"1100\" height=\"550\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"puntare-sul-principio-della-riduzione-del-danno\">Puntare sul principio della riduzione del danno<\/h2>\n<p>Mentre le terapie di sostituzione degli oppioidi, come la somministrazione di metadone, sono offerte solo ai tossicodipendenti con un rischio molto elevato e sono accompagnate da professionisti medici, le alternative al fumo classico contenenti nicotina sono prodotti di massa per il consumo. Nella maggior parte dei Paesi, sono facilmente accessibili alla popolazione generale. Mentre la prevalenza media del consumo di oppioidi tra gli adulti \u00e8 stimata allo 0,4% della popolazione dell&#8217;UE, quasi il 20% degli europei adulti sono fumatori [3,4]. In Svizzera, la situazione \u00e8 ancora peggiore: circa il 33% di tutti gli uomini fuma, e tra le donne \u00e8 quasi il 25%, nonostante sia ampiamente noto che il fumo \u00e8 dannoso per la salute. Quasi il 15% di tutti i decessi in questo Paese sono causati da malattie legate al tabacco.<\/p>\n<p>Nel 2003, l&#8217;Organizzazione Mondiale della Sanit\u00e0 (OMS) ha stabilito nell&#8217;Articolo 5.3 della Convenzione Quadro sul Controllo del Tabacco (FCTC) che la politica sanitaria deve essere protetta dagli interessi commerciali dell&#8217;industria del tabacco [5]. Finora, tutto bene. Ma questo approccio, che \u00e8 comprensibile e comprensibile nella sua essenza, \u00e8 stato ampliato nel 2008. Ora, secondo il Principio 1, esiste un conflitto fondamentale e inconciliabile tra gli interessi dell&#8217;industria del tabacco e quelli della politica sanitaria. Al contrario, questo significa che tutto ci\u00f2 che \u00e8 nell&#8217;interesse delle aziende del tabacco \u00e8 negativo per la salute pubblica. Un&#8217;affermazione espressa come fatto e verit\u00e0 vincolante per il futuro.<span style=\"color:rgb(255, 0, 0)\"> <\/span>In questo modo, la portata della FCTC \u00e8 stata notevolmente ampliata senza tenere conto delle possibili conseguenze negative. Infatti, gli obiettivi del controllo del tabacco si sono certamente spostati con l&#8217;avvento di prodotti alternativi alla nicotina senza combustione &#8211; dalla lotta alle conseguenze del fumo sulla salute a un&#8217;opposizione di principio all&#8217;uso della nicotina in s\u00e9. Questo crea dei conflitti. Anche quelli scientifici, come dimostrano i dibattiti molto controversi e non di rado accesi.<\/p>\n<h2 id=\"riduzione-del-danno-si-sigarette-elettroniche-no-loms-in-conflitto\">Riduzione del danno s\u00ec, sigarette elettroniche no &#8211; l&#8217;OMS in conflitto<\/h2>\n<p>L&#8217;Organizzazione Mondiale della Sanit\u00e0 (OMS) sostiene chiaramente la riduzione del danno nei suoi statuti. Tuttavia, ritiene che i prodotti alternativi alla nicotina senza combustione siano dannosi per la salute. Nella sua recente dichiarazione, rileva che non ci sono ancora dati sufficienti per comprendere la gamma di effetti sulla salute dei prodotti alternativi alla nicotina [6]. Tuttavia, l&#8217;OMS sostiene che le prove relative alle sostanze chimiche nocive presenti nella maggior parte dei sistemi elettronici di somministrazione della nicotina sono chiare. Pertanto, sono associati a un aumento del rischio di malattie cardiovascolari e polmonari. L&#8217;approccio pi\u00f9 sicuro, ha detto, \u00e8 evitare di usare sia i prodotti del tabacco che i prodotti alternativi alla nicotina.<\/p>\n<p>L&#8217;OMS vede anche uno sviluppo particolarmente preoccupante nel crescente uso di sigarette elettroniche da parte di bambini e adolescenti in alcuni Paesi. Secondo quanto riferito, ci sono prove sempre pi\u00f9 evidenti che gli adolescenti mai fumatori che usano le sigarette elettroniche raddoppiano il rischio di passare alle sigarette pi\u00f9 tardi nella vita. Inoltre, l&#8217;OMS osserva che l&#8217;esposizione di bambini e adolescenti alla nicotina pu\u00f2 avere un effetto dannoso e duraturo sullo sviluppo cerebrale.<\/p>\n<h2 id=\"posizione-dellers\">Posizione dell&#8217;ERS<\/h2>\n<p>Il Comitato per il Controllo del Tabacco (TCC) della European Respiratory Society (ERS) ha pubblicato un documento di posizione sull&#8217;uso del tabacco e la riduzione del danno nel maggio 2019, presentando sette argomenti per cui una strategia di riduzione del danno non dovrebbe essere utilizzata come strategia basata sulla popolazione nel controllo del tabacco. Tra le altre cose, la commissione ha ritenuto che i fornitori di prodotti alternativi alla nicotina sostengano falsamente che i fumatori non possono o generalmente non vogliono smettere di fumare. In realt\u00e0, la maggior parte dei fumatori vuole smettere. Secondo l&#8217;ERS, la maggior parte di coloro che sono riusciti a farlo hanno smesso con la sola forza di volont\u00e0, senza ricorrere alla terapia sostitutiva della nicotina (NRT) o a un farmaco per smettere di fumare.<\/p>\n<p>Inoltre, l&#8217;ERS afferma che le ipotesi e le affermazioni secondo cui i prodotti alternativi alla nicotina senza combustione sono altamente efficaci come ausili per smettere di fumare sono false o non documentate, cos\u00ec come le ipotesi secondo cui i prodotti alternativi alla nicotina sono generalmente innocui o le affermazioni secondo cui la diffusione del tabacco non pu\u00f2 essere controllata con altre strategie.<\/p>\n<p>Invece, l&#8217;ERS evidenzia il controllo del tabacco come uno dei maggiori successi della salute pubblica. I Paesi con un forte controllo del tabacco hanno registrato una diminuzione significativa della prevalenza del fumo. La sicurezza e l&#8217;efficacia dei prodotti alternativi alla nicotina come strumento per smettere di fumare non sono state dimostrate, il che rende ancora pi\u00f9 allarmante la diffusione di questi prodotti a precedenti non fumatori. L&#8217;uso delle alternative dovrebbe essere riservato ai fumatori pesanti con un rischio elevato per la salute. Tuttavia, non potrebbe essere una strategia basata sulla popolazione.<\/p>\n<p>Sebbene l&#8217;ERS sostenga i prodotti sostitutivi della nicotina (cerotti, spray, ecc.) approvati dalla FDA, consiglia ai medici di non raccomandare ai loro pazienti fumatori prodotti alternativi alla nicotina senza combustione. Questo contraddice il Giuramento di Ippocrate, in base al quale un medico giura di rispettare determinati standard etici e di &#8220;non nuocere&#8221; [7].<\/p>\n<h2 id=\"la-sigaretta-elettronica-e-meno-dannosa-del-95-secondo-la-relazione-di-un-esperto-britannico\">La sigaretta elettronica \u00e8 meno dannosa del 95%, secondo la relazione di un esperto britannico<\/h2>\n<p>L&#8217;ERS si \u00e8 quindi scontrato con alcuni esperti che sostengono un&#8217;opinione contraria. \u00c8 vero che non si sa molto sulle conseguenze a lungo termine dell&#8217;uso di prodotti alternativi alla nicotina. Ci\u00f2 \u00e8 dovuto anche al fatto che molti prodotti sono sul mercato da poco tempo. Tuttavia, una relazione di esperti indipendenti per l&#8217;autorit\u00e0 sanitaria britannica PHE ha concluso nel 2015 che le sigarette elettroniche potrebbero essere fino al 95% meno dannose delle sigarette tradizionali [8]. Un confronto diretto con le sigarette convenzionali mostra anche che i nuovi prodotti alternativi alla nicotina sono significativamente meno dannosi senza combustione<span style=\"font-family:franklin gothic demi\"> (Fig. 2) <\/span>. In linea di principio, il problema non \u00e8 la nicotina in s\u00e9, ma le sostanze chimiche nocive e potenzialmente dannose che vengono prodotte principalmente durante il processo di combustione del tabacco [9\u201311]. I prodotti alternativi alla nicotina riscaldano solo gli ingredienti, riducendo in modo massiccio le sostanze potenzialmente tossiche presenti nell&#8217;aerosol [12].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-14953 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/769;height:419px; width:600px\" width=\"1100\" height=\"769\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0-800x559.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0-120x84.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0-90x63.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0-320x224.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb2_hp11_s33_0-560x391.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Nuove prove suggerirebbero che i fumatori che utilizzano le sigarette elettroniche e ricevono un supporto aggiuntivo dai centri drop-in locali per combattere la dipendenza raggiungono tassi di abbandono tra i pi\u00f9 elevati. Le sigarette elettroniche non sono completamente prive di rischi, ma producono solo una frazione dei danni rispetto al fumo. Non \u00e8 stato osservato che le sigarette elettroniche abbiano compromesso il calo dei tassi di fumo in Inghilterra. Al contrario, sono risultati essere un altro mezzo per smettere di fumare<span style=\"font-family:franklin gothic demi\"> (Tab. 1)<\/span>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-14954 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/tab1_hp11_s34.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1294;height:706px; width:600px\" width=\"1100\" height=\"1294\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"il-vaping-non-piace-ai-giovani\">Il vaping non piace ai giovani<\/h2>\n<p>Il Piano di controllo del tabacco del Governo inglese stabilisce che PHE deve aggiornare il rapporto sull&#8217;uso delle sigarette elettroniche e di altri nuovi sistemi di somministrazione di nicotina ogni anno fino alla fine del 2022. Il rapporto pi\u00f9 recente \u00e8 stato pubblicato nel marzo 2020 e si concentra principalmente sul vaping [13]. Secondo questo, i dati relativi all&#8217;uso del vaping tra i giovani mostrano che si tratta soprattutto di giovani che hanno gi\u00e0 fumato sigarette tradizionali. Al contrario, meno dell&#8217;1% dei giovani che non hanno mai fumato sono vapers. Non \u00e8 stato possibile registrare un forte aumento della prevalenza del vaping. Al contrario, la prevalenza del fumo tra i giovani tra gli 11 e i 15 anni si \u00e8 pi\u00f9 che dimezzata tra il 2009 (11%) e il 2018 (5%) e da allora \u00e8 rimasta relativamente stabile.<\/p>\n<p>In Germania, osservazioni simili possono essere fatte anche con i riscaldatori di tabacco. Il Centro federale per l&#8217;educazione alla salute ha dichiarato, in un rapporto di ricerca pubblicato di recente, che l&#8217;esperienza dell&#8217;uso di riscaldatori di tabacco tra i giovani \u00e8 relativamente bassa, pari allo 0,5%. Per quanto riguarda il consumo negli ultimi 30 giorni, questo non ha quasi giocato un ruolo (0,1%) [14].<\/p>\n<p>Ci\u00f2 supporta i dati raccolti da Dipendenze Svizzera nel 2019. Concludono che meno del 2% dei ragazzi e delle ragazze di 15 anni hanno usato riscaldatori di tabacco almeno una volta nella loro vita precedente. E solo pochi di questi hanno dichiarato che ci\u00f2 \u00e8 avvenuto negli ultimi 30 giorni. Tuttavia, la grande maggioranza dei giovani di et\u00e0 compresa tra i 13 e i 15 anni non fa uso di riscaldatori di tabacco o non ne conosce nemmeno l&#8217;esistenza [15,16].<\/p>\n<h2 id=\"lattuale-revisione-cochrane-vede-dei-benefici-con-le-sigarette-elettroniche\">L&#8217;attuale revisione Cochrane vede dei benefici con le sigarette elettroniche<\/h2>\n<p>Gli esperti dell&#8217;Universit\u00e0 di Oxford hanno pubblicato una recente revisione che ha analizzato tutti i dati disponibili fino a gennaio 2020 [17]. Sono stati identificati 50 studi che hanno esaminato l&#8217;effetto delle sigarette elettroniche sull&#8217;astinenza da nicotina in un totale di 12.430 soggetti. L&#8217;endpoint primario era rappresentato da almeno sei mesi di astinenza da nicotina e da effetti collaterali gravi. Gli endpoint secondari sono stati definiti come variazioni della pressione sanguigna, della frequenza cardiaca e della saturazione di ossigeno, per esempio. Ha dimostrato che un numero maggiore di partecipanti ha smesso di fumare con i liquidi contenenti nicotina rispetto ai prodotti sostitutivi della nicotina. Il rischio di effetti collaterali era paragonabile, anche se in questo caso i dati mostrano un&#8217;evidenza piuttosto bassa. L&#8217;indagine ha concluso che 100 persone che hanno utilizzato le sigarette elettroniche alla nicotina per smettere di fumare hanno avuto un successo 10 volte maggiore rispetto a solo sei persone su 100 che hanno utilizzato la terapia sostitutiva alla nicotina o le sigarette elettroniche senza nicotina, o quattro persone su 100 che non hanno avuto alcun supporto o solo un supporto comportamentale. Gli esperti raccomandano studi a lungo termine per verificare questi risultati, soprattutto con i pi\u00f9 recenti prodotti alternativi alla nicotina.<\/p>\n<h2 id=\"le-sigarette-elettroniche-non-sono-responsabili-della-malattia-americana-del-vaping\">Le sigarette elettroniche non sono responsabili della malattia americana del vaping<\/h2>\n<p>In America, l&#8217;anno scorso sono aumentate le segnalazioni di malattie talvolta letali associate all&#8217;uso di sigarette elettroniche. Questi includevano malattie polmonari con dispnea crescente, tosse e dolore toracico. Si \u00e8 parlato anche di problemi gastrointestinali, febbre e perdita di peso. I disturbi, soprannominati &#8220;malattia del vapore&#8221;, hanno portato alla respirazione artificiale in una persona su tre tra quelle colpite. Nel frattempo, \u00e8 stato possibile dimostrare che la maggior parte delle persone colpite ha consumato liquidi acquistati illecitamente sul mercato nero e arricchiti con olio di THC. A questo \u00e8 stato aggiunto l&#8217;acetato di vitamina E per allungarlo, che alla fine \u00e8 stato incolpato dei reclami. La Food and Drug Administration (FDA) ha poi messo in guardia i consumatori dall&#8217;acquistare questi prodotti illegali [18].<\/p>\n<p>Al contrario, la FDA ha gi\u00e0 riconosciuto un riscaldatore di tabacco THS 2.2 (commercializzato come IQOS) come idoneo per la protezione della salute pubblica e ne ha approvato la commercializzazione nell&#8217;aprile 2019. Nel luglio 2020, questo riscaldatore di tabacco \u00e8 stato approvato come prodotto del tabacco con rischio modificato negli Stati Uniti, sulla base, tra l&#8217;altro, di un processo di revisione di 3 anni. Ci\u00f2 consente alla FDA di comunicare ai fumatori adulti che questo riscaldatore di tabacco riduce in modo significativo l&#8217;esposizione dell&#8217;organismo a sostanze chimiche nocive o potenzialmente nocive, quando viene completamente acceso. L&#8217;obbligo di sorveglianza e di studi post-market \u00e8 anche parte della decisione della FDA, per determinare l&#8217;impatto sulla percezione, sul comportamento e sulla salute dei consumatori e, soprattutto, per verificare la correttezza della decisione [19].<\/p>\n<h2 id=\"la-svizzera-e-disposta-ad-aprire-nuove-strade\">La Svizzera \u00e8 disposta ad aprire nuove strade<\/h2>\n<p>In Svizzera, la Federazione dei professionisti delle dipendenze, che riunisce le tre associazioni delle dipendenze Fachverband Sucht, Groupement Romand d&#8217;Etudes des Addictions (GREA) e Ticino Addiction, aveva gi\u00e0 chiesto un cambiamento di rotta nella politica svizzera sul tabacco nel 2017. Le sigarette elettroniche dovrebbero quindi essere riconosciute come un efficace strumento di riduzione del danno, in quanto la vaporizzazione \u00e8 migliore della combustione.<\/p>\n<p>Dalla primavera del 2018, in Svizzera \u00e8 consentita la vendita di liquidi contenenti nicotina per le sigarette elettroniche. Diversi produttori hanno sottolineato fin dall&#8217;inizio che i giovani non erano un gruppo target e hanno concordato fin dall&#8217;inizio una tavola rotonda sui regolamenti per la protezione dei minori. I firmatari si sono quindi impegnati a non fornire prodotti alternativi alla nicotina senza combustione a persone di et\u00e0 inferiore ai 18 anni. L&#8217;Ufficio federale della sicurezza alimentare e di veterinaria (FSVO), che \u00e8 responsabile delle sigarette elettroniche in Svizzera, ha accolto con favore questo accordo.<\/p>\n<p>All&#8217;inizio del 2019, nel Cantone di Soletta \u00e8 stato avviato un progetto pilota che offre un supporto attivo sotto forma di sigarette elettroniche ai fumatori che vogliono abbandonare il tabagismo: La &#8220;Suchthilfe Ost&#8221; distribuisce gratuitamente le alternative a coloro che vogliono smettere di fumare per un periodo iniziale di 18 mesi. Per questo, i fumatori devono solo accettare di essere accompagnati e sostenuti da consulenti. I partecipanti devono pagare personalmente l&#8217;evaporazione del liquido.<\/p>\n<p>L&#8217;associazione &#8220;Addiction Support East&#8221; \u00e8 convinta dei benefici del progetto. Nella loro relazione annuale, concordano con le seguenti affermazioni: Per la salute, smettere di fumare in modo coerente \u00e8 la migliore di tutte le misure. Il passaggio alle sigarette elettroniche non deve essere venduto come una &#8220;alternativa sana&#8221;. Tuttavia, pu\u00f2 essere consigliata per quello che \u00e8: l&#8217;alternativa meno dannosa &#8211; e come passo possibile e decisivo per smettere di fumare [20].<\/p>\n<h2 id=\"la-riduzione-del-danno-nel-fuoco-incrociato-di-diverse-istituzioni\">La riduzione del danno nel fuoco incrociato di diverse istituzioni<\/h2>\n<p>Oltre alla Cochrane Review, sono stati pubblicati numerosi altri studi che concludono di raccomandare il passaggio completo alle sigarette elettroniche e ai riscaldatori di tabacco per la cessazione in termini di principio di riduzione del danno [21\u201322]. Inoltre, uno studio del 2019 pubblicato sul NEJM ha indicato che le sigarette elettroniche sono anche significativamente pi\u00f9 efficaci della terapia sostitutiva della nicotina per la cessazione del fumo [23].<\/p>\n<p>Ma non tutti gli esperti condividono questo punto di vista. Innanzitutto, viene denunciata la mancanza di esperienza a lungo termine. Questa opinione \u00e8 sostenuta, ad esempio, dalla European Respiratory Society (ERS) o dalla Societ\u00e0 tedesca di pneumologia e medicina respiratoria (DGP) [24].<\/p>\n<p>La Task Force dell&#8217;American College of Cardiology (ACC), invece, ha una visione leggermente pi\u00f9 differenziata. Sottolinea inoltre che l&#8217;uso di entrambi i prodotti dovrebbe essere evitato. Ma certifica anche che i prodotti alternativi alla nicotina hanno un potenziale di grande beneficio pubblico se aiutano i fumatori a smettere di fumare le sigarette tradizionali. In particolare, i fumatori che non vogliono o non possono smettere con i trattamenti attuali<span style=\"font-family:franklin gothic demi\"> (Fig.&nbsp;3).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-14955 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/12\/abb3_hp11_s35.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1078;height:588px; width:600px\" width=\"1100\" height=\"1078\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Attualmente non \u00e8 chiaro quali siano le conseguenze dell&#8217;uso di una sigaretta elettronica o di un riscaldatore di tabacco per molti anni sull&#8217;organismo umano e se questo consumo sia effettivamente meno dannoso di quello delle sigarette convenzionali a lungo termine. Si pone la domanda se i nuovi prodotti alternativi alla nicotina senza combustione debbano quindi essere rifiutati ai fumatori o se debbano essere accettati gi\u00e0 ora nel quadro del principio della riduzione del danno?<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Rapporto del Chirurgo Generale: Come il fumo di tabacco provoca le malattie 2010. Le basi biologiche e comportamentali delle malattie legate al fumo. In: Helath USDo, Human S, eds. Ufficio del Chirurgo Generale, Rockville MD: Servizio di Salute Pubblica 2010.<\/li>\n<li>www.infodrog.ch\/files\/content\/schadensminderung_de\/international\/2019.05_faktenblatt_stand-der-schadensminderung-in-der-schweiz.pdf (ultimo accesso 06.11.2020)<\/li>\n<li>Rapporto europeo sui farmaci 2017. Prevalenza e tendenze del consumo di droga. Consumatori di oppioidi ad alto rischio: l&#8217;eroina domina ancora. www.emcdda.europa.eu\/publications\/edr\/trends-developments\/2017\/html\/prevalence-trends\/high-riskopioid-users_en: Osservatorio europeo delle droghe e delle tossicodipendenze; [visitato il 01.10]. 2018.<\/li>\n<li>Statistiche sul consumo di tabacco. https:\/\/ec.europa.eu\/eurostat\/statisticsexplained\/index.php\/Tobacco_consumption_statistics: Eurostat. Statistiche spiegate; [aggiornato al 24.09.2018. accesso 01.10. 2018.<\/li>\n<li>https:\/\/tobaccoreporter.com\/2020\/11\/01\/the-irreconcilable-conflict-principle\/ (ultimo accesso 11.11.2020)<\/li>\n<li>www.who.int\/news\/item\/05-02-2020-e-cigarettes-are-harmful-to-health (ultimo accesso 08.11.2020)<\/li>\n<li>Pisinger C, Dagli E, et al: ERS e riduzione del danno da tabacco. Eur Respir J 2019; 54: 1902009; doi: 10.1183\/13993003.02009-2019.<\/li>\n<li>McNeill A, et al: Sigarette elettroniche: un aggiornamento delle prove Un rapporto commissionato da Public Health England 2015; https:\/\/assets.publishing.service.gov.uk\/government\/uploads\/system\/uploads\/attachment_data\/file\/733022\/Ecigarettes_an_evidence_update_A_report_commissioned_by_Public_Health_England_FINAL.pdf<\/li>\n<li>www.pharmazeutische-zeitung.de\/ausgabe-302015\/die-seele-raucht-mit\/ (ultimo accesso 04.08.2020)<\/li>\n<li>www.health.govt.nz\/publication\/chemicalconstituents-cigarettes-and-cigarette-smoke-prioritiesharm-reduction (ultimo accesso 05.08.2020)<\/li>\n<li>Schmeltz I, Schlotzhauer WS: Benzo[a]pirene, fenoli e altri prodotti dalla pirolisi dell&#8217;additivo per sigarette, (d,l)-Mentolo. Natura 1968; 219: 370-371.<\/li>\n<li>Margham J, McAdam K, Forster M, et al.: Composizione chimica dell&#8217;aerosol di una sigaretta elettronica: un confronto quantitativo con il fumo di sigaretta. Chem&nbsp;Res Toxicol. 2016; 29(10): 1662-1678.<\/li>\n<li>McNeill A, et al: Vaping in Inghilterra: un aggiornamento delle prove che include la salute mentale e la gravidanza, marzo 2020: un rapporto commissionato da Public Health England 2015; https:\/\/assets.publishing.service.gov.uk\/government\/uploads\/system\/uploads\/attachment_data\/file\/869401\/Vaping_in_England_evidence_update_March_2020.pdf<\/li>\n<li>www.bzga.de\/fileadmin\/user_upload\/PDF\/studien\/Drogenaffinitaet_Jugendlicher_2019_Basisbericht.pdf (ultimo accesso 12.11.2020)<\/li>\n<li>www.hbsc.ch\/pdf\/hbsc_bibliographie_342.pdf (ultimo accesso 11.11.2020)<\/li>\n<li>https:\/\/shop.addictionsuisse.ch\/de\/schule\/33-47-alles-klar-hbsc-2018.html (ultimo accesso 11.11.2020)<\/li>\n<li>Hartmann-Boyce J, et al: Cochrane Database Syst Rev 220; 10:CD010216.<\/li>\n<li>Malattie da vaping: i consumatori possono proteggersi evitando i prodotti di vaping contenenti tetraidrocannabinolo (THC), FDA 06.09.2019<\/li>\n<li>www.fda.gov\/news-events\/press-announcements\/fda-authorizes-marketing-iqos-tobacco-heating-system-reduced-exposure-information (ultimo accesso 11.11.2020)<\/li>\n<li>https:\/\/suchthilfe-ost.ch\/media\/SHO_Jahresbericht_2019_web2.pdf (ultimo accesso 12.11.2020) Deutsches Krebsforschungszentrum (2020): Sigarette elettroniche e riscaldatori di tabacco &#8211; una panoramica. www.dkfz.de\/de\/tabakkontrolle\/download\/Publikationen\/sonstVeroeffentlichungen\/2020_E-Zigaretten-und-Tabakerhitzer-Ueberblick.pdf<\/li>\n<li>St\u00f6ver H, et al.: (2020) Neue Wege zur Eind\u00e4mmung des Rauchens: Tabakkonsum &amp; Schadensminimierung (&#8220;Riduzione del danno da tabacco&#8221;). www.frankfurt-university.de\/fileadmin\/standard\/Hoch-schule\/Fachbereich_4\/Forschung\/ISFF\/Veranstaltungen\/Webinar_E-Zigaretten_2020\/Positionspapier_E-Zigarette_final_12102020.pdf<\/li>\n<li>Hering T: Sigarette elettroniche &#8211; fiasco tossicologico o meglio del non fumare? Internist 2020; 61: 634-643<\/li>\n<li>Hajek P, Phillips-Waller A, Przulj D, et al: Uno studio randomizzato sulle sigarette elettroniche rispetto alla terapia di sostituzione della nicotina. NEJM 2019; 380: 629-637<\/li>\n<li>https:\/\/pneumologie.de\/fileadmin\/user_upload\/Aktuelles\/2020-11-02_DGP_Stellungnahme_Tabakentwoehnung_mit_E-Zigarette.pdf (ultimo accesso 08.11.2020)<\/li>\n<li>Abrams DB, Glasser AM, Pearson JL, et al.: Minimizzazione del danno e controllo del tabacco: riformulare la visione sociale dell&#8217;uso di nicotina per salvare rapidamente delle vite. Annu. Rev. Public Health 2018, 39: 193-213.<\/li>\n<li>Britton J, George J, Bauld L, et al.: Un approccio razionale alle sigarette elettroniche &#8211; sfidando la politica dell&#8217;ERS sulla riduzione dei danni del tabacco. Eur Respir J 2020; in stampa (Disponibile su: https:\/\/doi.org\/10.1183\/13993003.00166-2020).<\/li>\n<li>Task Force dell&#8217;American College of Cardiology. Percorso decisionale di consenso degli esperti ACC 2018 sul trattamento per la cessazione del tabagismo. JAAC 2018; 72(25): 3332-3336.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATICA GP 2020; 15(11): 32-35<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le malattie legate al fumo sono tra i maggiori problemi di salute del 21\u00b0 secolo. Si stima che circa un miliardo di persone morir\u00e0 a causa delle conseguenze del consumo&hellip;<\/p>\n","protected":false},"author":7,"featured_media":101323,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Sigarette elettroniche e co.  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11306,11468,11473,11479,11550],"tags":[22521,12099,22526,22516,22064,22530,22534],"powerkit_post_featured":[],"class_list":["post-330531","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-medicina-interna-generale","category-pneumologia","category-prevenzione-e-assistenza-sanitaria","category-psichiatria-e-psicoterapia","category-rx-it","tag-dipendenza-it","tag-il-fumo","tag-nicotina-it","tag-sigarette","tag-sigarette-elettroniche","tag-vaper-it","tag-vaping-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:20:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":330536,"slug":"principio-da-reducao-de-danos-para-o-tabaco-uma-verdadeira-alternativa-ou-um-penso-de-janela","post_title":"Princ\u00edpio da redu\u00e7\u00e3o de danos para o tabaco: Uma verdadeira alternativa ou um penso de janela?","href":"https:\/\/medizinonline.com\/pt-pt\/principio-da-reducao-de-danos-para-o-tabaco-uma-verdadeira-alternativa-ou-um-penso-de-janela\/"},"es_ES":{"locale":"es_ES","id":330491,"slug":"principio-de-reduccion-de-danos-para-el-tabaco-una-alternativa-real-o-un-escaparate","post_title":"Principio de reducci\u00f3n de da\u00f1os para el tabaco: \u00bfUna alternativa real o un escaparate?","href":"https:\/\/medizinonline.com\/es\/principio-de-reduccion-de-danos-para-el-tabaco-una-alternativa-real-o-un-escaparate\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/330531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=330531"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/330531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/101323"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=330531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=330531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=330531"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=330531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}