{"id":333055,"date":"2020-11-10T13:00:00","date_gmt":"2020-11-10T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-terapia-cellulare-car-t-e-la-sua-applicazione-pratica\/"},"modified":"2020-11-10T13:00:00","modified_gmt":"2020-11-10T12:00:00","slug":"la-terapia-cellulare-car-t-e-la-sua-applicazione-pratica","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/la-terapia-cellulare-car-t-e-la-sua-applicazione-pratica\/","title":{"rendered":"La terapia cellulare Car-T e la sua applicazione pratica"},"content":{"rendered":"<p><strong>La tecnologia delle cellule CAR-T \u00e8 considerata l&#8217;ultima conquista della medicina oncologica. Le prime approvazioni in Europa sono avvenute a met\u00e0 2018 &#8211; la Svizzera ha seguito alla fine del 2018. Attualmente, il nuovo approccio terapeutico sembra in grado di ottenere buoni risultati, soprattutto contro il linfoma a cellule B e nella leucemia linfatica acuta. Ma la ricerca continua&#8230;<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Quando due anni fa \u00e8 arrivata sul mercato una nuova forma di trattamento, la precedente medicina contro il cancro \u00e8 stata stravolta. Per la prima volta, la terapia cellulare CAR-T ha permesso di indirizzare le cellule T geneticamente modificate in modo specifico alle cellule tumorali maligne. A questo scopo, i linfociti T vengono prelevati dal paziente mediante leucaferesi e dotati di recettori antigenici chimerici (CAR). La molecola CAR \u00e8 costituita da tre componenti:<\/p>\n<ul>\n<li>un frammento di anticorpo extracellulare, legato all&#8217;antigene, che rileva la struttura target sulla cellula tumorale,<\/li>\n<li>una parte transmembrana che fissa il CAR nella membrana della cellula T e lo stabilizza, e<\/li>\n<li>la frequenza del segnale cellulare intralocale che \u00e8 decisiva per l&#8217;attivazione.<\/li>\n<\/ul>\n<p>Dopo l&#8217;attivazione tramite il legame con la cellula tumorale, le cellule CAR-T iniziano a proliferare e a distruggere la cellula tumorale. Le cellule CAR-T riconoscono il loro antigene bersaglio con la sensibilit\u00e0 di un anticorpo e agiscono con l&#8217;efficienza potenziata di una cellula T &#8211; anche se la cellula tumorale non ha espressione MHC [1,2]. Dopo l&#8217;eliminazione del tumore, le cellule alterate possono persistere e tornare attive in caso di recidiva [3].<\/p>\n<h2 id=\"focus-sullematologia\">Focus sull&#8217;ematologia<\/h2>\n<p>I preparati attualmente disponibili contengono recettori antigenici chimerici contro il CD19, una molecola di superficie dei linfociti B. Pertanto, vengono utilizzati nei pazienti con linfoma diffuso a grandi cellule B (DLBCL), linfoma primario mediastinico a grandi cellule B (PMBCL) o leucemia linfoblastica acuta (ALL), quando non hanno risposto alle terapie iniziali o subiscono una ricaduta. Molti esperti concordano sul fatto che la terapia cellulare CAR-T sia il metodo pi\u00f9 promettente e curativo per questi pazienti. La sfida principale \u00e8 quella di colmare il tempo che manca all&#8217;inizio della terapia. Questo perch\u00e9 la produzione di cellule CAR-T, che attualmente viene ancora effettuata esclusivamente negli Stati Uniti, \u00e8 costosa e richiede molto tempo. Gli effetti collaterali temuti da molti, come la tempesta di citochine, invece, sono gestibili. Secondo un sondaggio della Societ\u00e0 tedesca di ematologia e oncologia medica (DGHO), il trattamento presenta addirittura meno complicazioni di quanto si temesse. Di conseguenza, il tasso di pazienti che necessitano di cure intensive \u00e8 del 14% e la mortalit\u00e0 \u00e8 del 3% [4].<\/p>\n<h2 id=\"uno-sguardo-al-futuro\">Uno sguardo al futuro<\/h2>\n<p>Attualmente sono in corso studi per altre malattie, quindi si pu\u00f2 ipotizzare che questa terapia sar\u00e0 approvata anche per altri tipi di cancro, in particolare per il mieloma multiplo. Nei pazienti con mieloma pesantemente pretrattato, la terapia con cellule CAR T \u00e8 stata in grado di ottenere un alto tasso di remissione, in alcuni casi pi\u00f9 del 50&nbsp;per cento di remissioni complete e un tempo libero da progressione significativamente pi\u00f9 lungo rispetto a tutti i farmaci precedentemente disponibili [5]. Ma si sta studiando anche l&#8217;uso delle cellule CAR-T in altre neoplasie a cellule B e in alcuni linfomi a cellule B in uno stadio molto pi\u00f9 precoce. Il trasferimento per malattie come il cancro al seno o al colon non \u00e8 ancora tangibile, ma gli studi sono gi\u00e0 in corso.<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Dai H, et al: Cellule T modificate con recettori dell&#8217;antigene chimerici per la terapia del cancro. J Natl Cancer Inst. 2016; 108(7).<\/li>\n<li>Curran KJ, Pegram HJ, Brentjens RJ: Recettori antigenici chimerici per l&#8217;im-munoterapia delle cellule T: comprensione attuale e direzioni future. J Gene Med. 2012; 14(6): 405-415.<\/li>\n<li>Sch\u00fc\u00dfler-Lenz M, M\u00fcller-Berghaus J, Keller-Stanislawski B: Terapia cellulare CAR-T: territorio inesplorato: come valutare i farmaci &#8220;vivi&#8221;. Dtsch Arztebl 2018; 115(39).<\/li>\n<li>www.dgho.de\/publikationen\/stellungnahmen\/gute-aerztliche-praxis\/car-t-zelltherapie\/car-t-zellen-status-20200722.pdf (ultimo accesso 20.09.2020)<\/li>\n<li>www.aerzteblatt.de\/nachrichten\/115340\/CAR-T-Zell-Therapie-an-26-Zentren-in-Deutschland-verfuegbar (ultimo accesso 20.09.2020)<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGIA ED EMATOLOGIA 2020; 8(5): 20<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tecnologia delle cellule CAR-T \u00e8 considerata l&#8217;ultima conquista della medicina oncologica. Le prime approvazioni in Europa sono avvenute a met\u00e0 2018 &#8211; la Svizzera ha seguito alla fine del&hellip;<\/p>\n","protected":false},"author":7,"featured_media":100367,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"La medicina del cancro del futuro","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11361,11519,11376,11550,11515],"tags":[17695,23413,22722],"powerkit_post_featured":[],"class_list":["post-333055","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ematologia","category-formazione-continua","category-oncologia-it","category-rx-it","category-studi","tag-cellule-car-t","tag-linfoma-a-cellule-b","tag-tutti","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:31:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":333005,"slug":"a-terapia-celular-automovel-t-e-a-sua-aplicacao-na-pratica","post_title":"A terapia celular autom\u00f3vel-T e a sua aplica\u00e7\u00e3o na pr\u00e1tica","href":"https:\/\/medizinonline.com\/pt-pt\/a-terapia-celular-automovel-t-e-a-sua-aplicacao-na-pratica\/"},"es_ES":{"locale":"es_ES","id":333066,"slug":"la-terapia-celular-car-t-y-su-aplicacion-en-la-practica","post_title":"La terapia celular Car-T y su aplicaci\u00f3n en la pr\u00e1ctica","href":"https:\/\/medizinonline.com\/es\/la-terapia-celular-car-t-y-su-aplicacion-en-la-practica\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/333055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=333055"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/333055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/100367"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=333055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=333055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=333055"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=333055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}