{"id":333427,"date":"2020-09-16T02:00:00","date_gmt":"2020-09-16T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/il-controllo-precoce-del-ritmo-mira-a-ottenere-risultati-migliori\/"},"modified":"2020-09-16T02:00:00","modified_gmt":"2020-09-16T00:00:00","slug":"il-controllo-precoce-del-ritmo-mira-a-ottenere-risultati-migliori","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/il-controllo-precoce-del-ritmo-mira-a-ottenere-risultati-migliori\/","title":{"rendered":"Il controllo precoce del ritmo mira a ottenere risultati migliori"},"content":{"rendered":"<p><strong>Nei pazienti con fibrillazione atriale di nuova diagnosi, l&#8217;inizio precoce del controllo del ritmo pu\u00f2 ridurre gli esiti cardiovascolari. La terapia con farmaci antiaritmici e\/o l&#8217;ablazione con catetere ha ridotto i decessi cardiovascolari, gli ictus e i ricoveri per peggioramento dell&#8217;insufficienza cardiaca o della sindrome coronarica acuta rispetto all&#8217;attuale cura standard basata sull&#8217;evidenza.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Sebbene il controllo precoce del ritmo fosse associato a un maggior numero di eventi avversi, la sicurezza complessiva di entrambe le strategie era paragonabile e non influiva sul numero di notti di ospedale all&#8217;anno. Questi sono i risultati dello studio EAST-AFNET 4 [1,2]. Il team di ricerca ha dimostrato che, anche con l&#8217;attuale trattamento basato sulle linee guida, circa il 5% dei pazienti con FA va incontro a sindrome coronarica acuta, insufficienza cardiaca, ictus o morte cardiovascolare ogni anno. Soprattutto nel primo anno dopo la diagnosi di fibrillazione atriale, il rischio di complicazioni cardiovascolari \u00e8 aumentato. Quindi, prima si inizia la terapia di controllo del ritmo, pi\u00f9 velocemente pu\u00f2 funzionare.<\/p>\n<p>Sono stati inclusi 2789 pazienti con fibrillazione atriale precoce e malattia cardiovascolare, che hanno ricevuto un controllo precoce del ritmo o un&#8217;assistenza standard. Il controllo precoce del ritmo comprendeva il trattamento con farmaci antiaritmici o l&#8217;ablazione con catetere dopo la randomizzazione. L&#8217;assistenza standard limitava il controllo del ritmo al trattamento dei sintomi legati alla fibrillazione atriale. L&#8217;endpoint primario era la morte per cause cardiovascolari, l&#8217;ictus o il ricovero in ospedale con peggioramento dell&#8217;insufficienza cardiaca o della sindrome coronarica acuta. Dopo un follow-up mediano di 5,1 anni, lo studio \u00e8 stato interrotto prematuramente a causa della sua efficacia. La terapia di controllo precoce del ritmo \u00e8 risultata associata a un rischio inferiore di esiti cardiovascolari rispetto all&#8217;assistenza standard nei pazienti con FA precoce e malattia cardiovascolare.<\/p>\n<p><em>Fonte: Congresso ESC 2020 <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Kirchhof P. EAST &#8211; AFNET 4: Effetti della terapia di controllo precoce del ritmo nei pazienti con fibrillazione atriale. Hot Line 1, Congresso ESC 2020, 29 agosto.<\/li>\n<li>Kirchhof P, et al: Pazienti con fibrillazione atriale. New Engl J Med. 2020, 29 agosto. DOI: 10.1056\/NEJMoa2019422.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2020; 19(3): 36 (pubblicato il 18.9.20, prima della stampa).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei pazienti con fibrillazione atriale di nuova diagnosi, l&#8217;inizio precoce del controllo del ritmo pu\u00f2 ridurre gli esiti cardiovascolari. La terapia con farmaci antiaritmici e\/o l&#8217;ablazione con catetere ha ridotto&hellip;<\/p>\n","protected":false},"author":7,"featured_media":99582,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Fibrillazione atriale","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11366,11522,11550,11515],"tags":[14792],"powerkit_post_featured":[],"class_list":["post-333427","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia-it","category-rapporti-del-congresso","category-rx-it","category-studi","tag-fibrillazione-atriale","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:21:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":333435,"slug":"o-controlo-precoce-do-ritmo-visa-melhores-resultados","post_title":"O controlo precoce do ritmo visa melhores resultados","href":"https:\/\/medizinonline.com\/pt-pt\/o-controlo-precoce-do-ritmo-visa-melhores-resultados\/"},"es_ES":{"locale":"es_ES","id":333442,"slug":"el-control-precoz-del-ritmo-busca-mejores-resultados","post_title":"El control precoz del ritmo busca mejores resultados","href":"https:\/\/medizinonline.com\/es\/el-control-precoz-del-ritmo-busca-mejores-resultados\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/333427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=333427"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/333427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/99582"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=333427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=333427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=333427"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=333427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}