{"id":333584,"date":"2020-08-21T02:00:00","date_gmt":"2020-08-21T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/peggio-della-loro-reputazione\/"},"modified":"2020-08-21T02:00:00","modified_gmt":"2020-08-21T00:00:00","slug":"peggio-della-loro-reputazione","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/peggio-della-loro-reputazione\/","title":{"rendered":"Peggio della loro reputazione?"},"content":{"rendered":"<p><strong>L&#8217;omeopatia non corrisponde alla sua &#8220;buona reputazione&#8221; tra la popolazione, n\u00e9 secondo criteri oggettivi n\u00e9 come semplice metodo placebo. Non c&#8217;\u00e8 dubbio che sia, come spesso si sente dire dai suoi sostenitori, una &#8220;opzione terapeutica aggiuntiva&#8221; nella pratica medica. Questo vale sia per l&#8217;applicazione solitaria che per quella complementare dell&#8217;omeopatia.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Nel 2017, \u00e8 stato pubblicato uno studio che ha analizzato la frequenza di prescrizione dell&#8217;omeopatia e le aspettative associate tra i medici praticanti nell&#8217;area di Zurigo (n=4072, tasso di risposta: 38%) [1]. Secondo questo, solo la met\u00e0 delle prescrizioni erano esplicitamente destinate a ottenere effetti specifici dell&#8217;omeopatia. Inoltre, la maggior parte dei prescrittori riconosce che l&#8217;efficacia dell&#8217;omeopatia non \u00e8 provata e attribuisce poca importanza ai suoi principi tradizionali. Il 23% ritiene che esistano prove scientifiche dell&#8217;efficacia dell&#8217;omeopatia. Questi risultati sollevano nuovamente la questione della rilevanza dell&#8217;omeopatia nella pratica medica. Di seguito, si tenta un posizionamento.<\/p>\n<h2 id=\"omeopatia-unopzione-terapeutica\">Omeopatia: un&#8217;opzione terapeutica?<\/h2>\n<p>L&#8217;omeopatia, inventata oltre 200 anni fa dal medico tedesco Samuel Hahnemann, gode ancora oggi di un uso diffuso e persino di un riconoscimento. \u00c8 richiesto dai pazienti, utilizzato come automedicazione e offerto dai terapeuti, compresi i medici. In modo pi\u00f9 o meno esplicito, le decisioni politiche le assegnano un posto nella sanit\u00e0 pubblica.<\/p>\n<p>Queste decisioni politico-sociali, al di l\u00e0 della validit\u00e0 scientifica, sono una delle ragioni principali per cui l&#8217;omeopatia \u00e8 percepita e considerata come un metodo rilevante dal punto di vista medico &#8211; dopo tutto, \u00e8 &#8220;parte del sistema sanitario&#8221;. Tutto questo rende difficile affrontare il tema dell&#8217;omeopatia, soprattutto nel rapporto medico-paziente.<\/p>\n<p>Ad esempio, la Svizzera ha incluso i metodi pseudo-medici, soprattutto l&#8217;omeopatia, nell&#8217;assistenza primaria, nonostante la mancanza di prove &#8211; &#8220;decidendo&#8221; politicamente le questioni scientifiche. Non si tratta nemmeno di una decisione chiara, ma di un compromesso di riserva a favore dei &#8220;metodi complementari&#8221;, che non afferma l&#8217;evidenza n\u00e9 nega l&#8217;accesso al sistema sanitario a causa della mancanza di prove [2]. Questo viene ampiamente frainteso &#8211; anche al di fuori della Svizzera &#8211; per significare che l&#8217;omeopatia ha delle prove come metodo medico, altrimenti non avrebbe potuto essere implementata nel sistema sanitario [3]. La legge farmaceutica tedesca ha privilegiato l&#8217;omeopatia sin dalla legge sui farmaci del 1978. La prova di efficacia scientificamente valida \u00e8 sostituita da un &#8220;consenso interno&#8221;, in base al quale una commissione composta da rappresentanti dell&#8217;omeopatia decide internamente se un rimedio deve ottenere l&#8217;autorizzazione all&#8217;immissione in commercio e quindi lo status di medicinale e l&#8217;accesso al mercato. Una finzione legale prende il posto dell&#8217;efficacia scientificamente provata.<\/p>\n<p>Il consenso scientifico sull&#8217;omeopatia, invece, \u00e8 chiaro a livello mondiale: nessun effetto medicinale specifico pu\u00f2 essere attribuito all&#8217;omeopatia. Le principali revisioni di indicazioni incrociate sull&#8217;omeopatia non mostrano prove di efficacia specifica per nessuna indicazione. Non ci sono differenze tra i risultati dei ricercatori omeopatici e quelli di altri ricercatori.<\/p>\n<p>Questa grave discrepanza tra desiderio e realt\u00e0 implica la domanda se l&#8217;omeopatia abbia un posto nell&#8217;applicazione clinica pratica.<\/p>\n<h2 id=\"lefficacia-medica-rilevanza-clinica\">L&#8217;efficacia medica (rilevanza clinica)<\/h2>\n<p>In ogni momento, la medicina \u00e8 stata generalmente intesa come &#8220;ci\u00f2 che aiuta&#8221;. La medicina moderna, tuttavia, dispone di metodi per valutare ci\u00f2 che aiuta realmente in un intervento e ci\u00f2 che \u00e8 dovuto a coincidenze, sopravvalutazione di aneddoti, influenze cognitive, terapie parallele e cos\u00ec via. Questa \u00e8 la base della medicina basata sull&#8217;evidenza, che da un lato chiede pragmaticamente solo il risultato, l&#8217;effetto clinicamente rilevante dimostrabile, e dall&#8217;altro si aspetta la prova di una specificit\u00e0 del rimedio o del metodo.<\/p>\n<p>Questo criterio di delimitazione dell&#8217;efficacia specifica \u00e8 un problema centrale per i metodi non specificamente efficaci come l&#8217;omeopatia. A questo proposito, l&#8217;omeopatia opera un certo mimetismo: si considera una medicina, ma i suoi rappresentanti sanno che i loro rimedi non possono reggere lo standard di un effetto scientificamente provato. Pertanto, dipendono da privilegi come l&#8217;accesso al mercato farmaceutico senza prove scientifiche di efficacia. Questo costringe a una posizione incoerente in alcuni luoghi. Da un lato, l&#8217;omeopatia si sforza di ottenere un riconoscimento scientifico, che emerge chiaramente da molte dichiarazioni dei suoi sostenitori e dai suoi stessi sforzi di ricerca. D&#8217;altra parte, ha problemi ad accettare i risultati della ricerca che non le piacciono, che vanno dall&#8217;ignorarli alla loro reinterpretazione fino al postulato &#8211; confutato dagli stessi ricercatori omeopatici &#8211; che il metodo scientifico non \u00e8 adatto per indagare sull&#8217;omeopatia. Pertanto, l&#8217;omeopatia stessa solleva la questione della sua collocazione scientifica [4].<\/p>\n<p>La mancanza di plausibilit\u00e0 dell&#8217;omeopatia, il suo appello a presunti effetti e leggi, che in parte contraddicono fondamentalmente le scoperte scientifiche [5], non \u00e8 stata nemmeno presa in considerazione. Questo risultato \u00e8 confermato da tutte le revisioni di indicazioni incrociate presentate dal 1991 in poi [6]. Questa evidenza complessiva include singoli lavori che sembrano mostrare un vantaggio dell&#8217;omeopatia nel gruppo verum. Naturalmente, i rappresentanti dell&#8217;omeopatia cercano di guadagnare reputazione e di rivendicare prove con tali studi. Tuttavia, questo \u00e8 un errore, perch\u00e9<\/p>\n<ul>\n<li>Nel migliore dei casi, gli studi individuali danno come risultato un  L&#8217;<em>indicazione di una <\/em>possibile prova, ma non consente di trarre alcuna conclusione sulla sua effettiva esistenza, a maggior ragione se uno studio non \u00e8 stato replicato in modo indipendente &#8211; cosa che tende ad essere la regola negli studi omeopatici, l&#8217;errore alfa.  <em>(errore di tipo I)<\/em> produce inevitabilmente falsi positivi all&#8217;interno di una popolazione,<\/li>\n<li>Le carenze nella progettazione, nell&#8217;implementazione e nella valutazione spostano inevitabilmente il risultato degli studi verso l&#8217;errore alfa [7],<\/li>\n<li>Tali carenze si riscontrano praticamente in tutte le revisioni, il che pu\u00f2 portare al problema di quali articoli possono essere inclusi in modo significativo in una revisione [8],<\/li>\n<li>Gli effetti clinicamente rilevanti sono, nella migliore delle ipotesi, dimostrati molto debolmente anche in questi studi individuali, il che, insieme alla mancanza di riproduzione e all&#8217;evidenza complessiva fino ad oggi, suggerisce piuttosto che questi effetti non esistono nella realt\u00e0.<\/li>\n<\/ul>\n<p>La valutazione e l&#8217;analisi della situazione di studio e le prove complessive che ne derivano hanno portato negli ultimi anni diverse organizzazioni scientifiche e servizi pubblici alla conclusione che l&#8217;omeopatia non pu\u00f2 rivendicare un posto all&#8217;interno di un sistema di salute pubblica. Come voce generale in merito, va citato il Consiglio consultivo delle accademie scientifiche europee (EASAC), l&#8217;associazione di 29 accademie scientifiche nazionali europee [9], che ha postulato nel 2017,<\/p>\n<ul>\n<li>che per quanto riguarda i meccanismi d&#8217;azione scientifici, le affermazioni sull&#8217;omeopatia sono poco plausibili e contraddicono i concetti scientifici consolidati;<\/li>\n<li>che in termini di efficacia clinica, sebbene possa verificarsi un effetto placebo in singoli pazienti, l&#8217;EASAC concorda con le conclusioni di precedenti valutazioni complete, secondo le quali non esistono prove solide e riproducibili dell&#8217;efficacia dell&#8217;omeopatia al di l\u00e0 dell&#8217;effetto placebo per nessuna delle malattie conosciute; ci sono preoccupazioni relative al consenso dei pazienti (si veda anche la sezione &#8220;La questione placebo&#8221;, nota degli autori) e alla sicurezza;<\/li>\n<li>che per quanto riguarda la promozione dell&#8217;omeopatia, si \u00e8 notato che potrebbe esserci un danno significativo per il paziente se ci fossero dei ritardi nella ricerca di cure mediche basate sulle prove e che, in generale, c&#8217;\u00e8 il rischio di minare la fiducia del pubblico nella natura e nel valore delle prove scientifiche.<\/li>\n<\/ul>\n<h2 id=\"lomeopatia-nella-pratica-medica\">L&#8217;omeopatia nella pratica medica<\/h2>\n<p><strong>I pazienti e l&#8217;omeopatia<\/strong><\/p>\n<p>A nessun medico viene impedito di utilizzare l&#8217;omeopatia nell&#8217;ambito della libert\u00e0 terapeutica. La questione \u00e8, tuttavia, se in questo caso debbano essere osservati altri limiti, indipendentemente dalla libert\u00e0 di terapia.<\/p>\n<p>L&#8217;onest\u00e0 della pratica medica e il requisito dell&#8217;onest\u00e0 nei confronti dei pazienti richiedono informazioni sul valore medico o sulla mancanza di valore del metodo. Senza dubbio, questo comporta uno sforzo nel singolo caso di trattamento e forse anche un rifiuto diretto da parte dei pazienti, con tutte le conseguenze immaginabili. Tuttavia, la richiesta di una prescrizione di omeopatia non deve essere semplicemente accolta per questo motivo.<\/p>\n<p>Nonostante l&#8217;autonomia e la partecipazione del paziente, che devono essere altamente valorizzate, la responsabilit\u00e0 della decisione terapeutica non passa al paziente. I &#8220;desideri&#8221; del paziente non possono essere decisivi. Di conseguenza, la terminologia della medicina basata sull&#8217;evidenza non riconosce i &#8220;desideri del paziente&#8221; (una lettura frequente da parte dei rappresentanti dell&#8217;omeopatia), ma piuttosto la &#8220;considerazione delle preoccupazioni legittime del paziente&#8221; nella decisione terapeutica. Il desiderio dei pazienti di un trattamento di finzione non pu\u00f2 giustificare queste &#8220;legittime preoccupazioni&#8221;. Soprattutto perch\u00e9 non pu\u00f2 essere lo scopo dell&#8217;azione medica quello di promuovere l&#8217;affinit\u00e0 farmacologica in questo modo e di rafforzare le valutazioni errate, soprattutto la fiducia ingiustificata nei metodi pseudo-medici.<\/p>\n<p>Al contrario, c&#8217;\u00e8 un notevole potenziale per promuovere l&#8217;alfabetizzazione sanitaria tra i pazienti. Quando l&#8217;omeopatia &#8220;funziona&#8221; &#8211; attraverso la somma degli effetti contestuali &#8211; di solito non sono necessari interventi farmacologici, a parte i rimedi per alleviare i sintomi, che comprendono anche i comuni rimedi casalinghi.<br \/>\nNaturalmente, il rifiuto del metodo sham dell&#8217;omeopatia non persegue l&#8217;obiettivo di &#8220;sostituire&#8221; gli omeopatici con i farmaci, questo sarebbe un grossolano equivoco. Piuttosto, \u00e8 consigliabile comunicare che per un gran numero di reclami non \u00e8 affatto necessario un intervento farmacologico, ma che l'&#8221;attesa responsabile&#8221; pu\u00f2 spesso essere l&#8217;opzione pi\u00f9 sensata. Il fatto che una cosa del genere arrivi come una sorpresa e sia insolita per molti pazienti &#8211; soprattutto per quelli che hanno un&#8217;affinit\u00e0 con l&#8217;omeopatia &#8211; dimostra i deficit di alfabetizzazione sanitaria generale.<\/p>\n<p>La &#8220;prescrizione dell&#8217;imbarazzo&#8221;, che per motivi &#8211; spesso abbastanza comprensibili &#8211; mira a evitare una discussione con il paziente e\/o a risparmiare tempo, non pu\u00f2 essere giustificata in questo senso. Al contrario, si tratterebbe di una violazione del diritto all&#8217;informazione dei pazienti e non contribuirebbe minimamente alla loro competenza sanitaria e alla percezione di s\u00e9 in caso di malattia.<\/p>\n<p>Si pu\u00f2 ridurre in modo significativo il tempo individuale dedicato alla formazione, ad esempio fornendo materiale informativo nello studio che spieghi perch\u00e9 l&#8217;omeopatia non fa parte del portafoglio dello studio. Spesso \u00e8 efficace informare in modo specifico i pazienti che l&#8217;omeopatia non \u00e8 la stessa cosa della naturopatia e della fitoterapia, poich\u00e9 questa \u00e8 probabilmente l&#8217;idea sbagliata pi\u00f9 comune. Il desiderio di una terapia &#8220;dolce e naturale&#8221; pu\u00f2 essere sostituito, se necessario, dalla raccomandazione di una misura dal portafoglio di rimedi naturali riconosciuti o dalla prescrizione di un fitoterapico adatto.<\/p>\n<p>In definitiva, gli autori sono convinti che la base di pazienti apprezzer\u00e0 il fatto che il &#8220;loro&#8221; medico apprezza l&#8217;onest\u00e0 nei confronti dei pazienti e utilizza mezzi e metodi scientificamente validi per convinzione.<\/p>\n<h2 id=\"lomeopatia-non-ha-il-monopolio-dellempatia-e-dellattenzione-medica\">L&#8217;omeopatia non ha il monopolio dell&#8217;empatia e dell&#8217;attenzione medica.<\/h2>\n<p>Nel sistema sanitario tedesco, il medico che cura gli omeopati ha la possibilit\u00e0 di fatturare i servizi omeopatici a tariffe molto pi\u00f9 alte del solito, al di fuori dei budget forfettari. Questo crea una base economica per un dispendio di tempo per paziente significativamente pi\u00f9 elevato rispetto alla normale attivit\u00e0 quotidiana.<\/p>\n<p>Un certo beneficio di un colloquio dettagliato di anamnesi omeopatica pu\u00f2 forse essere dato al paziente, anche se secondo l&#8217;insegnamento omeopatico questo non ha un obiettivo terapeutico, ma serve a trovare il rimedio. Questo viene usato anche per giustificare l&#8217;omeopatia. Tuttavia, da un lato, si tratta al massimo di effetti non diretti e temporanei, non specifici. D&#8217;altra parte, l&#8217;omeopatia non ha il monopolio dell&#8217;attenzione empatica del medico verso il paziente (&#8220;olismo&#8221;). Questo dovrebbe essere il fulcro di ogni sforzo medico. Se, come nel sistema sanitario tedesco, le condizioni quadro economiche vengono spostate a favore dell&#8217;omeopatia, questo non \u00e8 affatto da considerarsi positivo, perch\u00e9 alla fine va a scapito del resto della popolazione di pazienti. Il tempo totale disponibile del medico non cambia. Migliorare la comunicazione medico-paziente non richiede necessariamente un investimento di tempo maggiore. Un ritorno ai principi elementari della comunicazione medico-paziente, come Michael Balint ha formulato e cercato di trasmettere decenni fa, sarebbe molto utile [10].<\/p>\n<h2 id=\"il-problema-del-placebo\">Il problema del placebo<\/h2>\n<p>Un problema significativo per la pratica medica \u00e8, come dimostra anche lo studio sul comportamento prescrittivo citato all&#8217;inizio di questo articolo, la visione dell&#8217;omeopatia come terapia placebo. Verr\u00e0 quindi esaminata la questione se da ci\u00f2 si possa ricavare una giustificazione per l&#8217;uso dell&#8217;omeopatia nella pratica medica.<\/p>\n<p><strong>Le implicazioni etiche &#8211; il consenso informato<\/strong><\/p>\n<p>Secondo la concezione odierna dell&#8217;etica medica, la cooperazione &#8220;a livello degli occhi&#8221; tra medico e paziente \u00e8 un&#8217;espressione dell&#8217;alto valore dell&#8217;autonomia del paziente e un requisito centrale dell&#8217;azione medica. Come ogni professionista sa, questo pu\u00f2 essere realizzato solo nella costante consapevolezza dei problemi intrinseci e delle circostanze individuali di ogni caso di trattamento.<\/p>\n<p>In molti casi, l&#8217;omeopatia \u00e8 giustificata come terapia placebo, che dopo tutto ha un &#8220;beneficio&#8221; intrinseco. Ad un esame pi\u00f9 attento, questa posizione si rivela una pietra di paragone per l&#8217;etica medica. Le linee guida di etica dell&#8217;Associazione Medica Mondiale [11] descrivono il consenso <em>informato,<\/em> il &#8220;consenso informato&#8221; tra medico e paziente su una decisione terapeutica, come &#8220;uno dei concetti centrali dell&#8217;etica medica contemporanea&#8221;. In breve: non \u00e8 pi\u00f9 un&#8217;opzione, come lo era in passato nella medicina &#8220;patriarcale&#8221;, dire ai pazienti la verit\u00e0 o nascondere deliberatamente le informazioni. Sulla base di ci\u00f2, bisognerebbe chiarire se il <em>consenso informato<\/em> pu\u00f2 essere raggiunto nel caso dell&#8217;omeopatia.<\/p>\n<p>L&#8217;omeopatia gode, almeno nei Paesi di lingua tedesca, di un&#8217;ampia reputazione come &#8220;alternativa&#8221; genuina, &#8220;dolce, naturale e senza effetti collaterali&#8221; alla cosiddetta &#8220;medicina convenzionale&#8221;. Vari aspetti individuali (desiderio di autoefficacia, tendenza generale all&#8217;individualizzazione, ecc.) determinano inoltre la predisposizione di molte persone che cercano la guarigione [12].<\/p>\n<p>Come si dovrebbe ottenere il <em>consenso informato<\/em> sulla somministrazione di un placebo omeopatico con pazienti che hanno per lo pi\u00f9 interiorizzato la reputazione generale dell&#8217;omeopatia? L&#8217;informazione da parte del medico che si tratta di un farmaco specificamente inefficace, che tuttavia intende prescrivere, provocher\u00e0 quasi incredulit\u00e0, o almeno una notevole incertezza &#8211; che in ogni caso ostacola un valido <em>consenso informato<\/em>.<\/p>\n<p>Il <em>consenso informato <\/em>\u00e8 ancora pi\u00f9 precluso se il professionista presume anche un effetto dei medicinali omeopatici in senso medico specifico, ad esempio, in quanto praticante da molti anni, \u00e8 soggetto a un classico pregiudizio di conferma o addirittura ritiene possibile un effetto dell&#8217;omeopatia. Pertanto, sembra quasi impossibile creare una base giustificabile per un trattamento placebo con farmaci omeopatici, ai sensi dell&#8217;attuale etica medica [13].<\/p>\n<p><strong>Il placebo come fattore di decisione del trattamento<\/strong><\/p>\n<p>Il placebo, come spiegato, \u00e8 solo una parte degli effetti contestuali che danno ai metodi sham l&#8217;apparenza dell&#8217;efficacia. Per arrivare a una valutazione appropriata del placebo per la pratica, \u00e8 importante distinguere il &#8220;vero effetto placebo&#8221; da altri effetti contestuali e poterlo classificare correttamente.<\/p>\n<p>Il placebo in senso stretto \u00e8 la somministrazione di un farmaco senza principi attivi o l&#8217;uso di un metodo finto. L&#8217;effetto placebo vero e proprio deve essere inteso come un effetto psicotropo innescato da reazioni neurobiologiche complesse dovute al processo di attenzione e trattamento (&#8220;cura&#8221;). Questo processo non \u00e8 assolutamente basato sull'&#8221;immaginazione&#8221;, non pu\u00f2 essere influenzato dal soggetto a suo piacimento, ma pu\u00f2 certamente causare reazioni fisiologicamente misurabili. Tuttavia, l&#8217;opzione spesso invocata di utilizzare il placebo come metodo terapeutico \u00e8 ampiamente limitata:<\/p>\n<ul>\n<li>La quota concreta del placebo negli effetti contestuali \u00e8 probabilmente molto sovrastimata [14], il fattore principale degli &#8220;effetti&#8221; osservati \u00e8 probabilmente un decorso autolimitante della malattia.<\/li>\n<li>Il ricercatore sui placebo Ted Kaptchuk sottolinea che &#8220;i placebo possono farla sentire meglio, ma non la cureranno&#8221; [15].<\/li>\n<li>Infatti, \u00e8 stato dimostrato empiricamente che il placebo e gli effetti correlati possono mascherare il reale stato di salute in modo potenzialmente pericoloso [16].<\/li>\n<li>L&#8217;entit\u00e0, la direzione (&#8220;nocebo&#8221;) e la presenza o meno di effetti placebo non possono essere valutati in anticipo e spesso non possono essere dimostrati al di l\u00e0 di ogni dubbio nemmeno a posteriori. Pertanto, gli effetti placebo non possono essere specificamente diretti &#8220;contro&#8221; una particolare malattia.<\/li>\n<li>Il placebo come terapia regolare pu\u00f2 promuovere l&#8217;affinit\u00e0 del farmaco nei pazienti.<\/li>\n<li>Per un gran numero di interventi, non si pu\u00f2 comunque considerare un trattamento con placebo, &#8220;l&#8217;elenco delle condizioni che non sono sensibili al placebo \u00e8 quasi infinito&#8221; [17].<\/li>\n<\/ul>\n<p>L&#8217;assistenza centrata sul paziente non pu\u00f2 consistere nel far credere al paziente che sta migliorando grazie alle risposte placebo, quando in realt\u00e0 la compromissione di una funzione fisiologica legata alla malattia pu\u00f2 metterlo a rischio di gravi complicazioni.<\/p>\n<p>Consideriamo molto problematica la tendenza a giustificare i metodi fasulli come l&#8217;omeopatia con il &#8220;beneficio&#8221; dell&#8217;effetto placebo. Questo \u00e8 riconosciuto anche nell&#8217;ambito della ricerca sul placebo. Fabrizio Benedetti, rinomato ricercatore sul placebo del Dipartimento di Neuroscienze della Scuola Medica di Torino, ha pubblicato un articolo nel dicembre 2019 [17], in cui riassume:<\/p>\n<p>&#8220;Il fenomeno placebo \u00e8 ancora oggi un paradosso e un effetto non facile da gestire. [..]. Purtroppo, la ciarlataneria oggi ha un&#8217;altra arma dalla sua parte, rappresentata paradossalmente dai meccanismi placebo sostenuti dalla scienza esatta. Questa nuova &#8216;ciarlataneria scientifica&#8217; pu\u00f2 fare molto male, quindi dobbiamo essere molto attenti e vigili su come vengono utilizzate le scoperte della scienza esatta [&#8230;].<\/p>\n<p>Credo che la riflessione sia necessaria per evitare una ricaduta della medicina in tempi passati, quando prevalevano la ciarlataneria e lo sciamanesimo. Purtroppo, le nuove scoperte della scienza esatta sui placebo stanno producendo effetti di ritorno [&#8230;] Una domanda cruciale a cui rispondere \u00e8: la ricerca sui placebo sta promuovendo la pseudoscienza?&#8221;.<\/p>\n<p>Alcune implicazioni concrete che sono congruenti con queste considerazioni sono state elaborate sopra per il caso specifico dell&#8217;omeopatia. Non vediamo quindi alcuna giustificazione per l&#8217;uso esplicito o implicito dell&#8217;effetto placebo come &#8220;giustificazione&#8221; dell&#8217;uso della pseudomedicina\/omeopatia.<\/p>\n<h2 id=\"conclusione\">Conclusione<\/h2>\n<p>L&#8217;omeopatia non corrisponde alla sua &#8220;buona reputazione&#8221; nella popolazione e anche nelle professioni sanitarie, n\u00e9 secondo criteri oggettivi n\u00e9 come semplice metodo placebo. Non si pu\u00f2 parlare di omeopatia &#8211; come spesso si sente dire dai suoi sostenitori &#8211; come di una &#8220;opzione terapeutica aggiuntiva&#8221; nella pratica medica. Questo vale sia per l&#8217;applicazione solitaria che per quella complementare dell&#8217;omeopatia.<\/p>\n<h2 id=\"messaggi-da-portare-a-casa\">Messaggi da portare a casa<\/h2>\n<ul>\n<li>Le prove negative degli effetti dell&#8217;omeopatia sono ampiamente accettate dalla comunit\u00e0 scientifica: non esistono prove di un&#8217;efficacia clinica rilevante, al di l\u00e0 degli effetti contestuali, per nessuna indicazione medica.<\/li>\n<li>La produzione di un consenso informato per l&#8217;uso di farmaci omeopatici come placebo, che \u00e8 richiesto secondo i principi etici, sembra quasi impossibile a causa dell&#8217;ancorata &#8220;reputazione pubblica&#8221; del metodo.<\/li>\n<li>L&#8217;invocazione degli effetti placebo per giustificare un beneficio di rimedi e metodi senza una prova specifica di efficacia deve essere respinta sia in generale che nei singoli casi di trattamento.<\/li>\n<li>L&#8217;ancoraggio generale dell&#8217;omeopatia come metodo medico valido nella coscienza generale \u00e8 un fenomeno socio-psicologico basato su influenze e disinformazioni di vario tipo per un lungo periodo di tempo. Questo fenomeno si combina &#8211; utilizzato da ambienti interessati per scopi pubblicitari &#8211; con la tendenza all&#8217;individualizzazione e all&#8217;autodeterminazione, anche e soprattutto quando non c&#8217;\u00e8 autocompetenza o informazione sufficiente.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Markun S, et al.: Credenze, approvazione e applicazione dell&#8217;omeopatia rivelate: A Survey Among Ambulatory Care Physicians, Swiss Med Wkly 2017 Oct 12; 147: w14505; doi: 10.4414\/smw.2017.14505. eCollection 2017. (https:\/\/smw.ch\/article\/doi\/smw.2017.14505)<\/li>\n<li>Informationsnetzwerk Hom\u00f6opathie: sulla decisione di utilizzare l&#8217;omeopatia in Svizzera. https:\/\/netzwerk-homoeopathie.info\/ueber-die-entscheidung-zur-homoeopathie-in-der-schweiz\/<\/li>\n<li>La Svizzera \u00e8 un Eldorado per i fan dei Globuli tedeschi, Neue Z\u00fcrcher Zeitung, 23.05.2018, www.nzz.ch\/schweiz\/homoeopathie-schweiz-als-eldorado-fuer-globuli-fans-ld.1387741<\/li>\n<li>Grams N, Endruscheit U: Quanto \u00e8 scientifica l&#8217;omeopatia? Forum Wissenschaft 4\/2019, ed. Federazione degli scienziati democratici (bdwi), ISBN 978-3-939864-26-4<\/li>\n<li>Maddox J, Randi J, Stewart W: Gli esperimenti ad alta diluizione sono un&#8217;illusione. Natura 1988; 334: 287-290; doi: 10.1038\/334287a0<\/li>\n<li>Hom\u00f6opedia: Revisioni sistematiche sull&#8217;omeopatia: panoramica (www.hom\u00f6opedia.eu\/index.php\/Artikel:Systematische_Reviews_zur_Hom\u00f6opathie_-_\u00dcbersicht)<\/li>\n<li>Valutare il rischio di parzialit\u00e0 in uno studio randomizzato, Capitolo 8. In: Cochrane Handbook for Systematic Reviews of Interventions, Versione 6, 2019; https:\/\/training.cochrane.org\/handbook\/current\/chapter-08<\/li>\n<li>Utilizzando l&#8217;esempio di Mathie R. et al. 2014: www.hom\u00f6opedia.eu\/index.php\/Artikel:Systematische_Reviews_zur_Hom\u00f6opathie_-_Mathie_(2014)<\/li>\n<li>Prodotti e pratiche omeopatiche: valutare le prove e garantire la coerenza nella regolamentazione delle indicazioni mediche nell&#8217;UE, EASAC 2017; https:\/\/easac.eu\/fileadmin\/PDF_s\/reports_statements\/EASAC_Homepathy_statement_web_final.pdf<\/li>\n<li>Elzer M: 50 anni di gruppi Balint: Acquisire una competenza olistica. In: Dt \u00c4rzteblatt PP 3, 08\/2004; 364; www.aerzteblatt.de\/archiv\/43044\/50-Jahre-Balint-Gruppen-Ganzheitliche-Kompetenz-erwerben\/<\/li>\n<li>World Medical Association, WMA Handbook of Medical Ethics, capitolo. 5; www.bundesaerztekammer.de\/fileadmin\/user_upload\/downloads\/WMA_aerztliche_Ethik.pdf<\/li>\n<li>Grammi N: Omeopatia &#8211; Dov&#8217;\u00e8 la scienza? EMBO Rep 2019; 20: e47761; doi: 10.15252\/embr.201947761.<\/li>\n<li>Kovic M: \u00c8 moralmente sostenibile prescrivere l&#8217;omeopatia come placebo? Skeptiker Schweiz, Associazione per il Pensiero Critico, 23.11.2017; www.skeptiker.ch\/homoeopathie-placebo-moralisch-haltbar<\/li>\n<li>Hr\u00f3bjartsson A, G\u00f8tzsche PC: Il placebo \u00e8 impotente? N Engl J Med 2001; 344; www.nejm.org\/doi\/full\/10.1056\/NEJM200105243442106<\/li>\n<li>Il potere dell&#8217;effetto placebo, Harvard Health Publishing maggio 2017, aggiornato il 9 maggio 2019; www.health.harvard.edu\/mental-health\/the-power-of-the-placebo-effect<\/li>\n<li>Wechsler ME, et al: Albuterolo attivo o placebo, agopuntura sham o nessun intervento nell&#8217;asma. N Engl J Med 2011; 365: 119-126; www.nejm.org\/doi\/full\/10.1056\/NEJMoa1103319<\/li>\n<li>Benedetti F: Il lato pericoloso della ricerca placebo: la scienza dura sta alimentando la pseudoscienza? Farmacologia clinica e terapeutica 2017; 106.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>PRATICA GP 2020; 15(8): 6-10<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;omeopatia non corrisponde alla sua &#8220;buona reputazione&#8221; tra la popolazione, n\u00e9 secondo criteri oggettivi n\u00e9 come semplice metodo placebo. Non c&#8217;\u00e8 dubbio che sia, come spesso si sente dire dai&hellip;<\/p>\n","protected":false},"author":7,"featured_media":98657,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Omeopatia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11306,11550,11515],"tags":[24241,24253,24245,24236,24250],"powerkit_post_featured":[],"class_list":["post-333584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-medicina-interna-generale","category-rx-it","category-studi","tag-base-delle-prove","tag-consenso-informato","tag-omeopatia","tag-placebo-it","tag-pseudoscienza","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:26:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":333591,"slug":"pior-do-que-a-sua-reputacao","post_title":"Pior do que a sua reputa\u00e7\u00e3o?","href":"https:\/\/medizinonline.com\/pt-pt\/pior-do-que-a-sua-reputacao\/"},"es_ES":{"locale":"es_ES","id":333594,"slug":"peor-que-su-reputacion","post_title":"\u00bfPeor que su reputaci\u00f3n?","href":"https:\/\/medizinonline.com\/es\/peor-que-su-reputacion\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/333584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=333584"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/333584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/98657"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=333584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=333584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=333584"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=333584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}