{"id":334474,"date":"2020-04-09T02:00:00","date_gmt":"2020-04-09T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/screening-del-cancro-al-seno-per-ogni-donna\/"},"modified":"2020-04-09T02:00:00","modified_gmt":"2020-04-09T00:00:00","slug":"screening-del-cancro-al-seno-per-ogni-donna","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/screening-del-cancro-al-seno-per-ogni-donna\/","title":{"rendered":"Screening del cancro al seno per ogni donna?"},"content":{"rendered":"<p><strong>Il cancro al seno \u00e8 il tumore pi\u00f9 comune nelle donne. Molti hanno una storia familiare. Gli scienziati hanno studiato quando dovrebbe iniziare la diagnosi precoce, utilizzando pi\u00f9 di cinque milioni di cartelle cliniche.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Il cancro al seno da solo rappresenta un quarto di tutti i nuovi casi di cancro e porta alla morte il 15%. Negli ultimi decenni, sono stati lanciati programmi di screening per ridurre i tassi di mortalit\u00e0. Questo perch\u00e9 molte opzioni terapeutiche sono pi\u00f9 efficaci nelle fasi iniziali. Finora, le donne di et\u00e0 compresa tra 50 e 69 anni sono generalmente invitate a sottoporsi a una mammografia ogni due anni. Se esistono fattori di rischio genetici, come le mutazioni BRCA1, BRCA2 o PALB2, la linea guida prevede un inizio anticipato dello screening per le pazienti ad alto rischio.<\/p>\n<p>Finora, i dati disponibili per una valutazione differenziata del rischio di cancro al seno nelle donne con una storia familiare di cancro al seno erano scarsi. Questo perch\u00e9 il rischio varia a seconda dell&#8217;et\u00e0 della persona colpita, del numero di parenti colpiti e dell&#8217;et\u00e0 in cui il parente si \u00e8 ammalato. In un ampio studio, sono stati quindi analizzati pi\u00f9 di cinque milioni di dati. Durante il periodo di studio, un totale di 118.953 donne sono state colpite dal cancro al seno. Il 13,6 percento aveva parenti affetti da cancro al seno al momento della propria diagnosi. Sulla base dei rischi familiari associati al numero e all&#8217;et\u00e0 della diagnosi dei parenti di primo e secondo grado, i ricercatori hanno determinato l&#8217;et\u00e0 iniziale corretta per il rischio di diagnosi precoce del cancro al seno nelle donne con diversi gradi di storia familiare.<br \/>\nIl rischio di cancro al seno variava notevolmente a seconda del numero di parenti di primo e secondo grado affetti dalla malattia. Anche l&#8217;et\u00e0 in cui i parenti di primo grado si sono ammalati ha avuto un impatto. Per esempio, una donna alla cui sorella \u00e8 stato diagnosticato un cancro al seno all&#8217;et\u00e0 di 43 anni, raggiunge il rischio medio delle donne di 50 anni all&#8217;et\u00e0 di 38 anni. In questo caso, la diagnosi precoce del cancro al seno dovrebbe iniziare dodici anni prima. Con un calcolo individuale del rischio personale, oltre a prendere in considerazione altri fattori di rischio, la diagnosi del cancro al seno potrebbe essere regolata di conseguenza.<\/p>\n<p><em>Fonte: &#8220;Rischio di cancro al seno familiare: a che punto ha senso la diagnosi precoce del cancro al seno?&#8221;, 15.11.2019, Centro Nazionale per le Malattie Tumorali (NCT) Heidelberg (D)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Ulteriori letture:<\/p>\n<ul>\n<li>Mukama T, Kharazmi E, Xu X, et al: Et\u00e0 di inizio dello screening adattata al rischio per i parenti di pazienti con cancro al seno. JAMA Oncology, 2019; doi: https:\/\/doi.org\/10.1001\/jamaoncol.2019.3876<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGIA &amp; EMATOLOGIA 2019; 7(6): 44 (pubblicato l&#8217;8.12.19, in anticipo sulla stampa).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cancro al seno \u00e8 il tumore pi\u00f9 comune nelle donne. Molti hanno una storia familiare. Gli scienziati hanno studiato quando dovrebbe iniziare la diagnosi precoce, utilizzando pi\u00f9 di cinque&hellip;<\/p>\n","protected":false},"author":7,"featured_media":93703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Carcinoma mammario","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11409,11511,11376,11550,11515],"tags":[13612,13614,12134],"powerkit_post_featured":[],"class_list":["post-334474","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-ginecologia-it","category-notizie","category-oncologia-it","category-rx-it","category-studi","tag-cancro-al-seno","tag-carcinoma-mammario","tag-rilevazione-precoce","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:54:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":334480,"slug":"rastreio-do-cancro-da-mama-para-cada-mulher","post_title":"Rastreio do cancro da mama para cada mulher?","href":"https:\/\/medizinonline.com\/pt-pt\/rastreio-do-cancro-da-mama-para-cada-mulher\/"},"es_ES":{"locale":"es_ES","id":334489,"slug":"cribado-del-cancer-de-mama-para-todas-las-mujeres","post_title":"\u00bfCribado del c\u00e1ncer de mama para todas las mujeres?","href":"https:\/\/medizinonline.com\/es\/cribado-del-cancer-de-mama-para-todas-las-mujeres\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/334474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=334474"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/334474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/93703"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=334474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=334474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=334474"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=334474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}