{"id":334853,"date":"2020-02-03T16:09:39","date_gmt":"2020-02-03T15:09:39","guid":{"rendered":"https:\/\/medizinonline.com\/similitudini-e-differenze-degli-agonisti-parziali-della-dopamina\/"},"modified":"2020-02-03T16:09:39","modified_gmt":"2020-02-03T15:09:39","slug":"similitudini-e-differenze-degli-agonisti-parziali-della-dopamina","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/similitudini-e-differenze-degli-agonisti-parziali-della-dopamina\/","title":{"rendered":"Similitudini e differenze degli agonisti parziali della dopamina"},"content":{"rendered":"<p><strong>Gli antipsicotici sono il pilastro del trattamento acuto e a lungo termine dei disturbi schizofrenici. Quanto prima inizia il trattamento antipsicotico, tanto maggiore \u00e8 la possibilit\u00e0 di controllare o arrestare la progressione della psicosi.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Il termine schizofrenia \u00e8 stato coniato da Eugen Bleuler e pubblicato per la prima volta nel 1911 nella sua monografia &#8220;Gruppo di schizofrenie&#8221;. Questo termine tecnico di 108 anni fa per il disturbo psicotico pi\u00f9 importante \u00e8 ancora in uso oggi. Sei anni fa, il DSM-5, il manuale diagnostico americano, ha introdotto il termine &#8220;disturbo dello spettro schizofrenico&#8221;. Tuttavia, il primo trattamento veramente efficace per il disturbo schizofrenico non fu disponibile negli ospedali psichiatrici fino al 1952\/53. Questa terapia era basata sui farmaci: Clorpromazina. La clorpromazina fu portata direttamente dalla clinica universitaria psichiatrica di Parigi alla clinica universitaria di Basilea gi\u00e0 nel 1952 da Felix Labhart. Si pu\u00f2 presumere che questo sia stato fatto senza grandi sforzi burocratici all&#8217;epoca.<\/p>\n<h2 id=\"breve-storia-dei-neurolettici-antipsicotici\">Breve storia dei neurolettici\/antipsicotici<\/h2>\n<p>La <sup>clorpromazina\/Largactil\u00ae<\/sup> ha portato, negli anni successivi, a uno sconvolgimento della psichiatria istituzionale dell&#8217;epoca. Secondo il Prof. Raymond Battegay, i reparti cosiddetti &#8220;irrequieti&#8221; con gli psicotici agitati sono diventati improvvisamente meno rumorosi e molto pi\u00f9 rilassati. Erano ora possibili modi nuovi e pi\u00f9 umani di trattare questi malati mentali gravi.<\/p>\n<p>Il termine &#8220;neurolettico&#8221; deriva dal greco ed \u00e8 stato introdotto nella letteratura scientifica da Delay e Deniker nel 1955. L&#8217;obiettivo era quello di sviluppare un modello &#8216;eziologico&#8217; per la modalit\u00e0 d&#8217;azione dei nuovi farmaci antipsicotici. I due francesi avevano scoperto che la clorpromazina ha effetti sedativi e ansiolitici. Di conseguenza, \u00e8 stato utilizzato per l&#8217;agitazione psicomotoria soprattutto nei pazienti schizofrenici.<\/p>\n<p>L&#8217;introduzione dei neurolettici ha aperto una porta importante nel trattamento dei disturbi schizofrenici. In primo luogo, si trattava di un trattamento reversibile (ad esempio, in contrasto con le lobotomie ancora in uso all&#8217;epoca) e, in secondo luogo, l&#8217;effetto era rapido ed efficace. Questo ha portato a una massiccia riduzione della durata del soggiorno delle persone psicotiche negli istituti dell&#8217;epoca, che ha alleggerito gli ospedali sovraffollati. Le ricadute si sono verificate quando i pazienti hanno smesso di assumere il farmaco. I motivi erano la mancanza di conoscenza della malattia o effetti collaterali non trascurabili, come sedazione massiccia, parkinsonismo (EPMS) o fotosensibilit\u00e0.<\/p>\n<h2 id=\"scoperta-della-dopamina-come-neurotrasmettitore\">Scoperta della dopamina come neurotrasmettitore<\/h2>\n<p>All&#8217;incirca nello stesso periodo in cui la clorpromazina fu introdotta negli ospedali psichiatrici, Arvid Carlsson (1923-2018) in Svezia scopr\u00ec la dopamina, la sua struttura e la sua funzione come importante neurotrasmettitore nel cervello. Con il loro lavoro, Carlsson e Lindqvist hanno anche fondato l&#8217;ipotesi della dopamina nelle psicosi, che \u00e8 stata successivamente stabilita da van Rossum e Snyder ed \u00e8 tuttora valida. Questo afferma che gli antagonisti della dopamina, cio\u00e8 i neurolettici o gli antipsicotici, occupano i recettori della dopamina (in particolare i recettori D2) a livello postsinaptico e quindi bloccano la neurotrasmissione della dopamina. Il risultato \u00e8 un miglioramento dei sintomi positivi del disturbo schizofrenico. Mentre i neurolettici tipici migliorano principalmente le delusioni e le allucinazioni, hanno scarso effetto o addirittura peggiorano le caratteristiche della malattia in seguito definite sintomi negativi, come l&#8217;appiattimento affettivo, l&#8217;alogia, il ritiro sociale e l&#8217;apatia. In questo caso, la clozapina e gli antipsicotici atipici, meglio conosciuti come antagonisti della serotonina-dopamina, hanno portato un chiaro ampliamento dello spettro d&#8217;azione.<\/p>\n<h2 id=\"introduzione-di-farmaci-antipsicotici\">Introduzione di farmaci antipsicotici<\/h2>\n<p>Dopo l&#8217;introduzione della clorpromazina nel 1952, nei 20 anni successivi sono stati approvati diversi neurolettici cosiddetti triciclici, alcuni dei quali sono ancora oggi disponibili:  &nbsp;<\/p>\n<ul>\n<li>Dal gruppo di sostanze fenotiaziniche (clorpromazina, levomepromazina, flufenazina, promazina e triflupromazina),<\/li>\n<li>Dal gruppo di sostanze dei tioxanteni (clorprotixene e flupentixolo).<\/li>\n<\/ul>\n<p>Nello stesso periodo, sono stati approvati altri neurolettici con strutture non tricicliche ma con profili di effetti collaterali simili:<\/p>\n<ul>\n<li>Dal gruppo di sostanze dei butirofenoni (aloperidolo, pipamperone, melperone),<\/li>\n<li>Dal gruppo di sostanze delle difenilbutilpiperidine (fluspirilene e pimozide\/ oggi non pi\u00f9 in commercio).<\/li>\n<\/ul>\n<p>La classificazione di cui sopra in base agli aspetti chimico-strutturali si basa sui libri di testo di M\u00f6ller et al (2015) e Kaplan Sadock (2015).<\/p>\n<p>Nel 1972, in Svizzera \u00e8 stata approvata la clozapina (scoperta gi\u00e0 nel 1959), che ha mostrato un profilo d&#8217;azione particolare e un diverso spettro di effetti collaterali rispetto ai neurolettici precedenti. L&#8217;FDA ha approvato la clozapina solo nel 1990, motivo per cui gli Stati Uniti hanno scoperto la sua unicit\u00e0 solo pi\u00f9 tardi. \u00c8 stato il primo &#8220;antipsicotico atipico&#8221;:<\/p>\n<ul>\n<li>Dal gruppo di sostanze dibenzodiazepine (clozapina): questo gruppo \u00e8 anche chiamato &#8220;pini&#8221; da St. Stahl nel suo libro di testo a causa della loro fine: Cloza-pin; Questi includono olanzapina, quetiapina (entrambi strettamente correlati strutturalmente alla clozapina); asenapina e zotepina. Ci\u00f2 che queste sostanze hanno in comune \u00e8 il loro profilo multi-recettore.<\/li>\n<\/ul>\n<p>Altri antipsicotici atipici:<\/p>\n<ul>\n<li>Dal gruppo di sostanze dei benzisoxazoli (risperidone e ziprasidone); per semplicit\u00e0, il termine ombrello &#8220;dones&#8221; (risperi-dones) suggerito da St. Stahl viene utilizzato anche per le sostanze che sono simili in termini di recettori: Risperidone, Paliperidone, Lurasidone, Ziprasidone. Questi hanno una farmacologia recettoriale meno &#8220;ricca&#8221; rispetto ai &#8220;pini&#8221; e, a dosi pi\u00f9 elevate con EPMS, hanno UAW simili agli antagonisti della sola dopamina. Risperidone e paliperidone possono anche provocare un aumento dose-indipendente della prolattina.<\/li>\n<li>Dal gruppo di sostanze dei derivati della piperazina (aripiprazolo, brexpiprazolo e cariprazina). Queste sostanze mostrano un effetto nuovo e farmacologicamente molto interessante. Sono agonisti parziali della dopamina. St. Stahl li chiama &#8220;due pipi e uno strappo&#8221;, che si rif\u00e0 ai loro nomi: Ari-pip-razolo, Brex-pip-razolo e Ca-rip-razina; nel nostro Paese sono chiamati memotecnicamente l&#8217;ABC degli agonisti parziali della dopamina.<\/li>\n<\/ul>\n<p>La caratteristica comune a tutte queste nuove sostanze (&#8220;pini\/doni\/due pipi e uno strappo&#8221;) \u00e8 l&#8217;antagonismo combinato della serotonina (5-HT2A) e della dopamina D2. Sono stati introdotti in Svizzera dopo il 1990. L&#8217;aripiprazolo \u00e8 disponibile in Svizzera dal 2004, la cariprazina e il brexpiprazolo dal 2018. A ci\u00f2 ha fatto seguito, in Europa (non negli Stati Uniti), l&#8217;introduzione di altre nuove sostanze antipsicotiche del gruppo delle benzamidi (sulpiride nel 1972 e amisulpride nel 1999); anche l&#8217;amisulpride \u00e8 considerata un antipsicotico atipico, sebbene sia prevalentemente un antagonista D2 e D3. A dosi pi\u00f9 elevate, sono noti gli EPMS e soprattutto l&#8217;aumento significativo della prolattina.<\/p>\n<h2 id=\"agonismo-parziale-della-dopamina\">Agonismo parziale della dopamina<\/h2>\n<p>Il razionale dell&#8217;agonismo parziale della dopamina \u00e8 la compensazione ottimale della disregolazione dopaminergica associata alla psicosi (ipotesi dopaminergica della psicosi). Lo sfondo \u00e8 costituito dalle note vie della dopamina nel cervello <strong>(Fig.&nbsp;1) <\/strong>. In queste condizioni ha senso,<\/p>\n<ul>\n<li>Diminuiscono l&#8217;attivit\u00e0 dopaminergica nella via mesolimbica (migliorano i sintomi positivi come le illusioni e le allucinazioni attraverso un&#8217;azione antagonista).<\/li>\n<li>Aumenta l&#8217;attivit\u00e0 dopaminergica nella via mesocorticale (i sintomi negativi e anche i deficit cognitivi migliorano grazie all&#8217;effetto agonistico sul recettore della dopamina).<\/li>\n<li>non hanno alcun effetto sulle vie nigrostriatali o tuberoinfundibolari (nessun cambiamento nella funzione motoria, nessuna EPMS e nessun aumento della prolattina).<\/li>\n<\/ul>\n<p>L&#8217;aripiprazolo ottiene questo effetto bloccando contemporaneamente il recettore D2 postsinaptico e l&#8217;autorecettore presinaptico. Il risultato \u00e8 un effetto agonistico parziale, ma anche un effetto intrinseco della dopamina di circa il 30%. Un eccesso di antagonismo avvicina la sostanza ai classici antagonisti della dopamina, un eccesso di agonismo porta ad un aumento dei sintomi psicotici.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-12717\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/abb1_np6_s17.jpg\" style=\"height:286px; width:600px\" width=\"1100\" height=\"524\"><\/p>\n<p>&nbsp;<\/p>\n<p>Tutti e tre gli agonisti parziali della dopamina presentano la costellazione tipica degli antipsicotici atipici, con un antagonismo sull&#8217;asse della serotonina con 5-HT2A, ma con il gi\u00e0 citato agonismo parziale per il recettore D2 e anche per il recettore 5-HT1A, che potrebbe essere una spiegazione dell&#8217;effetto antidepressivo delle sostanze.<br \/>\nL&#8217;aripiprazolo mostra poche prove farmacologiche di sedazione (basso blocco H1 e basso effetto muscarinergico\/anticolinergico M1). Inoltre, ha uno scarso aumento di peso e un basso effetto diabetogeno. L&#8217;aripiprazolo \u00e8 disponibile in Svizzera dal 2004 ed \u00e8 a disposizione dei medici sia per via orale che intramuscolare e anche come depot.<\/p>\n<p>Secondo St. Stahl, il brexpiprazolo \u00e8 un agonista della dopamina pi\u00f9 debole rispetto all&#8217;aripiprazolo, ma mostra un antagonismo pi\u00f9 forte sul recettore 5-HT2A, un effetto agonista parziale pi\u00f9 forte sul recettore 5-HT1A e un maggiore antagonismo alfa-1. Questo significa poca EPMS e soprattutto meno acatisia.<\/p>\n<p>La cariprazina si comporta in modo simile al brexpiprazolo in termini di antagonismo (5-HT2A) e agonismo parziale (D2 e 5-HT1A), ma ha un ulteriore agonismo parziale per il recettore D3, che si pensa promuova il rilascio di dopamina nell&#8217;area mesocorticale. Questo sarebbe favorevole per il trattamento dei sintomi negativi. Le propriet\u00e0 di riduzione dell&#8217;acatisia del brexpiprazolo sono meno presenti con la cariprazina. Inoltre, come con l&#8217;aripirazolo, il recettore dell&#8217;istamina \u00e8 moderatamente bloccato, il che potrebbe spiegare una certa stanchezza (St. Stahl, 2013).<\/p>\n<p>Le differenze tra i tre agonisti parziali della dopamina sono state raccolte da L. Citrome, 2018, anche se va notato che i confronti non sono ponderati<em> testa a testa<\/em>, ma indirettamente rispetto al placebo<strong> (Tabella 1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12718 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/787;height:429px; width:600px\" width=\"1100\" height=\"787\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-800x572.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-120x86.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-90x64.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-320x229.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab1_np6_s18_0-560x401.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"nomenclatura-degli-antipsicotici\">Nomenclatura degli antipsicotici<\/h2>\n<p>La denominazione chimica strutturale delle sostanze attive antipsicotiche \u00e8 stata utilizzata principalmente nelle pubblicazioni scientifiche e quando sono state introdotte nuove sostanze. Non era molto pratico nella pratica quotidiana della prescrizione. La maggior parte degli antipsicotici introdotti sul mercato prima della clozapina (CH 1972\/USA 1990) si differenziavano per la gamma di dosi e per la sedazione (bassa potenza contro media potenza contro alta potenza), ma in termini di frequenza di EPMS ci sono solo differenze minori <strong>(Panoramica 1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12719 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/ubersicht1_np6_s18.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/739;height:403px; width:600px\" width=\"1100\" height=\"739\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;adozione di questa classificazione in base alla potenza antipsicotica e le tabelle di equivalenza della dose da essa derivate, tradizionalmente calibrate su 100 mg di clorpromazina, sono ormai superate per gli antipsicotici atipici e difficili da stabilire a causa dei profili di effetti collaterali molto diversi. Il gruppo di lavoro svizzero intorno a St. Kaiser et al. ha comunque incluso tale valutazione di equivalenza degli antipsicotici atipici, misurata a 1 mg di olanzapina, nelle raccomandazioni terapeutiche del 2016 <strong>(tab.&nbsp;2)<\/strong>. La clozapina non provoca EPMS, discinesia tardiva o aumento della prolattina. Il suo profilo di effetti collaterali \u00e8 associato, ad esempio, ad agranulocitosi, aumento di peso o sialo-arrea. Pertanto, la clozapina \u00e8 stata la prima ad essere assegnata al nuovo gruppo di antipsicotici atipici.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12720 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/tab2_np6_s19.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1134;height:619px; width:600px\" width=\"1100\" height=\"1134\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>In contrasto con la psichiatria europea, soprattutto di lingua tedesca, il termine &#8220;antipsicotici&#8221; si \u00e8 affermato presto nei Paesi di lingua inglese al posto di neurolettici. Al pi\u00f9 tardi dall&#8217;introduzione della clozapina negli Stati Uniti nel 1990, si parla solo di antipsicotici e si fa una distinzione tra sostanze tipiche e atipiche. Sinonimi, e soprattutto nei libri di testo, sono classificati come antipsicotici di prima generazione (FGA) o antipsicotici di seconda generazione (SGA). Questo non significa una classe di sostanze uniforme, perch\u00e9 gli antipsicotici pi\u00f9 recenti sono strutturalmente molto diversi e hanno un profilo recettoriale notevolmente differente. Fondamentalmente, nella letteratura scientifica in lingua inglese, tutte le sostanze antipsicotiche introdotte dopo il 1990 sono definite &#8220;antipsicotici atipici&#8221; (Linee guida Maudsley, 2018). Negli ultimi anni, il Collegio Europeo di Neuropsicofarmacologia (ECNP) ha diffuso una nuova nomenclatura, che classifica le sostanze in base alla farmacologia e alla modalit\u00e0 d&#8217;azione: Nomenclatura basata sulle neuroscienze (NbN2, 2018). Solo il tempo ci dir\u00e0 se questa sofisticata classificazione prevarr\u00e0. Dopotutto, nel loro testo standard di psichiatria, Kaplan Sadock (2015) si riferisce agli antipsicotici tipici come antagonisti della dopamina e alle sostanze atipiche come antagonisti della serotonina-dopamina, poich\u00e9 hanno questo principio d&#8217;azione in comune (sviluppo della nomenclatura).<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img decoding=\"async\" class=\"size-full wp-image-12721 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/kasten_np6_s18.png\" style=\"--smush-placeholder-width: 1094px; --smush-placeholder-aspect-ratio: 1094\/1205;height:441px; width:400px\" width=\"1094\" height=\"1205\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"cosa-fa-questa-discussione-accademica-per-il-paziente\">Cosa fa questa discussione accademica per il paziente?<\/h2>\n<p>I pazienti di solito sono principalmente scettici\/critici quando viene loro prescritto un antipsicotico. Soprattutto, per loro \u00e8 importante un effetto efficace senza reazioni avverse ai farmaci.<\/p>\n<p>Creare o mantenere buoni antipsicotici dal punto di vista del paziente (estratto):<\/p>\n<ul>\n<li>Nessun sintomo di crampi (EPMS)<\/li>\n<li>Nessuna irrequietezza (acatisia)<\/li>\n<li>Nessuna lingua pesante, nessun problema di deglutizione (EPMS, discinesia precoce).<\/li>\n<li>Peso corporeo stabile<\/li>\n<li>Nessuna sedazione\/essere sedati<\/li>\n<li>Potenza\/Libido<\/li>\n<li>Nessun appiattimento dell&#8217;effetto<\/li>\n<li>Nessuna &#8220;dipendenza<\/li>\n<li>Nessun &#8220;danno genico<\/li>\n<\/ul>\n<p>Nella scelta di un antipsicotico, occorre quindi prestare attenzione alla sicurezza e alla tollerabilit\u00e0 ottimali con una buona efficacia <strong>(Panoramica 2) <\/strong>. Allo stesso tempo, i criteri sopra citati sono decisivi per consigliare il farmaco pi\u00f9 adatto all&#8217;individuo. \u00c8 importante procedere nel senso di un processo decisionale condiviso e tenere conto dei desideri del paziente.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12722 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/ubersicht2_np6_s19.png\" style=\"--smush-placeholder-width: 1099px; --smush-placeholder-aspect-ratio: 1099\/548;height:199px; width:400px\" width=\"1099\" height=\"548\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Per i pazienti psicotici al primo episodio (FEP = First Episode Psychosis), la maggior parte delle linee guida internazionali raccomandano la somministrazione di un antipsicotico del tipo &#8220;a base di sangue&#8221;. 2a generazione, per cui quelli della Anche la terza generazione pu\u00f2 essere inclusa in questa categoria. Questo vale anche per le raccomandazioni terapeutiche svizzere (Kaiser et al. 2016\/18). Gli antipsicotici di prima generazione (ad esempio, l&#8217;aloperidolo) sono oggi la seconda scelta nel trattamento dei disturbi psicotici. L&#8217;eccezione \u00e8 l&#8217;uso nel trattamento del delirio (Eich PH, Nick B. 2018).<\/p>\n<h2 id=\"-4\">&nbsp;<\/h2>\n<h2 id=\"-5\"><img decoding=\"async\" class=\"size-full wp-image-12723 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/02\/fallbeispiele_np6_s20.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1176;height:641px; width:600px\" width=\"1100\" height=\"1176\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-6\">&nbsp;<\/h2>\n<h2 id=\"conclusione\">Conclusione<\/h2>\n<p>La moderna farmacoterapia del disturbo schizofrenico deve svolgere molteplici funzioni, cio\u00e8 la prospettiva di trattamento dei pazienti \u00e8 multifocale. Lo far\u00e0 allo stesso tempo:<\/p>\n<ol>\n<li>Conoscere gli antipsicotici di prima generazione ed essere consapevoli dei loro vantaggi e svantaggi.<\/li>\n<li>Essere efficace con il minor numero possibile di reazioni avverse ai farmaci (ADR).<\/li>\n<li>Essere personalizzato, cio\u00e8 adattato alle persone interessate (se sono disponibili indicatori appropriati).<\/li>\n<li>Essere riparativi con l&#8217;obiettivo: Restitutio ad integrum, cio\u00e8 preservare la funzione e riabilitare.<\/li>\n<li>Essere inseriti in un&#8217;assistenza basata sulla comunit\u00e0 e sui bisogni.<\/li>\n<\/ol>\n<p>Da una prospettiva clinica, la  <em>Antipsicotici del 2. e Terza generazione<\/em>  vantaggi evidenti rispetto alle sostanze tipiche. Per quanto riguarda Ippocrate e il suo principio: &#8220;Primum non nocere &#8211; secundum cavere &#8211; tertium sanare&#8221; (primo, non nuocere\/non provocare danni &#8211; secondo, prestare attenzione &#8211; terzo, curare\/contribuire alla guarigione\/traduzione<em> dell&#8217;<\/em> autore<em>)<\/em>, gli agonisti parziali della dopamina, con il loro profilo favorevole di effetti collaterali, sono sicuramente farmaci di prima scelta.<\/p>\n<h2 id=\"messaggi-da-portare-a-casa\">Messaggi da portare a casa<\/h2>\n<ul>\n<li>Gli antipsicotici rimangono oggi il pilastro del trattamento acuto e a lungo termine dei disturbi schizofrenici. Storicamente, attualmente abbiamo una gamma abbastanza ampia di sostanze antipsicotiche moderne tra cui scegliere.<\/li>\n<li>L&#8217;ordine del trattamento farmacologico si basa sulla psicopatologia e sul livello di sofferenza dei pazienti affetti. Va notato che quanto prima inizia il trattamento antipsicotico, tanto maggiore \u00e8 la possibilit\u00e0 di controllare o arrestare la progressione della psicosi.<\/li>\n<li>La non aderenza \u00e8 il fattore di ricaduta pi\u00f9 importante.<\/li>\n<li>L&#8217;uso degli antipsicotici deve essere discusso nel processo decisionale condiviso; una buona conoscenza della modalit\u00e0 d&#8217;azione e dei potenziali effetti avversi \u00e8 un prerequisito.<\/li>\n<li>Gli antipsicotici di terza generazione (aripiprazolo, brexpiprazolo e cariprazina) sono un passo importante nella giusta direzione.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Ulteriori letture:<\/p>\n<ul>\n<li>Citrome L: Psichiatria attuale, 17(4), aprile 2018<\/li>\n<li>Eich PH, Nick B: Numero speciale &#8220;Schizofrenia&#8221;, Therapeutische Umschau, 01\/2018.<\/li>\n<li>Kaiser ST, et al: Raccomandazioni di trattamento SGPP per la schizofrenia, versione febbraio 2016; www.psychiatrie.ch\/sgpp\/fachleute-und-kommissionen<\/li>\n<li>Kaiser ST, et al: Raccomandazioni di trattamento SGPP per la schizofrenia, Swiss Med Forum 2018; 18(25): 532-539.<\/li>\n<li>Taylor D, et al: The Maudsley Prescribing Guidelines in Psychiatry 13th edition, Wiley Blackwell, 2018.<\/li>\n<li>Nomenclatura basata sulle neuroscienze (NbN-2R), pubblicato da ECNP, 2018.<\/li>\n<li>Falkai P, Wittchen HU: Diagnostisches und Statistisches Manual Psychischer St\u00f6rungen DSM-5, APA, 2013; Hogrefe 2015<\/li>\n<li>Kaplan &amp; Sadock&#8217;s Synopsis of Psychiatry, 11\u00aa edizione, Wolters Kluwer, 2015.<\/li>\n<li>M\u00f6ller HJ, Laux G, Deister A: Psichiatria, psicosomatica e psicoterapia, 6a edizione, Thieme Verlag, 2015.<\/li>\n<li>Stahl ST: Essential Psychopharmacology, 4th ed, Cambridge University Press, 2013.<\/li>\n<li>Woggon B: Behandlung mit Psychopharmaka, 3a edizione, Huber Verlag, 2009.<\/li>\n<\/ul>\n<p>\n<em>InFo NEUROLOGIA &amp; PSICHIATRIA 2019; 17(6): 16-21.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli antipsicotici sono il pilastro del trattamento acuto e a lungo termine dei disturbi schizofrenici. Quanto prima inizia il trattamento antipsicotico, tanto maggiore \u00e8 la possibilit\u00e0 di controllare o arrestare&hellip;<\/p>\n","protected":false},"author":7,"featured_media":92525,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Novit\u00e0 nel trattamento della schizofrenia","footnotes":""},"category":[11452,11695,11519,11371,11550],"tags":[26334,26326,11861],"powerkit_post_featured":[],"class_list":["post-334853","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farmacologia-e-tossicologia","category-formazione-con-il-partner","category-formazione-continua","category-neurologia-it","category-rx-it","tag-agonisti-parziali-della-dopamina","tag-neurolettici","tag-schizofrenia","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:48:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":334942,"slug":"semelhancas-e-diferencas-entre-os-agonistas-parciais-da-dopamina","post_title":"Semelhan\u00e7as e diferen\u00e7as entre os agonistas parciais da dopamina","href":"https:\/\/medizinonline.com\/pt-pt\/semelhancas-e-diferencas-entre-os-agonistas-parciais-da-dopamina\/"},"es_ES":{"locale":"es_ES","id":334866,"slug":"similitudes-y-diferencias-entre-los-agonistas-parciales-de-la-dopamina","post_title":"Similitudes y diferencias entre los agonistas parciales de la dopamina","href":"https:\/\/medizinonline.com\/es\/similitudes-y-diferencias-entre-los-agonistas-parciales-de-la-dopamina\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/334853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=334853"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/334853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/92525"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=334853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=334853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=334853"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=334853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}