{"id":335772,"date":"2019-08-29T02:00:00","date_gmt":"2019-08-29T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/ipersensibilita-ai-farmaci-forme-principali-e-segnali-di-allarme\/"},"modified":"2019-08-29T02:00:00","modified_gmt":"2019-08-29T00:00:00","slug":"ipersensibilita-ai-farmaci-forme-principali-e-segnali-di-allarme","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/ipersensibilita-ai-farmaci-forme-principali-e-segnali-di-allarme\/","title":{"rendered":"Ipersensibilit\u00e0 ai farmaci &#8211; forme principali e segnali di allarme"},"content":{"rendered":"<p><strong>Le allergie gravi ai farmaci possono essere potenzialmente pericolose per la vita, quindi la diagnosi e il trattamento precoci sono molto importanti. In molti casi, si tratta di esantemi piuttosto innocui. Nel 2-5% dei casi, tuttavia, sono potenzialmente molto pericolosi. Queste includono la necrolisi epidermica tossica e la sindrome di Stevens-Johnson.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<h2 id=\"allergie-ai-farmaci-suddivisione\">Allergie ai farmaci: suddivisione<\/h2>\n<p>L&#8217;ipersensibilit\u00e0 ai farmaci \u00e8 comune. In molti casi, si tratta di esantemi piuttosto innocui. Nel 2-5% dei casi, tuttavia, sono potenzialmente molto pericolosi. Si fa una distinzione tra reazioni prevedibili, cio\u00e8 indotte farmacologicamente (tipo A), e reazioni imprevedibili, allergiche o pseudo-allergiche (tipo B) distinto. Le reazioni di tipo A rappresentano circa l&#8217;80% di tutti gli effetti collaterali e, a differenza delle reazioni di tipo B, sono dose-dipendenti. Allergico (tipo B) Le reazioni si basano su una risposta immunitaria contro il farmaco in questione. Secondo Coombs e Gells, queste risposte immunitarie sono suddivise in 4 categorie, ognuna delle quali corrisponde a meccanismi diversi (IgE-, cellule T-, complesso immunitario- o recettore IgG-Fc-mediato). Clinicamente, questo si manifesta con quadri molto diversi, che vanno dall&#8217;orticaria e dalla dermatite da contatto alle reazioni anafilattiche e alle reazioni cutanee bollose.&nbsp;  Sebbene alcuni farmaci mostrino un particolare clustering per i tipi di allergia, potenzialmente (quasi) qualsiasi farmaco pu\u00f2 causare un&#8217;allergia.<\/p>\n<h2 id=\"le-piu-importanti-allergie-gravi-ai-farmaci\">Le pi\u00f9 importanti allergie gravi ai farmaci<\/h2>\n<p>Le allergie gravi ai farmaci includono<\/p>\n<ul>\n<li>anafilassi,<\/li>\n<li>La sindrome di Stevens-Johnson (SJS) e la sua variante massima, la necrolisi epidermica tossica (TEN),<\/li>\n<li>Eritema multiforme maggiore e<\/li>\n<li>DRESS (Reazione al farmaco con eosinofilia e sintomi sistemici).<\/li>\n<\/ul>\n<p>Le reazioni &#8220;non gravi&#8221;, che comprendono l&#8217;esantema maculopapulare da farmaco, l&#8217;AGEP (Pustolosi esantematica acuta generalizzata), lo SDRIFE (esantema intertriginoso e flessorio simmetrico correlato al farmaco), non vengono discusse in questa sede.<\/p>\n<h2 id=\"anafilassi\">Anafilassi<\/h2>\n<p>L&#8217;anafilassi \u00e8 una reazione di tipo I, nota anche come reazione di tipo immediato, in cui il farmaco viene riconosciuto dagli anticorpi IgE, provocando un rilascio massiccio di istamina dopo l&#8217;aggancio con i mastociti. I sintomi dell&#8217;anafilassi sono prurito, orticaria, vampate di calore, angioedema (grado I), nausea, vomito, crampi, rinorrea, raucedine e dispnea (grado II), defecazione, edema laringeo, broncospasmo, cianosi e shock (grado III) e arresto respiratorio e circolatorio (grado IV). In genere sono coinvolti 2 o pi\u00f9 sistemi di organi. Questa forma acuta di allergia ai farmaci si sviluppa solitamente entro pochi minuti dall&#8217;ingestione o dalla somministrazione; i fattori scatenanti pi\u00f9 comuni sono gli antibiotici beta-lattamici, i FANS, i miorilassanti o i disinfettanti come la clorexidina.<\/p>\n<p>I segnali di allarme in questo caso sono la comparsa di rantoli, angioedema e\/o sintomi generali da pochi minuti a un massimo di 1-2 ore dopo la somministrazione del farmaco, talvolta associati a prurito palmoplantare e\/o sapore metallico in bocca.<\/p>\n<p>L&#8217;anafilassi richiede un&#8217;azione immediata: La somministrazione orientativa (a seconda della gravit\u00e0) di corticosteroidi, antistaminici e, se necessario, adrenalina; il monitoraggio fino a 8 ore dopo la risoluzione dei sintomi gravi \u00e8 utile e quindi spesso richiede il trattamento e il monitoraggio in ospedale. A causa dell&#8217;acuirsi e del decorso degli eventi che richiedono un trattamento di emergenza immediato, rimandiamo alle istruzioni dettagliate preparate altrove.<\/p>\n<h2 id=\"sindrome-di-stevens-johnson-sjs-necrolisi-epidermica-tossica-ten\">Sindrome di Stevens-Johnson (SJS)\/Necrolisi epidermica tossica (TEN)<\/h2>\n<p>La SJS e la TEN sono reazioni bollose da farmaci, per lo pi\u00f9 con coinvolgimento della mucosa, che si differenziano per la gravit\u00e0, cio\u00e8 per la diffusione alla superficie corporea (&lt;10% nella SJS, &gt;30% nella TEN). Si tratta di reazioni relativamente rare (incidenza di circa 1-2 casi per milione all&#8217;anno), ma associate a una morbilit\u00e0 e a una mortalit\u00e0 molto elevate.&nbsp;  A differenza dell&#8217;anafilassi, la SJS\/TEN sono di tipo IV,&nbsp; le cosiddette reazioni di tipo tardivo, in cui la reazione allergica non \u00e8 mediata dagli anticorpi ma dalle cellule T (principalmente citotossiche). Dal punto di vista clinico, ci\u00f2 significa che prima deve verificarsi una sensibilizzazione, cio\u00e8 i sintomi possono svilupparsi entro 7-21 giorni con l&#8217;esposizione iniziale, e prima con la riesposizione. I fattori scatenanti pi\u00f9 importanti sono i sulfonamidi, l&#8217;allopurinolo, le tetracicline, gli anticonvulsivanti e i FANS.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-12266\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10.jpg\" style=\"height:600px; width:600px\" width=\"1100\" height=\"1100\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10-800x800.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10-80x80.jpg 80w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10-120x120.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10-90x90.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10-320x320.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/abb1_dp4_s10-560x560.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Sulla pelle si forma un esantema maculare, eritematoso e livido, insieme a vesciche rigonfie o a un distacco della pelle, che pu\u00f2 progredire molto rapidamente (in poche ore).  <strong>(Fig.1A). <\/strong>Le vesciche di solito colpiscono anche le membrane mucose (congiuntive, enorali, genitali), che si manifestano sotto forma di disfagia, bruciore agli occhi e bruciore genitale. Un bruciore\/dolore diffuso sulla pelle \u00e8 spesso descritto dai pazienti SJS\/TEN anche prima della formazione delle vesciche. Nella maggior parte dei casi, i pazienti sono in condizioni generali ridotte. Le complicanze acute pi\u00f9 temute sono la sepsi causata dalla superinfezione e la destabilizzazione emodinamica. In un massimo del 30% dei pazienti, il decorso della malattia \u00e8 letale. La diagnosi si basa sulla clinica, sull&#8217;anamnesi e sull&#8217;istologia.<\/p>\n<p>A causa della rarit\u00e0 della SJS\/TEN, \u00e8 molto difficile condurre studi di ricerca traslazionale e studi clinici con una potenza sufficiente. Tuttavia, sono indispensabili a causa della potenziale letalit\u00e0 delle reazioni e delle molte domande aperte in questo campo. Il team del Dipartimento di Dermatologia dell&#8217;Ospedale Universitario di Zurigo, insieme ai colleghi di Francia, Stati Uniti e Giappone, ha quindi istituito un registro internazionale per la documentazione accurata e standardizzata e la raccolta di tessuti dei casi di SJS\/TEN in tutto il mondo (www.irten.org). Il nostro obiettivo \u00e8 quello di contribuire a una migliore comprensione dei meccanismi patologici e del potenziale trattamento della SJS\/TEN e dei suoi effetti tardivi.<\/p>\n<h2 id=\"eritema-essudativo-maggiore-eem-maggiore\">Eritema essudativo maggiore (EEM maggiore)<\/h2>\n<p>Sebbene la demarcazione dall&#8217;SJS\/TEN sia ancora contestata, l&#8217;EEM \u00e8 considerata un&#8217;entit\u00e0 separata. L&#8217;EEM \u00e8 meno pericoloso rispetto alla SJS\/TEN, ma pu\u00f2 comunque essere molto pronunciato sulla pelle. Viene discussa una reazione sottostante di tipo IV (cellule T). L&#8217;EEM \u00e8 spesso accompagnato da un&#8217;infezione, in particolare dall&#8217;herpes simplex. Le caratteristiche cliniche sono lesioni simili a quelle di un gatto<strong> (Fig.&nbsp;1C)<\/strong> con una struttura zonale, cio\u00e8 un centro livido, una zona centrale rientrante e un bordo eritematoso <strong>(Fig.&nbsp;1C) <\/strong>. La diagnosi di EEM si basa sulla clinica, sull&#8217;anamnesi e, se necessario, sull&#8217;istologia e, soprattutto, sugli strisci virali.<\/p>\n<p>La variante minore dell&#8217;EEM (senza coinvolgimento della mucosa) deve essere distinta dall&#8217;EEM maggiore, che spesso si verifica nel contesto di un&#8217;infezione da herpes o di altre condizioni parainfettive e solo raramente \u00e8 causata dai farmaci.<\/p>\n<h2 id=\"reazione-da-farmaco-con-eosinofilia-e-sintomi-sistemici-dress\">Reazione da farmaco con eosinofilia e sintomi sistemici &#8211; DRESS<\/h2>\n<p>Un&#8217;entit\u00e0 relativamente nuova tra le allergie gravi ai farmaci \u00e8 la cosiddetta DRESS, originariamente chiamata anche sindrome di ipersensibilit\u00e0 alla carbamazepina-fenitoina<strong> (Fig.&nbsp;1B)<\/strong>. La DRESS \u00e8 una reazione di tipo IV causata principalmente dalle cellule T-helper, che di solito \u00e8 accompagnata da un ulteriore &#8220;segnale di pericolo&#8221;, di solito sotto forma di riattivazione di virus (soprattutto HHV6). In termini di decorso temporale, la DRESS \u00e8 caratterizzata dal fatto che di solito si sviluppa da settimane a mesi dopo l&#8217;inizio della terapia. La DRESS \u00e8 stata descritta pi\u00f9 frequentemente con gli anticonvulsivanti (soprattutto carbamazepina e fenitoina), ma anche con dapsone (sulfonamidi), barbiturici e vemurafenib\/cobimetinib. Le manifestazioni cliniche della DRESS sono molto eterogenee e vanno dall&#8217;esantema maculare, alle pustole, all&#8217;eritroderma fino alle vesciche (la cosiddetta DRESS simile alla TEN). Diagnosticamente rilevante \u00e8 l&#8217;associazione con gonfiore del viso, gonfiore dei linfonodi e febbre. La DRESS \u00e8 pericolosa a causa del coinvolgimento degli organi, che pu\u00f2 portare all&#8217;insufficienza degli organi e alla morte: L&#8217;epatite \u00e8 la pi\u00f9 comune, ma possono verificarsi anche miocardite, nefropatia, coinvolgimento del SNC e dell&#8217;apparato gastrointestinale.<\/p>\n<p>La diagnosi di DRESS si basa su una combinazione di criteri clinici (esantema, gonfiore del viso, gonfiore dei linfonodi, febbre) e sui risultati di laboratorio di eosinofilia (&gt;12%), linfociti atipici e parametri di laboratorio che suggeriscono un coinvolgimento degli organi, in particolare un aumento di AST\/ALT e un aumento della creatinina (e un eGFR ridotto).<\/p>\n<h2 id=\"i-segnali-di-allarme-piu-importanti-nella-clinica\">I segnali di allarme pi\u00f9 importanti nella clinica<\/h2>\n<p>Il riconoscimento dei segnali di allarme nelle allergie ai farmaci \u00e8 molto importante dal punto di vista clinico, in quanto il riconoscimento precoce e il conseguente trattamento adeguato sono di grande importanza prognostica, cio\u00e8 possono prevenire danni agli organi e un decorso potenzialmente letale. La distinzione tra reazioni allergiche innocue e gravi ai farmaci pu\u00f2 essere difficile anche per un occhio esperto. Ci\u00f2 rende ancora pi\u00f9 importante affrontare alcuni indizi clinici e anamnestici in questi pazienti <strong>(Tab.&nbsp;1, Tab.&nbsp;2).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12267 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10.png\" style=\"--smush-placeholder-width: 882px; --smush-placeholder-aspect-ratio: 882\/1469;height:666px; width:400px\" width=\"882\" height=\"1469\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10.png 882w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10-800x1332.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10-120x200.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10-90x150.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10-320x533.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab1_dp4_s10-560x933.png 560w\" data-sizes=\"(max-width: 882px) 100vw, 882px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La questione delle vesciche e del coinvolgimento della mucosa dovrebbe essere una parte centrale dell&#8217;anamnesi. Anche il bruciore della pelle, degli occhi, della mucosa orale e genitale e la disfagia devono essere richiesti esplicitamente. Questi sintomi forniscono indizi importanti sul coinvolgimento della mucosa.&nbsp;  Soprattutto il bruciore o il dolore della pelle \u00e8 tipico della SJS\/TEN, ma chiaramente meno osservato con il &#8220;banale&#8221; eczema da farmaci. Anche la questione dell&#8217;insorgenza e della diffusione delle alterazioni cutanee \u00e8 un indizio importante, poich\u00e9 la progressione pu\u00f2 essere molto rapida, soprattutto nella SJS\/TEN. Chiedere i tempi del precedente utilizzo di farmaci \u00e8 importante per identificare i potenziali fattori scatenanti e i &#8220;farmaci a rischio&#8221; (1. Cosa esattamente, 2. Da quando o fino a quando) e per restringere le reazioni. \u00c8 anche importante chiedere informazioni sull&#8217;esposizione precedente e sui sintomi di allora, poich\u00e9 le reazioni possono essere pi\u00f9 gravi e rapide con una nuova esposizione.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12268 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/558;height:304px; width:600px\" width=\"1100\" height=\"558\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11-800x406.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11-120x61.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11-90x46.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11-320x162.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/08\/tab2_dp4_s11-560x284.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>In base ai punti descritti sopra, occorre determinare clinicamente i segni vitali, esaminare l&#8217;intera pelle e le membrane mucose e palpare i linfonodi. Nello stato dermatologico, deve essere verificato anche il cosiddetto segno di Nikolski: Questo viene verificato applicando una pressione laterale con il dito sulla pelle non colpita (senza vesciche) per vedere se la pelle \u00e8 staccata (segno di Nikolski). I) e se una vescica esistente pu\u00f2 essere spostata applicando una pressione (Nikolski II). Anche uno stato interno incl. \u00c8 necessario determinare i segni vitali. Occorre prestare particolare attenzione all&#8217;interessamento della mucosa, alle vesciche (e al segno di Nikolski positivo), al gonfiore dei linfonodi e del viso, nonch\u00e9 alla febbre e ai segni vitali anomali, come gi\u00e0 detto.<\/p>\n<p>La chimica di laboratorio deve includere un emocromo. differenziazione manuale: Questo \u00e8 importante perch\u00e9 un&#8217;eosinofilia pronunciata \u00e8 una &#8220;bandiera rossa&#8221; e indica una reazione grave e, a seconda della sua gravit\u00e0, comporta il rischio di gravi danni agli organi, come la miocardite eosinofila potenzialmente letale. I linfociti atipici sono un altro segnale per la diagnosi di DRESS. Si deve anche determinare la CRP. Per quanto riguarda il potenziale danno d&#8217;organo (soprattutto nel DRESS), i valori epatici (AST, ALT, bilirubina) e renali (creatinina, eGFR) devono essere determinati come primo passo.<\/p>\n<h2 id=\"sospetto-di-una-grave-allergia-ai-farmaci-cosa-fare\">Sospetto di una grave allergia ai farmaci: cosa fare?<\/h2>\n<p>Se si sospetta una grave allergia ai farmaci, \u00e8 necessario contattare immediatamente il servizio di dermatologia di un centro ospedaliero per coordinare l&#8217;ulteriore corso d&#8217;azione: Dal punto di vista terapeutico, \u00e8 molto importante interrompere\/sostituire immediatamente i probabili fattori scatenanti (e le sostanze a reazione incrociata), tenendo conto o coprendo l&#8217;indicazione primaria, ovviamente. Ulteriori diagnosi (biopsia, emocolture, striscio, ecc.), la terapia e il trasferimento del paziente devono essere avviati immediatamente, come concordato, poich\u00e9 un ritardo pu\u00f2 avere conseguenze prognostiche.<\/p>\n<p>Anche in assenza di segnali di allarme, il potenziale fattore scatenante deve essere interrotto\/sostituito (a meno che non vi sia un&#8217;indicazione vitale) e si deve consultare direttamente un dermatologo.<\/p>\n<h2 id=\"allergie-gravi-ai-farmaci-trattamento-acuto-e-di-follow-up\">Allergie gravi ai farmaci:<strong> <\/strong>Trattamento acuto e di follow-up<\/h2>\n<p>Il trattamento acuto dei pazienti con TEN e, a seconda della gravit\u00e0, con DRESS viene effettuato nel reparto di terapia intensiva (ustioni) da un team interdisciplinare. Nella SJS\/TEN, viene somministrata la &#8220;migliore terapia di supporto&#8221; per il trattamento della ferita, la prevenzione della superinfezione e la stabilizzazione emodinamica, oltre al trattamento adiuvante (ad esempio con immunoglobuline per via endovenosa, inibitori del TNF-alfa o ciclosporina). Nella DRESS, glucocorticosteroidi ad alto dosaggio (oltre al trattamento sintomatico). L&#8217;EEM major viene trattato anche con glucocorticosteroidi sistemici.<\/p>\n<p>Il work-up allergologico in tutti i pazienti con St. n. Le allergie gravi ai farmaci vengono idealmente eseguite non prima di 4-6 settimane e fino a 6 mesi dopo la risoluzione e comprendono test sierologici (sierologie, test di trasformazione dei linfociti, test di attivazione dei basofili) e\/o test cutanei (prick, test intracutanei ed epicutanei, a volte con lettura tardiva dopo 24-48 ore) a seconda del tipo di reazione.<\/p>\n<p>Anche il follow-up del paziente dovrebbe essere una priorit\u00e0 elevata e coinvolgere team di diverse discipline. Nei pazienti DRESS, il trattamento deve essere interrotto gradualmente per un lungo periodo di tempo e con controlli adeguati, altrimenti la malattia si riacutizzer\u00e0. In particolare, i pazienti colpiti da SJS o TEN soffrono non solo del decorso estremamente grave e potenzialmente letale della malattia, ma anche degli effetti tardivi, talvolta gravi e spesso molto limitanti. Oltre all&#8217;iper- e all&#8217;ipopigmentazione, alla cicatrizzazione delle sclere o nell&#8217;area genitale, spesso sono presenti anche sequele psichiatriche, soprattutto sotto forma di malattia da stress post-traumatico (PTSD).<\/p>\n<h2 id=\"messaggi-da-portare-a-casa\">Messaggi da portare a casa<\/h2>\n<ul>\n<li>Le allergie gravi ai farmaci includono: Anafilassi (reazione di tipo 1), SJS \/ TEN, DRESS, EEM maggiore<\/li>\n<li>Le allergie gravi ai farmaci possono essere potenzialmente pericolose per la vita, quindi la diagnosi e il trattamento precoce sono molto importanti.<\/li>\n<li>I segnali clinici di allarme pi\u00f9 importanti sono vesciche, coinvolgimento della mucosa, espressione estesa, gonfiore del viso e dei linfonodi, riduzione dell&#8217;AZ e segni vitali anomali.<\/li>\n<li>Un laboratorio iniziale dovrebbe includere un emocromo con differenziazione microscopica, enzimi epatici e renali e CRP.<\/li>\n<li>A Vd.a. allergia grave ai farmaci: contatti immediatamente la dermatologia di un centro ospedaliero, in caso di TEN contatti un centro con un&#8217;unit\u00e0 di terapia intensiva per le ustioni.<\/li>\n<\/ul>\n<p>\nUlteriori letture:<\/p>\n<ul>\n<li>Mockenhaupt M: 2014. Sindrome di Stevens-Johnson e necrolisi epidermica tossica: modelli clinici, considerazioni diagnostiche, eziologia e gestione terapeutica. Semin Cutan Med Surg 33: 10-16.<\/li>\n<li>Deuel J, Schaer D, Schmid-Grendelmeier P, Vallelian F: [ECM. Grave reazione cutanea ai farmaci]. Practice 2014; 15; 103(21): 1231-1243.<\/li>\n<li>Leaute-Labreze C, Lamireau T, Chawki D, et al: 2000. Diagnosi, classificazione e gestione dell&#8217;eritema multiforme e della sindrome di Stevens-Johnson. Arch Dis Child 83: 347-352.<\/li>\n<li>Illing PT, Vivian JP, Dudek NL, et al.: 2012. Auto-reattivit\u00e0 immunitaria innescata dal repertorio HLA-peptidico modificato dai farmaci. Natura 486: 554-558.<\/li>\n<li>Nassif A, Bensussan A, Boumsell L, et al.: 2004. Necrolisi epidermica tossica: le cellule effettrici sono cellule T citotossiche specifiche per il farmaco. J Allergy Clin Immunol 114: 1209-1215.<\/li>\n<li>Viard I, Wehrli P, Bullani R, et al.: 1998. Inibizione della necrolisi epidermica tossica mediante blocco di CD95 con immunoglobulina umana per via endovenosa. Scienza 282: 490-493.<\/li>\n<li>Kardaun SH, Jonkman MF: 2007. Terapia a impulsi con desametasone per la sindrome di Stevens-Johnson\/necrolisi epidermica tossica. Acta Derm Venereol 87: 144-148.<\/li>\n<li>Brockow K1, Pf\u00fctzner W2: Ipersensibilit\u00e0 cutanea ai farmaci: sviluppi e controversie. Curr Opin Allergy Clin Immunol. 2019 May 22. doi: 10.1097\/ACI.0000000000000548.  [Epub ahead of print]<\/li>\n<li>Pichler WJ. Patomeccanismo immunitario e classificazione dell&#8217;ipersensibilit\u00e0 ai farmaci. Allergia. 2019 Mar 6. doi: 10.1111\/all.13765<\/li>\n<li>Phillips EJ, Bigliardi P, Bircher AJ, et al: Controversie nell&#8217;allergia ai farmaci: test per le reazioni ritardate. J Allergy Clin Immunol. 2019 Jan;143(1): 66-73.<\/li>\n<li>www.ck-care.ch\/documents\/10181\/14458\/Anaphylaxis_HandelnimNotfall_20180908.pdf\/58b48ad9-7c7e-4171-b090-48fa41ceb115 und www.ck-care.ch\/documents\/10181\/14458\/Anaphylaxie_NFP_KinderJugendliche_20190117_1.pdf\/02705bda-e424-4241-9e14-d0a648450c09).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>PRATICA DERMATOLOGICA 2019; 29(4): 8-12<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le allergie gravi ai farmaci possono essere potenzialmente pericolose per la vita, quindi la diagnosi e il trattamento precoci sono molto importanti. In molti casi, si tratta di esantemi piuttosto&hellip;<\/p>\n","protected":false},"author":7,"featured_media":90763,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Segnali di allarme per le allergie ai farmaci","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11343,11452,11519,11550],"tags":[25156,28034,28039,28042,28040,28033,28035,28038,28043,28041,28036,28037],"powerkit_post_featured":[],"class_list":["post-335772","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allergologia-e-immunologia-clinica","category-farmacologia-e-tossicologia","category-formazione-continua","category-rx-it","tag-abito","tag-allergie-ai-farmaci","tag-dieci","tag-eritema-essudativo-maggiore","tag-eritema-multiforme-maggiore","tag-esantema","tag-in-pericolo-di-vita","tag-necrolisi-epidermica-tossica","tag-principale-eem","tag-reazione-al-farmaco-con-eosinofilia-e-sintomi-sistemici","tag-sindrome-di-stevens-johnson","tag-sjs-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:15:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":335729,"slug":"hipersensibilidades-aos-medicamentos-principais-formas-e-sinais-de-aviso","post_title":"Hipersensibilidades aos medicamentos - principais formas e sinais de aviso","href":"https:\/\/medizinonline.com\/pt-pt\/hipersensibilidades-aos-medicamentos-principais-formas-e-sinais-de-aviso\/"},"es_ES":{"locale":"es_ES","id":335755,"slug":"hipersensibilidad-a-los-medicamentos-principales-formas-y-signos-de-alerta","post_title":"Hipersensibilidad a los medicamentos: principales formas y signos de alerta","href":"https:\/\/medizinonline.com\/es\/hipersensibilidad-a-los-medicamentos-principales-formas-y-signos-de-alerta\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/335772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=335772"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/335772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/90763"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=335772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=335772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=335772"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=335772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}