{"id":336667,"date":"2019-02-22T01:00:00","date_gmt":"2019-02-22T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/sono-possibili-buoni-effetti-sul-tasso-di-esacerbazione\/"},"modified":"2019-02-22T01:00:00","modified_gmt":"2019-02-22T00:00:00","slug":"sono-possibili-buoni-effetti-sul-tasso-di-esacerbazione","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/sono-possibili-buoni-effetti-sul-tasso-di-esacerbazione\/","title":{"rendered":"Sono possibili buoni effetti sul tasso di esacerbazione"},"content":{"rendered":"<p><strong>La carenza di vitamina D sembra essere collegata a una prognosi sfavorevole in un&#8217;intera gamma di malattie. Al contrario, una serie di effetti benefici sono attribuiti alla sostituzione, che sembra avere anche un effetto positivo in relazione alla prevenzione delle esacerbazioni nella BPCO.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La revisione sistematica e la meta-analisi [1] hanno riassunto i pazienti di quattro studi controllati randomizzati (RCT) (n=560) che avevano ricevuto la vitamina D3 orale rispetto al placebo. I pazienti sono stati valutati per il tasso di esacerbazioni da moderate a gravi.<\/p>\n<p>Il risultato \u00e8 stato presentato dal Professor Dr. Claus Vogelmeier, Clinica di Medicina Interna, Focus Pneumologia, Ospedale Universitario di Giessen e Marburgo, in occasione del Pneumo-Update a Mainz (D): Valutando la popolazione totale, il rapporto di tasso di esacerbazioni moderate\/severe della BPCO \u00e8 stato di 0,94 nel gruppo di intervento. Pertanto, non \u00e8 stato possibile rilevare alcun effetto rilevante della sostituzione. Tuttavia, quando i pazienti sono stati suddivisi in base ai loro livelli di vitamina D, si \u00e8 visto un chiaro segnale nel sottogruppo con livelli basali bassi di vitamina D: gli effetti protettivi erano rilevabili nei partecipanti con un livello basale misurato di vitamina D &lt;25&nbsp;nmol\/l (RR aggiustato 0,55). Tuttavia, questo effetto non \u00e8 stato osservato con livelli di vitamina D di almeno 25&nbsp;nmol\/l (RR aggiustato 1,04) <strong>(Fig. 1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-13060\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/02\/abb1_pa3_s36.png\" style=\"height:307px; width:600px\" width=\"1100\" height=\"563\"><\/p>\n<p>&nbsp;<\/p>\n<p>Quindi, in presenza di livelli ridotti di vitamina D, la sostituzione pu\u00f2 avere effetti benefici significativi sul tasso di esacerbazione. Si dovrebbe quindi considerare per il futuro se la somministrazione del farmaco possa essere utilizzata anche come misura preventiva nei pazienti con esacerbazioni ricorrenti.<\/p>\n<h2 id=\"conclusione\">Conclusione<\/h2>\n<ul>\n<li>La sostituzione della vitamina D deve essere presa in considerazione nei pazienti con esacerbazioni ricorrenti e bassi livelli ematici.<\/li>\n<li>La terapia \u00e8 economica e sicura.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Jolliffe DA, et al: La vitamina D per prevenire le esacerbazioni della BPCO. Thorax 2019; 74: 337-345.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo PNEUMOLOGIA &amp; ALLERGOLOGIA 2019; 1(3): 36<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carenza di vitamina D sembra essere collegata a una prognosi sfavorevole in un&#8217;intera gamma di malattie. Al contrario, una serie di effetti benefici sono attribuiti alla sostituzione, che sembra&hellip;<\/p>\n","protected":false},"author":7,"featured_media":93818,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"La vitamina D nella BPCO","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11468,11550,11515],"tags":[],"powerkit_post_featured":[],"class_list":["post-336667","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-pneumologia","category-rx-it","category-studi","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:27:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":336677,"slug":"possibilidade-de-bons-efeitos-na-taxa-de-exacerbacao","post_title":"Possibilidade de bons efeitos na taxa de exacerba\u00e7\u00e3o","href":"https:\/\/medizinonline.com\/pt-pt\/possibilidade-de-bons-efeitos-na-taxa-de-exacerbacao\/"},"es_ES":{"locale":"es_ES","id":336643,"slug":"posibles-buenos-efectos-sobre-la-tasa-de-exacerbacion","post_title":"Posibles buenos efectos sobre la tasa de exacerbaci\u00f3n","href":"https:\/\/medizinonline.com\/es\/posibles-buenos-efectos-sobre-la-tasa-de-exacerbacion\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/336667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=336667"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/336667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/93818"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=336667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=336667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=336667"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=336667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}