{"id":338305,"date":"2018-03-22T01:00:00","date_gmt":"2018-03-22T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/piu-raro-ma-piu-aggressivo-dei-melanomi-cutanei\/"},"modified":"2018-03-22T01:00:00","modified_gmt":"2018-03-22T00:00:00","slug":"piu-raro-ma-piu-aggressivo-dei-melanomi-cutanei","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/piu-raro-ma-piu-aggressivo-dei-melanomi-cutanei\/","title":{"rendered":"Pi\u00f9 raro, ma pi\u00f9 aggressivo dei melanomi cutanei."},"content":{"rendered":"<p><strong>Il melanoma mucoso primario della testa e del collo \u00e8 raro. Tuttavia, si comporta in modo molto pi\u00f9 aggressivo rispetto al melanoma cutaneo maligno. I sintomi principali corrispondenti dovrebbero essere il motivo di un rapido chiarimento da parte di un otorino.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>I melanomi della mucosa sono rari e rappresentano l&#8217;1% di tutti i melanomi maligni. La met\u00e0 di questi si trova nella zona della testa e del collo. Rispetto ai melanomi maligni cutanei, mostrano un comportamento molto pi\u00f9 aggressivo e sono pi\u00f9 inclini alle metastasi regionali e a distanza. Sono frequenti anche le recidive locali, che portano a un aumento del tasso di mortalit\u00e0 specifica della malattia.<\/p>\n<p>Il picco di incidenza di questi melanomi \u00e8 tra i 60 e gli 80 anni&nbsp;. Sembra esserci una leggera dominanza maschile nella distribuzione dei sessi. A causa della loro localizzazione nascosta, i melanomi mucosi della regione della testa e del collo vengono spesso diagnosticati solo in uno stadio locoregionale avanzato. Le metastasi linfonodali si trovano nel 5-48% dei pazienti al momento della diagnosi e le metastasi a distanza nel 4-14%. La cavit\u00e0 nasale \u00e8 la regione pi\u00f9 frequentemente colpita. In questo caso, i melanomi sono localizzati soprattutto nella parte anteriore del naso, seguiti dai turbinati medi e inferiori. Un melanoma nell&#8217;area della conca nasale superiore, del solco olfattivo o dell&#8217;etmoide \u00e8 una rarit\u00e0 assoluta. Nella cavit\u00e0 orale, le aree pi\u00f9 comunemente colpite sono il palato e la gengiva. Molto raramente, il melanoma mucoso pu\u00f2 essere riscontrato nella faringe, nella laringe o nell&#8217;esofago superiore. La posizione pi\u00f9 comune nella laringe \u00e8 la regione sopraglottica.<\/p>\n<p>L&#8217;aspetto del tumore varia e va da maculare a ulcerato o da nodulare a polipo. Il colore varia dal nero al grigio o dal rosa al rosso. Una forte pigmentazione si verifica in circa il 75% dei melanomi orali, ma solo nel 50% dei melanomi sinunali. A differenza del melanoma cutaneo, il melanoma mucoso della testa e del collo si presenta tipicamente al momento della diagnosi in una fase di crescita verticale pi\u00f9 aggressiva con invasione della sottomucosa sottostante. Di conseguenza, spesso manca l&#8217;estensione orizzontale superficiale di accompagnamento.<\/p>\n<p>La maggior parte dei pazienti con melanoma mucoso sinunasale presenta un&#8217;ostruzione nasale unilaterale, una massa tumorale, epistassi o una combinazione di sintomi <strong>(Fig.&nbsp;1)<\/strong>. Rinorrea, epifora, dolore facciale e gonfiore sono pi\u00f9 comuni nei casi avanzati. La presentazione clinica predominante dei tumori del cavo orale \u00e8 una massa indolore. Spesso possono essere presenti ulcerazioni ed emorragie.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9862\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/03\/abb1-oh1_s21.jpg\" style=\"height:419px; width:400px\" width=\"919\" height=\"963\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"diagnostica\">Diagnostica<\/h2>\n<p>La presenza di una lesione pigmentata nella cavit\u00e0 orale o nasale deve far sorgere il sospetto di un melanoma mucoso e una biopsia della lesione deve essere eseguita tempestivamente <strong>(Fig.&nbsp;2) <\/strong>. La diagnosi dipende dall&#8217;identificazione della melanina intracellulare. Tuttavia, l&#8217;immunoistochimica \u00e8 spesso necessaria per diagnosticare il melanoma maligno, poich\u00e9 solo il 50-70% delle lesioni nella cavit\u00e0 orale presenta melanina. I melanomi mostrano un&#8217;elevata positivit\u00e0 del marcatore immunitario S-100, una proteina legante il calcio che si trova nei tessuti neurali. Tuttavia, questa proteina \u00e8 presente in una variet\u00e0 di cellule normali e neoplastiche. La frequenza dell&#8217;immunoreattivit\u00e0 S-100 nei melanomi mucosi varia dall&#8217;86 al 100%. Un antigene reattivo pi\u00f9 specifico per le cellule di melanoma \u00e8 l&#8217;HBM-45 (antigene citoplasmatico del melanoma). Il melanoma risponde anche agli anticorpi antivimentina e NK1\/C-3, ma non agli anticorpi anti-cheratina o anti-ileucociti.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9863 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/03\/abb2_oh1_s21.jpg\" style=\"--smush-placeholder-width: 897px; --smush-placeholder-aspect-ratio: 897\/1026;height:458px; width:400px\" width=\"897\" height=\"1026\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"stabilizzazione\">Stabilizzazione<\/h2>\n<p>Non esiste un sistema di stadiazione generalmente accettato per il melanoma della mucosa della testa e del collo. La classica classificazione TNM \u00e8 comunque frequentemente utilizzata. A causa della mancanza di punti di riferimento istologici analoghi al derma papillare e reticolare, il valore prognostico dei diversi livelli di invasione, come stabilito nella classificazione di Clark per il melanoma cutaneo, non si applica al melanoma mucinoso. Pertanto, spesso si distinguono le seguenti tre fasi:<\/p>\n<ul>\n<li>Stadio I: malattia localizzata<\/li>\n<li>Stadio II: metastasi linfonodali regionali<\/li>\n<li>Stadio III: metastasi a distanza.<\/li>\n<\/ul>\n<h2 id=\"imaging\">Imaging<\/h2>\n<p>La risonanza magnetica \u00e8 significativamente pi\u00f9 specifica della tomografia computerizzata per la diagnosi di melanomi maligni. Ci\u00f2 \u00e8 dovuto alle propriet\u00e0 paramagnetiche della melanina. Spesso, la diagnosi deve essere integrata dalla tomografia computerizzata per valutare la possibile invasione delle strutture ossee <strong>(Fig.&nbsp;3).<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9864 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/03\/abb3_oh1_s22.jpg\" style=\"--smush-placeholder-width: 915px; --smush-placeholder-aspect-ratio: 915\/894;height:391px; width:400px\" width=\"915\" height=\"894\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>\nPoich\u00e9 il melanoma mucoso metastatizza precocemente, indipendentemente dalle dimensioni del tumore primario, l&#8217;esame PET\/CT dell&#8217;intero corpo \u00e8 importante per una stadiazione pi\u00f9 accurata del tumore.<\/p>\n<h2 id=\"terapia-chirurgica\">Terapia chirurgica<\/h2>\n<p>Il trattamento di prima linea per il melanoma mucoso \u00e8 simile a quello per il melanoma cutaneo e prevede l&#8217;escissione completa con un margine di sicurezza sufficiente. A causa della stretta vicinanza della regione della testa e del collo alle strutture anatomiche rilevanti circostanti, i margini chirurgici positivi non sono rari. Tuttavia, un approccio chirurgico radicale dovrebbe essere perseguito a condizione che ci sia una resecabilit\u00e0 topografica completa e che la morbilit\u00e0 associata sia accettabile. Se sono presenti metastasi linfonodali regionali, \u00e8 indicata la dissezione del collo. D&#8217;altra parte, la rilevanza di una dissezione elettiva del collo nel caso di un tumore localizzato \u00e8 ancora discutibile. Il dibattito sull&#8217;importanza dell&#8217;escissione del linfonodo sentinella rimane controverso. Questo rispetto al melanoma cutaneo, dove questa tecnica sta guadagnando sempre pi\u00f9 consenso.<\/p>\n<h2 id=\"radioterapia\">Radioterapia<\/h2>\n<p>Il ruolo della radioterapia nel trattamento del melanoma mucoso non \u00e8 chiaramente definito. Il melanoma maligno \u00e8 stato tradizionalmente considerato relativamente insensibile alle radiazioni, ma alcuni studi hanno dimostrato un beneficio positivo. Un&#8217;ampia serie di prove cliniche e di scienza di base sostiene la teoria che il melanoma ha un&#8217;elevata capacit\u00e0 di riparazione dei danni subletali, che lo rende resistente alle tecniche di frazionamento convenzionali.<\/p>\n<p>Pertanto, il trattamento con dosi pi\u00f9 elevate sembra spesso pi\u00f9 efficace. La radioterapia viene solitamente utilizzata come misura adiuvante, soprattutto in caso di margini di resezione positivi, recidive locali o nella palliazione. Diverse analisi di studi non sono ancora state in grado di confermare che la chirurgia con radioterapia aggiuntiva migliori significativamente la sopravvivenza globale del paziente. Nonostante la mancanza di significativit\u00e0, in alcuni studi i pazienti con terapia combinata hanno avuto il tempo di sopravvivenza pi\u00f9 lungo. D&#8217;altra parte, \u00e8 stato dimostrato che l&#8217;aggiunta della radioterapia riduce il tasso di recidiva locale.<\/p>\n<h2 id=\"chemioterapia-e-immunoterapia\">Chemioterapia e immunoterapia<\/h2>\n<p>La chemioterapia e\/o l&#8217;immunoterapia sono utilizzate sia nel contesto adiuvante che con intento palliativo. Gli agenti chemioterapici pi\u00f9 comunemente utilizzati sono la dacarbazina, gli analoghi del platino, le nitrosouree e le tossine microtubulari.<\/p>\n<p>L&#8217;immunoterapia \u00e8 attualmente efficace solo in una piccola percentuale di pazienti con melanoma maligno. \u00c8 stato osservato un aumento del tasso di risposta quando l&#8217;interleuchina 2 (IL-2) e l&#8217;interferone alfa (IFN-\u03b1) sono stati utilizzati con il cisplatino.<\/p>\n<h2 id=\"previsioni\">Previsioni<\/h2>\n<p>La maggior parte delle recidive si verifica entro i primi tre anni. La recidiva primaria si verifica in circa il 40% delle lesioni della cavit\u00e0 nasale, nel 25% delle lesioni della cavit\u00e0 orale e nel 32% delle lesioni faringee.<\/p>\n<p>Secondo uno studio del Memorial Sloan Kettering Cancer Center, lo stadio clinico alla presentazione, lo spessore del tumore &gt;5&nbsp;mm, l&#8217;invasione vascolare all&#8217;esame istologico e lo sviluppo di metastasi a distanza sono gli unici predittori indipendenti di sopravvivenza globale. L&#8217;importanza prognostica delle metastasi ai linfonodi cervicali o nucali non \u00e8 ancora chiara. Alcuni studi hanno dimostrato che il coinvolgimento linfonodale riduce il tempo di sopravvivenza mediano a 18&nbsp;mesi. Altri studi, tuttavia, non hanno mostrato alcuno svantaggio in termini di sopravvivenza nei pazienti con linfonodi regionali positivi rispetto a quelli con una situazione N0.<\/p>\n<p>Istologicamente, l&#8217;invasione della lamina propria e dei tessuti pi\u00f9 profondi \u00e8 un fattore prognostico negativo. Allo stesso modo, la presenza di strutture sarcomatoidi, pseudopapillari e di cellule indifferenziate sembra essere associata a una minore sopravvivenza specifica della malattia.<\/p>\n<h2 id=\"messaggi-da-portare-a-casa\">Messaggi da portare a casa<\/h2>\n<ul>\n<li>Il melanoma mucoso primario della testa e del collo \u00e8 un&#8217;entit\u00e0 clinica rara, ma si comporta in modo molto pi\u00f9 aggressivo rispetto ai melanomi maligni cutanei.<\/li>\n<li>La comparsa di sintomi di primo piano, come il mal di gola persistente, il gonfiore alla gola o il fastidio nasale unilaterale, dovrebbe sempre essere motivo di un rapido chiarimento da parte di un otorinolaringoiatra.<\/li>\n<li>La chirurgia rimane il pilastro del trattamento, con l&#8217;obiettivo di asportare il tumore nel modo pi\u00f9 radicale possibile. La radioterapia adiuvante sta diventando sempre pi\u00f9 importante, soprattutto per il controllo locale della malattia. Inoltre, una pi\u00f9 chiara comprensione della biologia del processo patologico sta portando all&#8217;implementazione di nuove immunoterapie.<\/li>\n<li>\u00c8 necessario uno studio prospettico multicentrico per identificare oggettivamente sistemi di stadiazione migliori e regimi di trattamento ottimali per questa rara entit\u00e0.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Ulteriori letture:<\/p>\n<ul>\n<li>Bakkal FK, et al: Melanoma mucoso della testa e del collo: caratteristiche di recidiva e risultati di sopravvivenza. Oral Surg Oral Med Oral Pathol Oral Radiol 2015 Nov; 120(5): 575-580.<\/li>\n<li>Warszawik-Hendzel O, et al: Melanoma del cavo orale: patogenesi, dermoscopia, caratteristiche cliniche, stadiazione e gestione. J Dermatol Case Rep 2014 Sep 30; 8(3): 60-66.<\/li>\n<li>Prasad ML, et al: Melanoma primario mucoso della testa e del collo: una proposta di microstadiazione dei tumori localizzati, in stadio I (linfonodo-negativo). Cancro 2004 Apr 15; 100(8): 1657-1664.<\/li>\n<li>Saida T, et al: Caratteristiche istopatologiche del melanoma maligno che colpisce le membrane mucose: un concetto unificante di istogenesi. Patologia 2004 ottobre; 36(5): 404-413.<\/li>\n<li>Christopherson K, et al: Radioterapia per il melanoma mucoso della testa e del collo. Am J Clin Oncol 2015 Feb; 38(1): 87-89.<\/li>\n<li>Temam S, et al: Radioterapia postoperatoria per il melanoma primario mucoso della testa e del collo. Cancer 2005 Jan 15; 103(2): 313-319.<\/li>\n<li>Sun CZ, et al: Trattamento e prognosi nel melanoma mucoso sinonasale: analisi retrospettiva di 65 pazienti di un unico centro oncologico. Head Neck 2014 maggio; 36(5): 675-681.<\/li>\n<li>Heppt MV, et al: Fattori prognostici ed esiti del trattamento in 444 pazienti con melanoma mucoso. Eur J Cancer 2017 Aug; 81: 36-44.<\/li>\n<li>Dreno M, et al: Melanoma mucoso sinonasale: studio di 44 casi e analisi della letteratura. Eur Ann Otorhinolaryngol Head Neck Dis 2017 Sep; 134(4): 237-242.<\/li>\n<li>Song H, et al: Fattori prognostici del melanoma della mucosa orale: analisi istopatologica in una coorte retrospettiva di 82 casi. Istopatologia 2015 ottobre; 67(4): 548-556.<\/li>\n<li>Goerres GW, et al: FDG PET per il melanoma maligno mucoso della testa e del collo. Laringoscopio 2002 Feb; 112(2): 381-385.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>InFo ONcOLOGIA &amp; EMATOLOGIA 2018; 6(1): 20-22.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il melanoma mucoso primario della testa e del collo \u00e8 raro. Tuttavia, si comporta in modo molto pi\u00f9 aggressivo rispetto al melanoma cutaneo maligno. I sintomi principali corrispondenti dovrebbero essere&hellip;<\/p>\n","protected":false},"author":7,"featured_media":75455,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Melanomi della mucosa nella regione della testa e del collo","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11376,11433,11550],"tags":[13611,34407,23182,26818],"powerkit_post_featured":[],"class_list":["post-338305","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-oncologia-it","category-orl-it","category-rx-it","tag-immunoterapia","tag-melanoma-della-mucosa","tag-radioterapia-it","tag-stabilizzazione-it-2","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 22:55:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":338312,"slug":"melanomas-mais-raros-mas-mais-agressivos-do-que-os-cutaneos","post_title":"Melanomas mais raros mas mais agressivos do que os cut\u00e2neos","href":"https:\/\/medizinonline.com\/pt-pt\/melanomas-mais-raros-mas-mais-agressivos-do-que-os-cutaneos\/"},"es_ES":{"locale":"es_ES","id":338318,"slug":"mas-raros-pero-mas-agresivos-que-los-melanomas-cutaneos","post_title":"M\u00e1s raros pero m\u00e1s agresivos que los melanomas cut\u00e1neos","href":"https:\/\/medizinonline.com\/es\/mas-raros-pero-mas-agresivos-que-los-melanomas-cutaneos\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/338305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=338305"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/338305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/75455"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=338305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=338305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=338305"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=338305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}