{"id":338750,"date":"2018-01-19T23:00:00","date_gmt":"2018-01-19T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/psicoterapia-modulare-un-modello-per-il-futuro\/"},"modified":"2018-01-19T23:00:00","modified_gmt":"2018-01-19T22:00:00","slug":"psicoterapia-modulare-un-modello-per-il-futuro","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/psicoterapia-modulare-un-modello-per-il-futuro\/","title":{"rendered":"Psicoterapia modulare &#8211; un modello per il futuro"},"content":{"rendered":"<p><strong>La psicoterapia modulare comprende diverse tecniche terapeutiche ed eurismi di trattamento. La selezione dei rispettivi interventi si basa sui patomeccanismi indicati, nonch\u00e9 sulle caratteristiche individuali del paziente e del suo ambiente sociale. Il Prof. Bohus presenta il quadro di riferimento storico e i principi organizzativi della Psicoterapia Modulare e fornisce un esempio di sviluppo di un concetto modulare per il PTSD complesso.<\/strong><\/p>\n<div style=\"display: block;\">\n<div style=\"display: none;\">\n<div>\n<div>\n<table cellspacing=\"1\">\n<tbody>\n<tr>\n<td><strong>Riconoscere una lingua africanaAlbaneseAraboArmenoAzerbaijaniBascoBengaliBosniacoBulgaroBirmanoCebuanoChichewaCinese (ver)CineseDaneseTedescoEsperantoEstonianoFinlandeseFranceseGeorgianoGrecoGujaratiHaitiani (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/strong><\/td>\n<td>\n<div id=\"SL_switch_b\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/switchb.png\") repeat scroll 0% 0%;\" title=\"Cambia lingua\">&nbsp;<\/div>\n<\/td>\n<td>\n<div style=\"display: block;\">\n<div style=\"display: none;\">\n<div>\n<div>\n<table cellspacing=\"1\">\n<tbody>\n<tr>\n<td><strong><strong>AfrikaansAlbanoAraboArmenoAzerbaijaniBascoBengaliBosniacoBulgaroBirmanoCebuanoChichewaCinese (ver)CineseDaneseIngleseEstonianoFinnicoFranceseGalizianoGeorgianoGrecoGiaratiHaitiano (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/strong><\/strong><\/td>\n<td>\n<div id=\"SL_TTS_voice\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/ttsvoice.png\") repeat scroll 0% 0%;\" title=\"Ascolta\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_copy\" id=\"SL_copy\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/copy.png\") repeat scroll 0% 0%;\" title=\"Copia\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_font_patch\">&nbsp;<\/div>\n<div class=\"SL_bbl_font\" id=\"SL_bbl_font\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/font.png\") repeat scroll 0% 0%;\" title=\"Dimensione del carattere\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_help\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bhelp.png\") repeat scroll 0% 0%;\" title=\"Aiuto\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_pin_off\" id=\"SL_pin\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/pin-on.png\") repeat scroll 0% 0%;\" title=\"Traduttore pop-up per unghie\">&nbsp;<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<div id=\"SL_shadow_translation_result\" style=\"visibility: visible;\">&nbsp;<\/div>\n<div class=\"SL_loading\" id=\"SL_loading\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/loading.gif\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_player2\">&nbsp;<\/div>\n<div id=\"SL_alert100\"><strong><strong><strong>La funzione audio \u00e8 limitata a 200 caratteri<\/strong><\/strong><\/strong><\/div>\n<div id=\"SL_Balloon_options\" style=\"background: rgb(255, 255, 255) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bg3.png\") repeat scroll 0% 0%;\">\n<div id=\"SL_arrow_down\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/down.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<table id=\"SL_tbl_opt\" style=\"width:100%\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td>\n<div id=\"SL_BBL_IMG\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bbl-logo.png\") repeat scroll 0% 0%;\" title=\"Mostra il pulsante inTranslator 3 secondi\">&nbsp;<\/div>\n<\/td>\n<td><strong><strong><strong><a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?bbl\" target=\"_blank\" title=\"Mostra le opzioni\" rel=\"noopener\">Opzioni<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?hist\" target=\"_blank\" title=\"Storia della traduzione\" rel=\"noopener\">Storia<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?feed\" target=\"_blank\" title=\"Feedback\" rel=\"noopener\">Feedback<\/a>: <a class=\"SL_options\" href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&amp;hosted_button_id=GD9D8CPW8HFA2\" target=\"_blank\" title=\"Contribuire\" rel=\"noopener\">Donazioni<\/a><\/strong><\/strong><\/strong><\/td>\n<td><strong><strong><strong>Chiudere<\/strong><\/strong><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p> <!--more--> <\/p>\n<p>Prof. Dr. Martin Bohus, Universit\u00e0 di Heidelberg<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe allowfullscreen=\"\" frameborder=\"0\" height=\"564\" mozallowfullscreen=\"\" data-src=\"https:\/\/player.vimeo.com\/video\/244022897\" webkitallowfullscreen=\"\" width=\"640\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9428\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1.png\" style=\"height:45px; width:200px\" width=\"1081\" height=\"243\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1.png 1081w, https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1-800x180.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1-120x27.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1-90x20.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1-320x72.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/01\/psy_1-560x126.png 560w\" sizes=\"(max-width: 1081px) 100vw, 1081px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La psicoterapia modulare comprende diverse tecniche terapeutiche ed eurismi di trattamento. La selezione dei rispettivi interventi si basa sui patomeccanismi indicati, nonch\u00e9 sulle caratteristiche individuali del paziente e del suo&hellip;<\/p>\n","protected":false},"author":7,"featured_media":72284,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Congresso annuale SGPP 2017 - Keynote","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11695,11479,11522,11550],"tags":[],"powerkit_post_featured":[],"class_list":["post-338750","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-con-il-partner","category-psichiatria-e-psicoterapia","category-rapporti-del-congresso","category-rx-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:25:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":338754,"slug":"psicoterapia-modular-um-modelo-para-o-futuro","post_title":"Psicoterapia modular - um modelo para o futuro","href":"https:\/\/medizinonline.com\/pt-pt\/psicoterapia-modular-um-modelo-para-o-futuro\/"},"es_ES":{"locale":"es_ES","id":338762,"slug":"psicoterapia-modular-un-modelo-para-el-futuro","post_title":"Psicoterapia modular: un modelo para el futuro","href":"https:\/\/medizinonline.com\/es\/psicoterapia-modular-un-modelo-para-el-futuro\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/338750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=338750"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/338750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/72284"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=338750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=338750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=338750"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=338750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}