{"id":339653,"date":"2017-06-23T02:00:00","date_gmt":"2017-06-23T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/dalla-pompa-per-il-pene-alla-pillola-blu\/"},"modified":"2017-06-23T02:00:00","modified_gmt":"2017-06-23T00:00:00","slug":"dalla-pompa-per-il-pene-alla-pillola-blu","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/dalla-pompa-per-il-pene-alla-pillola-blu\/","title":{"rendered":"Dalla pompa per il pene alla &#8220;pillola blu"},"content":{"rendered":"<p><strong>Con l&#8217;introduzione degli inibitori della PDE5 alla fine degli anni &#8217;90, il trattamento della disfunzione erettile ha subito una svolta. Tuttavia, l&#8217;ED non \u00e8 un fenomeno isolato. Pu\u00f2 essere una manifestazione di una malattia vascolare pi\u00f9 profonda.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>&#8220;Il grande cambiamento nel trattamento della disfunzione erettile \u00e8 avvenuto circa 20 anni fa, quando sono stati introdotti gli inibitori della PDE5&#8221;, ha spiegato Ashkan Mortezavi, MD, del Dipartimento di Urologia dell&#8217;Ospedale Universitario di Zurigo. Nonostante i nuovi farmaci dell&#8217;epoca, che offrivano un&#8217;alternativa interessante ai metodi invasivi e quindi per la prima volta offrivano la prospettiva di una terapia significativamente meno onerosa per la disfunzione erettile, la soglia di inibizione a parlare dell&#8217;argomento era ed \u00e8 ancora alta. Solo un quarto delle persone colpite si rivolge a un medico, e in media solo dopo due anni. Si scopre che l&#8217;interesse sessuale non scompare affatto in et\u00e0 avanzata. Nei sondaggi [1], anche tra gli uomini anziani e molto anziani fino a 95 anni, quasi la met\u00e0 concorda sul fatto che il sesso sia ancora importante. Allo stesso tempo, quasi lo stesso numero di persone era insoddisfatto o vedeva i propri desideri sessuali non sufficientemente soddisfatti (&#8220;meno spesso di quanto desiderato&#8221;). Tuttavia, gli uomini anziani non vogliono solo il sesso, ma lo fanno. La percentuale di uomini sessualmente attivi nei 70 anni \u00e8 ancora superiore al 60%.<\/p>\n<p>Tuttavia, \u00e8 proprio questa fascia di et\u00e0 che soffre particolarmente spesso di disfunzione erettile. Uno studio di Colonia ha rilevato una prevalenza di oltre il 50% nei tedeschi di 70-80 anni (prevalenza complessiva 19,2%) [2]. Per definizione, questo \u00e8 il caso se c&#8217;\u00e8 un&#8217;incapacit\u00e0 erettile (ripetuta) per pi\u00f9 di sei mesi, che non permette un rapporto sessuale soddisfacente. &#8220;I risultati mostrano anche che quasi una persona su dieci \u00e8 gi\u00e0 colpita a 40 anni. Le persone pi\u00f9 giovani tendono a parlarne ancora meno spesso con il proprio medico di famiglia&#8221;, ha detto. &#8220;Il fattore chiave dell&#8217;erezione \u00e8 il flusso sanguigno. Anche i nervi svolgono un ruolo, ma molto pi\u00f9 piccolo rispetto al sangue, quindi non sorprende che la disfunzione erettile sia spesso associata ad altri fattori di rischio cardiovascolare&#8221;.<\/p>\n<h2 id=\"la-punta-delliceberg\">La punta dell&#8217;iceberg<\/h2>\n<p>Fondamentalmente, si pu\u00f2 dire: pi\u00f9 il paziente \u00e8 giovane, pi\u00f9 spesso c&#8217;\u00e8 una causa psicogena. Complessivamente, circa il 50% delle disfunzioni erettili \u00e8 dovuto a cause puramente organiche e il 20% a cause puramente psicogene; il terzo rimanente \u00e8 costituito da patologie miste <strong>(tab.&nbsp;1)<\/strong>. A livello organico, le cause vascolari sono di gran lunga le pi\u00f9 comuni (oltre due terzi). &#8220;Non \u00e8 sorprendente se si considera l&#8217;importanza del sangue per l&#8217;erezione del tessuto erettile. Se i vasi del pene non funzionano pi\u00f9 correttamente, \u00e8 probabile che la disfunzione si verifichi anche altrove. La disfunzione erettile pu\u00f2 indicare la presenza di CHD, per esempio&#8221;, ha spiegato l&#8217;esperto. Quindi i problemi erettili sono solo la punta di un iceberg, che in questo caso \u00e8 la malattia vascolare sistemica, come suggerito da uno studio del 2003 [3]? Quasi il 70% dei pazienti con CHD soffriva di disfunzione erettile prima dei sintomi dell&#8217;angina. C&#8217;era un intervallo di pi\u00f9 di tre anni tra l&#8217;insorgenza della disfunzione erettile e la CHD. Ulteriori chiarimenti in questa direzione sono quindi utili per i pazienti con ED. Altri fattori di rischio associati sono l&#8217;ipertensione e il diabete (che fa male a tutti i vasi).<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-8770\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55.png\" style=\"height:245px; width:400px\" width=\"858\" height=\"525\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55.png 858w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55-800x490.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55-120x73.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55-90x55.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55-320x196.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/tab1_hp6_s55-560x343.png 560w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Sono rilevanti anche la disfunzione erettile indotta da farmaci e &#8211; particolarmente rappresentata in urologia &#8211; la disfunzione dopo interventi chirurgici, radiazioni o traumi al bacino&#8221;, ha spiegato il dottor Mortezavi. Le cause neurogene (complessivamente responsabili di circa il 5% dei casi di origine organica) possono essere la demenza, l&#8217;ictus, il morbo di Parkinson, ma anche l&#8217;epilessia o la SM. I traumi e le lesioni del midollo spinale tendono a giocare un ruolo importante nei pazienti pi\u00f9 giovani. Per quanto riguarda i farmaci, \u00e8 noto da molti anni che i beta-bloccanti, i tiazidici e la clonidina possono indurre la disfunzione erettile. Con gli antidepressivi, la disfunzione erettile \u00e8 spesso accompagnata da una perdita della libido.<\/p>\n<h2 id=\"la-disfunzione-erettile-e-fatale\">La disfunzione erettile \u00e8 fatale?<\/h2>\n<p>Se la disfunzione erettile e la CHD condividono fattori di rischio comuni, la prima \u00e8 addirittura un disturbo &#8220;pericoloso&#8221;? Infatti, i pazienti con ED hanno un aumento significativo del 19% del rischio di mortalit\u00e0 relativa rispetto ai pazienti non ED [4]. Al contrario, la morte coitale \u00e8 molto rara e rappresenta solo lo 0,6% circa delle morti improvvise. \u00c8 pi\u00f9 comune negli uomini che nelle donne, soprattutto quando i rapporti sessuali avvengono al di fuori del matrimonio, con partner pi\u00f9 giovani e in ambienti non familiari.<\/p>\n<h2 id=\"la-terapia-ha-senso\">La terapia ha senso<\/h2>\n<p>&#8220;Le associazioni con altre malattie cardiovascolari non vogliono suggerire che non possiamo o non dobbiamo fare nulla per la disfunzione erettile in s\u00e9. La maggior parte dei pazienti trae beneficio dalla terapia e si scopre che i requisiti di un trattamento risiedono principalmente nella sua affidabilit\u00e0, sicurezza e buon profilo di effetti collaterali, piuttosto che nel prezzo o nell&#8217;effetto rapido&#8221;, ha detto.<\/p>\n<p>Per prima cosa si consigliano misure di stile di vita. Sono utili, in particolare smettere di fumare pu\u00f2 &#8220;fare miracoli&#8221;, secondo la dottoressa Mortezavi. Anche la riduzione del peso \u00e8 importante. Le opzioni di trattamento sono illustrate nella <strong>figura&nbsp;1<\/strong>, dove si deve distinguere tra approcci invasivi e non invasivi.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8771 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/547;height:298px; width:600px\" width=\"1100\" height=\"547\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55-800x398.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55-120x60.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55-90x45.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55-320x159.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/06\/abb1_hp6_s55-560x278.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Se la spontaneit\u00e0 sessuale \u00e8 importante per lei durante un fine settimana programmato, pu\u00f2 prendere una compressa di tadalafil il venerd\u00ec pomeriggio, per esempio. Questo ha l&#8217;emivita pi\u00f9 lunga di 17,5 ore&#8221;, dice il dottor Mortezavi. &#8220;Gli inibitori della PDE5 sono complessivamente ben tollerati. Sono molto efficaci in molte forme diverse di DE [5]. Gli studi controllati e post-marketing non hanno evidenziato un aumento del rischio di infarto miocardico o di morte. Si consiglia cautela in caso di stenosi aortica, ostruzione del tratto di deflusso del ventricolo sinistro, ipotensione e ipovolemia. I nitrati, compresi i popper, sono una controindicazione assoluta&#8221;.<\/p>\n<p>Se l&#8217;effetto \u00e8 insufficiente, la terapia pu\u00f2 essere ottimizzata in diversi modi:<\/p>\n<ul>\n<li>Promemoria: la stimolazione sessuale \u00e8 un prerequisito.<\/li>\n<li>Assunzione di cibo ridotta (&#8220;non dopo un pasto di 7 portate&#8221;)<\/li>\n<li>Aumentare la dose<\/li>\n<li>Formazione (&#8220;pi\u00f9 a lungo \u00e8 esistita la disfunzione erettile, pi\u00f9 tempo ci vuole per tornare a funzionare&#8221;), risultato ottimale solo dopo la nona o decima assunzione.<\/li>\n<li>Non rispondente: sono necessari almeno quattro tentativi.<\/li>\n<\/ul>\n<h2 id=\"inizio-dazione-accelerato\">Inizio d&#8217;azione accelerato<\/h2>\n<p>La maggior parte degli uomini non sa in anticipo quando far\u00e0 sesso. I nuovi farmaci come <sup>Spedra\u00ae<\/sup> (avanafil) promettono quindi un inizio d&#8217;azione accelerato. Si tratta di un inibitore della PDE5 altamente selettivo ed efficace, che pu\u00f2 essere utilizzato anche per il desiderio sessuale pi\u00f9 o meno &#8220;spontaneo&#8221; (effetto dopo soli dieci minuti). Il profilo degli effetti collaterali \u00e8 molto basso, ma i dati empirici sono ancora relativamente pochi.<\/p>\n<p><em>Fonte: Aggiornamento di Medicina Interna Generale, 10-13 maggio 2017, Zurigo<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Hyde Z, et al: Prevalenza dell&#8217;attivit\u00e0 sessuale e fattori associati negli uomini di et\u00e0 compresa tra 75 e 95 anni: uno studio di coorte. Ann Intern Med 2010 Dec 7; 153(11): 693-702.<\/li>\n<li>Braun M, et al.: Epidemiologia della disfunzione erettile: risultati del &#8216;Cologne Male Survey&#8217;. Int J Impot Res 2000 Dec; 12(6): 305-311.<\/li>\n<li>Montorsi F, et al: prevalenza della disfunzione erettile, tempo di insorgenza e associazione con i fattori di rischio in 300 pazienti consecutivi con dolore toracico acuto e malattia coronarica documentata angiograficamente. Eur Urol 2003 Sep; 44(3): 360-364; discussione 364-365.<\/li>\n<li>Jackson G: Disfunzione erettile e malattia coronarica: valutare il legame. Maturitas 2012 Jul; 72(3): 263-264.<\/li>\n<li>Fink HA, et al: Sildenafil per la disfunzione erettile maschile: una revisione sistematica e una meta-analisi. Arch Intern Med 2002 Jun 24; 162(12): 1349-1360.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PRATICA GP 2017; 12(6): 54-55<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l&#8217;introduzione degli inibitori della PDE5 alla fine degli anni &#8217;90, il trattamento della disfunzione erettile ha subito una svolta. Tuttavia, l&#8217;ED non \u00e8 un fenomeno isolato. Pu\u00f2 essere una&hellip;<\/p>\n","protected":false},"author":7,"featured_media":67516,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Aggiornamento di Medicina Interna Generale","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11522,11550,11502],"tags":[27516,37968,37979,27596,37973],"powerkit_post_featured":[],"class_list":["post-339653","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rapporti-del-congresso","category-rx-it","category-urologia-it","tag-disfunzione-erettile","tag-inibitori-della-pde5","tag-rapporto-sessuale","tag-sessualita","tag-viagra-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 22:52:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":339662,"slug":"desde-a-bomba-de-penis-ate-a-pilula-azul","post_title":"Desde a bomba de p\u00e9nis at\u00e9 \u00e0 \"p\u00edlula azul","href":"https:\/\/medizinonline.com\/pt-pt\/desde-a-bomba-de-penis-ate-a-pilula-azul\/"},"es_ES":{"locale":"es_ES","id":339670,"slug":"de-la-bomba-para-el-pene-a-la-pildora-azul","post_title":"De la bomba para el pene a la \"p\u00edldora azul","href":"https:\/\/medizinonline.com\/es\/de-la-bomba-para-el-pene-a-la-pildora-azul\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/339653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=339653"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/339653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/67516"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=339653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=339653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=339653"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=339653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}