{"id":340068,"date":"2017-04-01T02:00:00","date_gmt":"2017-04-01T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/i-pazienti-beneficiano-dellintervento-attraverso-il-sistema-vascolare\/"},"modified":"2017-04-01T02:00:00","modified_gmt":"2017-04-01T00:00:00","slug":"i-pazienti-beneficiano-dellintervento-attraverso-il-sistema-vascolare","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/i-pazienti-beneficiano-dellintervento-attraverso-il-sistema-vascolare\/","title":{"rendered":"&#8220;I pazienti beneficiano dell&#8217;intervento attraverso il sistema vascolare&#8221;."},"content":{"rendered":"<p><strong>Alla 20esima conferenza annuale della Societ\u00e0 Cerebrovascolare Svizzera SHG, il Prof. Jan Gralla, MD, dell&#8217;Inselspital di Berna, ha parlato sul tema &#8220;Nuovi approcci nel trattamento intra-arterioso dell&#8217;ictus acuto&#8221;. Ha presentato gli studi attuali sull&#8217;efficacia delle diverse terapie e ha sottolineato quali sono le questioni da chiarire in seguito.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><strong>Qual \u00e8 attualmente la terapia pi\u00f9 efficace nel trattamento dell&#8217;ictus endovascolare?<\/strong><\/p>\n<p>Fino al 2014, la situazione degli studi era molto confusa. In seguito, sono stati pubblicati diversi studi randomizzati che dimostrano che i pazienti che ricevono solo la trombolisi sistemica vanno peggio di quelli che ricevono la trombolisi sistemica e poi la trombectomia. Il gold standard oggi \u00e8 quindi la trombolisi endovenosa, se possibile, ma seguita dalla rimozione meccanica del trombo. [1]\n<p><strong>Quali modelli di ictus beneficiano maggiormente di questo trattamento?<\/strong><\/p>\n<p>\u00c8 ormai noto che i pazienti con occlusioni di grandi vasi che coinvolgono la grande arteria cerebrale anteriore e media devono essere portati d&#8217;urgenza dopo la trombolisi sistemica o contemporaneamente all&#8217;intervento endovascolare. Questo \u00e8 il risultato di una meta-analisi con i dati dei pazienti di cinque studi randomizzati. [2]\n<p><strong>Quale tecnica viene utilizzata per la trombectomia?<\/strong><\/p>\n<p>Esiste una nuova tecnica che pu\u00f2 rimuovere i trombi in modo molto sicuro e con una probabilit\u00e0 molto alta. Questi sono gli stent retriever che vengono utilizzati con grande successo per le occlusioni dei grandi vasi, quindi in linea di principio tutti i pazienti dovrebbero essere trattati immediatamente con un trattamento endovascolare. Gli stent retriever in combinazione con la trombolisi endovenosa sono, come ho detto, il gold standard oggi.<\/p>\n<p><strong>Per quanto riguarda la trombolisi endovenosa, ci sono nuovi approcci?<\/strong><\/p>\n<p>Hanno cercato di somministrare un farmaco localmente nel trombo, anzich\u00e9 attraverso il sistema. Questa trombolisi interarteriosa \u00e8 possibile, ma non particolarmente efficiente. Anche la trombectomia distale si \u00e8 rivelata inefficace. Un altro approccio \u00e8 l&#8217;aspirazione del trombo, ma in questo caso i conti non sono ancora chiusi. Esistono studi in merito, il primo dei quali non ha mostrato alcun vantaggio rispetto alla trombolisi. Ma ora sono in corso due nuovi studi per riesaminare l&#8217;approccio di aspirazione del trombo. Nei prossimi due anni sapremo se questa tecnologia \u00e8 possibilmente efficiente. [3]\n<p><strong>Quali altri vantaggi vede nella combinazione di stent retriever e trombolisi endovenosa?  &nbsp;<\/strong><br \/>\nI pazienti hanno una degenza pi\u00f9 breve e in seguito sono meno disabili. Oltre all&#8217;aspetto medico e al destino del paziente, questa terapia \u00e8 anche molto efficiente dal punto di vista dei costi. Si risparmiano diverse migliaia di franchi per paziente, perch\u00e9 si riducono i costi dell&#8217;assistenza a lungo termine. Quando si riapre un paziente, costa di pi\u00f9 il giorno dell&#8217;intervento, ma il paziente \u00e8 meno disabile e ha bisogno di meno cure negli anni a venire. Questo aspetto \u00e8 stato analizzato nel 2016, in uno studio molto bello pubblicato sul Journal of Medical Economics. [4]\n<p><strong>La finestra temporale \u00e8 un aspetto cruciale per il successo del trattamento. Quali sono le opzioni per la terapia combinata?<\/strong><\/p>\n<p>La finestra temporale \u00e8 attualmente fino a otto ore. Presumiamo di poter ancora trattare i pazienti in modo sicuro, ma non lo sappiamo con certezza. Questa \u00e8 una domanda aperta. E i pazienti che hanno superato le otto ore? \u00c8 ancora consentito utilizzare la tecnica qui? E che dire dei pazienti per i quali non si conosce la finestra temporale perch\u00e9 l&#8217;ictus si \u00e8 verificato mentre dormivano? In questo caso sono necessari ulteriori studi.<\/p>\n<p><strong>Pu\u00f2 dare una prospettiva sull&#8217;ulteriore sviluppo del trattamento dell&#8217;ictus acuto?<\/strong><\/p>\n<p>Al momento, la domanda \u00e8 se la trombolisi sistemica sia necessaria per le occlusioni dei grandi vasi. Finora, la trombolisi endovenosa da sola \u00e8 stata confrontata con la trombolisi endovenosa con intervento endovascolare. Recentemente sono stati pubblicati diversi studi che hanno esaminato l&#8217;efficacia dell&#8217;intervento meccanico diretto rispetto all&#8217;attuale gold standard [5,6,7,8]. Nell&#8217;aprile 2017, inizier\u00e0 un altro studio su questo tema, chiamato SWIFT Direct. Sar\u00e0 lanciato a livello internazionale da Berna e sar\u00e0 realizzato in Europa e in Canada.<\/p>\n<p>Professor Gralla, la ringrazio molto per questa intervista.<\/p>\n<p><em><strong>Intervista: Karin Diod\u00e0<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>\nLetteratura:<\/p>\n<ol>\n<li>Campell, et al: Lancet Neurol 2015.<\/li>\n<li>Goyal M, et al: Lancet 2016; 387: 1723-31.<\/li>\n<li>Mocco J, et al: Trombectomia con aspirazione dopo alteplase endovenoso rispetto ad alteplase endovenoso da solo, Stroke 2017.<\/li>\n<li>Lobotesis K, et al: Costo-efficacia della trombectomia con stent-retriever in combinazione con t-PA endovena rispetto al solo t-PA endovena per l&#8217;ictus ischemico acuto nel Regno Unito, Journ of Medical Economics 2016; 8: 785-794.<\/li>\n<li>Broeg-Morvay A, et al: Intervento meccanico diretto rispetto all&#8217;intervento combinato endovenoso e meccanico nell&#8217;ictus da cirrosi anteriore di grande arteria, Stroke 2016.<\/li>\n<li>Coutino JC, et al: Trombolisi endovenosa combinata e trombectomia rispetto alla sola trombectomia per l&#8217;ictus ischemico acuto, un&#8217;analisi congiunta degli studi SWIFT e STAR.<\/li>\n<li>Abilleira S, et al: Gli esiti dopo trombectomia diretta o trattamento combinato endovenoso ed endovascolare non sono diversi, Stroke 2017.<\/li>\n<li>Rai AT, et al: La trombolisi endovenosa prima della terapia endovascolare per gli ictus dei grandi vasi pu\u00f2 portare a costi ospedalieri significativamente pi\u00f9 elevati senza migliorare gli esiti. NeuroIntervent Surg 2017.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOGIA &amp; PSICHIATRIA 2017; 15(2): 29-31<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alla 20esima conferenza annuale della Societ\u00e0 Cerebrovascolare Svizzera SHG, il Prof. Jan Gralla, MD, dell&#8217;Inselspital di Berna, ha parlato sul tema &#8220;Nuovi approcci nel trattamento intra-arterioso dell&#8217;ictus acuto&#8221;. Ha presentato&hellip;<\/p>\n","protected":false},"author":7,"featured_media":65095,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Terapia dell'ictus","footnotes":""},"category":[11525,11462,11371,11522,11550,11515],"tags":[12711,12725,39111,39106,39117],"powerkit_post_featured":[],"class_list":["post-340068","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interviste","category-medicina-fisica-e-riabilitazione","category-neurologia-it","category-rapporti-del-congresso","category-rx-it","category-studi","tag-ictus","tag-ictus-it","tag-trombectomia","tag-trombo","tag-trombolisi-endovenosa","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:07:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":340076,"slug":"os-pacientes-beneficiam-da-intervencao-atraves-do-sistema-vascular","post_title":"\"Os pacientes beneficiam da interven\u00e7\u00e3o atrav\u00e9s do sistema vascular\".","href":"https:\/\/medizinonline.com\/pt-pt\/os-pacientes-beneficiam-da-intervencao-atraves-do-sistema-vascular\/"},"es_ES":{"locale":"es_ES","id":340081,"slug":"los-pacientes-se-benefician-de-la-intervencion-a-traves-del-sistema-vascular","post_title":"\"Los pacientes se benefician de la intervenci\u00f3n a trav\u00e9s del sistema vascular\".","href":"https:\/\/medizinonline.com\/es\/los-pacientes-se-benefician-de-la-intervencion-a-traves-del-sistema-vascular\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/340068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=340068"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/340068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/65095"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=340068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=340068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=340068"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=340068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}