{"id":340170,"date":"2017-03-11T01:00:00","date_gmt":"2017-03-11T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-terapia-con-radiopeptidi-ha-successo-nella-progressione-della-malattia\/"},"modified":"2017-03-11T01:00:00","modified_gmt":"2017-03-11T00:00:00","slug":"la-terapia-con-radiopeptidi-ha-successo-nella-progressione-della-malattia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/la-terapia-con-radiopeptidi-ha-successo-nella-progressione-della-malattia\/","title":{"rendered":"La terapia con radiopeptidi ha successo nella progressione della malattia"},"content":{"rendered":"<p><strong>I pazienti con tumori neuroendocrini (NET) positivi al recettore della somatostatina, in fase avanzata e progressiva, possono beneficiare della cosiddetta terapia radiorecettoriale mediata da peptidi (PRRT), secondo una pubblicazione sul New England Journal of Medicine. Uno di questi bersaglia il tumore con peptidi analoghi della somatostatina marcati radioattivamente. Sia la sopravvivenza libera da progressione che il tasso di risposta sono stati prolungati rispetto all&#8217;analogo della somatostatina ad alto dosaggio octreotide LAR (intramuscolo alla dose di 60 mg ogni quattro settimane). I dati finali sulla sopravvivenza globale sono attualmente in attesa.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Per la PRRT, lo studio di fase 3 in questione [1] ha utilizzato il <sup>177lutezio dotatato<\/sup>, un peptide analogo della somatostatina marcato con Lu-177. Le cellule tumorali neuroendocrine di solito hanno un&#8217;alta densit\u00e0 di recettori della somatostatina. Il peptide analogo della somatostatina raggiunge il recettore interessato sulla cellula tumorale e vi rimane per diversi giorni. Nel frattempo, il 177lutezio, una particella radioattiva, assicura che le cellule tumorali circostanti vengano irradiate e uccise. Si tratta quindi di un&#8217;irradiazione interna mirata.<\/p>\n<p>Questi sono stati somministrati in modo casuale a 116 partecipanti in quattro infusioni endovenose insieme alla migliore terapia concomitante possibile, che comprendeva l&#8217;octreotide LAR per via intramuscolare alla dose di 30 mg. I restanti 113 pazienti sono stati sottoposti alla terapia con octreotide LAR solo alla dose sopra indicata.<\/p>\n<h2 id=\"i-dati-sulla-sopravvivenza-danno-speranza\">I dati sulla sopravvivenza danno speranza<\/h2>\n<p>L&#8217;endpoint primario \u00e8 stato definito come sopravvivenza libera da progressione. Gli endpoint secondari includevano il tasso di risposta e la sopravvivenza globale, per i quali al momento esiste solo un&#8217;analisi preliminare ad interim.<\/p>\n<ul>\n<li>Dopo 20 mesi, i tassi di PFS calcolati erano del 65,2% rispetto al 10,8% del gruppo di controllo. Di conseguenza, il rischio di progressione o di morte \u00e8 stato ridotto significativamente del 79% con la PRRT (rapporto di rischio 0,21; 95% CI 0,13-0,33; p&lt;0,0001).<\/li>\n<li>L&#8217;analisi ad interim sulla sopravvivenza globale era nella stessa direzione: 14 vs. 26 decessi nei due gruppi (p=0,004).<\/li>\n<li>Anche la risposta \u00e8 stata significativamente migliorata nel gruppo 177Lutezio Dotato, dal 3% al 18% rispetto al gruppo di controllo.<\/li>\n<\/ul>\n<p>La mielosoppressione clinicamente significativa si \u00e8 verificata in meno del 10% dei pazienti del gruppo di studio: Rispetto a zero pazienti nel gruppo di controllo, la neutropenia si \u00e8 verificata nell&#8217;1%, la trombocitopenia nel 2% e la linfopenia nel 9% dei pazienti trattati (ciascuno di grado 3-4). Gli effetti tossici sul rene non sono stati riscontrati con la somministrazione simultanea di un agente che protegge i reni &#8211; almeno durante questo periodo di studio.<\/p>\n<h2 id=\"la-progressione-della-malattia-e-una-sfida\">La progressione della malattia \u00e8 una sfida<\/h2>\n<p>Attualmente, le opzioni di trattamento sono limitate per le persone con NET dell&#8217;intestino medio in fase avanzata, che mostrano una progressione della malattia durante il trattamento di prima linea con un analogo della somatostatina. I risultati dello studio sono quindi promettenti e fanno sperare in una nuova alternativa di trattamento. I tassi di risposta oggettiva, in particolare, sono impressionanti e non erano prevedibili in questo collettivo. Si attendono i dati finali dell&#8217;analisi finale prevista.<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Strosberg J, et al: Studio di fase 3 del 177Lu-Dotatato per i tumori neuroendocrini dell&#8217;intestino medio. N Engl J Med 2017; 376: 125-135.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGIA &amp; EMATOLOGIA 2017; 5(1): 3<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I pazienti con tumori neuroendocrini (NET) positivi al recettore della somatostatina, in fase avanzata e progressiva, possono beneficiare della cosiddetta terapia radiorecettoriale mediata da peptidi (PRRT), secondo una pubblicazione sul&hellip;<\/p>\n","protected":false},"author":7,"featured_media":64267,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"NET avanzato dell'intestino medio","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11401,11511,11376,11550,11515],"tags":[39349,39365,39359,39353],"powerkit_post_featured":[],"class_list":["post-340170","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gastroenterologia-ed-epatologia","category-notizie","category-oncologia-it","category-rx-it","category-studi","tag-net-it","tag-peptide-it","tag-prrt-it","tag-somatostatina","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:30:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":340183,"slug":"terapia-de-radiopeptideos-bem-sucedida-na-progressao-da-doenca","post_title":"Terapia de radiopept\u00eddeos bem sucedida na progress\u00e3o da doen\u00e7a","href":"https:\/\/medizinonline.com\/pt-pt\/terapia-de-radiopeptideos-bem-sucedida-na-progressao-da-doenca\/"},"es_ES":{"locale":"es_ES","id":340186,"slug":"la-terapia-con-radiopeptidos-tiene-exito-en-la-progresion-de-la-enfermedad","post_title":"La terapia con radiop\u00e9ptidos tiene \u00e9xito en la progresi\u00f3n de la enfermedad","href":"https:\/\/medizinonline.com\/es\/la-terapia-con-radiopeptidos-tiene-exito-en-la-progresion-de-la-enfermedad\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/340170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=340170"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/340170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/64267"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=340170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=340170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=340170"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=340170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}