{"id":340338,"date":"2017-02-01T01:00:00","date_gmt":"2017-02-01T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/scoprire-le-differenze-nella-prevenzione-dellictus\/"},"modified":"2017-02-01T01:00:00","modified_gmt":"2017-02-01T00:00:00","slug":"scoprire-le-differenze-nella-prevenzione-dellictus","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/scoprire-le-differenze-nella-prevenzione-dellictus\/","title":{"rendered":"Scoprire le differenze nella prevenzione dell&#8217;ictus"},"content":{"rendered":"<p><strong>Le donne soffrono di ictus pi\u00f9 spesso e in et\u00e0 pi\u00f9 avanzata. Le donne hanno un esito peggiore dopo un ictus e soffrono particolarmente per gli effetti sulla loro indipendenza nella vita quotidiana. Oltre a fattori di rischio specifici come la gravidanza e l&#8217;uso di contraccettivi orali, altri fattori di rischio sono particolarmente importanti nelle donne: ipertensione arteriosa, fibrillazione atriale ed emicrania con aura. Le donne sono sottorappresentate negli studi clinici. Una maggiore inclusione delle donne nella ricerca sull&#8217;ictus \u00e8 fondamentale per migliorare i trattamenti futuri.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>In Svizzera vivono oltre 4,3 milioni di donne. In media, le donne vivono circa 4 anni in pi\u00f9 degli uomini. La natura e il decorso di molte malattie differiscono tra i sessi. Questo \u00e8 particolarmente vero per l&#8217;ictus. Purtroppo, le donne sono sottorappresentate negli studi clinici, il che limita notevolmente la trasferibilit\u00e0 dei risultati alle donne. Per rendere giustizia alle differenze specifiche di genere tra uomini e donne nell&#8217;ictus, le societ\u00e0 professionali americane (American Heart Association\/American Stroke Association) hanno sviluppato un documento di posizione congiunto nel 2014 [1]. Le linee guida raccomandate per la prevenzione dell&#8217;ictus ischemico nelle donne saranno discusse in questa sintesi.<\/p>\n<h2 id=\"incidenza-piu-bassa-nelle-donne-piu-giovani\">Incidenza pi\u00f9 bassa nelle donne pi\u00f9 giovani<\/h2>\n<p>L&#8217;ictus ischemico \u00e8 molto pi\u00f9 comune dell&#8217;ictus emorragico e rappresenta circa l&#8217;85% di tutti gli ictus. Grazie al miglioramento delle opzioni di prevenzione primaria, l&#8217;incidenza dell&#8217;ictus ischemico si \u00e8 ridotta in molti Paesi occidentali, con un calo particolare negli uomini. La mortalit\u00e0 per ictus ischemico \u00e8 di circa 74,3\/100.000 per le donne rispetto a 78\/100.000 per gli uomini. La mortalit\u00e0 \u00e8 pi\u00f9 bassa nelle donne pi\u00f9 giovani rispetto agli uomini; tuttavia, con l&#8217;aumentare dell&#8217;et\u00e0, diventa simile a quella degli uomini e pi\u00f9 tardi (intorno ai 75 anni) aumenta anche oltre. Inoltre, le donne sono in media pi\u00f9 anziane al momento dell&#8217;ictus. Ci\u00f2 \u00e8 probabilmente legato all&#8217;effetto neuroprotettivo degli ormoni steroidei femminili endogeni, come gli estrogeni e il progesterone [2]. Questo \u00e8 anche il motivo della minore incidenza di ictus nelle donne pi\u00f9 giovani. Con l&#8217;arrivo della menopausa e il calo dei livelli ormonali, l&#8217;effetto protettivo diminuisce. In sintesi, sebbene l&#8217;incidenza dell&#8217;ictus nelle donne sia inferiore di circa il 25% rispetto a quella degli uomini, si verificano pi\u00f9 ictus nelle donne che negli uomini in numero assoluto, a causa della maggiore aspettativa di vita delle donne [3].<\/p>\n<h2 id=\"recupero-dellictus-e-successo-delle-terapie-acute\">Recupero dell&#8217;ictus e successo delle terapie acute<\/h2>\n<p>Anche tenendo conto dell&#8217;et\u00e0 media pi\u00f9 elevata, le donne recuperano meno bene dall&#8217;ictus. \u00c8 meno probabile che riacquistino le capacit\u00e0 di gestire la propria vita quotidiana in modo indipendente. Le donne sono pi\u00f9 spesso colpite dalla depressione dopo un ictus, che ha anche un impatto negativo sulla qualit\u00e0 della vita [2]. Le ragioni di questo svantaggio nella guarigione non sono del tutto chiare; oltre agli effetti difficili da correggere derivanti dalla differenza (statistica) di et\u00e0 tra uomini e donne colpiti, anche i fattori socio-economici sembrano giocare un ruolo.<\/p>\n<p>Per esempio, la terapia trombolitica con l&#8217;attivatore reversibile del plasminogeno tissutale (rtPA), sebbene sia almeno altrettanto efficace nelle donne che negli uomini, viene utilizzata meno frequentemente nelle donne [4,5]. Questo non pu\u00f2 essere spiegato dal fatto che le donne richiedono assistenza medica pi\u00f9 tardi rispetto ai sintomi di un ictus o raggiungono l&#8217;ospedale pi\u00f9 tardi. Gli studi hanno dimostrato che le donne avevano meno probabilit\u00e0 di ricevere diagnosi avanzate come l&#8217;ecocardiografia e l&#8217;imaging cerebrale [6]. Le cause di queste differenze nella diagnosi e nel trattamento dell&#8217;ictus tra i due sessi non sono ancora state chiarite.<\/p>\n<h2 id=\"fattori-di-rischio\">Fattori di rischio<\/h2>\n<p><strong>Ipertensione arteriosa:<\/strong> oltre ai fattori di rischio specifici del genere, come la gravidanza e l&#8217;uso della terapia ormonale sostitutiva dopo la menopausa, anche altri fattori di rischio sono distribuiti in modo ineguale tra i generi<strong> (Tab. 1) <\/strong>. L&#8217;ipertensione arteriosa gioca un ruolo significativo in questo caso, influenzando il rischio di ictus in misura particolarmente elevata. Sebbene le donne abbiano meno probabilit\u00e0 di ricevere una diagnosi di ipertensione arteriosa prima della menopausa, l&#8217;incidenza dopo la menopausa supera quella degli uomini. Per esempio, le donne con ictus presentano un&#8217;ipertensione arteriosa pi\u00f9 spesso degli uomini. Proprio come gli uomini, beneficiano chiaramente del trattamento dell&#8217;ipertensione; il rischio di ictus pu\u00f2 essere ridotto di circa il 38% attraverso il controllo della pressione arteriosa, dove il tipo di trattamento \u00e8 meno importante del raggiungimento di valori pressori normotesi [7]. Sebbene le donne ricevano un trattamento per l&#8217;ipertensione e venga regolato con una frequenza simile a quella degli uomini, il raggiungimento dell&#8217;intervallo di pressione target sembra essere pi\u00f9 difficile nelle donne in postmenopausa rispetto agli uomini della stessa et\u00e0. Gli effetti collaterali dei farmaci per la pressione sanguigna si verificano pi\u00f9 spesso nelle donne. A parte i possibili problemi di compliance (finora non \u00e8 mai stata dimostrata una minore compliance nelle donne che assumono farmaci per la pressione sanguigna), i fattori ormonodipendenti e indipendenti dal sesso coinvolti nella regolazione della pressione sanguigna sistemica e nella modulazione locale della resistenza vascolare probabilmente giocano un ruolo in questo caso.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-8226\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/02\/tab1_np1_s20.png\" style=\"height:926px; width:600px\" width=\"1100\" height=\"1697\"><\/p>\n<p>&nbsp;<\/p>\n<p>Quindi, sebbene vi siano differenze nella regolazione della pressione arteriosa e nella risposta alla terapia, le attuali raccomandazioni per il trattamento dell&#8217;ipertensione arteriosa nella prevenzione primaria dell&#8217;ictus sono le stesse per le donne e gli uomini e dovrebbero essere implementate in modo coerente in entrambi i sessi.<\/p>\n<p><strong>Obesit\u00e0, sindrome metabolica e fattori di stile di vita:<\/strong> L&#8217;obesit\u00e0 \u00e8 un fattore di rischio indipendente per l&#8217;ictus. Soprattutto la forma addominale (circonferenza dei fianchi &gt;88 cm nelle donne) \u00e8 associata ad un aumento del rischio di ictus e si verifica pi\u00f9 spesso nelle donne che negli uomini. Esiste una relazione lineare tra l&#8217;indice di massa corporea (BMI) e il rischio di ictus, indipendentemente dal sesso. Non \u00e8 chiaro se l&#8217;obesit\u00e0 influisca sull&#8217;esito dell&#8217;ictus in modo diverso nelle donne e negli uomini. La sindrome metabolica, che combina diversi fattori cardiovascolari (obesit\u00e0 di tipo addominale, resistenza all&#8217;insulina, ipertensione arteriosa, dislipidemia), sembra essere associata a un rischio pi\u00f9 elevato di ictus nelle donne e a causare pi\u00f9 ictus nelle donne. Si sospetta che i fattori pro-infiammatori e pro-trombotici siano causali. Uno stile di vita sano con molto esercizio fisico, una dieta ricca di frutta e verdura e povera di acidi grassi saturi (&#8220;mediterranea&#8221;), senza fumare e con un consumo moderato di alcol ha un&#8217;influenza positiva sul rischio di ictus nelle donne e negli uomini [8]. Le misure per sostenere uno stile di vita sano sono raccomandate sia per le donne che per gli uomini nella prevenzione.<\/p>\n<p><strong>Fibrillazione atriale:<\/strong> La fibrillazione atriale (Vhfli) aumenta di frequenza con l&#8217;et\u00e0 ed \u00e8 quindi un fattore di rischio particolarmente rilevante per l&#8217;ictus nelle persone anziane (causa di circa il 25% degli ictus ischemici nelle persone di &gt;80 anni). Quando le donne raggiungono un&#8217;et\u00e0 pi\u00f9 avanzata, la Vhfli \u00e8 pi\u00f9 comune nelle donne con ictus. Inoltre, il rischio di ictus nelle donne con Vhfli &gt;75 anni \u00e8 superiore a quello degli uomini della stessa et\u00e0. Questo si riflette nei nuovi punteggi da utilizzare per stimare il rischio embolico e decidere l&#8217;anticoagulazione nei pazienti con FA, come il punteggio CHA2DS2-VASc. Secondo le attuali raccomandazioni dell&#8217;AHA, l&#8217;anticoagulazione dovrebbe essere iniziata in tutte le donne &gt;75 anni, anche se non sono presenti altri fattori di rischio. Il buon effetto dei nuovi anticoagulanti (inibitori diretti e indiretti della trombina) rispetto a Marcoumar era paragonabile per donne e uomini negli studi di registrazione.<\/p>\n<p><strong>Depressione e stress psicosociale: la <\/strong>depressione non solo \u00e8 una conseguenza nota dell&#8217;ictus, ma aumenta anche il rischio di ictus. L&#8217;importanza \u00e8 notevole (circa il 35% di aumento del rischio di ictus con sentimenti di tristezza o depressione auto-riferiti per 2 settimane negli ultimi 12 mesi) [9] e circa ugualmente pronunciata per entrambi i sessi. L&#8217;influenza delle terapie o del modo in cui la depressione viene rilevata negli studi non \u00e8 ancora stata chiarita. Poich\u00e9 la depressione e lo stress psicosociale si verificano pi\u00f9 frequentemente nelle donne che negli uomini, si pu\u00f2 presumere che questi fattori di rischio siano particolarmente importanti nelle donne.<\/p>\n<p><strong>Emicrania con aura: <\/strong>molte persone soffrono di emicrania tipica, le donne circa quattro volte pi\u00f9 spesso degli uomini. Solo l&#8217;emicrania con aura (prevalenza 4-5%) ha dimostrato di essere associata a un aumento del rischio di ictus. I sintomi dell&#8217;aura possono essere di varia natura (fenomeni visivi transitori, parestesie con formicolio unilaterale, paralisi o disturbi del linguaggio) e di solito si verificano prima dell&#8217;emicrania. Il rischio di ictus aumenta di circa 2 volte nelle persone con questo tipo di emicrania. Se ci sono altri fattori di rischio, come il fumo e l&#8217;assunzione di contraccettivi contenenti estrogeni, il rischio aumenta in modo significativo. Gli ictus emicranici sono meno gravi di altri e di solito non comportano limitazioni funzionali rilevanti. Tuttavia, in considerazione dell&#8217;aumento del rischio, soprattutto per le donne con emicrania, \u00e8 importante sostenere lo stop alla nicotina.&nbsp;  Si pu\u00f2 prendere in considerazione la riduzione della frequenza degli attacchi di emicrania attraverso una profilassi di base, anche se non \u00e8 stato dimostrato che riduce il rischio di ictus.<\/p>\n<p><strong>Fattori di rischio specifici per le donne:<\/strong> Solo raramente si verificano ictus durante la gravidanza (34\/100.000 gravidanze). Tuttavia, il rischio \u00e8 aumentato rispetto alle donne non incinte della stessa et\u00e0, soprattutto nel 3\u00b0 trimestre e nel post-partum. Le complicazioni durante la gravidanza, come il diabete gestazionale, l&#8217;aumento della pressione sanguigna e la pre-eclampsia, sono associate a un aumento del rischio di ictus pi\u00f9 tardi nella vita. Le linee guida raccomandano la profilassi con aspirina a basso dosaggio a partire dalla 12esima settimana di vita. Settimana di gravidanza in donne con ipertensione arteriosa cronica primaria o secondaria o precedente ipertensione associata alla gravidanza. L&#8217;integrazione di calcio pu\u00f2 essere presa in considerazione per prevenire la pre-eclampsia nelle donne con un basso apporto di calcio. Il trattamento dell&#8217;ipertensione arteriosa deve essere effettuato con l&#8217;ostetrica che ha in cura la paziente e tenendo conto del profilo degli effetti collaterali dei farmaci antipertensivi.<\/p>\n<p>L&#8217;uso di contraccettivi orali contenenti estrogeni, rispetto alle pillole progestiniche, \u00e8 associato a un leggero aumento del rischio di ictus ischemico. L&#8217;aumento del rischio \u00e8 inferiore a quello dovuto alla gravidanza. Le donne con fattori di rischio aggiuntivi (fumo, ipertensione arteriosa, et\u00e0 avanzata, fattori protrombotici) presentano un ulteriore aumento del rischio con i contraccettivi orali contenenti estrogeni, motivo per cui questi preparati dovrebbero essere evitati in questo caso. La terapia ormonale sostitutiva in postmenopausa non \u00e8 raccomandata per la profilassi primaria o secondaria dell&#8217;ictus, a causa dell&#8217;aumento del rischio.<\/p>\n<h2 id=\"ulteriori-strategie-per-la-prevenzione-dellictus\">Ulteriori strategie per la prevenzione dell&#8217;ictus<\/h2>\n<p>Sebbene le donne siano pi\u00f9 frequentemente colpite da ictus rispetto agli uomini, la sottorappresentazione delle donne negli studi di terapia clinica \u00e8 sorprendente. Questa asimmetria riguarda anche altri studi clinici al di fuori della neurologia. Negli studi sulla terapia farmacologica con inibitori dell&#8217;aggregazione piastrinica, la percentuale di donne era compresa tra il 30-53%, e negli studi di intervento carotideo solo tra il 25-34%. Ci\u00f2 implica che i risultati dello studio possono essere trasferiti alle donne solo in misura limitata.&nbsp;  L&#8217;attuale linea guida AHA afferma chiaramente che \u00e8 urgente una migliore rappresentazione delle donne negli studi terapeutici, per poter fare affermazioni sulle differenze specifiche di genere. Nella situazione attuale, per quanto riguarda le donne dovrebbero valere gli stessi principi terapeutici degli uomini:<\/p>\n<ol>\n<li>Stenosi sintomatica di grado medio-alto dell&#8217;arteria carotide interna (stenosi carotidea): Si raccomanda l&#8217;endarterectomia, preferibilmente entro due settimane dall&#8217;evento; lo stenting pu\u00f2 essere un&#8217;alternativa.<\/li>\n<li>La terapia con aspirina nella prevenzione secondaria; dovrebbe essere iniziata precocemente.<\/li>\n<\/ol>\n<p>Per la prevenzione primaria, l&#8217;aspirina a basso dosaggio dovrebbe essere presa in considerazione nelle donne a maggior rischio di ictus a causa del diabete o con un profilo di rischio vascolare elevato, se non ci sono controindicazioni. Il beneficio in termini di prevenzione dell&#8217;ictus nella prevenzione primaria sembra essere leggermente superiore nelle donne rispetto agli uomini. Le raccomandazioni per il trattamento interventistico preventivo primario della stenosi carotidea asintomatica non sono state formulate nella dichiarazione attuale, in quanto la situazione generale dei dati \u00e8 comunque controversa a causa della lunga storia di studi clinici sull&#8217;argomento e della terapia conservativa nel frattempo notevolmente migliorata. Se viene rilevata una stenosi carotidea di alto grado, asintomatica, ricercare e regolare i fattori di rischio e iniziare la terapia con aspirina.<\/p>\n<h2 id=\"migliore-esame-dei-fattori-specifici-di-genere\">Migliore esame dei fattori specifici di genere<\/h2>\n<p>Le donne sono colpite da ictus pi\u00f9 spesso degli uomini, hanno un esito peggiore e non hanno lo stesso accesso alle terapie. Un fattore potrebbe essere l&#8217;et\u00e0 avanzata al momento dell&#8217;ictus. Le differenze biologiche e socio-economiche sono certamente fattori che contribuiscono. I fattori di rischio sono presenti in misura diversa nelle donne e negli uomini e hanno effetti diversi sul rischio di ictus. Anche la risposta ai trattamenti preventivi non \u00e8 la stessa.<\/p>\n<p>Le donne possono quindi essere considerate particolarmente vulnerabili. \u00c8 importante che lo studio scopra le differenze nella prevenzione e crei un trattamento ottimale anche per le donne. Un migliore studio dei fattori specifici di genere nello sviluppo dell&#8217;ictus e nell&#8217;efficacia degli interventi terapeutici pu\u00f2 aiutare a sviluppare terapie che proteggano meglio le donne dall&#8217;ictus.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Bushnell C, et al: Linee guida per la prevenzione dell&#8217;ictus nelle donne: una dichiarazione per gli operatori sanitari dell&#8217;American Heart Association\/American Stroke Association. Ictus. 2014; 45(5): 1545-88.<\/li>\n<li>Girijala RL, Sohrabji F, Bush RL: Differenze di sesso nell&#8217;ictus: revisione delle conoscenze e delle prove attuali. Vasc Med. 2016.<\/li>\n<li>Ovbiagele B.: Tendenze nazionali specifiche per sesso nei tassi di ictus ospedalieri. J Stroke Cerebrovasc Dis. 2011; 20(6): 537-40.<\/li>\n<li>Meseguer, et al: Esiti della terapia con attivatore del plasminogeno tissutale ricombinante per via endovenosa in base al sesso: studio di registro clinico e revisione sistematica. Ictus. 2009; 40(6): 2104-10.<\/li>\n<li>Asdaghi N, et al: Disparit\u00e0 di sesso nella cura dell&#8217;ictus ischemico: Studio FL-PR CReSD (Florida-Puerto Rico Collaboration to Reduce Stroke Disparities). Ictus. 2016; 47(10): 2618-26.<\/li>\n<li>Reeves MJ, et al: Differenze di sesso nell&#8217;ictus: epidemiologia, presentazione clinica, assistenza medica ed esiti. Lancet Neurol. 2008; 7(10): 915-26.<\/li>\n<li>Turnbull F et al: Gli uomini e le donne rispondono in modo diverso al trattamento per abbassare la pressione sanguigna? Risultati di panoramiche prospettiche di studi randomizzati. Eur Heart J. 2008; 29(21): 2669-80.<\/li>\n<li>O&#8217;Donnell MJ, et al: Effetti globali e regionali dei fattori di rischio potenzialmente modificabili associati all&#8217;ictus acuto in 32 Paesi (INTERSTROKE): uno studio caso-controllo. Lancet. 2016; 388(10046): 761-75.<\/li>\n<li>O&#8217;Donnell MJ, et al: Fattori di rischio per l&#8217;ictus ischemico ed emorragico intracerebrale in 22 Paesi (studio INTERSTROKE): uno studio caso-controllo. Lancet. 2010; 376(9735): 112-23.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOGIA &amp; PSICHIATRIA 2017; 15(1): 19-23<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le donne soffrono di ictus pi\u00f9 spesso e in et\u00e0 pi\u00f9 avanzata. Le donne hanno un esito peggiore dopo un ictus e soffrono particolarmente per gli effetti sulla loro indipendenza&hellip;<\/p>\n","protected":false},"author":7,"featured_media":63485,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"La linea guida AHA\/ASA per la prevenzione dell'ictus nelle donne","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11348,11366,11519,11409,11371,11473,11479,11550],"tags":[14677,13884,12711,12725,13471],"powerkit_post_featured":[],"class_list":["post-340338","post","type-post","status-publish","format-standard","has-post-thumbnail","category-angiologia-it","category-cardiologia-it","category-formazione-continua","category-ginecologia-it","category-neurologia-it","category-prevenzione-e-assistenza-sanitaria","category-psichiatria-e-psicoterapia","category-rx-it","tag-depressione","tag-emicrania","tag-ictus","tag-ictus-it","tag-ipertensione","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:23:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":340342,"slug":"descobrindo-diferencas-na-prevencao-de-avc","post_title":"Descobrindo diferen\u00e7as na preven\u00e7\u00e3o de AVC","href":"https:\/\/medizinonline.com\/pt-pt\/descobrindo-diferencas-na-prevencao-de-avc\/"},"es_ES":{"locale":"es_ES","id":340349,"slug":"descubrir-las-diferencias-en-la-prevencion-del-ictus","post_title":"Descubrir las diferencias en la prevenci\u00f3n del ictus","href":"https:\/\/medizinonline.com\/es\/descubrir-las-diferencias-en-la-prevencion-del-ictus\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/340338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=340338"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/340338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/63485"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=340338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=340338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=340338"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=340338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}