{"id":342083,"date":"2016-02-12T02:00:00","date_gmt":"2016-02-12T01:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/una-rara-causa-di-mal-di-testa-e-mal-di-gola\/"},"modified":"2016-02-12T02:00:00","modified_gmt":"2016-02-12T01:00:00","slug":"una-rara-causa-di-mal-di-testa-e-mal-di-gola","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/una-rara-causa-di-mal-di-testa-e-mal-di-gola\/","title":{"rendered":"Una rara causa di mal di testa e mal di gola"},"content":{"rendered":"<p><strong><em>Caso clinico: <\/em>un paziente maschio di 44 anni si \u00e8 presentato con una forte cefalea al collo e all&#8217;occipite, con un aumento della flessione\/rotazione e un dolore progressivo al collo e alla deglutizione. In laboratorio, \u00e8 stato possibile rilevare una leucocitosi (13.000\u00d7 109\/l) e un aumento della CRP (52,2 mg\/l). Tuttavia, nel caso di sospetto primario di meningite, l&#8217;analisi del liquor non ha mostrato alcuna anomalia. Con un dolore al collo e una cefalea quasi refrattari (nonostante la terapia del dolore adattata), \u00e8 seguita una risonanza magnetica del cranio con risultati intracranici adeguati all&#8217;et\u00e0, ma con evidenza di un processo iperintenso T2 parzialmente registrato a livello retrofaringeo.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La faringo-laringoscopia non ha rivelato alcuna evidenza di infezione locale, ma i riflessi di deglutizione erano assenti alla provocazione del dolore sulla parete faringea posteriore. La successiva risonanza magnetica del collo ha dimostrato una marcata alterazione del segnale del muscolo longus colli, con una formazione iperintensa T2w a forma di fuso lungo tra il muscolo longus colli e la parete faringea posteriore <strong>(Fig. 1A) <\/strong>senza restrizione della diffusione e con una moderata e marginale captazione del contrasto. C&#8217;era anche un edema della parete faringea posteriore, compresa la mucosa (freccia nella Fig. 1B) e alterazioni di segnale piuttosto lievi nei tessuti molli adiacenti. Non c&#8217;erano linfadenopatie evidenti. Questi reperti tendevano a sconsigliare un ascesso retrofaringeo, che poteva essere escluso anche mediante una puntura locale (poco liquido sieroso senza evidenza di germi). Con un segnale regolare dai corpi vertebrali cervicali, era anche improbabile che la spondilodiscite fosse la causa di una raccolta retrofaringea.<br \/>\n&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-6693\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36.jpg\" style=\"height:606px; width:800px\" width=\"1100\" height=\"833\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36-800x606.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36-120x90.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36-90x68.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36-320x242.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/02\/abb1_np1_s36-560x424.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>In T1w e T2w, sono state trovate strutture a basso segnale nell&#8217;inserzione del tendine del muscolo longus colli al tubercolo antero dell&#8217;atlante (freccia in  <strong>Fig. 1C),  <\/strong>Questo ha portato al sospetto di una rara tendinite acuta e calcificante del muscolo longus colli, che \u00e8 stata confermata nel corso dell&#8217;esame mediante una TAC del collo.<br \/>\nLe calcificazioni amorfe nel tendine del muscolo lungo <strong>(Fig. 1C-E)<\/strong> sono patognomoniche per questo quadro clinico. Dopo alcuni giorni di terapia steroidea e successiva terapia antinfiammatoria, la tendinite \u00e8 chiaramente scomparsa, cos\u00ec come i disturbi del paziente.<\/p>\n<p><strong>Quadro clinico: <\/strong>il quadro clinico \u00e8 stato descritto per la prima volta nel 1964 [1]. Nel frattempo, esistono diversi rapporti di casi. Analogamente all&#8217;esempio precedente, i pazienti colpiti lamentano spesso cefalea occipitale e dolore al collo ad insorgenza subacuta, rigidit\u00e0 del collo, mal di gola e febbre [2]. Questi sintomi inizialmente suggeriscono meningite, emorragia subaracnoidea, spondilodiscite o ascesso retrofaringeo. I parametri di laboratorio sono per lo pi\u00f9 aspecifici, occasionalmente segni di infiammazione da lieve a moderatamente elevati. Le difficolt\u00e0 di deglutizione seguono nel corso dei giorni. L&#8217;et\u00e0 tipica dei pazienti \u00e8 dalla terza alla sesta decade di vita; donne e uomini sono colpiti con la stessa frequenza.<\/p>\n<p>Una possibile causa della tendinite calcificante del muscolo longus colli \u00e8 la malattia da deposito di pirofosfato di calcio diidrato (CPPD), che \u00e8 caratterizzata dalla deposizione di fosfati di calcio nei tessuti periarticolari (prevalentemente nei tendini) e colpisce principalmente le articolazioni di spalla, anca, mano e caviglia. L&#8217;esatta eziologia della CPPD \u00e8 sconosciuta, ma sono stati discussi i pato-meccanismi post-traumatici (o traumi ripetuti), necrotici, ischemici e metabolici [3]. In casi rari, la CPPD pu\u00f2 interessare il muscolo longus colli.<\/p>\n<p>La M. longus colli \u00e8 composto da tre parti, pars obliqua superior, pars recta e pars obliqua inferior<strong>(Fig. 1F)<\/strong>. Nella tendinite calcificante, tipicamente le fibre della pars obliqua superior (freccia in  <strong>Fig. 1F)<\/strong>  con attaccamento al tubercolo anterius atlantis colpito da calcificazioni tipiche che portano alla diagnosi. Nel caso mostrato, c&#8217;\u00e8 un&#8217;effusione retrofaringea pronunciata, ma questa pu\u00f2 anche essere molto pi\u00f9 stretta e manifestarsi solo come una traccia di fluido retrofaringeo larga qualche millimetro. Comuni a tutti i casi sono le calcificazioni patognomoniche dell&#8217;attacco del tendine.<\/p>\n<p><strong>Discussione <\/strong>: La tendinite calcificante dei colli lunghi \u00e8 una diagnosi differenziale rara ma importante rispetto all&#8217;ascesso retrofaringeo nel dolore al collo con versamento retrofaringeo. Soprattutto, le calcificazioni patognomoniche nell&#8217;inserzione del tendine a livello della tuberosit\u00e0 anteriore dell&#8217;atlante, nonch\u00e9 l&#8217;assenza di reazioni di accompagnamento (flemmone, linfoadenopatia) aiutano a stabilire la diagnosi e ad evitare interventi invasivi importanti. La tendinite calcificante acuta del muscolo longus colli viene trattata in modo conservativo con FANS e guarisce dopo poche settimane.<\/p>\n<p>\nLetteratura:<\/p>\n<ol>\n<li>Hartley J: Dolore cervicale acuto associato a un deposito di calcio retrofaringeo. Un caso clinico. The Journal of Bone and Joint Surgery 1964; 46(A): 1753-1754.<\/li>\n<li>Offiah CE, Hall E: Tendinite calcifica acuta del muscolo Longus Colli: spettro di apparenze TC e correlazione anatomica. The British Journal of Radiology 2009; 82(978): e117-121, doi:10.1259\/bjr\/19797697.<\/li>\n<li>Hayes CW, Conway WF: Malattia da deposito di idrossiapatite di calcio. Radiographics: A Review Publication of the Radiological Society of North America 1990; 10(6): 1031-1048, doi:10.1148\/radiographics.10.6.2175444.<\/li>\n<\/ol>\n<p>\nUlteriori letture:<\/p>\n<ul>\n<li>Eastwood JD, Hudgins PA, Malone D: Versamento retrofaringeo nella tendinite calcifica prevertebrale acuta: diagnosi con TC e risonanza magnetica. AJNR Am J Neuroradiol 1999; 19(9): 1789-1792.<\/li>\n<li>Chung T, Rebello R, Gooden EA: Tendinite calcifica retrofaringea: rapporto di caso e revisione della letteratura.<\/li>\n<li>Emerg Radiol 2005; 11(6): 375-380.<\/li>\n<li>Hviid C, et al: La tendinite retrofaringea potrebbe essere pi\u00f9 comune di quanto pensiamo: un rapporto su 45 casi visti nelle cliniche chiropratiche danesi. J Manipulative Physiol Ther 2009; 32(4): 315-320.<\/li>\n<li>Ellika SK, et al: Tendinite calcifica acuta dei colli lunghi: una diagnosi per immagini. Dentomaxillofac Radiol 2008; 37(2): 121-124.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOGIA &amp; PSICHIATRIA 2016; 14(1): 36-37<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caso clinico: un paziente maschio di 44 anni si \u00e8 presentato con una forte cefalea al collo e all&#8217;occipite, con un aumento della flessione\/rotazione e un dolore progressivo al collo&hellip;<\/p>\n","protected":false},"author":7,"featured_media":54712,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Tendinite calcificante acuta del muscolo longus colli","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11528,11484,11550],"tags":[43369,43366,43362,13883,43371],"powerkit_post_featured":[],"class_list":["post-342083","post","type-post","status-publish","format-standard","has-post-thumbnail","category-casi","category-radiologia-it","category-rx-it","tag-fosfato-di-calcio","tag-longus-colli-it","tag-mal-di-gola-it","tag-mal-di-testa","tag-rigidita-del-collo","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:30:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":342087,"slug":"uma-causa-rara-de-dores-de-cabeca-e-dores-de-garganta","post_title":"Uma causa rara de dores de cabe\u00e7a e dores de garganta","href":"https:\/\/medizinonline.com\/pt-pt\/uma-causa-rara-de-dores-de-cabeca-e-dores-de-garganta\/"},"es_ES":{"locale":"es_ES","id":342038,"slug":"una-causa-poco-frecuente-de-dolores-de-cabeza-y-garganta","post_title":"Una causa poco frecuente de dolores de cabeza y garganta","href":"https:\/\/medizinonline.com\/es\/una-causa-poco-frecuente-de-dolores-de-cabeza-y-garganta\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=342083"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/54712"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=342083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=342083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=342083"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=342083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}