{"id":342085,"date":"2016-02-06T02:00:00","date_gmt":"2016-02-06T01:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/le-attivita-sportive-sono-ancora-possibili-con-unarticolazione-artificiale\/"},"modified":"2016-02-06T02:00:00","modified_gmt":"2016-02-06T01:00:00","slug":"le-attivita-sportive-sono-ancora-possibili-con-unarticolazione-artificiale","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/le-attivita-sportive-sono-ancora-possibili-con-unarticolazione-artificiale\/","title":{"rendered":"Le attivit\u00e0 sportive sono ancora possibili con un&#8217;articolazione artificiale?"},"content":{"rendered":"<p><strong>L&#8217;osteoartrite viene spesso descritta come &#8220;malattia generale delle articolazioni&#8221; o &#8220;usura delle articolazioni&#8221;. Quanto \u00e8 compatibile questa &#8220;usura articolare&#8221; con lo sport? Come si pu\u00f2 far funzionare un&#8217;articolazione della caviglia, del ginocchio, dell&#8217;anca o della spalla sovraccaricata o addirittura gi\u00e0 usurata (ad esempio, nella ginnastica artistica)?<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>L&#8217;osteoartrite \u00e8 la malattia articolare pi\u00f9 comune nei Paesi occidentali. In linea di principio, pu\u00f2 verificarsi in qualsiasi articolazione, ma pi\u00f9 spesso nell&#8217;anca, nel ginocchio, nelle mani&nbsp; e nella colonna vertebrale. Nell&#8217;osteoartrite, praticamente tutte le parti dell&#8217;articolazione sono colpite in qualche modo ad un certo punto: le due superfici articolari con i loro rivestimenti cartilaginei, la capsula e, nell&#8217;articolazione del ginocchio, i due menischi. Le sostanze abrasive di solito causano l&#8217;infiammazione della capsula articolare con la formazione di un versamento, che porta a ulteriori disturbi e infine alla rottura dei muscoli stabilizzatori dell&#8217;articolazione.<\/p>\n<h2 id=\"cosa-succede-alla-cartilagine\">Cosa succede alla cartilagine?<\/h2>\n<p>Fondamentalmente, la cartilagine svolge un ruolo centrale nell&#8217;osteoartrite. La cartilagine \u00e8 un tessuto duro ma allo stesso tempo elastico che ricopre le estremit\u00e0 ossee e garantisce che le due superfici articolari possano scorrere armoniosamente l&#8217;una contro l&#8217;altra durante i movimenti. Per vari motivi, come l&#8217;et\u00e0, il sovrappeso, il danneggiamento di altre strutture articolari (menischi, legamenti, ad esempio a causa di attivit\u00e0 sportive eccessive), la malposizione degli arti inferiori a livello dell&#8217;anca o del ginocchio (ginocchia a scatto o gambe ad arco) o malattie specifiche, si sviluppano microscopiche crepe in questi rivestimenti cartilaginei, che possono aumentare gradualmente di dimensioni. In seguito, la cartilagine tende a scheggiarsi e i piccoli frammenti articolari che entrano nella cavit\u00e0 articolare diventano la causa dell&#8217;infiammazione, quindi anche del dolore, che mantiene il circolo vizioso e favorisce la cronicizzazione. Con l&#8217;usura progressiva, la cartilagine pu\u00f2 anche scomparire completamente, in modo che le ossa dell&#8217;articolazione premano direttamente l&#8217;una contro l&#8217;altra. Queste nuove sollecitazioni portano a reazioni ossee (ad esempio, osteofiti, chiamati anche &#8220;gangli&#8221;), che aggravano l&#8217;intera sintomatologia, soprattutto il dolore.<\/p>\n<h2 id=\"sintomi-e-decorso\">Sintomi e decorso<\/h2>\n<p>I sintomi dell&#8217;osteoartrite sono inizialmente il dolore all&#8217;interno e intorno alle articolazioni, che dipende prevalentemente dal carico: Il dolore \u00e8 quindi peggiore dopo lo sforzo che a riposo, per cui si finge un miglioramento, soprattutto nella fase iniziale, con un presunto &#8220;riscaldamento&#8221;. A causa delle infiammazioni descritte, possono verificarsi delle effusioni, che vengono percepite come gonfiore e deformazione dell&#8217;articolazione. A seconda della gravit\u00e0, si verifica anche la rigidit\u00e0.<\/p>\n<p>Il decorso naturale dell&#8217;osteoartrite varia da articolazione a articolazione e da persona a persona, ma quasi sempre progredisce, fortunatamente non troppo rapidamente.<\/p>\n<h2 id=\"diagnostica\">Diagnostica<\/h2>\n<p>Per la diagnosi \u00e8 necessario un interrogatorio preciso del paziente. L&#8217;esame dell&#8217;articolazione con le deformit\u00e0 associate e le limitazioni di mobilit\u00e0 \u00e8 un altro passo importante. Tuttavia, l&#8217;esame radiografico rimane centrale, se possibile in forma caricata (non sdraiato sul lettino da visita, ma in piedi, ad esempio per gli arti inferiori). Naturalmente si pu\u00f2 utilizzare anche la risonanza magnetica, oggi molto diffusa. Fornisce informazioni sui tessuti molli che non sono visibili nella radiografia.<\/p>\n<h2 id=\"e-cosa-si-puo-fare-al-riguardo\">E cosa si pu\u00f2 fare al riguardo?<\/h2>\n<p>Contrariamente a molte affermazioni, l&#8217;osteoartrite \u00e8 una condizione curabile. Si fa una distinzione approssimativa tra misure di trattamento conservativo non chirurgico e chirurgico.<\/p>\n<p>Le misure non chirurgiche pi\u00f9 comunemente utilizzate, almeno nelle fasi iniziali, comprendono trattamenti farmacologici e non farmacologici. Nel caso di quest&#8217;ultima, vorremmo menzionare in particolare la guida muscolare, la stabilizzazione e l&#8217;ammortizzazione delle articolazioni per coloro che sono attivi nello sport. \u00c8 stato dimostrato pi\u00f9 volte che le articolazioni che hanno un buon controllo muscolare sviluppano fondamentalmente meno osteoartrite. Ma anche chi \u00e8 gi\u00e0 affetto da osteoartrite pu\u00f2 trarre molti benefici dalla fisioterapia con allenamento muscolare. Come paziente, pu\u00f2 imparare i programmi di ginnastica specifici per le articolazioni da fisioterapisti esperti ed eseguirli autonomamente a casa senza alcuno sforzo, ma con la disciplina adeguata.<\/p>\n<p>Purtroppo, non \u00e8 raro che questi trattamenti conservativi siano insufficienti, nel qual caso pu\u00f2 essere indicato un intervento chirurgico. Va da s\u00e9 che queste operazioni devono essere coordinate individualmente. Nel complesso, tuttavia, si possono distinguere le seguenti opzioni chirurgiche:<\/p>\n<ul>\n<li>I cosiddetti bagni articolari artroscopici (sempre pi\u00f9 controversi)<\/li>\n<li>Correzioni assiali con riallineamenti (particolarmente frequenti nell&#8217;articolazione del ginocchio)<\/li>\n<li>Protesi articolari.<\/li>\n<\/ul>\n<h2 id=\"lavaggio-delle-articolazioni\">Lavaggio delle articolazioni<\/h2>\n<p>Il lavaggio articolare artroscopico \u00e8 una pulizia dell&#8217;articolazione in cui le varie irregolarit\u00e0 interessate dei rivestimenti cartilaginei e delle altre strutture articolari vengono appianate e ripristinate in una certa misura. Allo stesso tempo, l&#8217;articolazione viene anche risciacquata dalle varie abrasioni che si sono accumulate. Nelle forme di artrosi non troppo avanzate, questi interventi relativamente sicuri e non troppo costosi possono portare a un miglioramento temporaneo.<\/p>\n<h2 id=\"correzioni-degli-assi-con-conversioni\">Correzioni degli assi con conversioni<\/h2>\n<p>Nel caso delle correzioni e dei riallineamenti dell&#8217;asse, che vengono ancora eseguiti molto comunemente sull&#8217;articolazione del ginocchio, l&#8217;intero asse della gamba viene corretto mediante un intervento che prevede la rimozione di una parte ossea nella parte superiore o inferiore della gamba, in modo tale che il peso venga spostato su uno strato di cartilagine conservato. Quindi \u00e8 possibile eseguire un&#8217;operazione di questo tipo sul ginocchio solo se una parte dell&#8217;articolazione \u00e8 ancora ragionevolmente intatta. Questo accade spesso in relazione a lesioni sportive, ad esempio del menisco, dove di solito \u00e8 colpito solo un lato (pi\u00f9 spesso il lato interno). Soprattutto i pazienti pi\u00f9 giovani, che sono fondamentalmente troppo giovani per una sostituzione totale dell&#8217;articolazione, vengono sottoposti a una correzione dell&#8217;asse.<\/p>\n<h2 id=\"sostituzione-protesi-articolare\">Sostituzione\/protesi articolare<\/h2>\n<p>La terza opzione \u00e8 la sostituzione dell&#8217;articolazione o protesi, che pu\u00f2 essere totale o emipelvica. L&#8217;esperienza con questa tecnica chirurgica \u00e8 stata acquisita per ben 50 anni, prima nell&#8217;area dell&#8217;anca, ma ora frequentemente nell&#8217;area del ginocchio, nell&#8217;articolazione della caviglia e nelle articolazioni degli arti superiori (ad esempio, la spalla). Le parti danneggiate di entrambe le ossa che formano l&#8217;articolazione vengono rimosse e sostituite con materiale artificiale.<\/p>\n<p>Nella decisione accurata di farsi impiantare un&#8217;articolazione artificiale, il chirurgo di solito si preoccupa pi\u00f9 del paziente della domanda: la protesi invecchier\u00e0 pi\u00f9 del paziente o viceversa? Idealmente, l&#8217;articolazione artificiale sopravvive al paziente. Pi\u00f9 il paziente \u00e8 anziano al momento dell&#8217;intervento, pi\u00f9 questo obiettivo \u00e8 raggiungibile. Le ricerche dimostrano che dopo 15 anni, il 90-95% delle protesi del ginocchio e dell&#8217;anca sono ancora intatte. Per le persone giovani e attive, tuttavia, l&#8217;aspettativa di vita delle protesi \u00e8 leggermente inferiore. Pi\u00f9 attivo \u00e8 il portatore di protesi, maggiore \u00e8 l&#8217;usura delle varie parti della protesi. Gli accoppiamenti di materiali utilizzati nei giunti possono essere molto diversi (metallo, polietilene, ceramica). Lo scorrimento di questi diversi componenti l&#8217;uno sull&#8217;altro crea le cosiddette abrasioni, che sono attualmente il problema principale delle moderne articolazioni artificiali. \u00c8 stato dimostrato che nell&#8217;articolazione dell&#8217;anca, fino a 500.000 microparticelle vengono abrase dal cotile in polietilene in un solo passaggio. Se considera che una persona fa circa 1 milione di passi all&#8217;anno, pu\u00f2 ben immaginare che gli strati che scivolano l&#8217;uno sull&#8217;altro diventano sempre pi\u00f9 sottili e possono rompersi. Questa usura \u00e8 ovviamente anche proporzionale alle forze che agiscono sull&#8217;articolazione. Pertanto, le sollecitazioni sportive rappresentano di per s\u00e9 un certo pericolo. Quindi si pone sempre la domanda su quali sport siano consentiti e quali no. Allo stesso tempo, per\u00f2, bisogna rendersi conto che un osso caricato diventa pi\u00f9 solido grazie alle tensioni muscolari che agiscono su di esso, e che una muscolatura ben allenata funziona come un elemento di smorzamento. Quindi \u00e8 chiaro che bisogna trovare un compromesso ragionevole.<\/p>\n<p>Diversi studi hanno dimostrato che gli sport con movimenti di torsione stressanti, movimenti incontrollati (accelerazione, frenata, rapidi cambi di direzione), con forti carichi assiali (quando si atterra dopo i salti) e con un rapido e forte irrigidimento della gamba distesa sono piuttosto sfavorevoli. In questi studi, lo sci di fondo o addirittura lo sci alpino sono considerati possibili per le persone abili.<\/p>\n<p>Si pu\u00f2 affermare senza ulteriori indugi che alcune attivit\u00e0 sportive sono ancora possibili anche dopo l&#8217;installazione di un&#8217;articolazione artificiale. Tuttavia, tutto \u00e8 una questione di moderazione e deve essere ben discusso con il chirurgo. Come sempre, una riabilitazione ben costruita e realizzata con seriet\u00e0 \u00e8 la migliore garanzia contro l&#8217;allentamento precoce o l&#8217;abrasione eccessiva.<\/p>\n<p>&nbsp;<\/p>\n<p><em>PRATICA GP 2016; 11(1): 4-5<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;osteoartrite viene spesso descritta come &#8220;malattia generale delle articolazioni&#8221; o &#8220;usura delle articolazioni&#8221;. Quanto \u00e8 compatibile questa &#8220;usura articolare&#8221; con lo sport? Come si pu\u00f2 far funzionare un&#8217;articolazione della caviglia,&hellip;<\/p>\n","protected":false},"author":7,"featured_media":54647,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Osteoartrite e sport","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11355,11317,11511,11494,11550],"tags":[42031,43372,43370,21593,28010],"powerkit_post_featured":[],"class_list":["post-342085","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geriatria-it","category-medicina-dello-sport","category-notizie","category-reumatologia-it","category-rx-it","tag-cartilagine","tag-correzione-dellasse","tag-lavaggio-delle-articolazioni","tag-osteoartrite","tag-sport-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:58:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":342043,"slug":"as-actividades-desportivas-ainda-sao-possiveis-com-uma-articulacao-artificial","post_title":"As actividades desportivas ainda s\u00e3o poss\u00edveis com uma articula\u00e7\u00e3o artificial?","href":"https:\/\/medizinonline.com\/pt-pt\/as-actividades-desportivas-ainda-sao-possiveis-com-uma-articulacao-artificial\/"},"es_ES":{"locale":"es_ES","id":342057,"slug":"siguen-siendo-posibles-las-actividades-deportivas-con-una-articulacion-artificial","post_title":"\u00bfSiguen siendo posibles las actividades deportivas con una articulaci\u00f3n artificial?","href":"https:\/\/medizinonline.com\/es\/siguen-siendo-posibles-las-actividades-deportivas-con-una-articulacion-artificial\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=342085"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/54647"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=342085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=342085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=342085"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=342085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}