{"id":342379,"date":"2015-12-05T01:00:00","date_gmt":"2015-12-05T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/influenza-dello-stress-e-dellalimentazione\/"},"modified":"2015-12-05T01:00:00","modified_gmt":"2015-12-05T00:00:00","slug":"influenza-dello-stress-e-dellalimentazione","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/influenza-dello-stress-e-dellalimentazione\/","title":{"rendered":"Influenza dello stress e dell&#8217;alimentazione"},"content":{"rendered":"<p><strong>Chi soffre di psoriasi ha un rischio maggiore di disturbi affettivi. Di conseguenza, \u00e8 necessario chiedere loro informazioni sulla depressione, sull&#8217;ansia e sui problemi di gestione della malattia, come il comportamento di evitamento sociale e l&#8217;abuso di alcol. Esistono e si sono rivelati utili i corsi di formazione per affrontare la vita quotidiana, l&#8217;alimentazione e la cura della pelle. I medici e i pazienti devono essere consapevoli dell&#8217;aumento del rischio di malattie cardiovascolari e di diabete mellito. Lo stile di vita e la dieta (a ridotto contenuto calorico, preferibilmente mediterranea) devono essere adattati. Al paziente deve essere spiegata l&#8217;importanza dell&#8217;obesit\u00e0 e del fumo come fattori di rischio comprovati e anche i loro effetti talvolta negativi sulla terapia. Occorre sostenere un corrispondente cambiamento dello stile di vita. Gli psoriasici devono essere interrogati sui sintomi della sensibilit\u00e0 al glutine e, se positivi, devono sottoporsi al test degli anticorpi al glutine. Terapie complesse e costose potrebbero essere risparmiate da una dieta senza glutine.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Il trattamento della psoriasi si basa principalmente su terapie topiche e sistemiche immunomodulanti e sulla fototerapia. Molti malati non sanno che la psoriasi, in quanto malattia multifattoriale, pu\u00f2 essere influenzata favorevolmente anche da misure di stile di vita. Poich\u00e9 non tutti i malati rispondono allo stesso modo alle diverse misure, non esiste uno stile di vita o una dieta specifica per la psoriasi. Le persone interessate devono riconoscere molto di pi\u00f9 i fattori di influenza che sono rilevanti per loro e diventare consapevoli delle possibilit\u00e0 della propria influenza. Di seguito, vengono discussi i fattori stress, comorbidit\u00e0 psicologiche, alimentazione, obesit\u00e0 e fumo.<\/p>\n<h2 id=\"psoriasi-conoscenze-attuali-e-standard-di-trattamento\">Psoriasi &#8211; conoscenze attuali e standard di trattamento<\/h2>\n<p>La psoriasi \u00e8 una malattia infiammatoria sistemica della pelle con una prevalenza di circa il 2-3% nella popolazione generale. L&#8217;eziologia non \u00e8 del tutto chiara, ma si ipotizza un&#8217;eziologia multifattoriale con fattori genetici, ambientali e comportamentali, che molto probabilmente spiega la variabilit\u00e0 delle prevalenze nei diversi Paesi (USA 0,9%, Norvegia 8,5%) [1]. Il decorso pu\u00f2 essere molto fluttuante ed essere associato a una riduzione della qualit\u00e0 di vita simile a quella delle malattie cardiovascolari e di alcuni tipi di cancro [2].<\/p>\n<p>Negli ultimi anni, i nuovi immunosoppressori potenti ma anche costosi, i biologici, sono diventati sempre pi\u00f9 importanti nel trattamento della psoriasi. Questo \u00e8 accompagnato da costi di trattamento in aumento (25&#8217;000-35&#8217;000 CHF all&#8217;anno), soprattutto considerando la cronicit\u00e0 di questa malattia. \u00c8 quindi ancora pi\u00f9 importante prestare attenzione ai fattori eziologici non riconosciuti che influenzano favorevolmente la terapia o prevengono le esacerbazioni.<\/p>\n<p>Per rendere giustizia terapeutica alla genesi multifattoriale, si dovrebbe scegliere un approccio multimodale. Naturalmente, la predisposizione genetica di per s\u00e9 non pu\u00f2 essere modificata &#8211; ma negli ultimi anni \u00e8 diventato sempre pi\u00f9 chiaro che lo stile di vita e la dieta influenzano l&#8217;attivazione dei geni attraverso meccanismi epigenetici e influenzano i processi infiammatori [3]. Allo stesso tempo, \u00e8 possibile ridurre l&#8217;aumento del rischio di comorbidit\u00e0, come le malattie cardiovascolari e il diabete mellito.<\/p>\n<h2 id=\"psiche-e-stress\">Psiche e stress<\/h2>\n<p>Le malattie della pelle sono associate a una comorbidit\u00e0 notevolmente maggiore per le malattie mentali.<\/p>\n<p>L&#8217;entit\u00e0 di queste correlazioni \u00e8 emersa nuovamente in uno studio multicentrico europeo trasversale pubblicato nel 2014. In tredici Stati, 3635 persone con malattie della pelle e 1359 controlli sono stati intervistati in merito a depressione, disturbi d&#8217;ansia e pensieri suicidi. La psoriasi ha rappresentato il gruppo pi\u00f9 numeroso (17,4%). Complessivamente, i disturbi menzionati si sono verificati con una frequenza quasi doppia nei pazienti con pelle (29%) rispetto al gruppo di controllo (16%). La depressione si \u00e8 verificata con una frequenza pi\u00f9 che doppia, i disturbi d&#8217;ansia o i pensieri suicidi con una frequenza di una volta e mezza rispetto al gruppo di controllo. Il sottogruppo psoriasi, in particolare, ha mostrato valori elevati per questi tre disturbi (13,8%, 22,7% e 17,3% rispettivamente) [4]. La condizione psicologica pu\u00f2 essere causata dai sintomi stessi della malattia, dall&#8217;esperienza di stigmatizzazione, dalle paure sociali o da un&#8217;immagine corporea negativa <strong>(Fig.&nbsp;1) <\/strong>. D&#8217;altra parte, anche lo stress psicologico, cio\u00e8 lo stress emotivo (semplificato come &#8220;stress&#8221; nel seguito), pu\u00f2 scatenare attacchi di psoriasi o peggiorare il decorso della malattia.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-6481\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/12\/abb1_dp6_s27.png\" style=\"height:779px; width:800px\" width=\"1100\" height=\"1071\"><\/p>\n<p><strong>Stress:<\/strong> in generale, lo stress emotivo viene osservato come fattore scatenante di varie malattie dermatologiche, come la dermatite atopica, l&#8217;acne vulgaris e l&#8217;orticaria cronica. Anche nella psoriasi, gli studi mostrano una relazione coerente tra lo stress e l&#8217;espressione clinica [5]. Una grande percentuale di persone affette da psoriasi indica lo stress come la causa principale delle esacerbazioni, prima di infezioni, traumi, farmaci e dieta [6]. Tuttavia, anche l&#8217;estensione della malattia e l&#8217;esito della terapia possono essere influenzati negativamente dallo stress [7,8]. Al contrario, gli interventi psicologici sono spesso accompagnati da un miglioramento clinico [9,10]. Tuttavia, in accordo con la genesi multifattoriale, questo non vale per tutti i malati di psoriasi. Qui si fa una distinzione tra i cosiddetti &#8220;stress responders&#8221; e i &#8220;stress non-responders&#8221; [11].<\/p>\n<p>Tra il 39% e il 61% delle persone affette da psoriasi sono &#8220;rispondenti allo stress&#8221; [12]. Negli studi, lo stress \u00e8 stato suddiviso in tre categorie: &#8220;Grandi eventi di vita stressanti&#8221;, difficolt\u00e0 psicologiche o di personalit\u00e0 e mancanza di supporto sociale.<\/p>\n<p>Lo stress \u00e8 sempre un&#8217;esperienza soggettiva e si verifica quando una richiesta (dall&#8217;ambiente o da se stessi) o la sua valutazione supera le risorse disponibili (ad esempio, il supporto sociale, lo stile di personalit\u00e0, le strategie di soluzione).  <strong>(Fig.&nbsp;2).<\/strong>  In un recente studio trasversale, \u00e8 stato riscontrato che le &#8220;persone che rispondono allo stress&#8221; hanno punteggi significativamente elevati per quanto riguarda la depressione e i tratti della personalit\u00e0 come l&#8217;ansia, la sfiducia e la mancanza di assertivit\u00e0.  [13]. Sembra quindi che si tratti di una popolazione psicologicamente pi\u00f9 vulnerabile. Esistono solo pochi studi prospettici sullo stress e la psoriasi [7,14,15] e le relazioni e i meccanismi esatti non sono del tutto compresi.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6482 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/12\/abb2_dp6_s28.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/587;height:427px; width:800px\" width=\"1100\" height=\"587\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>Tuttavia, questo sottogruppo presenta biomarcatori di stress diversi, come evidenziato dal rilascio attenuato di cortisolo dopo uno stress acuto [16]. Diversi studi sperimentali hanno dimostrato un&#8217;attenuazione della risposta dell&#8217;asse ipotalamo-ipofisi-surrene e un aumento della risposta catecolaminergica simpatica allo stress nelle persone affette da psoriasi, che corrisponde a una riduzione del cortisolo e a un maggiore rilascio di catecolamine durante lo stress [16\u201319]. Questi cambiamenti indeboliscono l&#8217;effetto antinfiammatorio endogeno, che aumenta il rilascio di citochine proinfiammatorie, attiva i mastociti cutanei e compromette la funzione della barriera cutanea [19]. Si tratta quindi di un meccanismo simile al riacutizzarsi della psoriasi dopo la sospensione degli steroidi.<\/p>\n<p><strong>Terapia: <\/strong>dal punto di vista terapeutico, si raccomandano misure psicoterapeutiche, educative e di riduzione dello stress, vista l&#8217;elevata comorbilit\u00e0 con i disturbi affettivi. Tuttavia, la base di prove per interventi specifici \u00e8 eterogenea e mancano studi controllati randomizzati pi\u00f9 ampi. Tuttavia, \u00e8 importante ricordare che gli interventi psicologici sono pi\u00f9 difficili da standardizzare rispetto a quelli farmacologici, poich\u00e9 dipendono dall&#8217;utente e dalle preferenze e dalla conformit\u00e0 dei partecipanti. I metodi meglio studiati includono la terapia cognitivo-comportamentale, il rilassamento muscolare progressivo jakobsoniano e la meditazione mindfulness [12]. Centrale e indipendente dal metodo \u00e8 l&#8217;induzione di uno stato di rilassamento (&#8220;risposta di rilassamento&#8221;) per contrastare lo stato di stress. Per questo sono stati descritti meccanismi fisiologici-ormonali antagonisti <strong>(Fig.&nbsp;3)<\/strong>. Questo meccanismo pu\u00f2 essere supportato anche da sport di resistenza e da un sonno sufficiente.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6483 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/12\/abb3_dp6_s30.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1078;height:784px; width:800px\" width=\"1100\" height=\"1078\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>Il gold standard \u00e8 la terapia cognitivo-comportamentale in un contesto di gruppo multidisciplinare per sei settimane, che secondo gli studi \u00e8 associata a un miglioramento dei parametri fisici, psicologici e di qualit\u00e0 della vita [9]. Questo approccio \u00e8 tanto pi\u00f9 importante in quanto l&#8217;esperienza di malattia \u00e8 stata identificata come il pi\u00f9 forte predittore di stress e disabilit\u00e0 [20].<\/p>\n<h2 id=\"influenza-dei-fattori-nutrizionali\">Influenza dei fattori nutrizionali<\/h2>\n<p>Negli ultimi anni, \u00e8 diventato sempre pi\u00f9 chiaro che numerosi componenti della dieta hanno un effetto di modulazione dell&#8217;infiammazione sull&#8217;infiammazione cronica di basso grado [21]. Questo \u00e8 stato dimostrato dal punto di vista epidemiologico, soprattutto per quanto riguarda la dieta mediterranea con la sua alta percentuale di frutta, verdura, noci e pesce [22]. Questo effetto viene attribuito ai numerosi fitonutrienti, alle fibre e agli acidi grassi omega-3. Al contrario, i carboidrati raffinati e i vari grassi tendono ad essere pro-infiammatori [23]. Sebbene si tratti di effetti a bassa soglia, nel corso degli anni l&#8217;effetto si accumula in modo non trascurabile. Se la dieta viene pesantemente modificata a favore di una dieta a basso contenuto di carboidrati, la cosiddetta &#8220;dieta chetogenica&#8221;, sono possibili effetti pi\u00f9 potenti sull&#8217;infiammazione, come \u00e8 stato dimostrato per le malattie neurologiche, il cancro e l&#8217;acne [24]. Allo stesso modo, questo effetto \u00e8 supportato dall&#8217;assunzione di acidi grassi marini omega-3 (pesci marini grassi) [25]. Tuttavia, ci sono poche prove conclusive per le diete specifiche nella psoriasi. Ci\u00f2 \u00e8 probabilmente dovuto alla variabilit\u00e0 individuale e alle difficolt\u00e0 metodologiche della ricerca. Pertanto, sono stati studiati sempre pi\u00f9 i singoli componenti alimentari, come il glutine, gli acidi grassi, la vitamina D e gli integratori antiossidanti. \u00c8 stato dimostrato che una dieta ricca di frutta e verdura fresca \u00e8 associata a un minor rischio di psoriasi [26]. Tra gli integratori, il beneficio pi\u00f9 probabile \u00e8 stato riscontrato per gli acidi grassi omega-3, anche se i dati non sono chiari. La <strong>tabella&nbsp;1<\/strong> fornisce una panoramica della situazione dello studio.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6484 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/12\/tab1_dp6_s31.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/557;height:405px; width:800px\" width=\"1100\" height=\"557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p><strong>Acidi grassi: <\/strong>anche gli acidi grassi polinsaturi, che comprendono gli acidi grassi omega-6 e omega-3, sono coinvolti in modo significativo nei processi infiammatori, oltre alle loro funzioni ormonali e immunologiche. Livelli elevati di acido arachidonico, un acido grasso omega-6, si trovano nella pelle delle placche psoriasiche. L&#8217;acido arachidonico viene convertito dall&#8217;enzima fosfolipasi A2 in leucotriene B4, un potente mediatore proinfiammatorio. Lo stesso enzima converte l&#8217;EPA, un acido grasso omega-3, in leucotriene B5 e prostaglandina E3, che hanno una minore attivit\u00e0 infiammatoria. In questo processo, gli acidi grassi omega-3 e omega-6 competono per lo stesso enzima. La presenza del substrato di acidi grassi \u00e8 quindi decisiva per i metaboliti pi\u00f9 o meno infiammatori. Si ritiene che un aumento dei livelli di acidi grassi omega-3 abbia un effetto antinfiammatorio e migliori i sintomi della psoriasi [27]. Tuttavia, gli studi sull&#8217;integrazione di acidi grassi omega-3 nella psoriasi non hanno mostrato effetti conclusivi. Questo non \u00e8 sorprendente, dato che non sono stati misurati i valori basali del siero e ci sono state diverse dosi di integratori e biodisponibilit\u00e0. Di conseguenza, gli effetti pi\u00f9 forti sono stati mostrati dai trattamenti di infusione di lipidi.<\/p>\n<p><strong>Glutine:<\/strong> Chi soffre di psoriasi ha una maggiore prevalenza di altre malattie autoimmuni, come la celiachia, il morbo di Crohn e la colite ulcerosa. Gli studi indicano processi genetici e infiammatori comuni [28]. In un ampio studio di coorte americano [29], le persone affette da psoriasi (n=25.341) hanno mostrato un rischio aumentato di 2,2 volte per la presenza di celiachia e un rischio aumentato di 2,4 volte per la sensibilit\u00e0 al glutine (anticorpi anti-gliadina positivi, nessuna enteropatia). Di conseguenza, una dieta priva di glutine \u00e8 stata in grado di determinare una riduzione significativa della gravit\u00e0 della psoriasi in singoli case report [30,31] e in due studi clinici su pazienti AGA-positivi [32,33]. Questo suggerisce un&#8217;associazione tra la sensibilit\u00e0 al glutine e la psoriasi, soprattutto perch\u00e9 sono state trovate prove di una maggiore permeabilit\u00e0 intestinale nella psoriasi [34].<\/p>\n<p><strong>Riduzione del peso: l&#8217;<\/strong>obesit\u00e0 viscerale \u00e8 associata a uno stato proinfiammatorio attraverso la secrezione di citochine come TNF-\u03b1 e IL-6 dagli adipociti. In diversi studi, l&#8217;obesit\u00e0 \u00e8 stata associata a un aumento dell&#8217;incidenza e della gravit\u00e0 della psoriasi, nonch\u00e9 a un indebolimento degli effetti terapeutici di alcuni farmaci [35]. Inoltre, le citochine IL-17 e IL-23, che sono rilevanti per la psoriasi, erano elevate nelle donne obese ma non nelle donne magre [36]. In un ampio studio di coorte inglese su 75 395 pazienti affetti da psoriasi, l&#8217;obesit\u00e0 \u00e8 stata riconosciuta come un fattore di rischio per lo sviluppo dell&#8217;artrite psoriasica [37]. Diversi studi prospettici controllati di riduzione del peso attraverso diete ipocaloriche nell&#8217;obesit\u00e0 hanno dimostrato un effetto additivo al trattamento dermatologico sulla gravit\u00e0 della psoriasi e sull&#8217;artrite [35]. \u00c8 interessante notare che nelle persone obese \u00e8 stata osservata una riduzione delle citochine infiammatorie circolanti grazie alla dieta ipocalorica [38]. Molto esemplificativi sono anche gli effetti della chirurgia bariatrica, che ha prodotto un notevole miglioramento dell&#8217;attivit\u00e0 della psoriasi in diversi casi di studio [39,40].<\/p>\n<p>Chi soffre di psoriasi ha un rischio cardiovascolare maggiore e anche un rischio maggiore di diabete [41]. Si pensa che questo sia causato da una ridotta sensibilit\u00e0 all&#8217;insulina dovuta all&#8217;infiammazione sistemica. Allo stesso modo, \u00e8 di per s\u00e9 un fattore di rischio cardiovascolare indipendente [42]. \u00c8 quindi ancora pi\u00f9 importante che le persone affette da psoriasi siano consapevoli di questo rischio e si occupino del loro stile di vita di conseguenza.<\/p>\n<h2 id=\"fumo-e-alcol\">Fumo e alcol<\/h2>\n<p>Un&#8217;analisi di diversi studi di coorte di grandi dimensioni (Nurses Health Study, Health Professionals&#8217; Follow-up Study) ha confermato che il fumo \u00e8 un fattore di rischio indipendente, con un aumento graduale del rischio di incidenza a seconda del numero di anni-pacchetto e della durata del consumo di sigarette. Il rischio di incidenza relativa per 5-24 sigarette al giorno era addirittura doppio (RR 2,04) [43]. Uno studio prospettico su pazienti con pustolosi palmoplantare ha potuto persino mostrare un miglioramento clinico dopo la cessazione del fumo rispetto alla persistenza del fumo [44].<\/p>\n<p>Il consumo eccessivo di alcol \u00e8 comune anche tra le persone con psoriasi e si correla con la gravit\u00e0 della malattia e la risposta alla terapia [45]. Tuttavia, non \u00e8 stato possibile confermare una relazione causale. Questo comportamento \u00e8 altrettanto concepibile come reazione al peso della malattia.<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Parisi R, et al: Epidemiologia globale della psoriasi: una revisione sistematica dell&#8217;incidenza e della prevalenza. Journal of Investigative Dermatology 2013; 133(2): 377-385.<\/li>\n<li>Rapp SR, et al: La psoriasi causa una disabilit\u00e0 pari a quella di altre malattie mediche importanti. Giornale dell&#8217;Accademia Americana di Dermatologia 1999; 41(3): 401-407.<\/li>\n<li>Alegr\u00eda-Torres JA, Baccarelli A, Bollati V: Epigenetica e stile di vita. Epigenomica 2011; 3(3): 267-277.<\/li>\n<li>Dalgard F, et al: Il peso psicologico delle malattie della pelle: uno studio multicentrico trasversale tra i pazienti dermatologici ambulatoriali di 13 Paesi europei. Journal of Investigative Dermatology 2015; 135(4): 984-991.<\/li>\n<li>Heller M, Lee ES, Koo JY: Lo stress come fattore di influenza nella psoriasi. Skin Therapy Lett 2011; 16(5): 1-4.<\/li>\n<li>Rigopoulos D, et al: Caratteristiche della psoriasi in Grecia: uno studio epidemiologico di una popolazione in un clima mediterraneo soleggiato. European Journal of Dermatology 2010; 20(2): 189-195.<\/li>\n<li>Verhoeven EWM, et al: Differenze individuali nell&#8217;effetto dei fattori di stress quotidiano sulla psoriasi: uno studio prospettico. British Journal of Dermatology 2009; 161(2): 295-299.<\/li>\n<li>Fortune DG, et al.: Il disagio psicologico ostacola la scomparsa della psoriasi nei pazienti trattati con la fotochemioterapia. Archivi di Dermatologia 2003; 139(6): 752-756.<\/li>\n<li>Fortune DG, et al: Un programma di gestione cognitivo-comportamentale dei sintomi come aggiunta alla terapia della psoriasi. British Journal of Dermatology 2002; 146(3): 458-465.<\/li>\n<li>Fordham B, Griffiths CEM, Bundy C: Uno studio pilota che esamina la terapia cognitiva basata sulla mindfulness nella psoriasi. Psicologia, Salute e Medicina 2015; 20(1): 121-127.<\/li>\n<li>Koo J: Psicodermatologia: un manuale pratico per i medici. Problemi attuali in dermatologia 1995; 7(6): 204-232.<\/li>\n<li>Fordham B, Griffiths CEM, Bundy C: Gli interventi di riduzione dello stress possono migliorare la psoriasi? Una recensione. Psicologia, salute e medicina 2013; 18(5): 501-514.<\/li>\n<li>Remr\u00f6d C, Sj\u00f6str\u00f6m K, Svensson \u00c5: Reattivit\u00e0 allo stress soggettivo nella psoriasi &#8211; uno studio trasversale dei tratti psicologici associati. BMC dermatology 2015; 15(1): 6.<\/li>\n<li>Gaston L, et al: Psoriasi e stress: uno studio prospettico. Journal of the American Academy of Dermatology 1987; 17(1): 82-86.<\/li>\n<li>Berg M, et al: Psoriasi e stress: uno studio prospettico. Giornale dell&#8217;Accademia Europea di Dermatologia e Venereologia 2008; 22(6): 670-674.<\/li>\n<li>Richards HL, et al: Risposta dell&#8217;asse ipotalamo-ipofisi-surrene allo stress psicologico nei pazienti con psoriasi. British Journal of Dermatology 2005; 153(6): 1114-1120.<\/li>\n<li>Arnetz BB, et al: Stress e psoriasi: reazioni psicoendocrine e metaboliche nei pazienti psoriasici durante l&#8217;esposizione a fattori di stress standardizzati. Medicina psicosomatica 1985; 47(6): 528-541.<\/li>\n<li>Buske-Kirschbaum A, et al.: Le risposte endocrine allo stress nelle malattie infiammatorie croniche della pelle mediate da TH1 (psoriasi vulgaris) &#8211; sono parallele ai cambiamenti endocrini indotti dallo stress nelle dermatosi infiammatorie mediate da TH2 (dermatite atopica)? Psiconeuroendocrinologia 2006; 31(4): 439-446.<\/li>\n<li>Evers AWM, et al: Come lo stress entra nella pelle: cortisolo e reattivit\u00e0 allo stress nella psoriasi. British Journal of Dermatology 2010; 163(5): 986-991.<\/li>\n<li>Fortune DG, et al: Stress psicologico, disagio e disabilit\u00e0 nei pazienti con psoriasi: consenso e variazione nel contributo della percezione della malattia, del coping e dell&#8217;alessitimia. British Journal of Clinical Psychology 2002; 41(2): 157-174.<\/li>\n<li>Calder PC, et al: Fattori alimentari e infiammazione di basso grado in relazione al sovrappeso e all&#8217;obesit\u00e0. British Journal of Nutrition 2011; 106(S3): S1-S78.<\/li>\n<li>Casas R, Sacanella E, Estruch R: L&#8217;effetto immunoprotettivo della dieta mediterranea contro le malattie infiammatorie croniche di basso grado. Obiettivi farmacologici dei disturbi endocrini, metabolici e immunitari 2014; 14(4): 245.<\/li>\n<li>Forsythe CE, et al.: Confronto tra diete a basso contenuto di grassi e a basso contenuto di carboidrati sulla composizione degli acidi grassi circolanti e sui marcatori dell&#8217;infiammazione. Lipidi 2008; 43(1): 65-77.<\/li>\n<li>Paoli A, et al.: Oltre la perdita di peso: una revisione degli usi terapeutici delle diete a bassissimo contenuto di carboidrati (chetogeniche). European journal of clinical nutrition 2013; 67(8): 789-796.<\/li>\n<li>Paoli A, et al: Effetti dell&#8217;integrazione di acidi grassi polinsaturi n-3 (\u03c9-3) su alcuni fattori di rischio cardiovascolare con una dieta mediterranea chetogenica. Farmaci marini 2015; 13(2): 996-1009.<\/li>\n<li>Naldi L, et al.: Fattori alimentari e rischio di psoriasi. Risultati di uno studio italiano caso-controllo. Br J Dermatol 1996; 134: 101-106.<\/li>\n<li>Ricketts JR, Rothe MJ, Grant-Kels JM: Alimentazione e psoriasi. Cliniche di dermatologia 2010; 28(6): 615-626.<\/li>\n<li>Bhatia BK, et al: Dieta e psoriasi, parte II: celiachia e ruolo della dieta senza glutine. Journal of the American Academy of Dermatology 2014; 71(2): 350-358.<\/li>\n<li>Wu JJ, et al: L&#8217;associazione della psoriasi con le malattie autoimmuni. Journal of the American Academy of Dermatology 2012; 67(5): 924-930.<\/li>\n<li>Addolorato G, et al.: Rapida regressione della psoriasi in un paziente celiaco dopo una dieta senza glutine. Digestione 2003; 68(1): 9-12.<\/li>\n<li>Frikha F, Snoussi M, Bahloul Z: Osteomalacia associata a psoriasi cutanea come caratteristica di presentazione della celiachia: un rapporto di caso. Pan African Medical Journal 2012; 11: 58.<\/li>\n<li>Micha\u00eblsson G, et al: I pazienti affetti da psoriasi con anticorpi alla gliadina possono migliorare con una dieta priva di glutine. British Journal of Dermatology 2000; 142(1): 44-51.<\/li>\n<li>Micha\u00eblsson G, et al.: La dieta priva di glutine nei pazienti affetti da psoriasi con anticorpi alla gliadina determina una diminuzione dell&#8217;espressione della transglutaminasi tissutale e un minor numero di cellule Ki67+ nel derma. Acta dermato-venereologica 2002; 83(6): 425-429.<\/li>\n<li>Humbert P, et al: Permeabilit\u00e0 intestinale nei pazienti con psoriasi. Giornale di scienza dermatologica 1991; 2(4): 324-326.<\/li>\n<li>Debbaneh M, et al: Dieta e psoriasi, parte I: impatto degli interventi di perdita di peso. Giornale dell&#8217;Accademia Americana di Dermatologia 2014; 71(1): 133-140.<\/li>\n<li>Sumarac-Dumanovic M, et al.: Aumento dell&#8217;attivit\u00e0 dell&#8217;asse proinfiammatorio interleuchina-23\/interleuchina-17 nelle donne obese. International Journal of Obesity 2009; 33(1): 151-156.<\/li>\n<li>Love TJ, et al: Obesit\u00e0 e rischio di artrite psoriasica: uno studio basato sulla popolazione. Annali delle Malattie Reumatiche 2012; 71(8): 1273-1277.<\/li>\n<li>Hermsdorff HHM, et al.: Benefici discriminati di un modello alimentare mediterraneo all&#8217;interno di un programma dietetico ipocalorico sulle concentrazioni plasmatiche di RBP4 e altri marcatori infiammatori in soggetti obesi. Endocrine 2009; 36(3): 445-451.<\/li>\n<li>Hossler EW, Maroon MS, Mowad CM: L&#8217;intervento di bypass gastrico migliora la psoriasi. Giornale dell&#8217;Accademia Americana di Dermatologia 2011; 65(1): 198-200.<\/li>\n<li>Farias MM, et al: Psoriasi dopo la chirurgia bariatrica: evoluzione clinica e impatto sulla qualit\u00e0 di vita in 10 pazienti. Chirurgia dell&#8217;obesit\u00e0 2012; 22(6): 877-880.<\/li>\n<li>Gyldenl\u00f8ve M, et al: I pazienti con psoriasi sono resistenti all&#8217;insulina. Giornale dell&#8217;Accademia Americana di Dermatologia 2015; 72(4): 599-605.<\/li>\n<li>Coumbe AG, Pritzker MR, Duprez DA: Rischio cardiovascolare e psoriasi: oltre i fattori di rischio tradizionali. The American journal of medicine 2014; 127(1): 12-18.<\/li>\n<li>Li W, et al: Fumo e rischio di psoriasi incidente tra donne e uomini negli Stati Uniti: un&#8217;analisi combinata. American journal of epidemiology 2012; 175(5): 402-413.<\/li>\n<li>Micha\u00eblsson G, Gustafsson K, Hagforsen E: La variante della psoriasi pustolosa palmoplantare pu\u00f2 migliorare dopo la cessazione del fumo. Giornale dell&#8217;Accademia Americana di Dermatologia 2006; 54(4): 737-738.<\/li>\n<li>Murzaku EC, Bronsnick T, Rao BK: Dieta in dermatologia: parte II. Melanoma, orticaria cronica e psoriasi. Giornale dell&#8217;Accademia Americana di Dermatologia 2014; 71(6): 1053.e1-e16.<\/li>\n<li>Stangier U: Malattie della pelle e disturbo da dismorfismo corporeo. G\u00f6ttingen, Hogrefe, 2002.<\/li>\n<li>Dusek JA, Benson H: Medicina mente-corpo: un modello dell&#8217;impatto clinico comparativo delle risposte allo stress acuto e al rilassamento. Medicina del Minnesota 2009; 92(5): 47-50.&nbsp;<br \/>\n\t&nbsp;<\/li>\n<\/ol>\n<p><em>PRATICA DERMATOLOGICA 2015; 25(6): 26-32<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi soffre di psoriasi ha un rischio maggiore di disturbi affettivi. Di conseguenza, \u00e8 necessario chiedere loro informazioni sulla depressione, sull&#8217;ansia e sui problemi di gestione della malattia, come il&hellip;<\/p>\n","protected":false},"author":7,"featured_media":53905,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Stile di vita e psoriasi","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11343,11351,11519,11395,11550],"tags":[44136,12983,13986,12646,12981,13964,17227,13169],"powerkit_post_featured":[],"class_list":["post-342379","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allergologia-e-immunologia-clinica","category-dermatologia-e-venereologia","category-formazione-continua","category-nutrizione","category-rx-it","tag-biomarcatore-di-stress","tag-nutrizione","tag-orticaria","tag-prurito","tag-psoriasi","tag-psoriasi-it","tag-stress-it","tag-vitamina-d-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:14:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":342345,"slug":"influencias-do-stress-e-da-nutricao","post_title":"Influ\u00eancias do stress e da nutri\u00e7\u00e3o","href":"https:\/\/medizinonline.com\/pt-pt\/influencias-do-stress-e-da-nutricao\/"},"es_ES":{"locale":"es_ES","id":342351,"slug":"influencias-del-estres-y-la-nutricion","post_title":"Influencias del estr\u00e9s y la nutrici\u00f3n","href":"https:\/\/medizinonline.com\/es\/influencias-del-estres-y-la-nutricion\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=342379"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/53905"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=342379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=342379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=342379"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=342379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}